{"id":45561,"date":"2024-05-17T13:37:48","date_gmt":"2024-05-17T11:37:48","guid":{"rendered":"https:\/\/www.kiwoko.mom\/blogmundoanimal\/?post_type=ficha-de-raza&#038;p=45561"},"modified":"2025-04-08T15:56:51","modified_gmt":"2025-04-08T13:56:51","slug":"doberman","status":"publish","type":"ficha-de-raza","link":"https:\/\/www.kiwoko.mom\/blogmundoanimal\/ficha-de-raza\/doberman\/","title":{"rendered":"Doberman"},"content":{"rendered":"<!-- wp:heading -->\n<h2 class=\"wp-block-heading\" id=\"descripcion\">Descripci\u00f3n general de la raza<\/h2>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>El&nbsp;<strong>d\u00f3berman<\/strong>&nbsp;es una<strong> <a href=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/razas-de-perros\/\" target=\"_blank\" rel=\"noopener\" title=\"raza de perro\">raza de perro<\/a><\/strong> inconfundible. Este&nbsp;<strong>perro alem\u00e1n<\/strong>&nbsp;de gran porte y pelaje corto muy brillante es atl\u00e9tico, imponente y elegante como ning\u00fan otro.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Adem\u00e1s, el&nbsp;<strong>d\u00f3berman<\/strong>&nbsp;pertenece a la primera categor\u00eda de la&nbsp;<strong>escala de inteligencia de Stanley Coren<\/strong>. Esto quiere decir, que con el entrenamiento adecuado, ejecuta la orden a la primera el 95% de las veces. Lo que le hace ser un perro muy completo tanto en actitudes f\u00edsicas como mentales.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>\u00bfQuieres conocer su curiosa historia? Sigue leyendo, te sorprender\u00e1 su origen.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:heading {\"level\":3} -->\n<h3 class=\"wp-block-heading\">Origen<\/h3>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>El <strong>origen del D\u00f3berman<\/strong> se remonta al <strong>siglo XIX<\/strong>, cuando\u00a0un vigilante nocturno y recaudador de impuesto llamado\u00a0<strong>Karl Friedrich Luis Dobermann<\/strong>, al igual que hoy en d\u00eda, no era muy bien recibido en su labor. Por lo que el alem\u00e1n necesitaba un\u00a0<strong>perro de guardia<\/strong>\u00a0para que le acompa\u00f1ara en su jornada de trabajo y en sus rondas de vigilancia.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Empez\u00f3 a crear un perro guardi\u00e1n a trav\u00e9s del \u2014 probable\u2014 cruce entre el&nbsp;<em>black terrrier<\/em>,&nbsp;<em>rottweiler<\/em>&nbsp;y el pinscher alem\u00e1n. Luego, estos cruces se dieron con otras razas hasta que lleg\u00f3 a un perro muy parecido al&nbsp;<strong>d\u00f3berman<\/strong>&nbsp;actual.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>La aceptaci\u00f3n de la raza fue muy r\u00e1pida y el crecimiento de su popularidad se dio en tiempo r\u00e9cord. En 1899, se fund\u00f3 el primer club y enseguida, los&nbsp;<strong>d\u00f3berman<\/strong>&nbsp;se extendieron por toda Europa, empleados como perros polic\u00eda y perros guardianes.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:heading -->\n<h2 class=\"wp-block-heading\" id=\"etapas\">Etapa de cachorro del<\/h2>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>La<strong> etapa de cachorro del doberman<\/strong> es fundamental para su desarrollo emocional y conductual, extendi\u00e9ndose desde su nacimiento hasta los dos a\u00f1os aproximadamente. Durante este periodo, es crucial exponer al cachorro a diversos est\u00edmulos y situaciones para fomentar una buena adaptaci\u00f3n y evitar comportamientos temerosos o agresivos.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p> La socializaci\u00f3n temprana con personas, animales y entornos variados es esencial para desarrollar un perro adulto equilibrado y seguro. Adem\u00e1s, el entrenamiento de obediencia puede comenzar desde que son muy j\u00f3venes, aprovechando su inteligencia y capacidad de atenci\u00f3n para establecer las bases de una buena conducta. <\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>El juego y la exploraci\u00f3n del entorno tambi\u00e9n juegan un rol importante en su desarrollo cognitivo y f\u00edsico, ayudando al <strong>cachorro de D\u00f3berman<\/strong> a aprender y adaptarse de manera efectiva a su entorno. No te olvides de ofrecerles <a href=\"https:\/\/www.kiwoko.mom\/perros\/accesorios-para-perros\/juguetes-para-perros\/\" target=\"_blank\" rel=\"noopener\" title=\" juguetes para perros\"><strong>juguetes para perros<\/strong><\/a> para mordisquear y entretenerse.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:shortcode -->\n        <div id=\"external-products-TOO41850\" class=\"row external-products\">\n            <img decoding=\"async\" id=\"load-products-TOO41850\" data-src=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/themes\/kiwoko\/inc\/assets\/images\/loading.gif\" width=\"50\" height=\"50\" alt=\"loading\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 50px; --smush-placeholder-aspect-ratio: 50\/50;\">\n        <\/div>\n        <script>\n        var id_products = \"TOO41850,TOO41856,TOO41858\";\n        id_products = id_products.replace(\/\\s\/g, '');\n        var all_ids = id_products.split(\",\");\n\n        \/\/ Agregar sufijo _M a todos los c\u00f3digos\n        var all_ids = all_ids.map(function(id) {\n            return id + '_M';\n        });\n\n        var not_found_products = 1;\n        var not_found_img_product = 0;\n        var ramdom_id = Math.round(Math.random() * 10000);\n        var grid = '12';\n\t\tvar width = '220';\n\t\tvar height = '220';\n        if(all_ids.length >= 4){\n            grid = '3';\n\t\t\twidth = '151';\n\t\t\theight = '151';\n        }else if(all_ids.length == 3){\n            grid = '4';\n\t\t\twidth = '211';\n\t\t\theight = '211';\n        }else if(all_ids.length == 2){\n            grid = '6';\n        }\n\t\n\tif(!items){\n        var feed = \"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/themes\/kiwoko\/feed-channable.xml\";\n        var request = new XMLHttpRequest();\n        request.open(\"GET\", feed, false);\n        request.send();\n        var xmlFromUrl = request.responseXML;\n        var parser = new DOMParser();\n        var xmlDoc = parser.parseFromString(feed, \"text\/xml\");\n        var items = xmlFromUrl.getElementsByTagName(\"item\");\n        }\n\n        var products_found = 0;\n        for (var item of items) {\n            all_ids.forEach(function(word, index) {\n                if(item.getElementsByTagName(\"g:item_group_id\")[0].textContent == word){\n                    not_found_products = 0;\n                    id_products = item.getElementsByTagName(\"g:item_group_id\")[0].textContent;\n                    var link = item.getElementsByTagName(\"link\")[0].textContent;\n                    var image_link = 'src=\"'+item.getElementsByTagName(\"g:image_link\")[0].textContent+'\" ';\n                    var title = item.getElementsByTagName(\"title\")[0].textContent;\n\t\t\t\t\tvar customLabel0 = item.getElementsByTagName(\"g:custom_label_0\")[0]?.textContent || '';\n                    var customLabel1 = item.getElementsByTagName(\"g:custom_label_1\")[0]?.textContent || '';\n                    var product = '<div class=\"col-md-'+grid+' text-center ds-analytics-blog-cross-selling-product order-'+index+'\" style=\"cursor:pointer;\" onclick=\"dataLayer.push({'+\n                    '\\'event\\':\\'crosseling_product_click\\', '+\n                    '\\'event_name\\':\\'crosseling_product_click\\', '+\n                    '\\'link_text\\':\\'\u00a1Comprar ahora!\\', '+\n                    '\\'link_url\\':\\''+link+'\\', '+\n                    '\\'category\\':\\''+customLabel0+'\/'+customLabel1+'\\', '+\n                    '\\'product_name\\':\\''+title+'\\''+\n                    '});window.open(\\''+link+'\\');\"><img id=\"'+id_products+'\" '+image_link+' class=\"product-img-shop\" alt=\"'+title+'\"><p><a href=\"'+link+'\" target=\"_blank\" title=\"'+title+'\" style=\"color:#212529;\" class=\"ds-analytics-blog-cross-selling-product\"><strong>'+title+'<\/strong><\/a><\/p><button id=\"product-addtocart-button\" class=\"action primary tocart btn btn--secondary btn--big\" title=\"\u00a1Comprar ahora!\" type=\"submit\">\u00a1Comprar ahora! <\/button><\/div>';\n \t\t\t\t    \/\/var product = '<div class=\"col-md-'+grid+' text-center ds-analytics-blog-cross-selling-product order-'+index+'\" style=\"cursor:pointer;\" onclick=\"dataLayer.push({\\'event\\':\\'blog_cross_selling_product\\', \\'ga4EventData\\': { \\'name\\':\\'d_blog\\', \\'category\\':\\'click\\', \\'label\\':\\'producto\\', \\'element\\': \\''+link+'\\'}});window.open(\\''+link+'\\');\"><img id=\"'+id_products+'\" '+image_link+' class=\"product-img-shop\" alt=\"'+title+'\"><p><a href=\"'+link+'\" target=\"_blank\" title=\"'+title+'\" style=\"color:#212529;\" class=\"ds-analytics-blog-cross-selling-product\"><strong>'+title+'<\/strong><\/a><\/p><button id=\"product-addtocart-button\" class=\"action primary tocart btn btn--secondary btn--big\" title=\"\u00a1Comprar ahora!\" type=\"submit\">\u00a1Comprar ahora! <\/button><\/div>'; \n                    var grid_div = document.getElementById(\"external-products-TOO41850\");\n                    grid_div.innerHTML += product;\n                    products_found++;\n                }\n            });\n            if(products_found == all_ids.length){\n                break;\n            }\n        }\n        document.getElementById(\"load-products-TOO41850\").style.display = \"none\";\n        <\/script>\n    \n<!-- \/wp:shortcode -->\n\n<!-- wp:table {\"hasFixedLayout\":false,\"className\":\"is-style-stripes\"} -->\n<figure class=\"wp-block-table is-style-stripes\"><table><tbody><tr><td>        <style>.ds-icon-mobile{display:none;}@media screen and (max-width: 767px) {.ds-icon-desktop{display:none;}.ds-icon-mobile{display:inline;}}<\/style>\n    <span style=\"color:#e20b12\">\n            <svg class=\"bi d-sm-inline-block d-md-inline-block d-lg-inline-block d-xl-inline-block ds-icon-desktop\" width=\"35\" height=\"35\" fill=\"#e20b12\">\n        <use xlink:href=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/plugins\/ds-icons\/bootstrap-icons\/bootstrap-icons.svg#suit-heart-fill\"\/>\n        <\/svg>\n        <svg class=\"bi d-inline-block d-sm-none d-md-none d-lg-none d-xl-none ds-icon-mobile\" width=\"35\" height=\"35\" fill=\"#e20b12\">\n        <use xlink:href=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/plugins\/ds-icons\/bootstrap-icons\/bootstrap-icons.svg#suit-heart-fill\"\/>\n        <\/svg>\n        <\/span>\n    <\/td><td>\u00bfHa llegado un cachorro a casa? No te pierdas nuestro <strong><a href=\"https:\/\/www.kiwoko.mom\/perros\/especial-cachorro\/\" target=\"_blank\" rel=\"noopener\" title=\"especial cachorro\">especial cachorro<\/a><\/strong> con todo los productos esenciales para su bienestar y el tuyo. Y si necesitas un extra de consejos lee nuestra secci\u00f3n de \u00a1<strong><a href=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/consejos-para-cachorros-recien-llegados\/\" title=\"\">Reci\u00e9n llegados<\/a><\/strong>!<\/td><\/tr><\/tbody><\/table><\/figure>\n<!-- \/wp:table -->\n\n<!-- wp:shortcode -->\n        <section style=\"margin-top:21px;\">\n            <div class=\"\">\n                <div class=\"row\">\n                    <div class=\"container-fluid\">\n                        <div class=\"grid\">\n                            <div class=\"grid-sizer\"><\/div>\n                                                        <a href=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/el-cachorro-un-nuevo-miembro-en-la-familia\/\">\n                                <div class=\"grid-item lazyload\" style=\"background:inherit;\n                                background: -moz-linear-gradient(rgba(0, 0, 0, 0) 0%, rgba(0, 0, 0, 0.8) 100%), \n                                url(https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/uploads\/2018\/04\/bienvenida-cachorro.jpg);\n                                background: -webkit-linear-gradient(rgba(0, 0, 0, 0) 0%, rgba(0, 0, 0, 0.8) 100%), \n                                url(https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/uploads\/2018\/04\/bienvenida-cachorro.jpg);\n                                background: -o-linear-gradient(rgba(0, 0, 0, 0) 0%, rgba(0, 0, 0, 0.8) 100%), \n                                url(https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/uploads\/2018\/04\/bienvenida-cachorro.jpg);\n                                background: -ms-linear-gradient(rgba(0, 0, 0, 0) 0%, rgba(0, 0, 0, 0.8) 100%), \n                                url(https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/uploads\/2018\/04\/bienvenida-cachorro.jpg);background-size:cover;\n                                background-position: center;background-repeat: no-repeat;height:230px;\" data-bg=\"linear-gradient(rgba(0, 0, 0, 0) 0%, rgba(0, 0, 0, 0.8) 100%), \n                                url(https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/uploads\/2018\/04\/bienvenida-cachorro.jpg)\">\n                                    <p class=\"slider-caption\">Los primeros d\u00edas de un cachorro en casa: Consejos para un inicio feliz<\/p>\n                                    \n                                <\/div>\n                                <\/a>\n                                                        <a href=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/debo-dejar-a-mi-perro-dormir-en-mi-cuarto\/\">\n                                <div class=\"grid-item lazyload\" style=\"background:inherit;\n                                background: -moz-linear-gradient(rgba(0, 0, 0, 0) 0%, rgba(0, 0, 0, 0.8) 100%), \n                                url(https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/uploads\/2018\/02\/donde-debe-dormir-un-perro.jpg);\n                                background: -webkit-linear-gradient(rgba(0, 0, 0, 0) 0%, rgba(0, 0, 0, 0.8) 100%), \n                                url(https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/uploads\/2018\/02\/donde-debe-dormir-un-perro.jpg);\n                                background: -o-linear-gradient(rgba(0, 0, 0, 0) 0%, rgba(0, 0, 0, 0.8) 100%), \n                                url(https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/uploads\/2018\/02\/donde-debe-dormir-un-perro.jpg);\n                                background: -ms-linear-gradient(rgba(0, 0, 0, 0) 0%, rgba(0, 0, 0, 0.8) 100%), \n                                url(https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/uploads\/2018\/02\/donde-debe-dormir-un-perro.jpg);background-size:cover;\n                                background-position: center;background-repeat: no-repeat;height:230px;\" data-bg=\"linear-gradient(rgba(0, 0, 0, 0) 0%, rgba(0, 0, 0, 0.8) 100%), \n                                url(https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/uploads\/2018\/02\/donde-debe-dormir-un-perro.jpg)\">\n                                    <p class=\"slider-caption\">\u00bfD\u00f3nde debe dormir un perro? Consejos y recomendaciones<\/p>\n                                    \n                                <\/div>\n                                <\/a>\n                                                        <a href=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/que-tipo-de-antiparasitarios-debo-usar-con-cachorros\/\">\n                                <div class=\"grid-item lazyload\" style=\"background:inherit;\n                                background: -moz-linear-gradient(rgba(0, 0, 0, 0) 0%, rgba(0, 0, 0, 0.8) 100%), \n                                url(https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/uploads\/2019\/03\/como-desparasitar-a-un-cachorro-min.jpg);\n                                background: -webkit-linear-gradient(rgba(0, 0, 0, 0) 0%, rgba(0, 0, 0, 0.8) 100%), \n                                url(https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/uploads\/2019\/03\/como-desparasitar-a-un-cachorro-min.jpg);\n                                background: -o-linear-gradient(rgba(0, 0, 0, 0) 0%, rgba(0, 0, 0, 0.8) 100%), \n                                url(https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/uploads\/2019\/03\/como-desparasitar-a-un-cachorro-min.jpg);\n                                background: -ms-linear-gradient(rgba(0, 0, 0, 0) 0%, rgba(0, 0, 0, 0.8) 100%), \n                                url(https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/uploads\/2019\/03\/como-desparasitar-a-un-cachorro-min.jpg);background-size:cover;\n                                background-position: center;background-repeat: no-repeat;height:230px;\" data-bg=\"linear-gradient(rgba(0, 0, 0, 0) 0%, rgba(0, 0, 0, 0.8) 100%), \n                                url(https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/uploads\/2019\/03\/como-desparasitar-a-un-cachorro-min.jpg)\">\n                                    <p class=\"slider-caption\">Desparasitar a un cachorro: cu\u00e1ndo hacerlo, tipos de antiparasitarios y productos recomendados<\/p>\n                                    \n                                <\/div>\n                                <\/a>\n                                                    <\/div>\n                    <\/div>\n                <\/div>\n                <script src=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/themes\/kiwoko\/inc\/assets\/js\/masonry.pkgd.min.js\"><\/script>\n                <script type=\"text\/javascript\">\n                    var $grid = jQuery('.grid').masonry({\n                        itemSelector: '.grid-item',\n                        percentPosition: true,\n                        columnWidth: '.grid-sizer',\n                    });\n                <\/script>\n\n            <\/div>\n        <\/section>\n    \n<!-- \/wp:shortcode -->\n\n<!-- wp:heading -->\n<h2 class=\"wp-block-heading\" id=\"caracter\">Car\u00e1cter del<\/h2>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>El <strong>D\u00f3berman es uno de los perros m\u00e1s inteligentes<\/strong> (5\u00ba puesto en el\u00a0<em>ranking\u00a0<\/em>de Coren en su libro <em>The Intelligence of Dogs<\/em>) y tiene una\u00a0<strong>habilidad nata para aprender r\u00e1pido, proteger y anticipar el peligro<\/strong>. Es uno de los perros m\u00e1s leales. Pero necesita un adiestramiento correcto con pulso firme, porque tiene tendencia a comportarse como un \u201cmacho alfa\u201d y ser el l\u00edder de la manada.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Adem\u00e1s de&nbsp;<strong>entrenamiento constante<\/strong>, le hace falta cari\u00f1o y compa\u00f1\u00eda. Que tenga cualidades como&nbsp;<strong>perro de guardia<\/strong>&nbsp;no significa que pueda estar \u00fanicamente en el jard\u00edn guardando la casa, ya que se convertir\u00e1 en un perro destructivo, infeliz y ladrador. Por otro lado, si le das lo que necesita, tendr\u00e1s a un&nbsp;<strong>guardi\u00e1n educado, sumiso y muy fiel<\/strong>.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Un punto a destacar es que su fama de perro guardi\u00e1n ha sido la desgracia para muchos de ellos. Los d\u00f3berman al igual que todos los perros de cualquier raza o mestizaje, no soportan el aislamiento, las inclemencias del tiempo, estar atados, o no recibir cari\u00f1o. Todo esto les ocasionan grandes problemas psicol\u00f3gicos y de comportamiento, pudi\u00e9ndose volver agresivos y destructivos. Todos los perros tienen un valor intr\u00ednseco m\u00e1s all\u00e1 de su funci\u00f3n.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Al&nbsp;<strong>d\u00f3berman<\/strong>&nbsp;le ha cubierto durante los a\u00f1os 90 un halo de<strong>&nbsp;falsos mitos<\/strong>, como que se vuelven locos, que son agresivos, que les crece el cerebro, u otros rumores descabellados infundados por el cine del momento y las peleas ilegales de perros.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Nada m\u00e1s lejos, de hecho, no son todas las comunidades auton\u00f3micas las que lo incluyen en la lista de razas potencialmente peligrosas. El&nbsp;<strong><a href=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/adiestramiento-positivo-perros\/\" target=\"_blank\" rel=\"noreferrer noopener\">adiestramiento en positivo<\/a><\/strong>, un buen educador y una familia amorosa son, sin duda, fundamentales para tener una mascota d\u00f3cil y cari\u00f1osa.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>La naturaleza del&nbsp;<strong>d\u00f3berman<\/strong>&nbsp;es ser&nbsp;<strong>desconfiado con los extra\u00f1os<\/strong>, pero&nbsp;<strong>absoluto protector con su familia<\/strong>&nbsp;y&nbsp;<strong>fiel a su due\u00f1o<\/strong>. Es por estas cualidades sumadas a su&nbsp;<strong>gran inteligencia<\/strong>&nbsp;y&nbsp;<strong>potencia f\u00edsica<\/strong>&nbsp;lo que a esta raza le ha llevado a trabajar para cuerpos de la polic\u00eda y militancia.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Como curiosidad, en Estados Unidos existe una estatua conmemorativa por sus haza\u00f1as en la Segunda Guerra Mundial.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:heading -->\n<h2 class=\"wp-block-heading\" id=\"alimentacion\">Alimentaci\u00f3n del<\/h2>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>La<strong> alimentaci\u00f3n del D\u00f3berman<\/strong> es esencial para cuidar su salud, por lo que siempre debes invertir en\u00a0<a href=\"https:\/\/www.kiwoko.mom\/perros\/comida-para-perros\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>comida de alta calidad<\/strong><\/a>\u00a0recomendada por profesionales o\u00a0<strong><a href=\"https:\/\/www.kivet.com\/clinicas-veterinarias\/\" target=\"_blank\" rel=\"noreferrer noopener\">tu veterinario<\/a><\/strong>.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Las&nbsp;<strong>golosinas<\/strong>&nbsp;pueden ser una ayuda importante en el entrenamiento, pero dar demasiadas puede causar obesidad.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Si tu&nbsp;<strong>d\u00f3berman<\/strong>&nbsp;va a estar custodiando una parcela o jard\u00edn, recuerda que hay<strong>&nbsp;<a href=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/plantas-toxicas-para-perros\/\">plantas t\u00f3xicas que podr\u00edan envenenarle<\/a><\/strong>.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Como \u00faltima recomendaci\u00f3n, ser\u00eda preventivo que comiera en peque\u00f1as porciones en vez de una gran cantidad de comida de una sola vez. Un&nbsp;<a href=\"https:\/\/www.kiwoko.mom\/perros\/accesorios-para-perros\/comederos-y-bebederos\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>comedero y bebedero<\/strong><\/a>&nbsp;<strong>en altura<\/strong>&nbsp;ayudar\u00e1 a disminuir la posibilidad de&nbsp;<strong>torsi\u00f3n de est\u00f3mago<\/strong>.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:shortcode -->\n        <div id=\"external-products-TKP26130\" class=\"row external-products\">\n            <img decoding=\"async\" id=\"load-products-TKP26130\" data-src=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/themes\/kiwoko\/inc\/assets\/images\/loading.gif\" width=\"50\" height=\"50\" alt=\"loading\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 50px; --smush-placeholder-aspect-ratio: 50\/50;\">\n        <\/div>\n        <script>\n        var id_products = \"TKP26130,FLA520822\";\n        id_products = id_products.replace(\/\\s\/g, '');\n        var all_ids = id_products.split(\",\");\n\n        \/\/ Agregar sufijo _M a todos los c\u00f3digos\n        var all_ids = all_ids.map(function(id) {\n            return id + '_M';\n        });\n\n        var not_found_products = 1;\n        var not_found_img_product = 0;\n        var ramdom_id = Math.round(Math.random() * 10000);\n        var grid = '12';\n\t\tvar width = '220';\n\t\tvar height = '220';\n        if(all_ids.length >= 4){\n            grid = '3';\n\t\t\twidth = '151';\n\t\t\theight = '151';\n        }else if(all_ids.length == 3){\n            grid = '4';\n\t\t\twidth = '211';\n\t\t\theight = '211';\n        }else if(all_ids.length == 2){\n            grid = '6';\n        }\n\t\n\tif(!items){\n        var feed = \"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/themes\/kiwoko\/feed-channable.xml\";\n        var request = new XMLHttpRequest();\n        request.open(\"GET\", feed, false);\n        request.send();\n        var xmlFromUrl = request.responseXML;\n        var parser = new DOMParser();\n        var xmlDoc = parser.parseFromString(feed, \"text\/xml\");\n        var items = xmlFromUrl.getElementsByTagName(\"item\");\n        }\n\n        var products_found = 0;\n        for (var item of items) {\n            all_ids.forEach(function(word, index) {\n                if(item.getElementsByTagName(\"g:item_group_id\")[0].textContent == word){\n                    not_found_products = 0;\n                    id_products = item.getElementsByTagName(\"g:item_group_id\")[0].textContent;\n                    var link = item.getElementsByTagName(\"link\")[0].textContent;\n                    var image_link = 'src=\"'+item.getElementsByTagName(\"g:image_link\")[0].textContent+'\" ';\n                    var title = item.getElementsByTagName(\"title\")[0].textContent;\n\t\t\t\t\tvar customLabel0 = item.getElementsByTagName(\"g:custom_label_0\")[0]?.textContent || '';\n                    var customLabel1 = item.getElementsByTagName(\"g:custom_label_1\")[0]?.textContent || '';\n                    var product = '<div class=\"col-md-'+grid+' text-center ds-analytics-blog-cross-selling-product order-'+index+'\" style=\"cursor:pointer;\" onclick=\"dataLayer.push({'+\n                    '\\'event\\':\\'crosseling_product_click\\', '+\n                    '\\'event_name\\':\\'crosseling_product_click\\', '+\n                    '\\'link_text\\':\\'\u00a1Comprar ahora!\\', '+\n                    '\\'link_url\\':\\''+link+'\\', '+\n                    '\\'category\\':\\''+customLabel0+'\/'+customLabel1+'\\', '+\n                    '\\'product_name\\':\\''+title+'\\''+\n                    '});window.open(\\''+link+'\\');\"><img id=\"'+id_products+'\" '+image_link+' class=\"product-img-shop\" alt=\"'+title+'\"><p><a href=\"'+link+'\" target=\"_blank\" title=\"'+title+'\" style=\"color:#212529;\" class=\"ds-analytics-blog-cross-selling-product\"><strong>'+title+'<\/strong><\/a><\/p><button id=\"product-addtocart-button\" class=\"action primary tocart btn btn--secondary btn--big\" title=\"\u00a1Comprar ahora!\" type=\"submit\">\u00a1Comprar ahora! <\/button><\/div>';\n \t\t\t\t    \/\/var product = '<div class=\"col-md-'+grid+' text-center ds-analytics-blog-cross-selling-product order-'+index+'\" style=\"cursor:pointer;\" onclick=\"dataLayer.push({\\'event\\':\\'blog_cross_selling_product\\', \\'ga4EventData\\': { \\'name\\':\\'d_blog\\', \\'category\\':\\'click\\', \\'label\\':\\'producto\\', \\'element\\': \\''+link+'\\'}});window.open(\\''+link+'\\');\"><img id=\"'+id_products+'\" '+image_link+' class=\"product-img-shop\" alt=\"'+title+'\"><p><a href=\"'+link+'\" target=\"_blank\" title=\"'+title+'\" style=\"color:#212529;\" class=\"ds-analytics-blog-cross-selling-product\"><strong>'+title+'<\/strong><\/a><\/p><button id=\"product-addtocart-button\" class=\"action primary tocart btn btn--secondary btn--big\" title=\"\u00a1Comprar ahora!\" type=\"submit\">\u00a1Comprar ahora! <\/button><\/div>'; \n                    var grid_div = document.getElementById(\"external-products-TKP26130\");\n                    grid_div.innerHTML += product;\n                    products_found++;\n                }\n            });\n            if(products_found == all_ids.length){\n                break;\n            }\n        }\n        document.getElementById(\"load-products-TKP26130\").style.display = \"none\";\n        <\/script>\n    \n<!-- \/wp:shortcode -->\n\n<!-- wp:heading {\"level\":3} -->\n<h3 class=\"wp-block-heading\">Etapa cachorro<\/h3>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>La\u00a0<strong>alimentaci\u00f3n para los cachorros de D\u00f3berman<\/strong>\u00a0es un aspecto primordial para el desarrollo de tu d\u00f3berman durante los primeros meses de vida hasta que cumpla un a\u00f1o de edad.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:shortcode -->\n        <div id=\"external-products-NTH88570\" class=\"row external-products\">\n            <img decoding=\"async\" id=\"load-products-NTH88570\" data-src=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/themes\/kiwoko\/inc\/assets\/images\/loading.gif\" width=\"50\" height=\"50\" alt=\"loading\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 50px; --smush-placeholder-aspect-ratio: 50\/50;\">\n        <\/div>\n        <script>\n        var id_products = \"NTH88570,ROY153439,HIL2011DA\";\n        id_products = id_products.replace(\/\\s\/g, '');\n        var all_ids = id_products.split(\",\");\n\n        \/\/ Agregar sufijo _M a todos los c\u00f3digos\n        var all_ids = all_ids.map(function(id) {\n            return id + '_M';\n        });\n\n        var not_found_products = 1;\n        var not_found_img_product = 0;\n        var ramdom_id = Math.round(Math.random() * 10000);\n        var grid = '12';\n\t\tvar width = '220';\n\t\tvar height = '220';\n        if(all_ids.length >= 4){\n            grid = '3';\n\t\t\twidth = '151';\n\t\t\theight = '151';\n        }else if(all_ids.length == 3){\n            grid = '4';\n\t\t\twidth = '211';\n\t\t\theight = '211';\n        }else if(all_ids.length == 2){\n            grid = '6';\n        }\n\t\n\tif(!items){\n        var feed = \"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/themes\/kiwoko\/feed-channable.xml\";\n        var request = new XMLHttpRequest();\n        request.open(\"GET\", feed, false);\n        request.send();\n        var xmlFromUrl = request.responseXML;\n        var parser = new DOMParser();\n        var xmlDoc = parser.parseFromString(feed, \"text\/xml\");\n        var items = xmlFromUrl.getElementsByTagName(\"item\");\n        }\n\n        var products_found = 0;\n        for (var item of items) {\n            all_ids.forEach(function(word, index) {\n                if(item.getElementsByTagName(\"g:item_group_id\")[0].textContent == word){\n                    not_found_products = 0;\n                    id_products = item.getElementsByTagName(\"g:item_group_id\")[0].textContent;\n                    var link = item.getElementsByTagName(\"link\")[0].textContent;\n                    var image_link = 'src=\"'+item.getElementsByTagName(\"g:image_link\")[0].textContent+'\" ';\n                    var title = item.getElementsByTagName(\"title\")[0].textContent;\n\t\t\t\t\tvar customLabel0 = item.getElementsByTagName(\"g:custom_label_0\")[0]?.textContent || '';\n                    var customLabel1 = item.getElementsByTagName(\"g:custom_label_1\")[0]?.textContent || '';\n                    var product = '<div class=\"col-md-'+grid+' text-center ds-analytics-blog-cross-selling-product order-'+index+'\" style=\"cursor:pointer;\" onclick=\"dataLayer.push({'+\n                    '\\'event\\':\\'crosseling_product_click\\', '+\n                    '\\'event_name\\':\\'crosseling_product_click\\', '+\n                    '\\'link_text\\':\\'\u00a1Comprar ahora!\\', '+\n                    '\\'link_url\\':\\''+link+'\\', '+\n                    '\\'category\\':\\''+customLabel0+'\/'+customLabel1+'\\', '+\n                    '\\'product_name\\':\\''+title+'\\''+\n                    '});window.open(\\''+link+'\\');\"><img id=\"'+id_products+'\" '+image_link+' class=\"product-img-shop\" alt=\"'+title+'\"><p><a href=\"'+link+'\" target=\"_blank\" title=\"'+title+'\" style=\"color:#212529;\" class=\"ds-analytics-blog-cross-selling-product\"><strong>'+title+'<\/strong><\/a><\/p><button id=\"product-addtocart-button\" class=\"action primary tocart btn btn--secondary btn--big\" title=\"\u00a1Comprar ahora!\" type=\"submit\">\u00a1Comprar ahora! <\/button><\/div>';\n \t\t\t\t    \/\/var product = '<div class=\"col-md-'+grid+' text-center ds-analytics-blog-cross-selling-product order-'+index+'\" style=\"cursor:pointer;\" onclick=\"dataLayer.push({\\'event\\':\\'blog_cross_selling_product\\', \\'ga4EventData\\': { \\'name\\':\\'d_blog\\', \\'category\\':\\'click\\', \\'label\\':\\'producto\\', \\'element\\': \\''+link+'\\'}});window.open(\\''+link+'\\');\"><img id=\"'+id_products+'\" '+image_link+' class=\"product-img-shop\" alt=\"'+title+'\"><p><a href=\"'+link+'\" target=\"_blank\" title=\"'+title+'\" style=\"color:#212529;\" class=\"ds-analytics-blog-cross-selling-product\"><strong>'+title+'<\/strong><\/a><\/p><button id=\"product-addtocart-button\" class=\"action primary tocart btn btn--secondary btn--big\" title=\"\u00a1Comprar ahora!\" type=\"submit\">\u00a1Comprar ahora! <\/button><\/div>'; \n                    var grid_div = document.getElementById(\"external-products-NTH88570\");\n                    grid_div.innerHTML += product;\n                    products_found++;\n                }\n            });\n            if(products_found == all_ids.length){\n                break;\n            }\n        }\n        document.getElementById(\"load-products-NTH88570\").style.display = \"none\";\n        <\/script>\n    \n<!-- \/wp:shortcode -->\n\n<!-- wp:table {\"hasFixedLayout\":false,\"className\":\"is-style-stripes\"} -->\n<figure class=\"wp-block-table is-style-stripes\"><table><tbody><tr><td>        <style>.ds-icon-mobile{display:none;}@media screen and (max-width: 767px) {.ds-icon-desktop{display:none;}.ds-icon-mobile{display:inline;}}<\/style>\n    <span style=\"color:#e20b12\">\n            <svg class=\"bi d-sm-inline-block d-md-inline-block d-lg-inline-block d-xl-inline-block ds-icon-desktop\" width=\"35\" height=\"35\" fill=\"#e20b12\">\n        <use xlink:href=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/plugins\/ds-icons\/bootstrap-icons\/bootstrap-icons.svg#reception-4\"\/>\n        <\/svg>\n        <svg class=\"bi d-inline-block d-sm-none d-md-none d-lg-none d-xl-none ds-icon-mobile\" width=\"35\" height=\"35\" fill=\"#e20b12\">\n        <use xlink:href=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/plugins\/ds-icons\/bootstrap-icons\/bootstrap-icons.svg#reception-4\"\/>\n        <\/svg>\n        <\/span>\n    <\/td><td>Existe una gran variedad de<strong> <\/strong><a href=\"https:\/\/www.kiwoko.mom\/perros\/especial-cachorro\/pienso-para-cachorros\/\" target=\"_blank\" rel=\"noopener\" title=\"\"><strong>piensos para cachorros<\/strong><\/a> con la idea de cubrir las necesidades nutricionales de esta etapa sin renunciar a la calidad y al sabor. Si necesitas m\u00e1s informaci\u00f3n extra, no dudes en leer nuestro art\u00edculo especial \"<a href=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/alimentacion-cachorros\/\" target=\"_blank\" rel=\"noopener\" title=\"\"><strong>Mejor pienso para cachorros<\/strong><\/a>\" te ayudar\u00e1 a elegir entre una veriedad de 1\u00aa marcas.<\/td><\/tr><\/tbody><\/table><\/figure>\n<!-- \/wp:table -->\n\n<!-- wp:heading {\"level\":3} -->\n<h3 class=\"wp-block-heading\">Etapa adulto<\/h3>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>A partir del primer a\u00f1o de tu d\u00f3berman,&nbsp;<strong><a href=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/pautas-para-cambiar-la-comida-perro\/\" target=\"_blank\" rel=\"noreferrer noopener\">tendr\u00e1s que cambiarle el pienso<\/a><\/strong>&nbsp;a otro&nbsp;<strong>de alta calidad para perros adultos de raza grande.<\/strong><\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:shortcode -->\n        <div id=\"external-products-NTH88577\" class=\"row external-products\">\n            <img decoding=\"async\" id=\"load-products-NTH88577\" data-src=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/themes\/kiwoko\/inc\/assets\/images\/loading.gif\" width=\"50\" height=\"50\" alt=\"loading\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 50px; --smush-placeholder-aspect-ratio: 50\/50;\">\n        <\/div>\n        <script>\n        var id_products = \"NTH88577,DGX40017,ROY153637\";\n        id_products = id_products.replace(\/\\s\/g, '');\n        var all_ids = id_products.split(\",\");\n\n        \/\/ Agregar sufijo _M a todos los c\u00f3digos\n        var all_ids = all_ids.map(function(id) {\n            return id + '_M';\n        });\n\n        var not_found_products = 1;\n        var not_found_img_product = 0;\n        var ramdom_id = Math.round(Math.random() * 10000);\n        var grid = '12';\n\t\tvar width = '220';\n\t\tvar height = '220';\n        if(all_ids.length >= 4){\n            grid = '3';\n\t\t\twidth = '151';\n\t\t\theight = '151';\n        }else if(all_ids.length == 3){\n            grid = '4';\n\t\t\twidth = '211';\n\t\t\theight = '211';\n        }else if(all_ids.length == 2){\n            grid = '6';\n        }\n\t\n\tif(!items){\n        var feed = \"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/themes\/kiwoko\/feed-channable.xml\";\n        var request = new XMLHttpRequest();\n        request.open(\"GET\", feed, false);\n        request.send();\n        var xmlFromUrl = request.responseXML;\n        var parser = new DOMParser();\n        var xmlDoc = parser.parseFromString(feed, \"text\/xml\");\n        var items = xmlFromUrl.getElementsByTagName(\"item\");\n        }\n\n        var products_found = 0;\n        for (var item of items) {\n            all_ids.forEach(function(word, index) {\n                if(item.getElementsByTagName(\"g:item_group_id\")[0].textContent == word){\n                    not_found_products = 0;\n                    id_products = item.getElementsByTagName(\"g:item_group_id\")[0].textContent;\n                    var link = item.getElementsByTagName(\"link\")[0].textContent;\n                    var image_link = 'src=\"'+item.getElementsByTagName(\"g:image_link\")[0].textContent+'\" ';\n                    var title = item.getElementsByTagName(\"title\")[0].textContent;\n\t\t\t\t\tvar customLabel0 = item.getElementsByTagName(\"g:custom_label_0\")[0]?.textContent || '';\n                    var customLabel1 = item.getElementsByTagName(\"g:custom_label_1\")[0]?.textContent || '';\n                    var product = '<div class=\"col-md-'+grid+' text-center ds-analytics-blog-cross-selling-product order-'+index+'\" style=\"cursor:pointer;\" onclick=\"dataLayer.push({'+\n                    '\\'event\\':\\'crosseling_product_click\\', '+\n                    '\\'event_name\\':\\'crosseling_product_click\\', '+\n                    '\\'link_text\\':\\'\u00a1Comprar ahora!\\', '+\n                    '\\'link_url\\':\\''+link+'\\', '+\n                    '\\'category\\':\\''+customLabel0+'\/'+customLabel1+'\\', '+\n                    '\\'product_name\\':\\''+title+'\\''+\n                    '});window.open(\\''+link+'\\');\"><img id=\"'+id_products+'\" '+image_link+' class=\"product-img-shop\" alt=\"'+title+'\"><p><a href=\"'+link+'\" target=\"_blank\" title=\"'+title+'\" style=\"color:#212529;\" class=\"ds-analytics-blog-cross-selling-product\"><strong>'+title+'<\/strong><\/a><\/p><button id=\"product-addtocart-button\" class=\"action primary tocart btn btn--secondary btn--big\" title=\"\u00a1Comprar ahora!\" type=\"submit\">\u00a1Comprar ahora! <\/button><\/div>';\n \t\t\t\t    \/\/var product = '<div class=\"col-md-'+grid+' text-center ds-analytics-blog-cross-selling-product order-'+index+'\" style=\"cursor:pointer;\" onclick=\"dataLayer.push({\\'event\\':\\'blog_cross_selling_product\\', \\'ga4EventData\\': { \\'name\\':\\'d_blog\\', \\'category\\':\\'click\\', \\'label\\':\\'producto\\', \\'element\\': \\''+link+'\\'}});window.open(\\''+link+'\\');\"><img id=\"'+id_products+'\" '+image_link+' class=\"product-img-shop\" alt=\"'+title+'\"><p><a href=\"'+link+'\" target=\"_blank\" title=\"'+title+'\" style=\"color:#212529;\" class=\"ds-analytics-blog-cross-selling-product\"><strong>'+title+'<\/strong><\/a><\/p><button id=\"product-addtocart-button\" class=\"action primary tocart btn btn--secondary btn--big\" title=\"\u00a1Comprar ahora!\" type=\"submit\">\u00a1Comprar ahora! <\/button><\/div>'; \n                    var grid_div = document.getElementById(\"external-products-NTH88577\");\n                    grid_div.innerHTML += product;\n                    products_found++;\n                }\n            });\n            if(products_found == all_ids.length){\n                break;\n            }\n        }\n        document.getElementById(\"load-products-NTH88577\").style.display = \"none\";\n        <\/script>\n    \n<!-- \/wp:shortcode -->\n\n<!-- wp:heading {\"level\":3} -->\n<h3 class=\"wp-block-heading\">Etapa senior<\/h3>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>Tu d\u00f3berman senior necesitar\u00e1 un \u00faltimo cambio cuando cumpla siete a\u00f1os, un\u00a0<strong>pienso espec\u00edfico para perros senior de raza grande<\/strong>.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:shortcode -->\n        <div id=\"external-products-DZL121\" class=\"row external-products\">\n            <img decoding=\"async\" id=\"load-products-DZL121\" data-src=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/themes\/kiwoko\/inc\/assets\/images\/loading.gif\" width=\"50\" height=\"50\" alt=\"loading\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 50px; --smush-placeholder-aspect-ratio: 50\/50;\">\n        <\/div>\n        <script>\n        var id_products = \"DZL121,ROY154170,PRO12272557\";\n        id_products = id_products.replace(\/\\s\/g, '');\n        var all_ids = id_products.split(\",\");\n\n        \/\/ Agregar sufijo _M a todos los c\u00f3digos\n        var all_ids = all_ids.map(function(id) {\n            return id + '_M';\n        });\n\n        var not_found_products = 1;\n        var not_found_img_product = 0;\n        var ramdom_id = Math.round(Math.random() * 10000);\n        var grid = '12';\n\t\tvar width = '220';\n\t\tvar height = '220';\n        if(all_ids.length >= 4){\n            grid = '3';\n\t\t\twidth = '151';\n\t\t\theight = '151';\n        }else if(all_ids.length == 3){\n            grid = '4';\n\t\t\twidth = '211';\n\t\t\theight = '211';\n        }else if(all_ids.length == 2){\n            grid = '6';\n        }\n\t\n\tif(!items){\n        var feed = \"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/themes\/kiwoko\/feed-channable.xml\";\n        var request = new XMLHttpRequest();\n        request.open(\"GET\", feed, false);\n        request.send();\n        var xmlFromUrl = request.responseXML;\n        var parser = new DOMParser();\n        var xmlDoc = parser.parseFromString(feed, \"text\/xml\");\n        var items = xmlFromUrl.getElementsByTagName(\"item\");\n        }\n\n        var products_found = 0;\n        for (var item of items) {\n            all_ids.forEach(function(word, index) {\n                if(item.getElementsByTagName(\"g:item_group_id\")[0].textContent == word){\n                    not_found_products = 0;\n                    id_products = item.getElementsByTagName(\"g:item_group_id\")[0].textContent;\n                    var link = item.getElementsByTagName(\"link\")[0].textContent;\n                    var image_link = 'src=\"'+item.getElementsByTagName(\"g:image_link\")[0].textContent+'\" ';\n                    var title = item.getElementsByTagName(\"title\")[0].textContent;\n\t\t\t\t\tvar customLabel0 = item.getElementsByTagName(\"g:custom_label_0\")[0]?.textContent || '';\n                    var customLabel1 = item.getElementsByTagName(\"g:custom_label_1\")[0]?.textContent || '';\n                    var product = '<div class=\"col-md-'+grid+' text-center ds-analytics-blog-cross-selling-product order-'+index+'\" style=\"cursor:pointer;\" onclick=\"dataLayer.push({'+\n                    '\\'event\\':\\'crosseling_product_click\\', '+\n                    '\\'event_name\\':\\'crosseling_product_click\\', '+\n                    '\\'link_text\\':\\'\u00a1Comprar ahora!\\', '+\n                    '\\'link_url\\':\\''+link+'\\', '+\n                    '\\'category\\':\\''+customLabel0+'\/'+customLabel1+'\\', '+\n                    '\\'product_name\\':\\''+title+'\\''+\n                    '});window.open(\\''+link+'\\');\"><img id=\"'+id_products+'\" '+image_link+' class=\"product-img-shop\" alt=\"'+title+'\"><p><a href=\"'+link+'\" target=\"_blank\" title=\"'+title+'\" style=\"color:#212529;\" class=\"ds-analytics-blog-cross-selling-product\"><strong>'+title+'<\/strong><\/a><\/p><button id=\"product-addtocart-button\" class=\"action primary tocart btn btn--secondary btn--big\" title=\"\u00a1Comprar ahora!\" type=\"submit\">\u00a1Comprar ahora! <\/button><\/div>';\n \t\t\t\t    \/\/var product = '<div class=\"col-md-'+grid+' text-center ds-analytics-blog-cross-selling-product order-'+index+'\" style=\"cursor:pointer;\" onclick=\"dataLayer.push({\\'event\\':\\'blog_cross_selling_product\\', \\'ga4EventData\\': { \\'name\\':\\'d_blog\\', \\'category\\':\\'click\\', \\'label\\':\\'producto\\', \\'element\\': \\''+link+'\\'}});window.open(\\''+link+'\\');\"><img id=\"'+id_products+'\" '+image_link+' class=\"product-img-shop\" alt=\"'+title+'\"><p><a href=\"'+link+'\" target=\"_blank\" title=\"'+title+'\" style=\"color:#212529;\" class=\"ds-analytics-blog-cross-selling-product\"><strong>'+title+'<\/strong><\/a><\/p><button id=\"product-addtocart-button\" class=\"action primary tocart btn btn--secondary btn--big\" title=\"\u00a1Comprar ahora!\" type=\"submit\">\u00a1Comprar ahora! <\/button><\/div>'; \n                    var grid_div = document.getElementById(\"external-products-DZL121\");\n                    grid_div.innerHTML += product;\n                    products_found++;\n                }\n            });\n            if(products_found == all_ids.length){\n                break;\n            }\n        }\n        document.getElementById(\"load-products-DZL121\").style.display = \"none\";\n        <\/script>\n    \n<!-- \/wp:shortcode -->\n\n<!-- wp:table {\"hasFixedLayout\":false,\"className\":\"is-style-stripes\"} -->\n<figure class=\"wp-block-table is-style-stripes\"><table><tbody><tr><td>        <style>.ds-icon-mobile{display:none;}@media screen and (max-width: 767px) {.ds-icon-desktop{display:none;}.ds-icon-mobile{display:inline;}}<\/style>\n    <span style=\"color:#e20b12\">\n            <svg class=\"bi d-sm-inline-block d-md-inline-block d-lg-inline-block d-xl-inline-block ds-icon-desktop\" width=\"35\" height=\"35\" fill=\"#e20b12\">\n        <use xlink:href=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/plugins\/ds-icons\/bootstrap-icons\/bootstrap-icons.svg#reply-all-fill\"\/>\n        <\/svg>\n        <svg class=\"bi d-inline-block d-sm-none d-md-none d-lg-none d-xl-none ds-icon-mobile\" width=\"35\" height=\"35\" fill=\"#e20b12\">\n        <use xlink:href=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/plugins\/ds-icons\/bootstrap-icons\/bootstrap-icons.svg#reply-all-fill\"\/>\n        <\/svg>\n        <\/span>\n    <\/td><td>Si quieres seguir ofreciendo los mejores cuidados a tu compa\u00f1ero peludo cuando sea mayor debes elegir el <a href=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/nutricion-optima-perro-senior\/\"><strong>mejor pienso para tu perro anciano<\/strong><\/a>. Para ello lee nuestro art\u00edculo <strong><a href=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/como-cambiar-la-alimentacion-de-un-perro-adulto-a-senior\/\">C\u00f3mo cambiar la alimentaci\u00f3n de un perro adulto a senior<\/a><\/strong> para realizarlo correctamente. Mira nuestras ofertas en <strong><a href=\"https:\/\/www.kiwoko.mom\/perros\/comida-para-perros\/senior1\/\" title=\"pienso senior\">pienso senior<\/a><\/strong>! <\/td><\/tr><\/tbody><\/table><\/figure>\n<!-- \/wp:table -->\n\n<!-- wp:shortcode -->\n        <section style=\"margin-top:21px;\">\n            <div class=\"\">\n                <div class=\"row\">\n                    <div class=\"container-fluid\">\n                        <div class=\"grid\">\n                            <div class=\"grid-sizer\"><\/div>\n                                                        <a href=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/descubre-la-comida-perros-gatos-true-origins\/\">\n                                <div class=\"grid-item lazyload\" style=\"background:inherit;\n                                background: -moz-linear-gradient(rgba(0, 0, 0, 0) 0%, rgba(0, 0, 0, 0.8) 100%), \n                                url(https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/uploads\/2018\/12\/True-Origins_-un-alimento-natural-completo-y-equilibrado.jpg);\n                                background: -webkit-linear-gradient(rgba(0, 0, 0, 0) 0%, rgba(0, 0, 0, 0.8) 100%), \n                                url(https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/uploads\/2018\/12\/True-Origins_-un-alimento-natural-completo-y-equilibrado.jpg);\n                                background: -o-linear-gradient(rgba(0, 0, 0, 0) 0%, rgba(0, 0, 0, 0.8) 100%), \n                                url(https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/uploads\/2018\/12\/True-Origins_-un-alimento-natural-completo-y-equilibrado.jpg);\n                                background: -ms-linear-gradient(rgba(0, 0, 0, 0) 0%, rgba(0, 0, 0, 0.8) 100%), \n                                url(https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/uploads\/2018\/12\/True-Origins_-un-alimento-natural-completo-y-equilibrado.jpg);background-size:cover;\n                                background-position: center;background-repeat: no-repeat;height:230px;\" data-bg=\"linear-gradient(rgba(0, 0, 0, 0) 0%, rgba(0, 0, 0, 0.8) 100%), \n                                url(https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/uploads\/2018\/12\/True-Origins_-un-alimento-natural-completo-y-equilibrado.jpg)\">\n                                    <p class=\"slider-caption\">True Origins: Alimentaci\u00f3n natural, completa y equilibrada para tu perro o gato<\/p>\n                                    \n                                <\/div>\n                                <\/a>\n                                                        <a href=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/descubre-nath-la-marca-de-comida-superpremium-para-perros-y-gatos\/\">\n                                <div class=\"grid-item lazyload\" style=\"background:inherit;\n                                background: -moz-linear-gradient(rgba(0, 0, 0, 0) 0%, rgba(0, 0, 0, 0.8) 100%), \n                                url(https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/uploads\/2023\/03\/nath-nueva-linea-de-comida-para-mascotas-premium.jpg);\n                                background: -webkit-linear-gradient(rgba(0, 0, 0, 0) 0%, rgba(0, 0, 0, 0.8) 100%), \n                                url(https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/uploads\/2023\/03\/nath-nueva-linea-de-comida-para-mascotas-premium.jpg);\n                                background: -o-linear-gradient(rgba(0, 0, 0, 0) 0%, rgba(0, 0, 0, 0.8) 100%), \n                                url(https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/uploads\/2023\/03\/nath-nueva-linea-de-comida-para-mascotas-premium.jpg);\n                                background: -ms-linear-gradient(rgba(0, 0, 0, 0) 0%, rgba(0, 0, 0, 0.8) 100%), \n                                url(https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/uploads\/2023\/03\/nath-nueva-linea-de-comida-para-mascotas-premium.jpg);background-size:cover;\n                                background-position: center;background-repeat: no-repeat;height:230px;\" data-bg=\"linear-gradient(rgba(0, 0, 0, 0) 0%, rgba(0, 0, 0, 0.8) 100%), \n                                url(https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/uploads\/2023\/03\/nath-nueva-linea-de-comida-para-mascotas-premium.jpg)\">\n                                    <p class=\"slider-caption\">NATH, la marca de comida superpremium para perros y gatos<\/p>\n                                    \n                                <\/div>\n                                <\/a>\n                                                        <a href=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/mejor-pienso-natural-para-perros\/\">\n                                <div class=\"grid-item lazyload\" style=\"background:inherit;\n                                background: -moz-linear-gradient(rgba(0, 0, 0, 0) 0%, rgba(0, 0, 0, 0.8) 100%), \n                                url(https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/uploads\/2022\/01\/mejor-pienso-natural-para-perros.jpg);\n                                background: -webkit-linear-gradient(rgba(0, 0, 0, 0) 0%, rgba(0, 0, 0, 0.8) 100%), \n                                url(https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/uploads\/2022\/01\/mejor-pienso-natural-para-perros.jpg);\n                                background: -o-linear-gradient(rgba(0, 0, 0, 0) 0%, rgba(0, 0, 0, 0.8) 100%), \n                                url(https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/uploads\/2022\/01\/mejor-pienso-natural-para-perros.jpg);\n                                background: -ms-linear-gradient(rgba(0, 0, 0, 0) 0%, rgba(0, 0, 0, 0.8) 100%), \n                                url(https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/uploads\/2022\/01\/mejor-pienso-natural-para-perros.jpg);background-size:cover;\n                                background-position: center;background-repeat: no-repeat;height:230px;\" data-bg=\"linear-gradient(rgba(0, 0, 0, 0) 0%, rgba(0, 0, 0, 0.8) 100%), \n                                url(https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/uploads\/2022\/01\/mejor-pienso-natural-para-perros.jpg)\">\n                                    <p class=\"slider-caption\">\u00bfCu\u00e1l es el mejor pienso natural para perros?<\/p>\n                                    \n                                <\/div>\n                                <\/a>\n                                                    <\/div>\n                    <\/div>\n                <\/div>\n                <script src=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/themes\/kiwoko\/inc\/assets\/js\/masonry.pkgd.min.js\"><\/script>\n                <script type=\"text\/javascript\">\n                    var $grid = jQuery('.grid').masonry({\n                        itemSelector: '.grid-item',\n                        percentPosition: true,\n                        columnWidth: '.grid-sizer',\n                    });\n                <\/script>\n\n            <\/div>\n        <\/section>\n    \n<!-- \/wp:shortcode -->\n\n<!-- wp:heading -->\n<h2 class=\"wp-block-heading\" id=\"salud\">Salud del<\/h2>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>Entre las <strong>enfermedades del D\u00f3berman<\/strong> m\u00e1s comunes se encuentran las afecciones card\u00edacas, especialmente la cardiomiopat\u00eda dilatada, que afecta la capacidad del coraz\u00f3n para bombear sangre eficientemente. Tambi\u00e9n son susceptibles a la displasia de cadera, una<strong> malformaci\u00f3n de la articulaci\u00f3n de la cadera <\/strong>que puede provocar dolor y problemas de movilidad. Adem\u00e1s, los d\u00f3berman pueden padecer<strong> hipotiroidismo<\/strong>, una condici\u00f3n donde la gl\u00e1ndula tiroides no produce suficientes hormonas, afectando su metabolismo y energ\u00eda. Para garantizar una vida saludable y larga, se recomienda una dieta equilibrada, ejercicio regular y seguimiento m\u00e9dico continuo para detectar y tratar cualquier signo de estas y otras <strong>enfermedades del D\u00f3berman<\/strong> a tiempo. A veces, el veterinario puede recomendar alg\u00fan tipo de suplementaci\u00f3n:<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:shortcode -->\n        <div id=\"external-products-ESTSE506111\" class=\"row external-products\">\n            <img decoding=\"async\" id=\"load-products-ESTSE506111\" data-src=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/themes\/kiwoko\/inc\/assets\/images\/loading.gif\" width=\"50\" height=\"50\" alt=\"loading\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 50px; --smush-placeholder-aspect-ratio: 50\/50;\">\n        <\/div>\n        <script>\n        var id_products = \"ESTSE506111,VETVK0RVJ,BIIF104200\";\n        id_products = id_products.replace(\/\\s\/g, '');\n        var all_ids = id_products.split(\",\");\n\n        \/\/ Agregar sufijo _M a todos los c\u00f3digos\n        var all_ids = all_ids.map(function(id) {\n            return id + '_M';\n        });\n\n        var not_found_products = 1;\n        var not_found_img_product = 0;\n        var ramdom_id = Math.round(Math.random() * 10000);\n        var grid = '12';\n\t\tvar width = '220';\n\t\tvar height = '220';\n        if(all_ids.length >= 4){\n            grid = '3';\n\t\t\twidth = '151';\n\t\t\theight = '151';\n        }else if(all_ids.length == 3){\n            grid = '4';\n\t\t\twidth = '211';\n\t\t\theight = '211';\n        }else if(all_ids.length == 2){\n            grid = '6';\n        }\n\t\n\tif(!items){\n        var feed = \"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/themes\/kiwoko\/feed-channable.xml\";\n        var request = new XMLHttpRequest();\n        request.open(\"GET\", feed, false);\n        request.send();\n        var xmlFromUrl = request.responseXML;\n        var parser = new DOMParser();\n        var xmlDoc = parser.parseFromString(feed, \"text\/xml\");\n        var items = xmlFromUrl.getElementsByTagName(\"item\");\n        }\n\n        var products_found = 0;\n        for (var item of items) {\n            all_ids.forEach(function(word, index) {\n                if(item.getElementsByTagName(\"g:item_group_id\")[0].textContent == word){\n                    not_found_products = 0;\n                    id_products = item.getElementsByTagName(\"g:item_group_id\")[0].textContent;\n                    var link = item.getElementsByTagName(\"link\")[0].textContent;\n                    var image_link = 'src=\"'+item.getElementsByTagName(\"g:image_link\")[0].textContent+'\" ';\n                    var title = item.getElementsByTagName(\"title\")[0].textContent;\n\t\t\t\t\tvar customLabel0 = item.getElementsByTagName(\"g:custom_label_0\")[0]?.textContent || '';\n                    var customLabel1 = item.getElementsByTagName(\"g:custom_label_1\")[0]?.textContent || '';\n                    var product = '<div class=\"col-md-'+grid+' text-center ds-analytics-blog-cross-selling-product order-'+index+'\" style=\"cursor:pointer;\" onclick=\"dataLayer.push({'+\n                    '\\'event\\':\\'crosseling_product_click\\', '+\n                    '\\'event_name\\':\\'crosseling_product_click\\', '+\n                    '\\'link_text\\':\\'\u00a1Comprar ahora!\\', '+\n                    '\\'link_url\\':\\''+link+'\\', '+\n                    '\\'category\\':\\''+customLabel0+'\/'+customLabel1+'\\', '+\n                    '\\'product_name\\':\\''+title+'\\''+\n                    '});window.open(\\''+link+'\\');\"><img id=\"'+id_products+'\" '+image_link+' class=\"product-img-shop\" alt=\"'+title+'\"><p><a href=\"'+link+'\" target=\"_blank\" title=\"'+title+'\" style=\"color:#212529;\" class=\"ds-analytics-blog-cross-selling-product\"><strong>'+title+'<\/strong><\/a><\/p><button id=\"product-addtocart-button\" class=\"action primary tocart btn btn--secondary btn--big\" title=\"\u00a1Comprar ahora!\" type=\"submit\">\u00a1Comprar ahora! <\/button><\/div>';\n \t\t\t\t    \/\/var product = '<div class=\"col-md-'+grid+' text-center ds-analytics-blog-cross-selling-product order-'+index+'\" style=\"cursor:pointer;\" onclick=\"dataLayer.push({\\'event\\':\\'blog_cross_selling_product\\', \\'ga4EventData\\': { \\'name\\':\\'d_blog\\', \\'category\\':\\'click\\', \\'label\\':\\'producto\\', \\'element\\': \\''+link+'\\'}});window.open(\\''+link+'\\');\"><img id=\"'+id_products+'\" '+image_link+' class=\"product-img-shop\" alt=\"'+title+'\"><p><a href=\"'+link+'\" target=\"_blank\" title=\"'+title+'\" style=\"color:#212529;\" class=\"ds-analytics-blog-cross-selling-product\"><strong>'+title+'<\/strong><\/a><\/p><button id=\"product-addtocart-button\" class=\"action primary tocart btn btn--secondary btn--big\" title=\"\u00a1Comprar ahora!\" type=\"submit\">\u00a1Comprar ahora! <\/button><\/div>'; \n                    var grid_div = document.getElementById(\"external-products-ESTSE506111\");\n                    grid_div.innerHTML += product;\n                    products_found++;\n                }\n            });\n            if(products_found == all_ids.length){\n                break;\n            }\n        }\n        document.getElementById(\"load-products-ESTSE506111\").style.display = \"none\";\n        <\/script>\n    \n<!-- \/wp:shortcode -->\n\n<!-- wp:heading -->\n<h2 class=\"wp-block-heading\" id=\"cuidados\">Cuidados del<\/h2>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>El&nbsp;<strong>d\u00f3berman,<\/strong>&nbsp;como hemos ido se\u00f1alando, necesita actividad f\u00edsica, un due\u00f1o que intervenga en su educaci\u00f3n y&nbsp;<strong><a href=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/importancia-socializacion-temprana-perros\/\" target=\"_blank\" rel=\"noreferrer noopener\">socializaci\u00f3n<\/a><\/strong>&nbsp;con personas y otros animales. Pues el comportamiento de un d\u00f3berman, o cualquier otro perro, se debe \u00fanicamente en la&nbsp;<strong>educaci\u00f3n<\/strong>&nbsp;y&nbsp;<strong>experiencias vividas<\/strong>.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>La raza&nbsp;<strong>d\u00f3berman<\/strong>&nbsp;es una de las razas con la que m\u00e1s se ha practicado la amputaci\u00f3n de rabo y orejas por fines est\u00e9ticos. Desde el 1 de febrero de 2018 es una pr\u00e1ctica es ilegal en Espa\u00f1a.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>El mantenimiento de esta raza es b\u00e1sico. Controlar la suciedad de las orejas, la&nbsp;<a href=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/la-higiene-dental-en-los-perros\/\" title=\"\"><strong>higiene bucal<\/strong><\/a>, un cepillado una vez al mes, y un control veterinario regular para mantener su salud y anticiparse a posibles enfermedades. Igualmente, debes protegerlo durante todo el a\u00f1o de par\u00e1sitos tanto internamente como externamente con <strong><a href=\"https:\/\/www.kiwoko.mom\/perros\/higiene-para-perros\/antiparasitarios\/\" target=\"_blank\" rel=\"noopener\" title=\"\">productos antiparasitarios para perros<\/a><\/strong>. \u00a1Cons\u00faltalo con tu veterinario!<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:shortcode -->\n        <div id=\"external-products-MSD178993\" class=\"row external-products\">\n            <img decoding=\"async\" id=\"load-products-MSD178993\" data-src=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/themes\/kiwoko\/inc\/assets\/images\/loading.gif\" width=\"50\" height=\"50\" alt=\"loading\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 50px; --smush-placeholder-aspect-ratio: 50\/50;\">\n        <\/div>\n        <script>\n        var id_products = \"MSD178993,MDC41260,BEA17233,BAY83883988_5_X2_B\";\n        id_products = id_products.replace(\/\\s\/g, '');\n        var all_ids = id_products.split(\",\");\n\n        \/\/ Agregar sufijo _M a todos los c\u00f3digos\n        var all_ids = all_ids.map(function(id) {\n            return id + '_M';\n        });\n\n        var not_found_products = 1;\n        var not_found_img_product = 0;\n        var ramdom_id = Math.round(Math.random() * 10000);\n        var grid = '12';\n\t\tvar width = '220';\n\t\tvar height = '220';\n        if(all_ids.length >= 4){\n            grid = '3';\n\t\t\twidth = '151';\n\t\t\theight = '151';\n        }else if(all_ids.length == 3){\n            grid = '4';\n\t\t\twidth = '211';\n\t\t\theight = '211';\n        }else if(all_ids.length == 2){\n            grid = '6';\n        }\n\t\n\tif(!items){\n        var feed = \"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/themes\/kiwoko\/feed-channable.xml\";\n        var request = new XMLHttpRequest();\n        request.open(\"GET\", feed, false);\n        request.send();\n        var xmlFromUrl = request.responseXML;\n        var parser = new DOMParser();\n        var xmlDoc = parser.parseFromString(feed, \"text\/xml\");\n        var items = xmlFromUrl.getElementsByTagName(\"item\");\n        }\n\n        var products_found = 0;\n        for (var item of items) {\n            all_ids.forEach(function(word, index) {\n                if(item.getElementsByTagName(\"g:item_group_id\")[0].textContent == word){\n                    not_found_products = 0;\n                    id_products = item.getElementsByTagName(\"g:item_group_id\")[0].textContent;\n                    var link = item.getElementsByTagName(\"link\")[0].textContent;\n                    var image_link = 'src=\"'+item.getElementsByTagName(\"g:image_link\")[0].textContent+'\" ';\n                    var title = item.getElementsByTagName(\"title\")[0].textContent;\n\t\t\t\t\tvar customLabel0 = item.getElementsByTagName(\"g:custom_label_0\")[0]?.textContent || '';\n                    var customLabel1 = item.getElementsByTagName(\"g:custom_label_1\")[0]?.textContent || '';\n                    var product = '<div class=\"col-md-'+grid+' text-center ds-analytics-blog-cross-selling-product order-'+index+'\" style=\"cursor:pointer;\" onclick=\"dataLayer.push({'+\n                    '\\'event\\':\\'crosseling_product_click\\', '+\n                    '\\'event_name\\':\\'crosseling_product_click\\', '+\n                    '\\'link_text\\':\\'\u00a1Comprar ahora!\\', '+\n                    '\\'link_url\\':\\''+link+'\\', '+\n                    '\\'category\\':\\''+customLabel0+'\/'+customLabel1+'\\', '+\n                    '\\'product_name\\':\\''+title+'\\''+\n                    '});window.open(\\''+link+'\\');\"><img id=\"'+id_products+'\" '+image_link+' class=\"product-img-shop\" alt=\"'+title+'\"><p><a href=\"'+link+'\" target=\"_blank\" title=\"'+title+'\" style=\"color:#212529;\" class=\"ds-analytics-blog-cross-selling-product\"><strong>'+title+'<\/strong><\/a><\/p><button id=\"product-addtocart-button\" class=\"action primary tocart btn btn--secondary btn--big\" title=\"\u00a1Comprar ahora!\" type=\"submit\">\u00a1Comprar ahora! <\/button><\/div>';\n \t\t\t\t    \/\/var product = '<div class=\"col-md-'+grid+' text-center ds-analytics-blog-cross-selling-product order-'+index+'\" style=\"cursor:pointer;\" onclick=\"dataLayer.push({\\'event\\':\\'blog_cross_selling_product\\', \\'ga4EventData\\': { \\'name\\':\\'d_blog\\', \\'category\\':\\'click\\', \\'label\\':\\'producto\\', \\'element\\': \\''+link+'\\'}});window.open(\\''+link+'\\');\"><img id=\"'+id_products+'\" '+image_link+' class=\"product-img-shop\" alt=\"'+title+'\"><p><a href=\"'+link+'\" target=\"_blank\" title=\"'+title+'\" style=\"color:#212529;\" class=\"ds-analytics-blog-cross-selling-product\"><strong>'+title+'<\/strong><\/a><\/p><button id=\"product-addtocart-button\" class=\"action primary tocart btn btn--secondary btn--big\" title=\"\u00a1Comprar ahora!\" type=\"submit\">\u00a1Comprar ahora! <\/button><\/div>'; \n                    var grid_div = document.getElementById(\"external-products-MSD178993\");\n                    grid_div.innerHTML += product;\n                    products_found++;\n                }\n            });\n            if(products_found == all_ids.length){\n                break;\n            }\n        }\n        document.getElementById(\"load-products-MSD178993\").style.display = \"none\";\n        <\/script>\n    \n<!-- \/wp:shortcode -->\n\n<!-- wp:paragraph -->\n<p>Como \u00faltimo consejo sobre cuidados, si va a estar fuera de casa algunas horas que no le falte una&nbsp;<strong><a href=\"https:\/\/www.kiwoko.mom\/perros\/accesorios-para-perros\/casetas-para-perros\/\" target=\"_blank\" rel=\"noreferrer noopener\">caseta<\/a><\/strong>&nbsp;donde pueda estar<strong>&nbsp;c\u00f3modo<\/strong>&nbsp;y&nbsp;<strong>protegido<\/strong>. Es importante que sea de calidad y<strong>&nbsp;dise\u00f1ada para ser habitada por perros<\/strong>. Por supuesto, el perro necesitar\u00e1 de paseos y salir de la parcela o jard\u00edn diariamente. <\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:shortcode -->\n        <div id=\"external-products-TKP41103\" class=\"row external-products\">\n            <img decoding=\"async\" id=\"load-products-TKP41103\" data-src=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/themes\/kiwoko\/inc\/assets\/images\/loading.gif\" width=\"50\" height=\"50\" alt=\"loading\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 50px; --smush-placeholder-aspect-ratio: 50\/50;\">\n        <\/div>\n        <script>\n        var id_products = \"TKP41103,TKP58498,TKP30242\";\n        id_products = id_products.replace(\/\\s\/g, '');\n        var all_ids = id_products.split(\",\");\n\n        \/\/ Agregar sufijo _M a todos los c\u00f3digos\n        var all_ids = all_ids.map(function(id) {\n            return id + '_M';\n        });\n\n        var not_found_products = 1;\n        var not_found_img_product = 0;\n        var ramdom_id = Math.round(Math.random() * 10000);\n        var grid = '12';\n\t\tvar width = '220';\n\t\tvar height = '220';\n        if(all_ids.length >= 4){\n            grid = '3';\n\t\t\twidth = '151';\n\t\t\theight = '151';\n        }else if(all_ids.length == 3){\n            grid = '4';\n\t\t\twidth = '211';\n\t\t\theight = '211';\n        }else if(all_ids.length == 2){\n            grid = '6';\n        }\n\t\n\tif(!items){\n        var feed = \"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/themes\/kiwoko\/feed-channable.xml\";\n        var request = new XMLHttpRequest();\n        request.open(\"GET\", feed, false);\n        request.send();\n        var xmlFromUrl = request.responseXML;\n        var parser = new DOMParser();\n        var xmlDoc = parser.parseFromString(feed, \"text\/xml\");\n        var items = xmlFromUrl.getElementsByTagName(\"item\");\n        }\n\n        var products_found = 0;\n        for (var item of items) {\n            all_ids.forEach(function(word, index) {\n                if(item.getElementsByTagName(\"g:item_group_id\")[0].textContent == word){\n                    not_found_products = 0;\n                    id_products = item.getElementsByTagName(\"g:item_group_id\")[0].textContent;\n                    var link = item.getElementsByTagName(\"link\")[0].textContent;\n                    var image_link = 'src=\"'+item.getElementsByTagName(\"g:image_link\")[0].textContent+'\" ';\n                    var title = item.getElementsByTagName(\"title\")[0].textContent;\n\t\t\t\t\tvar customLabel0 = item.getElementsByTagName(\"g:custom_label_0\")[0]?.textContent || '';\n                    var customLabel1 = item.getElementsByTagName(\"g:custom_label_1\")[0]?.textContent || '';\n                    var product = '<div class=\"col-md-'+grid+' text-center ds-analytics-blog-cross-selling-product order-'+index+'\" style=\"cursor:pointer;\" onclick=\"dataLayer.push({'+\n                    '\\'event\\':\\'crosseling_product_click\\', '+\n                    '\\'event_name\\':\\'crosseling_product_click\\', '+\n                    '\\'link_text\\':\\'\u00a1Comprar ahora!\\', '+\n                    '\\'link_url\\':\\''+link+'\\', '+\n                    '\\'category\\':\\''+customLabel0+'\/'+customLabel1+'\\', '+\n                    '\\'product_name\\':\\''+title+'\\''+\n                    '});window.open(\\''+link+'\\');\"><img id=\"'+id_products+'\" '+image_link+' class=\"product-img-shop\" alt=\"'+title+'\"><p><a href=\"'+link+'\" target=\"_blank\" title=\"'+title+'\" style=\"color:#212529;\" class=\"ds-analytics-blog-cross-selling-product\"><strong>'+title+'<\/strong><\/a><\/p><button id=\"product-addtocart-button\" class=\"action primary tocart btn btn--secondary btn--big\" title=\"\u00a1Comprar ahora!\" type=\"submit\">\u00a1Comprar ahora! <\/button><\/div>';\n \t\t\t\t    \/\/var product = '<div class=\"col-md-'+grid+' text-center ds-analytics-blog-cross-selling-product order-'+index+'\" style=\"cursor:pointer;\" onclick=\"dataLayer.push({\\'event\\':\\'blog_cross_selling_product\\', \\'ga4EventData\\': { \\'name\\':\\'d_blog\\', \\'category\\':\\'click\\', \\'label\\':\\'producto\\', \\'element\\': \\''+link+'\\'}});window.open(\\''+link+'\\');\"><img id=\"'+id_products+'\" '+image_link+' class=\"product-img-shop\" alt=\"'+title+'\"><p><a href=\"'+link+'\" target=\"_blank\" title=\"'+title+'\" style=\"color:#212529;\" class=\"ds-analytics-blog-cross-selling-product\"><strong>'+title+'<\/strong><\/a><\/p><button id=\"product-addtocart-button\" class=\"action primary tocart btn btn--secondary btn--big\" title=\"\u00a1Comprar ahora!\" type=\"submit\">\u00a1Comprar ahora! <\/button><\/div>'; \n                    var grid_div = document.getElementById(\"external-products-TKP41103\");\n                    grid_div.innerHTML += product;\n                    products_found++;\n                }\n            });\n            if(products_found == all_ids.length){\n                break;\n            }\n        }\n        document.getElementById(\"load-products-TKP41103\").style.display = \"none\";\n        <\/script>\n    \n<!-- \/wp:shortcode -->\n\n<!-- wp:heading -->\n<h2 class=\"wp-block-heading\">Fotos de<\/h2>\n<!-- \/wp:heading -->\n\n<!-- wp:columns -->\n<div class=\"wp-block-columns\"><!-- wp:column -->\n<div class=\"wp-block-column\"><!-- wp:image {\"id\":50890,\"sizeSlug\":\"full\",\"linkDestination\":\"none\"} -->\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"300\" height=\"600\" data-src=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/uploads\/2024\/05\/foos-de-doberman.jpg\" alt=\"fotos de doberman\" class=\"wp-image-50890 lazyload\" data-srcset=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/uploads\/2024\/05\/foos-de-doberman.jpg 300w, https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/uploads\/2024\/05\/foos-de-doberman-150x300.jpg 150w\" data-sizes=\"(max-width: 300px) 100vw, 300px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/600;\" \/><\/figure>\n<!-- \/wp:image --><\/div>\n<!-- \/wp:column -->\n\n<!-- wp:column -->\n<div class=\"wp-block-column\"><!-- wp:image {\"id\":50891,\"sizeSlug\":\"full\",\"linkDestination\":\"none\"} -->\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"300\" height=\"600\" data-src=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/uploads\/2024\/05\/doberman-fotos.jpg\" alt=\"fotos de doberman 1\" class=\"wp-image-50891 lazyload\" data-srcset=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/uploads\/2024\/05\/doberman-fotos.jpg 300w, https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/uploads\/2024\/05\/doberman-fotos-150x300.jpg 150w\" data-sizes=\"(max-width: 300px) 100vw, 300px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/600;\" \/><\/figure>\n<!-- \/wp:image --><\/div>\n<!-- \/wp:column -->\n\n<!-- wp:column -->\n<div class=\"wp-block-column\"><!-- wp:image {\"id\":50892,\"sizeSlug\":\"full\",\"linkDestination\":\"none\"} -->\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"300\" height=\"600\" data-src=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/uploads\/2024\/05\/fotos-de-doberman-2.jpg\" alt=\"doberman fotos\" class=\"wp-image-50892 lazyload\" data-srcset=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/uploads\/2024\/05\/fotos-de-doberman-2.jpg 300w, https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/uploads\/2024\/05\/fotos-de-doberman-2-150x300.jpg 150w\" data-sizes=\"(max-width: 300px) 100vw, 300px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/600;\" \/><\/figure>\n<!-- \/wp:image --><\/div>\n<!-- \/wp:column --><\/div>\n<!-- \/wp:columns -->\n\n<!-- wp:heading -->\n<h2 class=\"wp-block-heading\">Nombres para<\/h2>\n<!-- \/wp:heading -->\n\n<!-- wp:table {\"hasFixedLayout\":false,\"className\":\"is-style-stripes\"} -->\n<figure class=\"wp-block-table is-style-stripes\"><table><thead><tr><th class=\"has-text-align-center\" data-align=\"center\">Nombres para D\u00f3berman macho<\/th><th class=\"has-text-align-center\" data-align=\"center\">Nombres para D\u00f3berman hembra<\/th><\/tr><\/thead><tbody><tr><td class=\"has-text-align-center\" data-align=\"center\">Thor<\/td><td class=\"has-text-align-center\" data-align=\"center\">Hera<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">Maximus<\/td><td class=\"has-text-align-center\" data-align=\"center\">Bella<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">Titan<\/td><td class=\"has-text-align-center\" data-align=\"center\">Raven<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">Nero<\/td><td class=\"has-text-align-center\" data-align=\"center\">Luna<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">Zeus<\/td><td class=\"has-text-align-center\" data-align=\"center\">Sombra<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">Ragnar<\/td><td class=\"has-text-align-center\" data-align=\"center\">Nala<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">Hunter<\/td><td class=\"has-text-align-center\" data-align=\"center\">Zaira<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">Rocky<\/td><td class=\"has-text-align-center\" data-align=\"center\">Maya<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">Diesel<\/td><td class=\"has-text-align-center\" data-align=\"center\">Roxa<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">Apollo<\/td><td class=\"has-text-align-center\" data-align=\"center\">Karma<\/td><\/tr><\/tbody><\/table><\/figure>\n<!-- \/wp:table -->\n\n<!-- wp:shortcode -->\n        <section style=\"margin-top:21px;\">\n            <div class=\"\">\n                <div class=\"row\">\n                    <div class=\"container-fluid\">\n                        <div class=\"grid\">\n                            <div class=\"grid-sizer\"><\/div>\n                                                        <a href=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/ley-bienestar-animal\/\">\n                                <div class=\"grid-item lazyload\" style=\"background:inherit;\n                                background: -moz-linear-gradient(rgba(0, 0, 0, 0) 0%, rgba(0, 0, 0, 0.8) 100%), \n                                url(https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/uploads\/2023\/02\/Proyecto-nuevo-58-min.jpg);\n                                background: -webkit-linear-gradient(rgba(0, 0, 0, 0) 0%, rgba(0, 0, 0, 0.8) 100%), \n                                url(https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/uploads\/2023\/02\/Proyecto-nuevo-58-min.jpg);\n                                background: -o-linear-gradient(rgba(0, 0, 0, 0) 0%, rgba(0, 0, 0, 0.8) 100%), \n                                url(https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/uploads\/2023\/02\/Proyecto-nuevo-58-min.jpg);\n                                background: -ms-linear-gradient(rgba(0, 0, 0, 0) 0%, rgba(0, 0, 0, 0.8) 100%), \n                                url(https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/uploads\/2023\/02\/Proyecto-nuevo-58-min.jpg);background-size:cover;\n                                background-position: center;background-repeat: no-repeat;height:230px;\" data-bg=\"linear-gradient(rgba(0, 0, 0, 0) 0%, rgba(0, 0, 0, 0.8) 100%), \n                                url(https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/uploads\/2023\/02\/Proyecto-nuevo-58-min.jpg)\">\n                                    <p class=\"slider-caption\">Informaci\u00f3n sobre la Ley de Bienestar Animal<\/p>\n                                    \n                                <\/div>\n                                <\/a>\n                                                        <a href=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/ley-de-perros-potencialmente-peligrosos-en-espana\/\">\n                                <div class=\"grid-item lazyload\" style=\"background:inherit;\n                                background: -moz-linear-gradient(rgba(0, 0, 0, 0) 0%, rgba(0, 0, 0, 0.8) 100%), \n                                url(https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/uploads\/2021\/12\/ley-perros-potencialmente-peligrosos-21.jpg);\n                                background: -webkit-linear-gradient(rgba(0, 0, 0, 0) 0%, rgba(0, 0, 0, 0.8) 100%), \n                                url(https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/uploads\/2021\/12\/ley-perros-potencialmente-peligrosos-21.jpg);\n                                background: -o-linear-gradient(rgba(0, 0, 0, 0) 0%, rgba(0, 0, 0, 0.8) 100%), \n                                url(https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/uploads\/2021\/12\/ley-perros-potencialmente-peligrosos-21.jpg);\n                                background: -ms-linear-gradient(rgba(0, 0, 0, 0) 0%, rgba(0, 0, 0, 0.8) 100%), \n                                url(https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/uploads\/2021\/12\/ley-perros-potencialmente-peligrosos-21.jpg);background-size:cover;\n                                background-position: center;background-repeat: no-repeat;height:230px;\" data-bg=\"linear-gradient(rgba(0, 0, 0, 0) 0%, rgba(0, 0, 0, 0.8) 100%), \n                                url(https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/uploads\/2021\/12\/ley-perros-potencialmente-peligrosos-21.jpg)\">\n                                    <p class=\"slider-caption\">Sobre la Ley de Perros Potencialmente Peligrosos en Espa\u00f1a (Actualizaci\u00f3n 2025)<\/p>\n                                    \n                                <\/div>\n                                <\/a>\n                                                        <a href=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/que-derechos-tienen-los-animales\/\">\n                                <div class=\"grid-item lazyload\" style=\"background:inherit;\n                                background: -moz-linear-gradient(rgba(0, 0, 0, 0) 0%, rgba(0, 0, 0, 0.8) 100%), \n                                url(https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/uploads\/2022\/12\/Dia-internacional-de-los-derechos-de-los-animlaes-Kiwoko.jpg);\n                                background: -webkit-linear-gradient(rgba(0, 0, 0, 0) 0%, rgba(0, 0, 0, 0.8) 100%), \n                                url(https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/uploads\/2022\/12\/Dia-internacional-de-los-derechos-de-los-animlaes-Kiwoko.jpg);\n                                background: -o-linear-gradient(rgba(0, 0, 0, 0) 0%, rgba(0, 0, 0, 0.8) 100%), \n                                url(https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/uploads\/2022\/12\/Dia-internacional-de-los-derechos-de-los-animlaes-Kiwoko.jpg);\n                                background: -ms-linear-gradient(rgba(0, 0, 0, 0) 0%, rgba(0, 0, 0, 0.8) 100%), \n                                url(https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/uploads\/2022\/12\/Dia-internacional-de-los-derechos-de-los-animlaes-Kiwoko.jpg);background-size:cover;\n                                background-position: center;background-repeat: no-repeat;height:230px;\" data-bg=\"linear-gradient(rgba(0, 0, 0, 0) 0%, rgba(0, 0, 0, 0.8) 100%), \n                                url(https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/uploads\/2022\/12\/Dia-internacional-de-los-derechos-de-los-animlaes-Kiwoko.jpg)\">\n                                    <p class=\"slider-caption\">Los derechos de los animales<\/p>\n                                    \n                                <\/div>\n                                <\/a>\n                                                    <\/div>\n                    <\/div>\n                <\/div>\n                <script src=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/themes\/kiwoko\/inc\/assets\/js\/masonry.pkgd.min.js\"><\/script>\n                <script type=\"text\/javascript\">\n                    var $grid = jQuery('.grid').masonry({\n                        itemSelector: '.grid-item',\n                        percentPosition: true,\n                        columnWidth: '.grid-sizer',\n                    });\n                <\/script>\n\n            <\/div>\n        <\/section>\n    \n<!-- \/wp:shortcode -->\n\n<!-- wp:heading -->\n<h2 class=\"wp-block-heading\" id=\"faqs\">Preguntas frecuentes sobre el<\/h2>\n<!-- \/wp:heading -->\n\n<!-- wp:shortcode -->\n        <style>\n            .accordion .card{\n                border:0;\n            }\n            .accordion .card-header{\n                background:#cc3333;\n                cursor:pointer;\n            }\n            .accordion .card-header h3{color:#FFFFFF;font-family:'Affogato-Medium';font-size:18px;}\n            .accordion .card-body{\n                border:1px solid #cc3333;\n            }\n        <\/style>\n\n        <div class=\"accordion\" id=\"faqs-doberman\">\n                    <div class=\"card\">\n                <div class=\"card-header\"\n                     id=\"faqs-item-heading-doberman-1\"\n                     class=\"btn btn-link\"\n                     data-toggle=\"collapse\"\n                     data-target=\"#faqs-item-doberman-1\"\n                     aria-expanded=\"true\"\n                     aria-controls=\"collapseOne\">\n                    <h3 class=\"mb-0 mt-0\">\u00bfEl Doberman es una raza agresiva o violenta?<\/h3>\n                <\/div>\n\n                <div id=\"faqs-item-doberman-1\"\n                     class=\"collapse\"\n                     aria-labelledby=\"faqs-item-heading-doberman-1\"\n                     data-parent=\"#accordion\">\n                    <div class=\"card-body\">\n                        <!-- wp:paragraph -->\n<p>No. Es importante entender que la agresividad en los perros no est\u00e1 determinada \u00fanicamente por su raza, sino por diversos factores como la gen\u00e9tica, el ambiente en el que se cr\u00edan, la socializaci\u00f3n y el entrenamiento que reciben. En general, el Doberman es una raza que puede ser muy leal y protectora de su familia, pero con una socializaci\u00f3n adecuada y un entrenamiento consistente, pueden ser perros amigables y equilibrados. Como cualquier raza, es crucial proporcionarles una crianza y educaci\u00f3n adecuadas para fomentar un comportamiento positivo con respeto, amor y atenci\u00f3n. <\/p>\n<!-- \/wp:paragraph -->                    <\/div>\n                <\/div>\n            <\/div>\n                        <div class=\"card\">\n                <div class=\"card-header\"\n                     id=\"faqs-item-heading-doberman-2\"\n                     class=\"btn btn-link\"\n                     data-toggle=\"collapse\"\n                     data-target=\"#faqs-item-doberman-2\"\n                     aria-expanded=\"true\"\n                     aria-controls=\"collapseOne\">\n                    <h3 class=\"mb-0 mt-0\">\u00bfQu\u00e9 pasa si le corto las orejas a mi D\u00f3berman?<\/h3>\n                <\/div>\n\n                <div id=\"faqs-item-doberman-2\"\n                     class=\"collapse\"\n                     aria-labelledby=\"faqs-item-heading-doberman-2\"\n                     data-parent=\"#accordion\">\n                    <div class=\"card-body\">\n                        <!-- wp:paragraph -->\n<p><strong>Cortar las orejas a un D\u00f3berman no solo es innecesario, sino que puede causarle mucho dolor, infecciones y problemas a largo plazo, como dificultades para escuchar o mantener el equilibrio<\/strong>.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Adem\u00e1s, <strong>esta pr\u00e1ctica est\u00e1 prohibida por la Ley de Bienestar Animal (LBA)<\/strong> en muchos pa\u00edses, como Espa\u00f1a, porque no tiene una raz\u00f3n m\u00e9dica y solo busca un cambio est\u00e9tico. <\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Por tanto,<strong> si le cortas las orejas a un D\u00f3berman, no solo le estar\u00e1s perjudicando, sino que tambi\u00e9n estar\u00e1s incurriendo en un delito contra el bienestar animal. <\/strong><\/p>\n<!-- \/wp:paragraph -->                    <\/div>\n                <\/div>\n            <\/div>\n                        <div class=\"card\">\n                <div class=\"card-header\"\n                     id=\"faqs-item-heading-doberman-3\"\n                     class=\"btn btn-link\"\n                     data-toggle=\"collapse\"\n                     data-target=\"#faqs-item-doberman-3\"\n                     aria-expanded=\"true\"\n                     aria-controls=\"collapseOne\">\n                    <h3 class=\"mb-0 mt-0\">\u00bfC\u00f3mo hacer que mi D\u00f3berman obedezca?<\/h3>\n                <\/div>\n\n                <div id=\"faqs-item-doberman-3\"\n                     class=\"collapse\"\n                     aria-labelledby=\"faqs-item-heading-doberman-3\"\n                     data-parent=\"#accordion\">\n                    <div class=\"card-body\">\n                        <!-- wp:paragraph {\"className\":\"\"} -->\n<p>Para <strong>lograr que tu D\u00f3berman obedezca<\/strong>, es fundamental establecer una relaci\u00f3n basada en la confianza, el respeto y la consistencia. Nosotros te recomendamos:<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:list {\"ordered\":true} -->\n<ol class=\"wp-block-list\"><!-- wp:list-item -->\n<li><strong>Entrenamiento positivo<\/strong>: Utiliza recompensas como golosinas, caricias y palabras de aliento para reforzar los comportamientos que deseas. Premia a tu D\u00f3berman inmediatamente despu\u00e9s de que obedezca una orden.<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li><strong>Comienza desde cachorro<\/strong>: Aunque los D\u00f3berman son inteligentes y aprenden r\u00e1pido, es importante comenzar el entrenamiento desde cachorros. A esta edad, son m\u00e1s receptivos a nuevas \u00f3rdenes y rutinas.<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li><strong>Establece \u00f3rdenes claras<\/strong>: Usa comandos simples y consistentes para que tu perro entienda lo que esperas de \u00e9l. Evita usar demasiadas palabras o frases, y repite las \u00f3rdenes con claridad.<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li><strong>S\u00e9 paciente y constante<\/strong>: Los D\u00f3berman son perros muy activos y a veces pueden distraerse f\u00e1cilmente. La paciencia y la constancia en las sesiones de entrenamiento son claves para que obedezcan.<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li><strong>Hazlo divertido<\/strong>: Mant\u00e9n las sesiones de entrenamiento cortas y din\u00e1micas para evitar que tu Doberman se aburra. Esto mantendr\u00e1 su motivaci\u00f3n alta y har\u00e1 que el proceso sea m\u00e1s efectivo.<\/li>\n<!-- \/wp:list-item --><\/ol>\n<!-- \/wp:list -->                    <\/div>\n                <\/div>\n            <\/div>\n                    <\/div>\n\n        <script type=\"application\/ld+json\">{\"@context\":\"https:\/\/schema.org\",\"@type\":\"FAQPage\",\"mainEntity\":[{\"@type\":\"Question\",\"name\":\"\u00bfEl Doberman es una raza agresiva o violenta?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"No. Es importante entender que la agresividad en los perros no est\u00e1 determinada \u00fanicamente por su raza, sino por diversos factores como la gen\u00e9tica, el ambiente en el que se cr\u00edan, la socializaci\u00f3n y el entrenamiento que reciben. En general, el Doberman es una raza que puede ser muy leal y protectora de su familia, pero con una socializaci\u00f3n adecuada y un entrenamiento consistente, pueden ser perros amigables y equilibrados. Como cualquier raza, es crucial proporcionarles una crianza y educaci\u00f3n adecuadas para fomentar un comportamiento positivo con respeto, amor y atenci\u00f3n.\"}},{\"@type\":\"Question\",\"name\":\"\u00bfQu\u00e9 pasa si le corto las orejas a mi D\u00f3berman?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"Cortar las orejas a un D\u00f3berman no solo es innecesario, sino que puede causarle mucho dolor, infecciones y problemas a largo plazo, como dificultades para escuchar o mantener el equilibrio. Adem\u00e1s, esta pr\u00e1ctica est\u00e1 prohibida por la Ley de Bienestar Animal (LBA) en muchos pa\u00edses, como Espa\u00f1a, porque no tiene una raz\u00f3n m\u00e9dica y solo busca un cambio est\u00e9tico. Por tanto, si le cortas las orejas a un D\u00f3berman, no solo le estar\u00e1s perjudicando, sino que tambi\u00e9n estar\u00e1s incurriendo en un delito contra el bienestar animal.\"}},{\"@type\":\"Question\",\"name\":\"\u00bfC\u00f3mo hacer que mi D\u00f3berman obedezca?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"Para lograr que tu D\u00f3berman obedezca, es fundamental establecer una relaci\u00f3n basada en la confianza, el respeto y la consistencia. Nosotros te recomendamos: Entrenamiento positivo: Utiliza recompensas como golosinas, caricias y palabras de aliento para reforzar los comportamientos que deseas. Premia a tu D\u00f3berman inmediatamente despu\u00e9s de que obedezca una orden. Comienza desde cachorro: Aunque los D\u00f3berman son inteligentes y aprenden r\u00e1pido, es importante comenzar el entrenamiento desde cachorros. A esta edad, son m\u00e1s receptivos a nuevas \u00f3rdenes y rutinas. Establece \u00f3rdenes claras: Usa comandos simples y consistentes para que tu perro entienda lo que esperas de \u00e9l. Evita usar demasiadas palabras o frases, y repite las \u00f3rdenes con claridad. S\u00e9 paciente y constante: Los D\u00f3berman son perros muy activos y a veces pueden distraerse f\u00e1cilmente. La paciencia y la constancia en las sesiones de entrenamiento son claves para que obedezcan. Hazlo divertido: Mant\u00e9n las sesiones de entrenamiento cortas y din\u00e1micas para evitar que tu Doberman se aburra. Esto mantendr\u00e1 su motivaci\u00f3n alta y har\u00e1 que el proceso sea m\u00e1s efectivo.\"}}]}<\/script>\n<!-- \/wp:shortcode -->","protected":false},"excerpt":{"rendered":"<p>Para lograr que tu D\u00f3berman obedezca, es fundamental establecer una relaci\u00f3n basada en la confianza, el respeto y la consistencia. Nosotros te recomendamos: Entrenamiento positivo: Utiliza recompensas como golosinas, caricias y palabras de aliento para reforzar los comportamientos que deseas. Premia a tu D\u00f3berman inmediatamente despu\u00e9s de que obedezca una orden. Comienza desde cachorro: Aunque [&hellip;]<\/p>\n","protected":false},"featured_media":45635,"template":"","tipo-raza":[1452],"class_list":["post-45561","ficha-de-raza","type-ficha-de-raza","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-json\/wp\/v2\/ficha-de-raza\/45561","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-json\/wp\/v2\/ficha-de-raza"}],"about":[{"href":"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-json\/wp\/v2\/types\/ficha-de-raza"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-json\/wp\/v2\/media\/45635"}],"wp:attachment":[{"href":"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-json\/wp\/v2\/media?parent=45561"}],"wp:term":[{"taxonomy":"tipo-raza","embeddable":true,"href":"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-json\/wp\/v2\/tipo-raza?post=45561"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}