{"id":47194,"date":"2024-07-18T16:48:37","date_gmt":"2024-07-18T14:48:37","guid":{"rendered":"https:\/\/www.kiwoko.mom\/blogmundoanimal\/?post_type=ficha-de-raza&#038;p=47194"},"modified":"2024-10-23T08:46:48","modified_gmt":"2024-10-23T06:46:48","slug":"braco-de-weimar","status":"publish","type":"ficha-de-raza","link":"https:\/\/www.kiwoko.mom\/blogmundoanimal\/ficha-de-raza\/braco-de-weimar\/","title":{"rendered":"Braco de Weimar"},"content":{"rendered":"<!-- wp:heading -->\n<h2 id=\"descripcion\">Descripci\u00f3n general de la raza<\/h2>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>El <strong>Braco de Weimar<\/strong> es un perro con un porte elegante, atl\u00e9tico y estilizado. \u00bfTe gustar\u00eda conocerle? Entonces, entra en este post y descubre todo lo que necesitas saber sobre el <strong>Weimaraner<\/strong>.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Aprende sobre su origen, caracter\u00edsticas, y diferencias con otras razas. Conoce c\u00f3mo cuidarlo en cada etapa de su vida y aseg\u00farate de proporcionarle el mejor entorno para un desarrollo saludable.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:heading {\"level\":3} -->\n<h3>Origen<\/h3>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>La raza <strong>toma su nombre del lugar de Alemania donde se desarroll\u00f3: la Corte de Weimar<\/strong>, a mediados del siglo XV, cuyos miembros, con el Gran Duque Carlos Augusto a la cabeza, quer\u00edan tener un perro asociado a su noble estirpe que fuese valiente e inteligente y que, adem\u00e1s, poseyera gran olfato, velocidad y resistencia para la cacer\u00eda. Y, para mayor distinci\u00f3n, el can deb\u00eda sobresalir entre los dem\u00e1s con un elegante manto de color gris plata.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>El proceso de selecci\u00f3n para desarrollar el <strong>Braco de Weimar <\/strong>fue incierto por largo tiempo, pues no solo <strong>no se conservan las trazas de su origen<\/strong>, sino que muy probablemente se ocultaron, de forma deliberada, para que la Corte de Weimar pudiera asegurarse la exclusividad de tan magn\u00edfico ejemplar. <\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Actualmente, el misterio del origen se ha ido desvelando, gracias a los esfuerzos de los amantes de la raza, ilustraciones antiguas y los avances de la gen\u00e9tica.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Un rasgo peculiar de esta raza es que <strong>el color de ojos va cambiando a medida que crece<\/strong>. Un Braco de <strong>Weimar cachorro <\/strong>tendr\u00e1 los ojos azules, que despu\u00e9s se vuelven aguamarina y m\u00e1s tarde tornar\u00e1n a verde, para finalmente fijarse en los tonos naranjas y ambarinos de la edad adulta.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:heading {\"level\":3} -->\n<h3>Tipos<\/h3>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>Hay <strong>tres subtipos<\/strong> dentro de la raza. Por cierto, su cruce est\u00e1 estrictamente prohibido por las federaciones caninas para preservar su pureza.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:heading {\"level\":4} -->\n<h4>Por tipo de pelo<\/h4>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>Las federaciones reconocen tres subtipos de acuerdo al tipo de pelo del manto del animal, pero todos <strong>conservan los colores<\/strong> propios de la raza. Estos subtipos son:<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:list -->\n<ul><!-- wp:list-item -->\n<li>Braco de Weimar de <strong>pelo corto.<\/strong><\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>Braco de Weimar de <strong>pelo duro.<\/strong><\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>Braco de Weimar de <strong>pelo largo.<\/strong><\/li>\n<!-- \/wp:list-item --><\/ul>\n<!-- \/wp:list -->\n\n<!-- wp:heading -->\n<h2 id=\"etapas\">Etapa de cachorro del<\/h2>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>Estos perros son criaturas muy inteligentes y piensan por s\u00ed mismas, por lo que el <strong><a href=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/adiestramiento-positivo-perros\/\" title=\"Adiestramiento en positivo: La clave para un entrenamiento efectivo\">adiestramiento en positivo<\/a><\/strong> debe comenzar desde muy temprana edad y continuar durante toda su vida. Tienen buena disposici\u00f3n y pueden aprender r\u00e1pidamente lo que se les ense\u00f1e; pero, si su inteligencia y energ\u00eda no se canalizan de forma constructiva, pueden aprender algunas cosas que t\u00fa no quieres que sepan, como abrir puertas y escapar.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Un <strong>Braco de Weimar cachorro<\/strong> pondr\u00e1 tus l\u00edmites a prueba. Llevarlo a un centro de aprendizaje para cachorros a que reciba clases de obediencia es una buena idea. En todo caso, el <strong>adiestramiento debe ser en positivo<\/strong>, puesto que la dureza en el trato lo har\u00e1 resentirse. \u00a1Utiliza los accesorios adecuados! <\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:shortcode -->\n        <div id=\"external-products-TOO41849\" class=\"row external-products\">\n            <img decoding=\"async\" id=\"load-products-TOO41849\" data-src=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/themes\/kiwoko\/inc\/assets\/images\/loading.gif\" width=\"50\" height=\"50\" alt=\"loading\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 50px; --smush-placeholder-aspect-ratio: 50\/50;\">\n        <\/div>\n        <script>\n        var id_products = \"TOO41849,TOO41846,TOO41863\";\n        id_products = id_products.replace(\/\\s\/g, '');\n        var all_ids = id_products.split(\",\");\n\n        \/\/ Agregar sufijo _M a todos los c\u00f3digos\n        var all_ids = all_ids.map(function(id) {\n            return id + '_M';\n        });\n\n        var not_found_products = 1;\n        var not_found_img_product = 0;\n        var ramdom_id = Math.round(Math.random() * 10000);\n        var grid = '12';\n\t\tvar width = '220';\n\t\tvar height = '220';\n        if(all_ids.length >= 4){\n            grid = '3';\n\t\t\twidth = '151';\n\t\t\theight = '151';\n        }else if(all_ids.length == 3){\n            grid = '4';\n\t\t\twidth = '211';\n\t\t\theight = '211';\n        }else if(all_ids.length == 2){\n            grid = '6';\n        }\n\t\n\tif(!items){\n        var feed = \"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/themes\/kiwoko\/feed-channable.xml\";\n        var request = new XMLHttpRequest();\n        request.open(\"GET\", feed, false);\n        request.send();\n        var xmlFromUrl = request.responseXML;\n        var parser = new DOMParser();\n        var xmlDoc = parser.parseFromString(feed, \"text\/xml\");\n        var items = xmlFromUrl.getElementsByTagName(\"item\");\n        }\n\n        var products_found = 0;\n        for (var item of items) {\n            all_ids.forEach(function(word, index) {\n                if(item.getElementsByTagName(\"g:item_group_id\")[0].textContent == word){\n                    not_found_products = 0;\n                    id_products = item.getElementsByTagName(\"g:item_group_id\")[0].textContent;\n                    var link = item.getElementsByTagName(\"link\")[0].textContent;\n                    var image_link = 'src=\"'+item.getElementsByTagName(\"g:image_link\")[0].textContent+'\" ';\n                    var title = item.getElementsByTagName(\"title\")[0].textContent;\n\t\t\t\t\tvar customLabel0 = item.getElementsByTagName(\"g:custom_label_0\")[0]?.textContent || '';\n                    var customLabel1 = item.getElementsByTagName(\"g:custom_label_1\")[0]?.textContent || '';\n                    var product = '<div class=\"col-md-'+grid+' text-center ds-analytics-blog-cross-selling-product order-'+index+'\" style=\"cursor:pointer;\" onclick=\"dataLayer.push({'+\n                    '\\'event\\':\\'crosseling_product_click\\', '+\n                    '\\'event_name\\':\\'crosseling_product_click\\', '+\n                    '\\'link_text\\':\\'\u00a1Comprar ahora!\\', '+\n                    '\\'link_url\\':\\''+link+'\\', '+\n                    '\\'category\\':\\''+customLabel0+'\/'+customLabel1+'\\', '+\n                    '\\'product_name\\':\\''+title+'\\''+\n                    '});window.open(\\''+link+'\\');\"><img id=\"'+id_products+'\" '+image_link+' class=\"product-img-shop\" alt=\"'+title+'\"><p><a href=\"'+link+'\" target=\"_blank\" title=\"'+title+'\" style=\"color:#212529;\" class=\"ds-analytics-blog-cross-selling-product\"><strong>'+title+'<\/strong><\/a><\/p><button id=\"product-addtocart-button\" class=\"action primary tocart btn btn--secondary btn--big\" title=\"\u00a1Comprar ahora!\" type=\"submit\">\u00a1Comprar ahora! <\/button><\/div>';\n \t\t\t\t    \/\/var product = '<div class=\"col-md-'+grid+' text-center ds-analytics-blog-cross-selling-product order-'+index+'\" style=\"cursor:pointer;\" onclick=\"dataLayer.push({\\'event\\':\\'blog_cross_selling_product\\', \\'ga4EventData\\': { \\'name\\':\\'d_blog\\', \\'category\\':\\'click\\', \\'label\\':\\'producto\\', \\'element\\': \\''+link+'\\'}});window.open(\\''+link+'\\');\"><img id=\"'+id_products+'\" '+image_link+' class=\"product-img-shop\" alt=\"'+title+'\"><p><a href=\"'+link+'\" target=\"_blank\" title=\"'+title+'\" style=\"color:#212529;\" class=\"ds-analytics-blog-cross-selling-product\"><strong>'+title+'<\/strong><\/a><\/p><button id=\"product-addtocart-button\" class=\"action primary tocart btn btn--secondary btn--big\" title=\"\u00a1Comprar ahora!\" type=\"submit\">\u00a1Comprar ahora! <\/button><\/div>'; \n                    var grid_div = document.getElementById(\"external-products-TOO41849\");\n                    grid_div.innerHTML += product;\n                    products_found++;\n                }\n            });\n            if(products_found == all_ids.length){\n                break;\n            }\n        }\n        document.getElementById(\"load-products-TOO41849\").style.display = \"none\";\n        <\/script>\n    \n<!-- \/wp:shortcode -->\n\n<!-- wp:table {\"className\":\"is-style-stripes\"} -->\n<figure class=\"wp-block-table is-style-stripes\"><table><tbody><tr><td>        <style>.ds-icon-mobile{display:none;}@media screen and (max-width: 767px) {.ds-icon-desktop{display:none;}.ds-icon-mobile{display:inline;}}<\/style>\n    <span style=\"color:#e20b12\">\n            <svg class=\"bi d-sm-inline-block d-md-inline-block d-lg-inline-block d-xl-inline-block ds-icon-desktop\" width=\"35\" height=\"35\" fill=\"#e20b12\">\n        <use xlink:href=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/plugins\/ds-icons\/bootstrap-icons\/bootstrap-icons.svg#suit-heart-fill\"\/>\n        <\/svg>\n        <svg class=\"bi d-inline-block d-sm-none d-md-none d-lg-none d-xl-none ds-icon-mobile\" width=\"35\" height=\"35\" fill=\"#e20b12\">\n        <use xlink:href=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/plugins\/ds-icons\/bootstrap-icons\/bootstrap-icons.svg#suit-heart-fill\"\/>\n        <\/svg>\n        <\/span>\n    <\/td><td>\u00bfHa llegado un cachorro a casa? No te pierdas nuestro <strong><a href=\"https:\/\/www.kiwoko.mom\/perros\/especial-cachorro\/\" target=\"_blank\" rel=\"noopener\" title=\"especial cachorro\">especial cachorro<\/a><\/strong> con todo los productos esenciales para su bienestar y el tuyo. Y si necesitas un extra de consejos lee nuestra secci\u00f3n de \u00a1<strong><a href=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/consejos-para-cachorros-recien-llegados\/\" title=\"\">Reci\u00e9n llegados<\/a><\/strong>!<\/td><\/tr><\/tbody><\/table><\/figure>\n<!-- \/wp:table -->\n\n<!-- wp:shortcode -->\n        <section style=\"margin-top:21px;\">\n            <div class=\"\">\n                <div class=\"row\">\n                    <div class=\"container-fluid\">\n                        <div class=\"grid\">\n                            <div class=\"grid-sizer\"><\/div>\n                                                        <a href=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/elegir-cama-cachorro\/\">\n                                <div class=\"grid-item lazyload\" style=\"background:inherit;\n                                background: -moz-linear-gradient(rgba(0, 0, 0, 0) 0%, rgba(0, 0, 0, 0.8) 100%), \n                                url(https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/uploads\/2024\/04\/mejor-cama-para-cachorros.jpg);\n                                background: -webkit-linear-gradient(rgba(0, 0, 0, 0) 0%, rgba(0, 0, 0, 0.8) 100%), \n                                url(https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/uploads\/2024\/04\/mejor-cama-para-cachorros.jpg);\n                                background: -o-linear-gradient(rgba(0, 0, 0, 0) 0%, rgba(0, 0, 0, 0.8) 100%), \n                                url(https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/uploads\/2024\/04\/mejor-cama-para-cachorros.jpg);\n                                background: -ms-linear-gradient(rgba(0, 0, 0, 0) 0%, rgba(0, 0, 0, 0.8) 100%), \n                                url(https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/uploads\/2024\/04\/mejor-cama-para-cachorros.jpg);background-size:cover;\n                                background-position: center;background-repeat: no-repeat;height:230px;\" data-bg=\"linear-gradient(rgba(0, 0, 0, 0) 0%, rgba(0, 0, 0, 0.8) 100%), \n                                url(https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/uploads\/2024\/04\/mejor-cama-para-cachorros.jpg)\">\n                                    <p class=\"slider-caption\">\u00bfCu\u00e1les son las mejores camas para cachorros?<\/p>\n                                    \n                                <\/div>\n                                <\/a>\n                                                        <a href=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/cuando-puedo-sacar-a-mi-cachorro-a-pasear\/\">\n                                <div class=\"grid-item lazyload\" style=\"background:inherit;\n                                background: -moz-linear-gradient(rgba(0, 0, 0, 0) 0%, rgba(0, 0, 0, 0.8) 100%), \n                                url(https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/uploads\/2020\/10\/cuando-puede-salir-un-cachorro-a-la-calle.jpg);\n                                background: -webkit-linear-gradient(rgba(0, 0, 0, 0) 0%, rgba(0, 0, 0, 0.8) 100%), \n                                url(https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/uploads\/2020\/10\/cuando-puede-salir-un-cachorro-a-la-calle.jpg);\n                                background: -o-linear-gradient(rgba(0, 0, 0, 0) 0%, rgba(0, 0, 0, 0.8) 100%), \n                                url(https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/uploads\/2020\/10\/cuando-puede-salir-un-cachorro-a-la-calle.jpg);\n                                background: -ms-linear-gradient(rgba(0, 0, 0, 0) 0%, rgba(0, 0, 0, 0.8) 100%), \n                                url(https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/uploads\/2020\/10\/cuando-puede-salir-un-cachorro-a-la-calle.jpg);background-size:cover;\n                                background-position: center;background-repeat: no-repeat;height:230px;\" data-bg=\"linear-gradient(rgba(0, 0, 0, 0) 0%, rgba(0, 0, 0, 0.8) 100%), \n                                url(https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/uploads\/2020\/10\/cuando-puede-salir-un-cachorro-a-la-calle.jpg)\">\n                                    <p class=\"slider-caption\">\u00bfCu\u00e1ndo puede salir un cachorro a la calle? Todo lo que necesitas saber<\/p>\n                                    \n                                <\/div>\n                                <\/a>\n                                                        <a href=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/guia-para-dar-la-bienvenida-a-casa-a-un-peludo-adoptado\/\">\n                                <div class=\"grid-item lazyload\" style=\"background:inherit;\n                                background: -moz-linear-gradient(rgba(0, 0, 0, 0) 0%, rgba(0, 0, 0, 0.8) 100%), \n                                url(https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/uploads\/2019\/01\/bienvenida-mascota.jpg);\n                                background: -webkit-linear-gradient(rgba(0, 0, 0, 0) 0%, rgba(0, 0, 0, 0.8) 100%), \n                                url(https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/uploads\/2019\/01\/bienvenida-mascota.jpg);\n                                background: -o-linear-gradient(rgba(0, 0, 0, 0) 0%, rgba(0, 0, 0, 0.8) 100%), \n                                url(https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/uploads\/2019\/01\/bienvenida-mascota.jpg);\n                                background: -ms-linear-gradient(rgba(0, 0, 0, 0) 0%, rgba(0, 0, 0, 0.8) 100%), \n                                url(https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/uploads\/2019\/01\/bienvenida-mascota.jpg);background-size:cover;\n                                background-position: center;background-repeat: no-repeat;height:230px;\" data-bg=\"linear-gradient(rgba(0, 0, 0, 0) 0%, rgba(0, 0, 0, 0.8) 100%), \n                                url(https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/uploads\/2019\/01\/bienvenida-mascota.jpg)\">\n                                    <p class=\"slider-caption\">Primer d\u00eda de un perro adoptado en casa: gu\u00eda completa<\/p>\n                                    \n                                <\/div>\n                                <\/a>\n                                                    <\/div>\n                    <\/div>\n                <\/div>\n                <script src=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/themes\/kiwoko\/inc\/assets\/js\/masonry.pkgd.min.js\"><\/script>\n                <script type=\"text\/javascript\">\n                    var $grid = jQuery('.grid').masonry({\n                        itemSelector: '.grid-item',\n                        percentPosition: true,\n                        columnWidth: '.grid-sizer',\n                    });\n                <\/script>\n\n            <\/div>\n        <\/section>\n    \n<!-- \/wp:shortcode -->\n\n<!-- wp:heading -->\n<h2 id=\"caracter\">Car\u00e1cter del<\/h2>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>El mayor deseo del <strong>Braco de Weimar<\/strong> es estar con los suyos, preferiblemente siempre en contacto. <strong>Se tumbar\u00e1n a tus pies<\/strong> o te seguir\u00e1n por la casa como tu sombra. Por lo que si tienes los cuidados adecuados, su temperamento ser\u00e1 apacible.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Pero, esta raza fue creada para tener <strong>mucha energ\u00eda y resistencia<\/strong>, as\u00ed que prep\u00e1rate para proporcionarle mucho ejercicio y estimulaci\u00f3n mental, ya que sino se la ofreces tendr\u00e1s un perro desequilibrado, frustrado e infeliz. <\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>No controla bien la presi\u00f3n de la mordida, tendr\u00e1s que ser paciente y educarle, algunos tienen <strong>poca tolerancia a animales peque\u00f1os y peludos<\/strong>, como conejos y gatos e, incluso, otros perros, a los que puede ver como presas.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Los <strong>Weinmaraner<\/strong> son nerviosos sino se le ofrece grandes paseos y una vida con est\u00edmulos, tambi\u00e9n <strong>pueden sufrir ansiedad por separaci\u00f3n<\/strong>. Si los dejas solos durante mucho tiempo, pueden ladrar, destruir lo que tengan a su alcance o lesionarse a s\u00ed mismos.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Suelen <strong>desconfiar de los extra\u00f1os<\/strong> y pueden ser inaceptablemente <strong>agresivos<\/strong> si no se le dedica tiempo a ser educados.  El <a href=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/importancia-socializacion-temprana-perros\/\" title=\"\u00bfPor qu\u00e9 es tan importante la socializaci\u00f3n temprana de los perros?\"><strong>proceso de socializaci\u00f3n desde muy temprana edad<\/strong><\/a> es fundamental para controlar esta tendencia.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:shortcode -->\n        <section style=\"margin-top:21px;\">\n            <div class=\"\">\n                <div class=\"row\">\n                    <div class=\"container-fluid\">\n                        <div class=\"grid\">\n                            <div class=\"grid-sizer\"><\/div>\n                                                        <a href=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/como-hacer-que-tu-perro-te-haga-caso\/\">\n                                <div class=\"grid-item lazyload\" style=\"background:inherit;\n                                background: -moz-linear-gradient(rgba(0, 0, 0, 0) 0%, rgba(0, 0, 0, 0.8) 100%), \n                                url(https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/uploads\/2021\/04\/como-hacer-que-mi-perro-me-haga-caso-min.jpg);\n                                background: -webkit-linear-gradient(rgba(0, 0, 0, 0) 0%, rgba(0, 0, 0, 0.8) 100%), \n                                url(https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/uploads\/2021\/04\/como-hacer-que-mi-perro-me-haga-caso-min.jpg);\n                                background: -o-linear-gradient(rgba(0, 0, 0, 0) 0%, rgba(0, 0, 0, 0.8) 100%), \n                                url(https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/uploads\/2021\/04\/como-hacer-que-mi-perro-me-haga-caso-min.jpg);\n                                background: -ms-linear-gradient(rgba(0, 0, 0, 0) 0%, rgba(0, 0, 0, 0.8) 100%), \n                                url(https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/uploads\/2021\/04\/como-hacer-que-mi-perro-me-haga-caso-min.jpg);background-size:cover;\n                                background-position: center;background-repeat: no-repeat;height:230px;\" data-bg=\"linear-gradient(rgba(0, 0, 0, 0) 0%, rgba(0, 0, 0, 0.8) 100%), \n                                url(https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/uploads\/2021\/04\/como-hacer-que-mi-perro-me-haga-caso-min.jpg)\">\n                                    <p class=\"slider-caption\">C\u00f3mo hacer que tu perro te haga caso: Todas las claves<\/p>\n                                    \n                                <\/div>\n                                <\/a>\n                                                        <a href=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/por-que-los-animales-son-buenos-para-los-ninos\/\">\n                                <div class=\"grid-item lazyload\" style=\"background:inherit;\n                                background: -moz-linear-gradient(rgba(0, 0, 0, 0) 0%, rgba(0, 0, 0, 0.8) 100%), \n                                url(https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/uploads\/2019\/08\/thumb-animales-buenos-para-los-ni_os-96.jpg);\n                                background: -webkit-linear-gradient(rgba(0, 0, 0, 0) 0%, rgba(0, 0, 0, 0.8) 100%), \n                                url(https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/uploads\/2019\/08\/thumb-animales-buenos-para-los-ni_os-96.jpg);\n                                background: -o-linear-gradient(rgba(0, 0, 0, 0) 0%, rgba(0, 0, 0, 0.8) 100%), \n                                url(https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/uploads\/2019\/08\/thumb-animales-buenos-para-los-ni_os-96.jpg);\n                                background: -ms-linear-gradient(rgba(0, 0, 0, 0) 0%, rgba(0, 0, 0, 0.8) 100%), \n                                url(https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/uploads\/2019\/08\/thumb-animales-buenos-para-los-ni_os-96.jpg);background-size:cover;\n                                background-position: center;background-repeat: no-repeat;height:230px;\" data-bg=\"linear-gradient(rgba(0, 0, 0, 0) 0%, rgba(0, 0, 0, 0.8) 100%), \n                                url(https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/uploads\/2019\/08\/thumb-animales-buenos-para-los-ni_os-96.jpg)\">\n                                    <p class=\"slider-caption\">\u00bfPor qu\u00e9 los animales son buenos compa\u00f1eros para los ni\u00f1os?<\/p>\n                                    \n                                <\/div>\n                                <\/a>\n                                                        <a href=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/ninos-y-perros-convivencia-segura\/\">\n                                <div class=\"grid-item lazyload\" style=\"background:inherit;\n                                background: -moz-linear-gradient(rgba(0, 0, 0, 0) 0%, rgba(0, 0, 0, 0.8) 100%), \n                                url(https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/uploads\/2019\/08\/thumb-ninos-perros-de-forma-segura.jpg);\n                                background: -webkit-linear-gradient(rgba(0, 0, 0, 0) 0%, rgba(0, 0, 0, 0.8) 100%), \n                                url(https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/uploads\/2019\/08\/thumb-ninos-perros-de-forma-segura.jpg);\n                                background: -o-linear-gradient(rgba(0, 0, 0, 0) 0%, rgba(0, 0, 0, 0.8) 100%), \n                                url(https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/uploads\/2019\/08\/thumb-ninos-perros-de-forma-segura.jpg);\n                                background: -ms-linear-gradient(rgba(0, 0, 0, 0) 0%, rgba(0, 0, 0, 0.8) 100%), \n                                url(https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/uploads\/2019\/08\/thumb-ninos-perros-de-forma-segura.jpg);background-size:cover;\n                                background-position: center;background-repeat: no-repeat;height:230px;\" data-bg=\"linear-gradient(rgba(0, 0, 0, 0) 0%, rgba(0, 0, 0, 0.8) 100%), \n                                url(https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/uploads\/2019\/08\/thumb-ninos-perros-de-forma-segura.jpg)\">\n                                    <p class=\"slider-caption\">5 consejos para que ni\u00f1os y perros convivan de forma segura<\/p>\n                                    \n                                <\/div>\n                                <\/a>\n                                                    <\/div>\n                    <\/div>\n                <\/div>\n                <script src=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/themes\/kiwoko\/inc\/assets\/js\/masonry.pkgd.min.js\"><\/script>\n                <script type=\"text\/javascript\">\n                    var $grid = jQuery('.grid').masonry({\n                        itemSelector: '.grid-item',\n                        percentPosition: true,\n                        columnWidth: '.grid-sizer',\n                    });\n                <\/script>\n\n            <\/div>\n        <\/section>\n    \n<!-- \/wp:shortcode -->\n\n<!-- wp:heading -->\n<h2 id=\"alimentacion\">Alimentaci\u00f3n del<\/h2>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>La <strong>alimentaci\u00f3n del Braco de Weimar<\/strong> es muy importante para mantener su energ\u00eda y salud a lo largo de las diferentes etapas de su vida. Este perro es muy activo y atl\u00e9tico, por lo que necesita una dieta equilibrada que apoye su desarrollo muscular, salud \u00f3sea y bienestar general. A continuaci\u00f3n, te contamos al detalle como tiene que ser su alimentaci\u00f3n dependiendo su edad:<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:heading {\"level\":3} -->\n<h3>Etapa cachorro<\/h3>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>Cuando es cachorro, el <strong>Braco de Weimar<\/strong> necesita una dieta rica en nutrientes que apoye su crecimiento. Adem\u00e1s, es importante que su alimentaci\u00f3n sea a base de <strong><a href=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/mejores-piensos-para-cachorros-de-raza-grande\/\" title=\"El mejor pienso para cachorros de raza grande\">pienso para cachorros de raza grande<\/a><\/strong>, y que estos contengan las cantidades adecuadas de prote\u00ednas, grasas y calcio para el desarrollo saludable de m\u00fasculos y huesos.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:shortcode -->\n        <div id=\"external-products-NTH88570\" class=\"row external-products\">\n            <img decoding=\"async\" id=\"load-products-NTH88570\" data-src=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/themes\/kiwoko\/inc\/assets\/images\/loading.gif\" width=\"50\" height=\"50\" alt=\"loading\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 50px; --smush-placeholder-aspect-ratio: 50\/50;\">\n        <\/div>\n        <script>\n        var id_products = \"NTH88570,ROY153439,HIL2011DA\";\n        id_products = id_products.replace(\/\\s\/g, '');\n        var all_ids = id_products.split(\",\");\n\n        \/\/ Agregar sufijo _M a todos los c\u00f3digos\n        var all_ids = all_ids.map(function(id) {\n            return id + '_M';\n        });\n\n        var not_found_products = 1;\n        var not_found_img_product = 0;\n        var ramdom_id = Math.round(Math.random() * 10000);\n        var grid = '12';\n\t\tvar width = '220';\n\t\tvar height = '220';\n        if(all_ids.length >= 4){\n            grid = '3';\n\t\t\twidth = '151';\n\t\t\theight = '151';\n        }else if(all_ids.length == 3){\n            grid = '4';\n\t\t\twidth = '211';\n\t\t\theight = '211';\n        }else if(all_ids.length == 2){\n            grid = '6';\n        }\n\t\n\tif(!items){\n        var feed = \"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/themes\/kiwoko\/feed-channable.xml\";\n        var request = new XMLHttpRequest();\n        request.open(\"GET\", feed, false);\n        request.send();\n        var xmlFromUrl = request.responseXML;\n        var parser = new DOMParser();\n        var xmlDoc = parser.parseFromString(feed, \"text\/xml\");\n        var items = xmlFromUrl.getElementsByTagName(\"item\");\n        }\n\n        var products_found = 0;\n        for (var item of items) {\n            all_ids.forEach(function(word, index) {\n                if(item.getElementsByTagName(\"g:item_group_id\")[0].textContent == word){\n                    not_found_products = 0;\n                    id_products = item.getElementsByTagName(\"g:item_group_id\")[0].textContent;\n                    var link = item.getElementsByTagName(\"link\")[0].textContent;\n                    var image_link = 'src=\"'+item.getElementsByTagName(\"g:image_link\")[0].textContent+'\" ';\n                    var title = item.getElementsByTagName(\"title\")[0].textContent;\n\t\t\t\t\tvar customLabel0 = item.getElementsByTagName(\"g:custom_label_0\")[0]?.textContent || '';\n                    var customLabel1 = item.getElementsByTagName(\"g:custom_label_1\")[0]?.textContent || '';\n                    var product = '<div class=\"col-md-'+grid+' text-center ds-analytics-blog-cross-selling-product order-'+index+'\" style=\"cursor:pointer;\" onclick=\"dataLayer.push({'+\n                    '\\'event\\':\\'crosseling_product_click\\', '+\n                    '\\'event_name\\':\\'crosseling_product_click\\', '+\n                    '\\'link_text\\':\\'\u00a1Comprar ahora!\\', '+\n                    '\\'link_url\\':\\''+link+'\\', '+\n                    '\\'category\\':\\''+customLabel0+'\/'+customLabel1+'\\', '+\n                    '\\'product_name\\':\\''+title+'\\''+\n                    '});window.open(\\''+link+'\\');\"><img id=\"'+id_products+'\" '+image_link+' class=\"product-img-shop\" alt=\"'+title+'\"><p><a href=\"'+link+'\" target=\"_blank\" title=\"'+title+'\" style=\"color:#212529;\" class=\"ds-analytics-blog-cross-selling-product\"><strong>'+title+'<\/strong><\/a><\/p><button id=\"product-addtocart-button\" class=\"action primary tocart btn btn--secondary btn--big\" title=\"\u00a1Comprar ahora!\" type=\"submit\">\u00a1Comprar ahora! <\/button><\/div>';\n \t\t\t\t    \/\/var product = '<div class=\"col-md-'+grid+' text-center ds-analytics-blog-cross-selling-product order-'+index+'\" style=\"cursor:pointer;\" onclick=\"dataLayer.push({\\'event\\':\\'blog_cross_selling_product\\', \\'ga4EventData\\': { \\'name\\':\\'d_blog\\', \\'category\\':\\'click\\', \\'label\\':\\'producto\\', \\'element\\': \\''+link+'\\'}});window.open(\\''+link+'\\');\"><img id=\"'+id_products+'\" '+image_link+' class=\"product-img-shop\" alt=\"'+title+'\"><p><a href=\"'+link+'\" target=\"_blank\" title=\"'+title+'\" style=\"color:#212529;\" class=\"ds-analytics-blog-cross-selling-product\"><strong>'+title+'<\/strong><\/a><\/p><button id=\"product-addtocart-button\" class=\"action primary tocart btn btn--secondary btn--big\" title=\"\u00a1Comprar ahora!\" type=\"submit\">\u00a1Comprar ahora! <\/button><\/div>'; \n                    var grid_div = document.getElementById(\"external-products-NTH88570\");\n                    grid_div.innerHTML += product;\n                    products_found++;\n                }\n            });\n            if(products_found == all_ids.length){\n                break;\n            }\n        }\n        document.getElementById(\"load-products-NTH88570\").style.display = \"none\";\n        <\/script>\n    \n<!-- \/wp:shortcode -->\n\n<!-- wp:table {\"className\":\"is-style-stripes\"} -->\n<figure class=\"wp-block-table is-style-stripes\"><table><tbody><tr><td>        <style>.ds-icon-mobile{display:none;}@media screen and (max-width: 767px) {.ds-icon-desktop{display:none;}.ds-icon-mobile{display:inline;}}<\/style>\n    <span style=\"color:#e20b12\">\n            <svg class=\"bi d-sm-inline-block d-md-inline-block d-lg-inline-block d-xl-inline-block ds-icon-desktop\" width=\"35\" height=\"35\" fill=\"#e20b12\">\n        <use xlink:href=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/plugins\/ds-icons\/bootstrap-icons\/bootstrap-icons.svg#reception-4\"\/>\n        <\/svg>\n        <svg class=\"bi d-inline-block d-sm-none d-md-none d-lg-none d-xl-none ds-icon-mobile\" width=\"35\" height=\"35\" fill=\"#e20b12\">\n        <use xlink:href=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/plugins\/ds-icons\/bootstrap-icons\/bootstrap-icons.svg#reception-4\"\/>\n        <\/svg>\n        <\/span>\n    <\/td><td>Existe una gran variedad de<strong> <\/strong><a href=\"https:\/\/www.kiwoko.mom\/perros\/especial-cachorro\/pienso-para-cachorros\/\" target=\"_blank\" rel=\"noopener\" title=\"\"><strong>piensos para cachorros<\/strong><\/a> con la idea de cubrir las necesidades nutricionales de esta etapa sin renunciar a la calidad y al sabor. Si necesitas m\u00e1s informaci\u00f3n extra, no dudes en leer nuestro art\u00edculo especial \"<a href=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/alimentacion-cachorros\/\" target=\"_blank\" rel=\"noopener\" title=\"\"><strong>Mejor pienso para cachorros<\/strong><\/a>\" te ayudar\u00e1 a elegir entre una veriedad de 1\u00aa marcas.<\/td><\/tr><\/tbody><\/table><\/figure>\n<!-- \/wp:table -->\n\n<!-- wp:heading {\"level\":3} -->\n<h3>Etapa adulto<\/h3>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>Cuando el <strong>Braco de Weimar<\/strong> alcanza la edad adulta, es importante ajustar su dieta por una que mantenga su alta energ\u00eda y su salud en general. Para ello, los <strong><a href=\"https:\/\/www.kiwoko.mom\/perros\/comida-para-perros\/pienso-seco-para-perros\/pienso-razas-grandes\/\" target=\"_blank\" rel=\"noopener\" title=\"\">piensos para perros de raza grande<\/a><\/strong> proporcionan una mezcla equilibrada de prote\u00ednas magras, grasas saludables y vitaminas y minerales esenciales.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph {\"style\":{\"color\":{\"background\":\"#eeeeeeed\"}}} -->\n<p class=\"has-background\" style=\"background-color:#eeeeeeed\">\u00a1Te recomendamos que eches un vistazo a nuestra <strong><a href=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/alimentacion-perros-razas-grandes\/\" title=\"Mejor pienso para perros de razas grandes\">gu\u00eda de mejor pienso para perros de raza grande<\/a><\/strong>, as\u00ed como a nuestro post sobre el <strong><a href=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/alimentacion-perros-alta-energia\/\" title=\"\u00bfSabes cu\u00e1l es el mejor pienso para perros con alta actividad f\u00edsica?\">mejor pienso para perros de alta actividad f\u00edsica<\/a><\/strong>!<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:shortcode -->\n        <div id=\"external-products-NTH88577\" class=\"row external-products\">\n            <img decoding=\"async\" id=\"load-products-NTH88577\" data-src=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/themes\/kiwoko\/inc\/assets\/images\/loading.gif\" width=\"50\" height=\"50\" alt=\"loading\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 50px; --smush-placeholder-aspect-ratio: 50\/50;\">\n        <\/div>\n        <script>\n        var id_products = \"NTH88577,DGX40017,ROY153637\";\n        id_products = id_products.replace(\/\\s\/g, '');\n        var all_ids = id_products.split(\",\");\n\n        \/\/ Agregar sufijo _M a todos los c\u00f3digos\n        var all_ids = all_ids.map(function(id) {\n            return id + '_M';\n        });\n\n        var not_found_products = 1;\n        var not_found_img_product = 0;\n        var ramdom_id = Math.round(Math.random() * 10000);\n        var grid = '12';\n\t\tvar width = '220';\n\t\tvar height = '220';\n        if(all_ids.length >= 4){\n            grid = '3';\n\t\t\twidth = '151';\n\t\t\theight = '151';\n        }else if(all_ids.length == 3){\n            grid = '4';\n\t\t\twidth = '211';\n\t\t\theight = '211';\n        }else if(all_ids.length == 2){\n            grid = '6';\n        }\n\t\n\tif(!items){\n        var feed = \"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/themes\/kiwoko\/feed-channable.xml\";\n        var request = new XMLHttpRequest();\n        request.open(\"GET\", feed, false);\n        request.send();\n        var xmlFromUrl = request.responseXML;\n        var parser = new DOMParser();\n        var xmlDoc = parser.parseFromString(feed, \"text\/xml\");\n        var items = xmlFromUrl.getElementsByTagName(\"item\");\n        }\n\n        var products_found = 0;\n        for (var item of items) {\n            all_ids.forEach(function(word, index) {\n                if(item.getElementsByTagName(\"g:item_group_id\")[0].textContent == word){\n                    not_found_products = 0;\n                    id_products = item.getElementsByTagName(\"g:item_group_id\")[0].textContent;\n                    var link = item.getElementsByTagName(\"link\")[0].textContent;\n                    var image_link = 'src=\"'+item.getElementsByTagName(\"g:image_link\")[0].textContent+'\" ';\n                    var title = item.getElementsByTagName(\"title\")[0].textContent;\n\t\t\t\t\tvar customLabel0 = item.getElementsByTagName(\"g:custom_label_0\")[0]?.textContent || '';\n                    var customLabel1 = item.getElementsByTagName(\"g:custom_label_1\")[0]?.textContent || '';\n                    var product = '<div class=\"col-md-'+grid+' text-center ds-analytics-blog-cross-selling-product order-'+index+'\" style=\"cursor:pointer;\" onclick=\"dataLayer.push({'+\n                    '\\'event\\':\\'crosseling_product_click\\', '+\n                    '\\'event_name\\':\\'crosseling_product_click\\', '+\n                    '\\'link_text\\':\\'\u00a1Comprar ahora!\\', '+\n                    '\\'link_url\\':\\''+link+'\\', '+\n                    '\\'category\\':\\''+customLabel0+'\/'+customLabel1+'\\', '+\n                    '\\'product_name\\':\\''+title+'\\''+\n                    '});window.open(\\''+link+'\\');\"><img id=\"'+id_products+'\" '+image_link+' class=\"product-img-shop\" alt=\"'+title+'\"><p><a href=\"'+link+'\" target=\"_blank\" title=\"'+title+'\" style=\"color:#212529;\" class=\"ds-analytics-blog-cross-selling-product\"><strong>'+title+'<\/strong><\/a><\/p><button id=\"product-addtocart-button\" class=\"action primary tocart btn btn--secondary btn--big\" title=\"\u00a1Comprar ahora!\" type=\"submit\">\u00a1Comprar ahora! <\/button><\/div>';\n \t\t\t\t    \/\/var product = '<div class=\"col-md-'+grid+' text-center ds-analytics-blog-cross-selling-product order-'+index+'\" style=\"cursor:pointer;\" onclick=\"dataLayer.push({\\'event\\':\\'blog_cross_selling_product\\', \\'ga4EventData\\': { \\'name\\':\\'d_blog\\', \\'category\\':\\'click\\', \\'label\\':\\'producto\\', \\'element\\': \\''+link+'\\'}});window.open(\\''+link+'\\');\"><img id=\"'+id_products+'\" '+image_link+' class=\"product-img-shop\" alt=\"'+title+'\"><p><a href=\"'+link+'\" target=\"_blank\" title=\"'+title+'\" style=\"color:#212529;\" class=\"ds-analytics-blog-cross-selling-product\"><strong>'+title+'<\/strong><\/a><\/p><button id=\"product-addtocart-button\" class=\"action primary tocart btn btn--secondary btn--big\" title=\"\u00a1Comprar ahora!\" type=\"submit\">\u00a1Comprar ahora! <\/button><\/div>'; \n                    var grid_div = document.getElementById(\"external-products-NTH88577\");\n                    grid_div.innerHTML += product;\n                    products_found++;\n                }\n            });\n            if(products_found == all_ids.length){\n                break;\n            }\n        }\n        document.getElementById(\"load-products-NTH88577\").style.display = \"none\";\n        <\/script>\n    \n<!-- \/wp:shortcode -->\n\n<!-- wp:heading {\"level\":3} -->\n<h3>Etapa senior<\/h3>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>Durante su etapa senior, los <strong>Bracos de Weimar<\/strong> se benefician de piensos que contengan niveles moderados de prote\u00ednas y grasas para prevenir el aumento de peso, as\u00ed como suplementos como la glucosamina y la condroitina para mantener la salud de sus articulaciones. <\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:shortcode -->\n        <div id=\"external-products-ROY153871\" class=\"row external-products\">\n            <img decoding=\"async\" id=\"load-products-ROY153871\" data-src=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/themes\/kiwoko\/inc\/assets\/images\/loading.gif\" width=\"50\" height=\"50\" alt=\"loading\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 50px; --smush-placeholder-aspect-ratio: 50\/50;\">\n        <\/div>\n        <script>\n        var id_products = \"ROY153871,ADV965804.,LIB921664\";\n        id_products = id_products.replace(\/\\s\/g, '');\n        var all_ids = id_products.split(\",\");\n\n        \/\/ Agregar sufijo _M a todos los c\u00f3digos\n        var all_ids = all_ids.map(function(id) {\n            return id + '_M';\n        });\n\n        var not_found_products = 1;\n        var not_found_img_product = 0;\n        var ramdom_id = Math.round(Math.random() * 10000);\n        var grid = '12';\n\t\tvar width = '220';\n\t\tvar height = '220';\n        if(all_ids.length >= 4){\n            grid = '3';\n\t\t\twidth = '151';\n\t\t\theight = '151';\n        }else if(all_ids.length == 3){\n            grid = '4';\n\t\t\twidth = '211';\n\t\t\theight = '211';\n        }else if(all_ids.length == 2){\n            grid = '6';\n        }\n\t\n\tif(!items){\n        var feed = \"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/themes\/kiwoko\/feed-channable.xml\";\n        var request = new XMLHttpRequest();\n        request.open(\"GET\", feed, false);\n        request.send();\n        var xmlFromUrl = request.responseXML;\n        var parser = new DOMParser();\n        var xmlDoc = parser.parseFromString(feed, \"text\/xml\");\n        var items = xmlFromUrl.getElementsByTagName(\"item\");\n        }\n\n        var products_found = 0;\n        for (var item of items) {\n            all_ids.forEach(function(word, index) {\n                if(item.getElementsByTagName(\"g:item_group_id\")[0].textContent == word){\n                    not_found_products = 0;\n                    id_products = item.getElementsByTagName(\"g:item_group_id\")[0].textContent;\n                    var link = item.getElementsByTagName(\"link\")[0].textContent;\n                    var image_link = 'src=\"'+item.getElementsByTagName(\"g:image_link\")[0].textContent+'\" ';\n                    var title = item.getElementsByTagName(\"title\")[0].textContent;\n\t\t\t\t\tvar customLabel0 = item.getElementsByTagName(\"g:custom_label_0\")[0]?.textContent || '';\n                    var customLabel1 = item.getElementsByTagName(\"g:custom_label_1\")[0]?.textContent || '';\n                    var product = '<div class=\"col-md-'+grid+' text-center ds-analytics-blog-cross-selling-product order-'+index+'\" style=\"cursor:pointer;\" onclick=\"dataLayer.push({'+\n                    '\\'event\\':\\'crosseling_product_click\\', '+\n                    '\\'event_name\\':\\'crosseling_product_click\\', '+\n                    '\\'link_text\\':\\'\u00a1Comprar ahora!\\', '+\n                    '\\'link_url\\':\\''+link+'\\', '+\n                    '\\'category\\':\\''+customLabel0+'\/'+customLabel1+'\\', '+\n                    '\\'product_name\\':\\''+title+'\\''+\n                    '});window.open(\\''+link+'\\');\"><img id=\"'+id_products+'\" '+image_link+' class=\"product-img-shop\" alt=\"'+title+'\"><p><a href=\"'+link+'\" target=\"_blank\" title=\"'+title+'\" style=\"color:#212529;\" class=\"ds-analytics-blog-cross-selling-product\"><strong>'+title+'<\/strong><\/a><\/p><button id=\"product-addtocart-button\" class=\"action primary tocart btn btn--secondary btn--big\" title=\"\u00a1Comprar ahora!\" type=\"submit\">\u00a1Comprar ahora! <\/button><\/div>';\n \t\t\t\t    \/\/var product = '<div class=\"col-md-'+grid+' text-center ds-analytics-blog-cross-selling-product order-'+index+'\" style=\"cursor:pointer;\" onclick=\"dataLayer.push({\\'event\\':\\'blog_cross_selling_product\\', \\'ga4EventData\\': { \\'name\\':\\'d_blog\\', \\'category\\':\\'click\\', \\'label\\':\\'producto\\', \\'element\\': \\''+link+'\\'}});window.open(\\''+link+'\\');\"><img id=\"'+id_products+'\" '+image_link+' class=\"product-img-shop\" alt=\"'+title+'\"><p><a href=\"'+link+'\" target=\"_blank\" title=\"'+title+'\" style=\"color:#212529;\" class=\"ds-analytics-blog-cross-selling-product\"><strong>'+title+'<\/strong><\/a><\/p><button id=\"product-addtocart-button\" class=\"action primary tocart btn btn--secondary btn--big\" title=\"\u00a1Comprar ahora!\" type=\"submit\">\u00a1Comprar ahora! <\/button><\/div>'; \n                    var grid_div = document.getElementById(\"external-products-ROY153871\");\n                    grid_div.innerHTML += product;\n                    products_found++;\n                }\n            });\n            if(products_found == all_ids.length){\n                break;\n            }\n        }\n        document.getElementById(\"load-products-ROY153871\").style.display = \"none\";\n        <\/script>\n    \n<!-- \/wp:shortcode -->\n\n<!-- wp:table {\"className\":\"is-style-stripes\"} -->\n<figure class=\"wp-block-table is-style-stripes\"><table><tbody><tr><td>        <style>.ds-icon-mobile{display:none;}@media screen and (max-width: 767px) {.ds-icon-desktop{display:none;}.ds-icon-mobile{display:inline;}}<\/style>\n    <span style=\"color:#e20b12\">\n            <svg class=\"bi d-sm-inline-block d-md-inline-block d-lg-inline-block d-xl-inline-block ds-icon-desktop\" width=\"35\" height=\"35\" fill=\"#e20b12\">\n        <use xlink:href=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/plugins\/ds-icons\/bootstrap-icons\/bootstrap-icons.svg#reply-all-fill\"\/>\n        <\/svg>\n        <svg class=\"bi d-inline-block d-sm-none d-md-none d-lg-none d-xl-none ds-icon-mobile\" width=\"35\" height=\"35\" fill=\"#e20b12\">\n        <use xlink:href=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/plugins\/ds-icons\/bootstrap-icons\/bootstrap-icons.svg#reply-all-fill\"\/>\n        <\/svg>\n        <\/span>\n    <\/td><td>Si quieres seguir ofreciendo los mejores cuidados a tu compa\u00f1ero peludo cuando sea mayor debes elegir el <a href=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/nutricion-optima-perro-senior\/\"><strong>mejor pienso para tu perro anciano<\/strong><\/a>. Para ello lee nuestro art\u00edculo <strong><a href=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/como-cambiar-la-alimentacion-de-un-perro-adulto-a-senior\/\">C\u00f3mo cambiar la alimentaci\u00f3n de un perro adulto a senior<\/a><\/strong> para realizarlo correctamente. Mira nuestras ofertas en <strong><a href=\"https:\/\/www.kiwoko.mom\/perros\/comida-para-perros\/senior1\/\" title=\"pienso senior\">pienso senior<\/a><\/strong>! <\/td><\/tr><\/tbody><\/table><\/figure>\n<!-- \/wp:table -->\n\n<!-- wp:shortcode -->\n        <section style=\"margin-top:21px;\">\n            <div class=\"\">\n                <div class=\"row\">\n                    <div class=\"container-fluid\">\n                        <div class=\"grid\">\n                            <div class=\"grid-sizer\"><\/div>\n                                                        <a href=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/descubre-nath-la-marca-de-comida-superpremium-para-perros-y-gatos\/\">\n                                <div class=\"grid-item lazyload\" style=\"background:inherit;\n                                background: -moz-linear-gradient(rgba(0, 0, 0, 0) 0%, rgba(0, 0, 0, 0.8) 100%), \n                                url(https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/uploads\/2023\/03\/nath-nueva-linea-de-comida-para-mascotas-premium.jpg);\n                                background: -webkit-linear-gradient(rgba(0, 0, 0, 0) 0%, rgba(0, 0, 0, 0.8) 100%), \n                                url(https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/uploads\/2023\/03\/nath-nueva-linea-de-comida-para-mascotas-premium.jpg);\n                                background: -o-linear-gradient(rgba(0, 0, 0, 0) 0%, rgba(0, 0, 0, 0.8) 100%), \n                                url(https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/uploads\/2023\/03\/nath-nueva-linea-de-comida-para-mascotas-premium.jpg);\n                                background: -ms-linear-gradient(rgba(0, 0, 0, 0) 0%, rgba(0, 0, 0, 0.8) 100%), \n                                url(https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/uploads\/2023\/03\/nath-nueva-linea-de-comida-para-mascotas-premium.jpg);background-size:cover;\n                                background-position: center;background-repeat: no-repeat;height:230px;\" data-bg=\"linear-gradient(rgba(0, 0, 0, 0) 0%, rgba(0, 0, 0, 0.8) 100%), \n                                url(https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/uploads\/2023\/03\/nath-nueva-linea-de-comida-para-mascotas-premium.jpg)\">\n                                    <p class=\"slider-caption\">NATH, la marca de comida superpremium para perros y gatos<\/p>\n                                    \n                                <\/div>\n                                <\/a>\n                                                        <a href=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/guia-definitiva-mejor-pienso-para-perros\/\">\n                                <div class=\"grid-item lazyload\" style=\"background:inherit;\n                                background: -moz-linear-gradient(rgba(0, 0, 0, 0) 0%, rgba(0, 0, 0, 0.8) 100%), \n                                url(https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/uploads\/2024\/01\/mejores-piensos-para-perros.jpg);\n                                background: -webkit-linear-gradient(rgba(0, 0, 0, 0) 0%, rgba(0, 0, 0, 0.8) 100%), \n                                url(https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/uploads\/2024\/01\/mejores-piensos-para-perros.jpg);\n                                background: -o-linear-gradient(rgba(0, 0, 0, 0) 0%, rgba(0, 0, 0, 0.8) 100%), \n                                url(https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/uploads\/2024\/01\/mejores-piensos-para-perros.jpg);\n                                background: -ms-linear-gradient(rgba(0, 0, 0, 0) 0%, rgba(0, 0, 0, 0.8) 100%), \n                                url(https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/uploads\/2024\/01\/mejores-piensos-para-perros.jpg);background-size:cover;\n                                background-position: center;background-repeat: no-repeat;height:230px;\" data-bg=\"linear-gradient(rgba(0, 0, 0, 0) 0%, rgba(0, 0, 0, 0.8) 100%), \n                                url(https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/uploads\/2024\/01\/mejores-piensos-para-perros.jpg)\">\n                                    <p class=\"slider-caption\">Gu\u00eda definitiva del mejor pienso para perros<\/p>\n                                    \n                                <\/div>\n                                <\/a>\n                                                        <a href=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/alimentacion-perros-alta-energia\/\">\n                                <div class=\"grid-item lazyload\" style=\"background:inherit;\n                                background: -moz-linear-gradient(rgba(0, 0, 0, 0) 0%, rgba(0, 0, 0, 0.8) 100%), \n                                url(https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/uploads\/2017\/11\/mejor-pienso-para-perros-con-alta-actividad-fisica.jpg);\n                                background: -webkit-linear-gradient(rgba(0, 0, 0, 0) 0%, rgba(0, 0, 0, 0.8) 100%), \n                                url(https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/uploads\/2017\/11\/mejor-pienso-para-perros-con-alta-actividad-fisica.jpg);\n                                background: -o-linear-gradient(rgba(0, 0, 0, 0) 0%, rgba(0, 0, 0, 0.8) 100%), \n                                url(https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/uploads\/2017\/11\/mejor-pienso-para-perros-con-alta-actividad-fisica.jpg);\n                                background: -ms-linear-gradient(rgba(0, 0, 0, 0) 0%, rgba(0, 0, 0, 0.8) 100%), \n                                url(https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/uploads\/2017\/11\/mejor-pienso-para-perros-con-alta-actividad-fisica.jpg);background-size:cover;\n                                background-position: center;background-repeat: no-repeat;height:230px;\" data-bg=\"linear-gradient(rgba(0, 0, 0, 0) 0%, rgba(0, 0, 0, 0.8) 100%), \n                                url(https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/uploads\/2017\/11\/mejor-pienso-para-perros-con-alta-actividad-fisica.jpg)\">\n                                    <p class=\"slider-caption\">\u00bfSabes cu\u00e1l es el mejor pienso para perros con alta actividad f\u00edsica?<\/p>\n                                    \n                                <\/div>\n                                <\/a>\n                                                    <\/div>\n                    <\/div>\n                <\/div>\n                <script src=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/themes\/kiwoko\/inc\/assets\/js\/masonry.pkgd.min.js\"><\/script>\n                <script type=\"text\/javascript\">\n                    var $grid = jQuery('.grid').masonry({\n                        itemSelector: '.grid-item',\n                        percentPosition: true,\n                        columnWidth: '.grid-sizer',\n                    });\n                <\/script>\n\n            <\/div>\n        <\/section>\n    \n<!-- \/wp:shortcode -->\n\n<!-- wp:heading -->\n<h2 id=\"salud\">Salud del<\/h2>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>El Braco de Weimar es un perro generalmente saludable, pero como sucede con todas las razas, son propensos a <strong>ciertas condiciones de salud<\/strong>. Entre ellas podemos mencionar:<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:list -->\n<ul><!-- wp:list-item -->\n<li>Displasia de cadera.<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>Dilataci\u00f3n-volvulaci\u00f3n g\u00e1strica, tambi\u00e9n llamada torsi\u00f3n.<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>Enfermedad de von Willebrand.<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>Distiquiasis.<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>Entropi\u00f3n.<\/li>\n<!-- \/wp:list-item --><\/ul>\n<!-- \/wp:list -->\n\n<!-- wp:heading -->\n<h2 id=\"cuidados\">Cuidados del<\/h2>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>E<strong>l Braco de Weimar<\/strong> es una raza que requiere de m\u00ednimos cuidados: adem\u00e1s del ba\u00f1o cuando sea necesario, basta con cepillarlo de forma regular para deshacerse de los pelos que puedan soltarse y caer sobre muebles y ropa. As\u00ed se mantiene en forma el <a href=\"https:\/\/www.kiwoko.mom\/perros\/higiene-para-perros\/salud-del-perro\/pelo-y-piel\/\" target=\"_blank\" rel=\"noopener\" title=\"\"><strong>pelaje y la piel<\/strong><\/a>. Recortar sus u\u00f1as y asear sus orejas completa la rutina.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:shortcode -->\n        <div id=\"external-products-NCR70122\" class=\"row external-products\">\n            <img decoding=\"async\" id=\"load-products-NCR70122\" data-src=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/themes\/kiwoko\/inc\/assets\/images\/loading.gif\" width=\"50\" height=\"50\" alt=\"loading\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 50px; --smush-placeholder-aspect-ratio: 50\/50;\">\n        <\/div>\n        <script>\n        var id_products = \"NCR70122,NCR70360,YESTA38NCHAR\";\n        id_products = id_products.replace(\/\\s\/g, '');\n        var all_ids = id_products.split(\",\");\n\n        \/\/ Agregar sufijo _M a todos los c\u00f3digos\n        var all_ids = all_ids.map(function(id) {\n            return id + '_M';\n        });\n\n        var not_found_products = 1;\n        var not_found_img_product = 0;\n        var ramdom_id = Math.round(Math.random() * 10000);\n        var grid = '12';\n\t\tvar width = '220';\n\t\tvar height = '220';\n        if(all_ids.length >= 4){\n            grid = '3';\n\t\t\twidth = '151';\n\t\t\theight = '151';\n        }else if(all_ids.length == 3){\n            grid = '4';\n\t\t\twidth = '211';\n\t\t\theight = '211';\n        }else if(all_ids.length == 2){\n            grid = '6';\n        }\n\t\n\tif(!items){\n        var feed = \"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/themes\/kiwoko\/feed-channable.xml\";\n        var request = new XMLHttpRequest();\n        request.open(\"GET\", feed, false);\n        request.send();\n        var xmlFromUrl = request.responseXML;\n        var parser = new DOMParser();\n        var xmlDoc = parser.parseFromString(feed, \"text\/xml\");\n        var items = xmlFromUrl.getElementsByTagName(\"item\");\n        }\n\n        var products_found = 0;\n        for (var item of items) {\n            all_ids.forEach(function(word, index) {\n                if(item.getElementsByTagName(\"g:item_group_id\")[0].textContent == word){\n                    not_found_products = 0;\n                    id_products = item.getElementsByTagName(\"g:item_group_id\")[0].textContent;\n                    var link = item.getElementsByTagName(\"link\")[0].textContent;\n                    var image_link = 'src=\"'+item.getElementsByTagName(\"g:image_link\")[0].textContent+'\" ';\n                    var title = item.getElementsByTagName(\"title\")[0].textContent;\n\t\t\t\t\tvar customLabel0 = item.getElementsByTagName(\"g:custom_label_0\")[0]?.textContent || '';\n                    var customLabel1 = item.getElementsByTagName(\"g:custom_label_1\")[0]?.textContent || '';\n                    var product = '<div class=\"col-md-'+grid+' text-center ds-analytics-blog-cross-selling-product order-'+index+'\" style=\"cursor:pointer;\" onclick=\"dataLayer.push({'+\n                    '\\'event\\':\\'crosseling_product_click\\', '+\n                    '\\'event_name\\':\\'crosseling_product_click\\', '+\n                    '\\'link_text\\':\\'\u00a1Comprar ahora!\\', '+\n                    '\\'link_url\\':\\''+link+'\\', '+\n                    '\\'category\\':\\''+customLabel0+'\/'+customLabel1+'\\', '+\n                    '\\'product_name\\':\\''+title+'\\''+\n                    '});window.open(\\''+link+'\\');\"><img id=\"'+id_products+'\" '+image_link+' class=\"product-img-shop\" alt=\"'+title+'\"><p><a href=\"'+link+'\" target=\"_blank\" title=\"'+title+'\" style=\"color:#212529;\" class=\"ds-analytics-blog-cross-selling-product\"><strong>'+title+'<\/strong><\/a><\/p><button id=\"product-addtocart-button\" class=\"action primary tocart btn btn--secondary btn--big\" title=\"\u00a1Comprar ahora!\" type=\"submit\">\u00a1Comprar ahora! <\/button><\/div>';\n \t\t\t\t    \/\/var product = '<div class=\"col-md-'+grid+' text-center ds-analytics-blog-cross-selling-product order-'+index+'\" style=\"cursor:pointer;\" onclick=\"dataLayer.push({\\'event\\':\\'blog_cross_selling_product\\', \\'ga4EventData\\': { \\'name\\':\\'d_blog\\', \\'category\\':\\'click\\', \\'label\\':\\'producto\\', \\'element\\': \\''+link+'\\'}});window.open(\\''+link+'\\');\"><img id=\"'+id_products+'\" '+image_link+' class=\"product-img-shop\" alt=\"'+title+'\"><p><a href=\"'+link+'\" target=\"_blank\" title=\"'+title+'\" style=\"color:#212529;\" class=\"ds-analytics-blog-cross-selling-product\"><strong>'+title+'<\/strong><\/a><\/p><button id=\"product-addtocart-button\" class=\"action primary tocart btn btn--secondary btn--big\" title=\"\u00a1Comprar ahora!\" type=\"submit\">\u00a1Comprar ahora! <\/button><\/div>'; \n                    var grid_div = document.getElementById(\"external-products-NCR70122\");\n                    grid_div.innerHTML += product;\n                    products_found++;\n                }\n            });\n            if(products_found == all_ids.length){\n                break;\n            }\n        }\n        document.getElementById(\"load-products-NCR70122\").style.display = \"none\";\n        <\/script>\n    \n<!-- \/wp:shortcode -->\n\n<!-- wp:paragraph -->\n<p>El <strong>Braco de Weimar es un perro de casa<\/strong>. No est\u00e1 hecho para vivir en una perrera o en el patio trasero. <strong>Tampoco es adecuado para vivir en un apartamento<\/strong>. Este perro necesita un patio grande y cercado donde pueda correr y una familia que pueda <strong>proporcionarle el ejercicio y la estimulaci\u00f3n mental que necesita<\/strong>, por lo que disfrutar\u00e1 mucho con <strong><a href=\"https:\/\/www.kiwoko.mom\/perros\/accesorios-para-perros\/juguetes-para-perros\/interactivos\/\" target=\"_blank\" rel=\"noopener\" title=\"juguetes de inteligencia para perros\">juguetes de inteligencia para perros<\/a><\/strong>.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:shortcode -->\n        <div id=\"external-products-NIN70886M\" class=\"row external-products\">\n            <img decoding=\"async\" id=\"load-products-NIN70886M\" data-src=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/themes\/kiwoko\/inc\/assets\/images\/loading.gif\" width=\"50\" height=\"50\" alt=\"loading\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 50px; --smush-placeholder-aspect-ratio: 50\/50;\">\n        <\/div>\n        <script>\n        var id_products = \"NIN70886M,NIN71419M,NIN44046\";\n        id_products = id_products.replace(\/\\s\/g, '');\n        var all_ids = id_products.split(\",\");\n\n        \/\/ Agregar sufijo _M a todos los c\u00f3digos\n        var all_ids = all_ids.map(function(id) {\n            return id + '_M';\n        });\n\n        var not_found_products = 1;\n        var not_found_img_product = 0;\n        var ramdom_id = Math.round(Math.random() * 10000);\n        var grid = '12';\n\t\tvar width = '220';\n\t\tvar height = '220';\n        if(all_ids.length >= 4){\n            grid = '3';\n\t\t\twidth = '151';\n\t\t\theight = '151';\n        }else if(all_ids.length == 3){\n            grid = '4';\n\t\t\twidth = '211';\n\t\t\theight = '211';\n        }else if(all_ids.length == 2){\n            grid = '6';\n        }\n\t\n\tif(!items){\n        var feed = \"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/themes\/kiwoko\/feed-channable.xml\";\n        var request = new XMLHttpRequest();\n        request.open(\"GET\", feed, false);\n        request.send();\n        var xmlFromUrl = request.responseXML;\n        var parser = new DOMParser();\n        var xmlDoc = parser.parseFromString(feed, \"text\/xml\");\n        var items = xmlFromUrl.getElementsByTagName(\"item\");\n        }\n\n        var products_found = 0;\n        for (var item of items) {\n            all_ids.forEach(function(word, index) {\n                if(item.getElementsByTagName(\"g:item_group_id\")[0].textContent == word){\n                    not_found_products = 0;\n                    id_products = item.getElementsByTagName(\"g:item_group_id\")[0].textContent;\n                    var link = item.getElementsByTagName(\"link\")[0].textContent;\n                    var image_link = 'src=\"'+item.getElementsByTagName(\"g:image_link\")[0].textContent+'\" ';\n                    var title = item.getElementsByTagName(\"title\")[0].textContent;\n\t\t\t\t\tvar customLabel0 = item.getElementsByTagName(\"g:custom_label_0\")[0]?.textContent || '';\n                    var customLabel1 = item.getElementsByTagName(\"g:custom_label_1\")[0]?.textContent || '';\n                    var product = '<div class=\"col-md-'+grid+' text-center ds-analytics-blog-cross-selling-product order-'+index+'\" style=\"cursor:pointer;\" onclick=\"dataLayer.push({'+\n                    '\\'event\\':\\'crosseling_product_click\\', '+\n                    '\\'event_name\\':\\'crosseling_product_click\\', '+\n                    '\\'link_text\\':\\'\u00a1Comprar ahora!\\', '+\n                    '\\'link_url\\':\\''+link+'\\', '+\n                    '\\'category\\':\\''+customLabel0+'\/'+customLabel1+'\\', '+\n                    '\\'product_name\\':\\''+title+'\\''+\n                    '});window.open(\\''+link+'\\');\"><img id=\"'+id_products+'\" '+image_link+' class=\"product-img-shop\" alt=\"'+title+'\"><p><a href=\"'+link+'\" target=\"_blank\" title=\"'+title+'\" style=\"color:#212529;\" class=\"ds-analytics-blog-cross-selling-product\"><strong>'+title+'<\/strong><\/a><\/p><button id=\"product-addtocart-button\" class=\"action primary tocart btn btn--secondary btn--big\" title=\"\u00a1Comprar ahora!\" type=\"submit\">\u00a1Comprar ahora! <\/button><\/div>';\n \t\t\t\t    \/\/var product = '<div class=\"col-md-'+grid+' text-center ds-analytics-blog-cross-selling-product order-'+index+'\" style=\"cursor:pointer;\" onclick=\"dataLayer.push({\\'event\\':\\'blog_cross_selling_product\\', \\'ga4EventData\\': { \\'name\\':\\'d_blog\\', \\'category\\':\\'click\\', \\'label\\':\\'producto\\', \\'element\\': \\''+link+'\\'}});window.open(\\''+link+'\\');\"><img id=\"'+id_products+'\" '+image_link+' class=\"product-img-shop\" alt=\"'+title+'\"><p><a href=\"'+link+'\" target=\"_blank\" title=\"'+title+'\" style=\"color:#212529;\" class=\"ds-analytics-blog-cross-selling-product\"><strong>'+title+'<\/strong><\/a><\/p><button id=\"product-addtocart-button\" class=\"action primary tocart btn btn--secondary btn--big\" title=\"\u00a1Comprar ahora!\" type=\"submit\">\u00a1Comprar ahora! <\/button><\/div>'; \n                    var grid_div = document.getElementById(\"external-products-NIN70886M\");\n                    grid_div.innerHTML += product;\n                    products_found++;\n                }\n            });\n            if(products_found == all_ids.length){\n                break;\n            }\n        }\n        document.getElementById(\"load-products-NIN70886M\").style.display = \"none\";\n        <\/script>\n    \n<!-- \/wp:shortcode -->\n\n<!-- wp:paragraph -->\n<p>Por \u00faltimo, no olvides que es esencial seguir el calendario de vacunaci\u00f3n, y hablar con tu veterinario para que te recomiende el mejor <strong><a href=\"https:\/\/www.kiwoko.mom\/perros\/higiene-para-perros\/antiparasitarios\/\" target=\"_blank\" rel=\"noopener\" title=\"\">antiparasitario canino<\/a><\/strong>. <\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:shortcode -->\n        <div id=\"external-products-MSD178993\" class=\"row external-products\">\n            <img decoding=\"async\" id=\"load-products-MSD178993\" data-src=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/themes\/kiwoko\/inc\/assets\/images\/loading.gif\" width=\"50\" height=\"50\" alt=\"loading\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 50px; --smush-placeholder-aspect-ratio: 50\/50;\">\n        <\/div>\n        <script>\n        var id_products = \"MSD178993,MDC41260,BEA17233,BAY83883988_5_X2_B\";\n        id_products = id_products.replace(\/\\s\/g, '');\n        var all_ids = id_products.split(\",\");\n\n        \/\/ Agregar sufijo _M a todos los c\u00f3digos\n        var all_ids = all_ids.map(function(id) {\n            return id + '_M';\n        });\n\n        var not_found_products = 1;\n        var not_found_img_product = 0;\n        var ramdom_id = Math.round(Math.random() * 10000);\n        var grid = '12';\n\t\tvar width = '220';\n\t\tvar height = '220';\n        if(all_ids.length >= 4){\n            grid = '3';\n\t\t\twidth = '151';\n\t\t\theight = '151';\n        }else if(all_ids.length == 3){\n            grid = '4';\n\t\t\twidth = '211';\n\t\t\theight = '211';\n        }else if(all_ids.length == 2){\n            grid = '6';\n        }\n\t\n\tif(!items){\n        var feed = \"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/themes\/kiwoko\/feed-channable.xml\";\n        var request = new XMLHttpRequest();\n        request.open(\"GET\", feed, false);\n        request.send();\n        var xmlFromUrl = request.responseXML;\n        var parser = new DOMParser();\n        var xmlDoc = parser.parseFromString(feed, \"text\/xml\");\n        var items = xmlFromUrl.getElementsByTagName(\"item\");\n        }\n\n        var products_found = 0;\n        for (var item of items) {\n            all_ids.forEach(function(word, index) {\n                if(item.getElementsByTagName(\"g:item_group_id\")[0].textContent == word){\n                    not_found_products = 0;\n                    id_products = item.getElementsByTagName(\"g:item_group_id\")[0].textContent;\n                    var link = item.getElementsByTagName(\"link\")[0].textContent;\n                    var image_link = 'src=\"'+item.getElementsByTagName(\"g:image_link\")[0].textContent+'\" ';\n                    var title = item.getElementsByTagName(\"title\")[0].textContent;\n\t\t\t\t\tvar customLabel0 = item.getElementsByTagName(\"g:custom_label_0\")[0]?.textContent || '';\n                    var customLabel1 = item.getElementsByTagName(\"g:custom_label_1\")[0]?.textContent || '';\n                    var product = '<div class=\"col-md-'+grid+' text-center ds-analytics-blog-cross-selling-product order-'+index+'\" style=\"cursor:pointer;\" onclick=\"dataLayer.push({'+\n                    '\\'event\\':\\'crosseling_product_click\\', '+\n                    '\\'event_name\\':\\'crosseling_product_click\\', '+\n                    '\\'link_text\\':\\'\u00a1Comprar ahora!\\', '+\n                    '\\'link_url\\':\\''+link+'\\', '+\n                    '\\'category\\':\\''+customLabel0+'\/'+customLabel1+'\\', '+\n                    '\\'product_name\\':\\''+title+'\\''+\n                    '});window.open(\\''+link+'\\');\"><img id=\"'+id_products+'\" '+image_link+' class=\"product-img-shop\" alt=\"'+title+'\"><p><a href=\"'+link+'\" target=\"_blank\" title=\"'+title+'\" style=\"color:#212529;\" class=\"ds-analytics-blog-cross-selling-product\"><strong>'+title+'<\/strong><\/a><\/p><button id=\"product-addtocart-button\" class=\"action primary tocart btn btn--secondary btn--big\" title=\"\u00a1Comprar ahora!\" type=\"submit\">\u00a1Comprar ahora! <\/button><\/div>';\n \t\t\t\t    \/\/var product = '<div class=\"col-md-'+grid+' text-center ds-analytics-blog-cross-selling-product order-'+index+'\" style=\"cursor:pointer;\" onclick=\"dataLayer.push({\\'event\\':\\'blog_cross_selling_product\\', \\'ga4EventData\\': { \\'name\\':\\'d_blog\\', \\'category\\':\\'click\\', \\'label\\':\\'producto\\', \\'element\\': \\''+link+'\\'}});window.open(\\''+link+'\\');\"><img id=\"'+id_products+'\" '+image_link+' class=\"product-img-shop\" alt=\"'+title+'\"><p><a href=\"'+link+'\" target=\"_blank\" title=\"'+title+'\" style=\"color:#212529;\" class=\"ds-analytics-blog-cross-selling-product\"><strong>'+title+'<\/strong><\/a><\/p><button id=\"product-addtocart-button\" class=\"action primary tocart btn btn--secondary btn--big\" title=\"\u00a1Comprar ahora!\" type=\"submit\">\u00a1Comprar ahora! <\/button><\/div>'; \n                    var grid_div = document.getElementById(\"external-products-MSD178993\");\n                    grid_div.innerHTML += product;\n                    products_found++;\n                }\n            });\n            if(products_found == all_ids.length){\n                break;\n            }\n        }\n        document.getElementById(\"load-products-MSD178993\").style.display = \"none\";\n        <\/script>\n    \n<!-- \/wp:shortcode -->\n\n<!-- wp:shortcode -->\n        <section style=\"margin-top:21px;\">\n            <div class=\"\">\n                <div class=\"row\">\n                    <div class=\"container-fluid\">\n                        <div class=\"grid\">\n                            <div class=\"grid-sizer\"><\/div>\n                                                        <a href=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/ficha-de-raza\/fox-terrier\/\">\n                                <div class=\"grid-item lazyload\" style=\"background:inherit;\n                                background: -moz-linear-gradient(rgba(0, 0, 0, 0) 0%, rgba(0, 0, 0, 0.8) 100%), \n                                url(https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/uploads\/2024\/06\/fox-terrier-ficha-raza-perro.jpg);\n                                background: -webkit-linear-gradient(rgba(0, 0, 0, 0) 0%, rgba(0, 0, 0, 0.8) 100%), \n                                url(https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/uploads\/2024\/06\/fox-terrier-ficha-raza-perro.jpg);\n                                background: -o-linear-gradient(rgba(0, 0, 0, 0) 0%, rgba(0, 0, 0, 0.8) 100%), \n                                url(https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/uploads\/2024\/06\/fox-terrier-ficha-raza-perro.jpg);\n                                background: -ms-linear-gradient(rgba(0, 0, 0, 0) 0%, rgba(0, 0, 0, 0.8) 100%), \n                                url(https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/uploads\/2024\/06\/fox-terrier-ficha-raza-perro.jpg);background-size:cover;\n                                background-position: center;background-repeat: no-repeat;height:230px;\" data-bg=\"linear-gradient(rgba(0, 0, 0, 0) 0%, rgba(0, 0, 0, 0.8) 100%), \n                                url(https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/uploads\/2024\/06\/fox-terrier-ficha-raza-perro.jpg)\">\n                                    <p class=\"slider-caption\">Fox Terrier<\/p>\n                                    \n                                <\/div>\n                                <\/a>\n                                                        <a href=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/ficha-de-raza\/presa-canario\/\">\n                                <div class=\"grid-item lazyload\" style=\"background:inherit;\n                                background: -moz-linear-gradient(rgba(0, 0, 0, 0) 0%, rgba(0, 0, 0, 0.8) 100%), \n                                url(https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/uploads\/2024\/03\/presa-canario-ficha-raza.png);\n                                background: -webkit-linear-gradient(rgba(0, 0, 0, 0) 0%, rgba(0, 0, 0, 0.8) 100%), \n                                url(https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/uploads\/2024\/03\/presa-canario-ficha-raza.png);\n                                background: -o-linear-gradient(rgba(0, 0, 0, 0) 0%, rgba(0, 0, 0, 0.8) 100%), \n                                url(https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/uploads\/2024\/03\/presa-canario-ficha-raza.png);\n                                background: -ms-linear-gradient(rgba(0, 0, 0, 0) 0%, rgba(0, 0, 0, 0.8) 100%), \n                                url(https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/uploads\/2024\/03\/presa-canario-ficha-raza.png);background-size:cover;\n                                background-position: center;background-repeat: no-repeat;height:230px;\" data-bg=\"linear-gradient(rgba(0, 0, 0, 0) 0%, rgba(0, 0, 0, 0.8) 100%), \n                                url(https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/uploads\/2024\/03\/presa-canario-ficha-raza.png)\">\n                                    <p class=\"slider-caption\">Presa Canario<\/p>\n                                    \n                                <\/div>\n                                <\/a>\n                                                        <a href=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/ficha-de-raza\/bichon-frise\/\">\n                                <div class=\"grid-item lazyload\" style=\"background:inherit;\n                                background: -moz-linear-gradient(rgba(0, 0, 0, 0) 0%, rgba(0, 0, 0, 0.8) 100%), \n                                url(https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/uploads\/2024\/03\/bichon-frise-ficha-raza.png);\n                                background: -webkit-linear-gradient(rgba(0, 0, 0, 0) 0%, rgba(0, 0, 0, 0.8) 100%), \n                                url(https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/uploads\/2024\/03\/bichon-frise-ficha-raza.png);\n                                background: -o-linear-gradient(rgba(0, 0, 0, 0) 0%, rgba(0, 0, 0, 0.8) 100%), \n                                url(https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/uploads\/2024\/03\/bichon-frise-ficha-raza.png);\n                                background: -ms-linear-gradient(rgba(0, 0, 0, 0) 0%, rgba(0, 0, 0, 0.8) 100%), \n                                url(https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/uploads\/2024\/03\/bichon-frise-ficha-raza.png);background-size:cover;\n                                background-position: center;background-repeat: no-repeat;height:230px;\" data-bg=\"linear-gradient(rgba(0, 0, 0, 0) 0%, rgba(0, 0, 0, 0.8) 100%), \n                                url(https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/uploads\/2024\/03\/bichon-frise-ficha-raza.png)\">\n                                    <p class=\"slider-caption\">Bich\u00f3n Fris\u00e9<\/p>\n                                    \n                                <\/div>\n                                <\/a>\n                                                    <\/div>\n                    <\/div>\n                <\/div>\n                <script src=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/themes\/kiwoko\/inc\/assets\/js\/masonry.pkgd.min.js\"><\/script>\n                <script type=\"text\/javascript\">\n                    var $grid = jQuery('.grid').masonry({\n                        itemSelector: '.grid-item',\n                        percentPosition: true,\n                        columnWidth: '.grid-sizer',\n                    });\n                <\/script>\n\n            <\/div>\n        <\/section>\n    \n<!-- \/wp:shortcode -->\n\n<!-- wp:heading -->\n<h2 id=\"faqs\">Preguntas frecuentes sobre el<\/h2>\n<!-- \/wp:heading -->\n\n<!-- wp:shortcode -->\n        <style>\n            .accordion .card{\n                border:0;\n            }\n            .accordion .card-header{\n                background:#cc3333;\n                cursor:pointer;\n            }\n            .accordion .card-header h3{color:#FFFFFF;font-family:'Affogato-Medium';font-size:18px;}\n            .accordion .card-body{\n                border:1px solid #cc3333;\n            }\n        <\/style>\n\n        <div class=\"accordion\" id=\"faqs-braco-de-weimar\">\n                    <div class=\"card\">\n                <div class=\"card-header\"\n                     id=\"faqs-item-heading-braco-de-weimar-1\"\n                     class=\"btn btn-link\"\n                     data-toggle=\"collapse\"\n                     data-target=\"#faqs-item-braco-de-weimar-1\"\n                     aria-expanded=\"true\"\n                     aria-controls=\"collapseOne\">\n                    <h3 class=\"mb-0 mt-0\">\u00bfD\u00f3nde adoptar un Braco de Weimar?<\/h3>\n                <\/div>\n\n                <div id=\"faqs-item-braco-de-weimar-1\"\n                     class=\"collapse\"\n                     aria-labelledby=\"faqs-item-heading-braco-de-weimar-1\"\n                     data-parent=\"#accordion\">\n                    <div class=\"card-body\">\n                        <!-- wp:paragraph -->\n<p>Con frecuencia se compran perros de esta raza sin saber lo que implica ser propietario de un perro tan en\u00e9rgico. Muchos<strong> Bracos de Weimar<\/strong> terminan en las protectoras o, peor a\u00fan, deambulando por las calles. <strong>Si piensas que esta es la raza ideal para ti<\/strong>, considera elegir entre los centenares de animales que se encuentran disponibles para <strong>adopci\u00f3n<\/strong> en alguna protectora de animales cercana a tu domicilio. Si no conoces ninguna, puedes informarte en el Ayuntamiento o en un centro veterinario. Tambi\u00e9n puedes visitar <strong><a href=\"https:\/\/www.kiwoko.mom\/servicios\/kiwokoadopta\/\" target=\"_blank\" rel=\"noopener\" title=\"\">Kiwoko adopta<\/a><\/strong>, donde realizamos colaboraci\u00f3n con protectoras locales y ONGs de animales.<\/p>\n<!-- \/wp:paragraph -->                    <\/div>\n                <\/div>\n            <\/div>\n                        <div class=\"card\">\n                <div class=\"card-header\"\n                     id=\"faqs-item-heading-braco-de-weimar-2\"\n                     class=\"btn btn-link\"\n                     data-toggle=\"collapse\"\n                     data-target=\"#faqs-item-braco-de-weimar-2\"\n                     aria-expanded=\"true\"\n                     aria-controls=\"collapseOne\">\n                    <h3 class=\"mb-0 mt-0\">\u00bfCu\u00e1nto tarda en crecer un Braco de Weimar?<\/h3>\n                <\/div>\n\n                <div id=\"faqs-item-braco-de-weimar-2\"\n                     class=\"collapse\"\n                     aria-labelledby=\"faqs-item-heading-braco-de-weimar-2\"\n                     data-parent=\"#accordion\">\n                    <div class=\"card-body\">\n                        <!-- wp:paragraph -->\n<p><strong>El Braco de Weimar suele alcanzar su tama\u00f1o adulto completo entre los 12 y 18 meses de edad.<\/strong> Sin embargo, su desarrollo muscular y su maduraci\u00f3n pueden continuar hasta los 2 a\u00f1os. Es importante proporcionar una dieta adecuada y ejercicio regular durante este per\u00edodo para asegurar un crecimiento saludable.<\/p>\n<!-- \/wp:paragraph -->                    <\/div>\n                <\/div>\n            <\/div>\n                        <div class=\"card\">\n                <div class=\"card-header\"\n                     id=\"faqs-item-heading-braco-de-weimar-3\"\n                     class=\"btn btn-link\"\n                     data-toggle=\"collapse\"\n                     data-target=\"#faqs-item-braco-de-weimar-3\"\n                     aria-expanded=\"true\"\n                     aria-controls=\"collapseOne\">\n                    <h3 class=\"mb-0 mt-0\">\u00bfCu\u00e1nto ejercicio necesita un Braco de Weimar?<\/h3>\n                <\/div>\n\n                <div id=\"faqs-item-braco-de-weimar-3\"\n                     class=\"collapse\"\n                     aria-labelledby=\"faqs-item-heading-braco-de-weimar-3\"\n                     data-parent=\"#accordion\">\n                    <div class=\"card-body\">\n                        <!-- wp:paragraph -->\n<p><strong>El Braco de Weimar es una raza muy activa y en\u00e9rgica que necesita mucho ejercicio diario. <\/strong>Se recomienda al menos una hora de ejercicio intenso cada d\u00eda. <\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Actividades como correr, hacer senderismo, jugar a buscar y practicar <strong><a href=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/lista-deportes-para-practicar-perros\/\" title=\"Descubre los mejores deportes con perros para disfrutar este verano\">deportes caninos<\/a><\/strong> son ideales para satisfacer sus necesidades f\u00edsicas y mentales. Sin suficiente ejercicio, el Braco de Weimar puede volverse inquieto y desarrollar comportamientos destructivos.<\/p>\n<!-- \/wp:paragraph -->                    <\/div>\n                <\/div>\n            <\/div>\n                    <\/div>\n\n        <script type=\"application\/ld+json\">{\"@context\":\"https:\/\/schema.org\",\"@type\":\"FAQPage\",\"mainEntity\":[{\"@type\":\"Question\",\"name\":\"\u00bfD\u00f3nde adoptar un Braco de Weimar?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"Con frecuencia se compran perros de esta raza sin saber lo que implica ser propietario de un perro tan en\u00e9rgico. Muchos Bracos de Weimar terminan en las protectoras o, peor a\u00fan, deambulando por las calles. Si piensas que esta es la raza ideal para ti, considera elegir entre los centenares de animales que se encuentran disponibles para adopci\u00f3n en alguna protectora de animales cercana a tu domicilio. Si no conoces ninguna, puedes informarte en el Ayuntamiento o en un centro veterinario. Tambi\u00e9n puedes visitar Kiwoko adopta, donde realizamos colaboraci\u00f3n con protectoras locales y ONGs de animales.\"}},{\"@type\":\"Question\",\"name\":\"\u00bfCu\u00e1nto tarda en crecer un Braco de Weimar?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"El Braco de Weimar suele alcanzar su tama\u00f1o adulto completo entre los 12 y 18 meses de edad. Sin embargo, su desarrollo muscular y su maduraci\u00f3n pueden continuar hasta los 2 a\u00f1os. Es importante proporcionar una dieta adecuada y ejercicio regular durante este per\u00edodo para asegurar un crecimiento saludable.\"}},{\"@type\":\"Question\",\"name\":\"\u00bfCu\u00e1nto ejercicio necesita un Braco de Weimar?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"El Braco de Weimar es una raza muy activa y en\u00e9rgica que necesita mucho ejercicio diario. Se recomienda al menos una hora de ejercicio intenso cada d\u00eda. Actividades como correr, hacer senderismo, jugar a buscar y practicar deportes caninos son ideales para satisfacer sus necesidades f\u00edsicas y mentales. Sin suficiente ejercicio, el Braco de Weimar puede volverse inquieto y desarrollar comportamientos destructivos.\"}}]}<\/script>\n<!-- \/wp:shortcode -->","protected":false},"excerpt":{"rendered":"<p>El Braco de Weimar es una raza muy activa y en\u00e9rgica que necesita mucho ejercicio diario. Se recomienda al menos una hora de ejercicio intenso cada d\u00eda. Actividades como correr, hacer senderismo, jugar a buscar y practicar deportes caninos son ideales para satisfacer sus necesidades f\u00edsicas y mentales. Sin suficiente ejercicio, el Braco de Weimar [&hellip;]<\/p>\n","protected":false},"featured_media":47428,"template":"","tipo-raza":[1452],"class_list":["post-47194","ficha-de-raza","type-ficha-de-raza","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-json\/wp\/v2\/ficha-de-raza\/47194","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-json\/wp\/v2\/ficha-de-raza"}],"about":[{"href":"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-json\/wp\/v2\/types\/ficha-de-raza"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-json\/wp\/v2\/media\/47428"}],"wp:attachment":[{"href":"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-json\/wp\/v2\/media?parent=47194"}],"wp:term":[{"taxonomy":"tipo-raza","embeddable":true,"href":"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-json\/wp\/v2\/tipo-raza?post=47194"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}