{"id":10549,"date":"2023-06-12T15:45:19","date_gmt":"2023-06-12T13:45:19","guid":{"rendered":"https:\/\/dev-kiwoko-es.on-dev.com\/blogmundoanimal\/cuidados-alimentacion-peces-vacaciones\/"},"modified":"2023-12-19T17:07:08","modified_gmt":"2023-12-19T16:07:08","slug":"cuidados-alimentacion-peces-vacaciones","status":"publish","type":"post","link":"https:\/\/www.kiwoko.mom\/blogmundoanimal\/cuidados-alimentacion-peces-vacaciones\/","title":{"rendered":"Cuidados y alimentaci\u00f3n de los peces durante las vacaciones"},"content":{"rendered":"<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_82_2 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">\u00cdndice<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Alternar tabla de contenidos\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/cuidados-alimentacion-peces-vacaciones\/#Como_mantener_el_acuario_durante_las_vacaciones\" >C\u00f3mo mantener el acuario durante las vacaciones<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/cuidados-alimentacion-peces-vacaciones\/#Comida_de_peces_especial_para_las_vacaciones\" >Comida de peces especial para las vacaciones<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/cuidados-alimentacion-peces-vacaciones\/#Comedero_automatico_para_acuarios\" >Comedero autom\u00e1tico para acuarios<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/cuidados-alimentacion-peces-vacaciones\/#Temperatura_del_agua_del_acuario\" >Temperatura del agua del acuario<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/cuidados-alimentacion-peces-vacaciones\/#Hazte_con_un_temporizador_para_el_acuario\" >Hazte con un temporizador para el acuario<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/cuidados-alimentacion-peces-vacaciones\/#Estado_fisico_de_los_peces\" >Estado f\u00edsico de los peces<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/cuidados-alimentacion-peces-vacaciones\/#Cuidador_de_peces\" >Cuidador de peces<\/a><\/li><\/ul><\/li><\/ul><\/nav><\/div>\n<!-- wp:paragraph -->\n<p>Destino elegido, billetes comprados, maletas preparadas, pero\u2026 \u00bfy los peces? \u00bfPuedes irte tranquilamente de&nbsp;<strong>vacaciones con un&nbsp;acuario&nbsp;en casa<\/strong>? Teniendo en cuenta que ya sabes&nbsp;<strong><a href=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/cuantas-veces-tengo-que-alimentar-a-mis-peces\/\" title=\"\">cu\u00e1ntas veces hay que alimentar a los peces al d\u00eda<\/a><\/strong>&nbsp;habr\u00e1 que buscar una soluci\u00f3n para tu periodo de ausencia. Sigue leyendo porque hay varias cosas que puedes hacer para asegurarte de que tus peces permanezcan sanos y salvos mientras est\u00e1s fuera y saber <strong>como alimentar a tus peces si te vas de vacaciones<\/strong>. <\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:heading -->\n<h2><span class=\"ez-toc-section\" id=\"Como_mantener_el_acuario_durante_las_vacaciones\"><\/span>C\u00f3mo mantener el acuario durante las vacaciones<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>Afortunadamente, hay varias opciones muy sencillas para que tus&nbsp;peces est\u00e9n bien durante las vacaciones, lo primero es <strong>hacer un cambio de agua de alrededor de un 10%<\/strong>, posteriormente aqu\u00ed tienes las soluciones respecto a la comida:<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:heading {\"level\":3} -->\n<h3><span class=\"ez-toc-section\" id=\"Comida_de_peces_especial_para_las_vacaciones\"><\/span>Comida de peces especial para las vacaciones<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>Si te vas solamente un&nbsp;fin de semana&nbsp;puedes dejarles un&nbsp;bloque especial de alimento&nbsp;que se disuelve solo cuando los <strong>peces lo comen y dura&nbsp;tres d\u00edas<\/strong>. Tambi\u00e9n hay&nbsp;pastillas gelificadas&nbsp;que&nbsp;duran hasta catorce d\u00edas, con la caracter\u00edstica de que no ensucian el agua y se disuelven poco a poco. Con esta opci\u00f3n no tendr\u00e1s que preocuparte por <strong>como alimentar a tus peces si te vas de vacaciones<\/strong>.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:shortcode -->\n        <div id=\"external-products-KWK565\" class=\"row external-products\">\n            <img decoding=\"async\" id=\"load-products-KWK565\" data-src=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/themes\/kiwoko\/inc\/assets\/images\/loading.gif\" width=\"50\" height=\"50\" alt=\"loading\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 50px; --smush-placeholder-aspect-ratio: 50\/50;\">\n        <\/div>\n        <script>\n        var id_products = \"KWK565,KWK566,VAS39476\";\n        id_products = id_products.replace(\/\\s\/g, '');\n        var all_ids = id_products.split(\",\");\n\n        \/\/ Agregar sufijo _M a todos los c\u00f3digos\n        var all_ids = all_ids.map(function(id) {\n            return id + '_M';\n        });\n\n        var not_found_products = 1;\n        var not_found_img_product = 0;\n        var ramdom_id = Math.round(Math.random() * 10000);\n        var grid = '12';\n\t\tvar width = '220';\n\t\tvar height = '220';\n        if(all_ids.length >= 4){\n            grid = '3';\n\t\t\twidth = '151';\n\t\t\theight = '151';\n        }else if(all_ids.length == 3){\n            grid = '4';\n\t\t\twidth = '211';\n\t\t\theight = '211';\n        }else if(all_ids.length == 2){\n            grid = '6';\n        }\n\t\n\tif(!items){\n        var feed = \"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/themes\/kiwoko\/feed-channable.xml\";\n        var request = new XMLHttpRequest();\n        request.open(\"GET\", feed, false);\n        request.send();\n        var xmlFromUrl = request.responseXML;\n        var parser = new DOMParser();\n        var xmlDoc = parser.parseFromString(feed, \"text\/xml\");\n        var items = xmlFromUrl.getElementsByTagName(\"item\");\n        }\n\n        var products_found = 0;\n        for (var item of items) {\n            all_ids.forEach(function(word, index) {\n                if(item.getElementsByTagName(\"g:item_group_id\")[0].textContent == word){\n                    not_found_products = 0;\n                    id_products = item.getElementsByTagName(\"g:item_group_id\")[0].textContent;\n                    var link = item.getElementsByTagName(\"link\")[0].textContent;\n                    var image_link = 'src=\"'+item.getElementsByTagName(\"g:image_link\")[0].textContent+'\" ';\n                    var title = item.getElementsByTagName(\"title\")[0].textContent;\n\t\t\t\t\tvar customLabel0 = item.getElementsByTagName(\"g:custom_label_0\")[0]?.textContent || '';\n                    var customLabel1 = item.getElementsByTagName(\"g:custom_label_1\")[0]?.textContent || '';\n                    var product = '<div class=\"col-md-'+grid+' text-center ds-analytics-blog-cross-selling-product order-'+index+'\" style=\"cursor:pointer;\" onclick=\"dataLayer.push({'+\n                    '\\'event\\':\\'crosseling_product_click\\', '+\n                    '\\'event_name\\':\\'crosseling_product_click\\', '+\n                    '\\'link_text\\':\\'\u00a1Comprar ahora!\\', '+\n                    '\\'link_url\\':\\''+link+'\\', '+\n                    '\\'category\\':\\''+customLabel0+'\/'+customLabel1+'\\', '+\n                    '\\'product_name\\':\\''+title+'\\''+\n                    '});window.open(\\''+link+'\\');\"><img id=\"'+id_products+'\" '+image_link+' class=\"product-img-shop\" alt=\"'+title+'\"><p><a href=\"'+link+'\" target=\"_blank\" title=\"'+title+'\" style=\"color:#212529;\" class=\"ds-analytics-blog-cross-selling-product\"><strong>'+title+'<\/strong><\/a><\/p><button id=\"product-addtocart-button\" class=\"action primary tocart btn btn--secondary btn--big\" title=\"\u00a1Comprar ahora!\" type=\"submit\">\u00a1Comprar ahora! <\/button><\/div>';\n \t\t\t\t    \/\/var product = '<div class=\"col-md-'+grid+' text-center ds-analytics-blog-cross-selling-product order-'+index+'\" style=\"cursor:pointer;\" onclick=\"dataLayer.push({\\'event\\':\\'blog_cross_selling_product\\', \\'ga4EventData\\': { \\'name\\':\\'d_blog\\', \\'category\\':\\'click\\', \\'label\\':\\'producto\\', \\'element\\': \\''+link+'\\'}});window.open(\\''+link+'\\');\"><img id=\"'+id_products+'\" '+image_link+' class=\"product-img-shop\" alt=\"'+title+'\"><p><a href=\"'+link+'\" target=\"_blank\" title=\"'+title+'\" style=\"color:#212529;\" class=\"ds-analytics-blog-cross-selling-product\"><strong>'+title+'<\/strong><\/a><\/p><button id=\"product-addtocart-button\" class=\"action primary tocart btn btn--secondary btn--big\" title=\"\u00a1Comprar ahora!\" type=\"submit\">\u00a1Comprar ahora! <\/button><\/div>'; \n                    var grid_div = document.getElementById(\"external-products-KWK565\");\n                    grid_div.innerHTML += product;\n                    products_found++;\n                }\n            });\n            if(products_found == all_ids.length){\n                break;\n            }\n        }\n        document.getElementById(\"load-products-KWK565\").style.display = \"none\";\n        <\/script>\n    \n<!-- \/wp:shortcode -->\n\n<!-- wp:heading {\"level\":3} -->\n<h3><span class=\"ez-toc-section\" id=\"Comedero_automatico_para_acuarios\"><\/span>Comedero autom\u00e1tico para acuarios<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>Otra forma, es optar por instalar un dispensador de <a aria-label=\"comida para peces (abre en una nueva pesta\u00f1a)\" href=\"https:\/\/www.kiwoko.mom\/peces\/comida-para-peces\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>comida para peces<\/strong><\/a>. Coloca la cantidad de alimento adecuada en uno de los compartimentos del comedero. Si es programable, podr\u00e1s automatizar el momento en el que el dispensador libera la cantidad exacta de comida que quieras dar a tus mascotas. Es la opci\u00f3n ideal para&nbsp;acuarios m\u00e1s grandes o con mucha demanda de alimentaci\u00f3n.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:shortcode -->\n        <div id=\"external-products-EHE3581000\" class=\"row external-products\">\n            <img decoding=\"async\" id=\"load-products-EHE3581000\" data-src=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/themes\/kiwoko\/inc\/assets\/images\/loading.gif\" width=\"50\" height=\"50\" alt=\"loading\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 50px; --smush-placeholder-aspect-ratio: 50\/50;\">\n        <\/div>\n        <script>\n        var id_products = \"EHE3581000\";\n        id_products = id_products.replace(\/\\s\/g, '');\n        var all_ids = id_products.split(\",\");\n\n        \/\/ Agregar sufijo _M a todos los c\u00f3digos\n        var all_ids = all_ids.map(function(id) {\n            return id + '_M';\n        });\n\n        var not_found_products = 1;\n        var not_found_img_product = 0;\n        var ramdom_id = Math.round(Math.random() * 10000);\n        var grid = '12';\n\t\tvar width = '220';\n\t\tvar height = '220';\n        if(all_ids.length >= 4){\n            grid = '3';\n\t\t\twidth = '151';\n\t\t\theight = '151';\n        }else if(all_ids.length == 3){\n            grid = '4';\n\t\t\twidth = '211';\n\t\t\theight = '211';\n        }else if(all_ids.length == 2){\n            grid = '6';\n        }\n\t\n\tif(!items){\n        var feed = \"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/themes\/kiwoko\/feed-channable.xml\";\n        var request = new XMLHttpRequest();\n        request.open(\"GET\", feed, false);\n        request.send();\n        var xmlFromUrl = request.responseXML;\n        var parser = new DOMParser();\n        var xmlDoc = parser.parseFromString(feed, \"text\/xml\");\n        var items = xmlFromUrl.getElementsByTagName(\"item\");\n        }\n\n        var products_found = 0;\n        for (var item of items) {\n            all_ids.forEach(function(word, index) {\n                if(item.getElementsByTagName(\"g:item_group_id\")[0].textContent == word){\n                    not_found_products = 0;\n                    id_products = item.getElementsByTagName(\"g:item_group_id\")[0].textContent;\n                    var link = item.getElementsByTagName(\"link\")[0].textContent;\n                    var image_link = 'src=\"'+item.getElementsByTagName(\"g:image_link\")[0].textContent+'\" ';\n                    var title = item.getElementsByTagName(\"title\")[0].textContent;\n\t\t\t\t\tvar customLabel0 = item.getElementsByTagName(\"g:custom_label_0\")[0]?.textContent || '';\n                    var customLabel1 = item.getElementsByTagName(\"g:custom_label_1\")[0]?.textContent || '';\n                    var product = '<div class=\"col-md-'+grid+' text-center ds-analytics-blog-cross-selling-product order-'+index+'\" style=\"cursor:pointer;\" onclick=\"dataLayer.push({'+\n                    '\\'event\\':\\'crosseling_product_click\\', '+\n                    '\\'event_name\\':\\'crosseling_product_click\\', '+\n                    '\\'link_text\\':\\'\u00a1Comprar ahora!\\', '+\n                    '\\'link_url\\':\\''+link+'\\', '+\n                    '\\'category\\':\\''+customLabel0+'\/'+customLabel1+'\\', '+\n                    '\\'product_name\\':\\''+title+'\\''+\n                    '});window.open(\\''+link+'\\');\"><img id=\"'+id_products+'\" '+image_link+' class=\"product-img-shop\" alt=\"'+title+'\"><p><a href=\"'+link+'\" target=\"_blank\" title=\"'+title+'\" style=\"color:#212529;\" class=\"ds-analytics-blog-cross-selling-product\"><strong>'+title+'<\/strong><\/a><\/p><button id=\"product-addtocart-button\" class=\"action primary tocart btn btn--secondary btn--big\" title=\"\u00a1Comprar ahora!\" type=\"submit\">\u00a1Comprar ahora! <\/button><\/div>';\n \t\t\t\t    \/\/var product = '<div class=\"col-md-'+grid+' text-center ds-analytics-blog-cross-selling-product order-'+index+'\" style=\"cursor:pointer;\" onclick=\"dataLayer.push({\\'event\\':\\'blog_cross_selling_product\\', \\'ga4EventData\\': { \\'name\\':\\'d_blog\\', \\'category\\':\\'click\\', \\'label\\':\\'producto\\', \\'element\\': \\''+link+'\\'}});window.open(\\''+link+'\\');\"><img id=\"'+id_products+'\" '+image_link+' class=\"product-img-shop\" alt=\"'+title+'\"><p><a href=\"'+link+'\" target=\"_blank\" title=\"'+title+'\" style=\"color:#212529;\" class=\"ds-analytics-blog-cross-selling-product\"><strong>'+title+'<\/strong><\/a><\/p><button id=\"product-addtocart-button\" class=\"action primary tocart btn btn--secondary btn--big\" title=\"\u00a1Comprar ahora!\" type=\"submit\">\u00a1Comprar ahora! <\/button><\/div>'; \n                    var grid_div = document.getElementById(\"external-products-EHE3581000\");\n                    grid_div.innerHTML += product;\n                    products_found++;\n                }\n            });\n            if(products_found == all_ids.length){\n                break;\n            }\n        }\n        document.getElementById(\"load-products-EHE3581000\").style.display = \"none\";\n        <\/script>\n    \n<!-- \/wp:shortcode -->\n\n<!-- wp:heading {\"level\":3} -->\n<h3><span class=\"ez-toc-section\" id=\"Temperatura_del_agua_del_acuario\"><\/span>Temperatura del agua del acuario<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>Los <strong>peces est\u00e1n acostumbrados a&nbsp;cambios c\u00edclicos en la&nbsp;temperatura<\/strong>, <strong>pero si el cambio es muy extremo pueden sufrir da\u00f1os<\/strong>. Durante las vacaciones de verano, hay dos opciones, o bien dejar el acuario en el lugar m\u00e1s fresco de la casa a una temperatura constante, o llamar a alguien para que vaya a echar un vistazo en caso de ola de calor y si es necesario que ponga el aire acondicionado durante esos d\u00edas para mantener el ambiente estable. Lee nuestro post sobre&nbsp;<strong><a href=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/acuarios-el-calor-veraniego\/\" title=\"\">c\u00f3mo solventar los problemas con el calor y los acuarios en verano<\/a><\/strong>&nbsp;para tener m\u00e1s informaci\u00f3n sobre este tema.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:heading {\"level\":3} -->\n<h3><span class=\"ez-toc-section\" id=\"Hazte_con_un_temporizador_para_el_acuario\"><\/span>Hazte con un temporizador para el acuario<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>Est\u00e1s acostumbrado a que haya luz durante el d\u00eda y oscuridad por la noche, \u00a1tus peces tambi\u00e9n! La iluminaci\u00f3n ser\u00e1 m\u00e1s f\u00e1cil de gestionar si te haces con un&nbsp;<strong>temporizador<\/strong>, as\u00ed tus peces seguir\u00e1n su&nbsp;<strong>ciclo diurno y nocturno<\/strong>. Con esto tendr\u00e1s una cosa menos en la que preocuparte cada d\u00eda, incluso cuando est\u00e9s en casa.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:heading {\"level\":3} -->\n<h3><span class=\"ez-toc-section\" id=\"Estado_fisico_de_los_peces\"><\/span>Estado f\u00edsico de los peces<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>Otro factor importante es la condici\u00f3n f\u00edsica de tus peces. <strong>Justo antes de salir de vacaciones, exam\u00ednalos para asegurarte de que ninguno de ellos parece estar enfermo<\/strong>. Si notas cualquier anomal\u00eda, consulta en tu&nbsp;tienda Kiwoko&nbsp;m\u00e1s cercana antes de salir. De lo contrario corres el riesgo de volver a casa y encontrar a un&nbsp;<strong>acuario lleno de peces enfermos o moribundos<\/strong>.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:heading {\"level\":3} -->\n<h3><span class=\"ez-toc-section\" id=\"Cuidador_de_peces\"><\/span>Cuidador de peces<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>Si vas a estar mucho tiempo fuera, lo mejor es que llames a alguien para que vaya a cuidar de tu acuario. La informaci\u00f3n m\u00e1s importante para tu ayudante es que&nbsp;<strong>no tiene que sobrealimentar<\/strong>&nbsp;a los peces, ya que puede resultar letal para ellos. D\u00e9jale al alcance los botes de comida y la cantidad recomendada.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:shortcode -->\n        <div id=\"external-products-KWK506\" class=\"row external-products\">\n            <img decoding=\"async\" id=\"load-products-KWK506\" data-src=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/themes\/kiwoko\/inc\/assets\/images\/loading.gif\" width=\"50\" height=\"50\" alt=\"loading\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 50px; --smush-placeholder-aspect-ratio: 50\/50;\">\n        <\/div>\n        <script>\n        var id_products = \"KWK506,SER150,JBL303160\";\n        id_products = id_products.replace(\/\\s\/g, '');\n        var all_ids = id_products.split(\",\");\n\n        \/\/ Agregar sufijo _M a todos los c\u00f3digos\n        var all_ids = all_ids.map(function(id) {\n            return id + '_M';\n        });\n\n        var not_found_products = 1;\n        var not_found_img_product = 0;\n        var ramdom_id = Math.round(Math.random() * 10000);\n        var grid = '12';\n\t\tvar width = '220';\n\t\tvar height = '220';\n        if(all_ids.length >= 4){\n            grid = '3';\n\t\t\twidth = '151';\n\t\t\theight = '151';\n        }else if(all_ids.length == 3){\n            grid = '4';\n\t\t\twidth = '211';\n\t\t\theight = '211';\n        }else if(all_ids.length == 2){\n            grid = '6';\n        }\n\t\n\tif(!items){\n        var feed = \"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/themes\/kiwoko\/feed-channable.xml\";\n        var request = new XMLHttpRequest();\n        request.open(\"GET\", feed, false);\n        request.send();\n        var xmlFromUrl = request.responseXML;\n        var parser = new DOMParser();\n        var xmlDoc = parser.parseFromString(feed, \"text\/xml\");\n        var items = xmlFromUrl.getElementsByTagName(\"item\");\n        }\n\n        var products_found = 0;\n        for (var item of items) {\n            all_ids.forEach(function(word, index) {\n                if(item.getElementsByTagName(\"g:item_group_id\")[0].textContent == word){\n                    not_found_products = 0;\n                    id_products = item.getElementsByTagName(\"g:item_group_id\")[0].textContent;\n                    var link = item.getElementsByTagName(\"link\")[0].textContent;\n                    var image_link = 'src=\"'+item.getElementsByTagName(\"g:image_link\")[0].textContent+'\" ';\n                    var title = item.getElementsByTagName(\"title\")[0].textContent;\n\t\t\t\t\tvar customLabel0 = item.getElementsByTagName(\"g:custom_label_0\")[0]?.textContent || '';\n                    var customLabel1 = item.getElementsByTagName(\"g:custom_label_1\")[0]?.textContent || '';\n                    var product = '<div class=\"col-md-'+grid+' text-center ds-analytics-blog-cross-selling-product order-'+index+'\" style=\"cursor:pointer;\" onclick=\"dataLayer.push({'+\n                    '\\'event\\':\\'crosseling_product_click\\', '+\n                    '\\'event_name\\':\\'crosseling_product_click\\', '+\n                    '\\'link_text\\':\\'\u00a1Comprar ahora!\\', '+\n                    '\\'link_url\\':\\''+link+'\\', '+\n                    '\\'category\\':\\''+customLabel0+'\/'+customLabel1+'\\', '+\n                    '\\'product_name\\':\\''+title+'\\''+\n                    '});window.open(\\''+link+'\\');\"><img id=\"'+id_products+'\" '+image_link+' class=\"product-img-shop\" alt=\"'+title+'\"><p><a href=\"'+link+'\" target=\"_blank\" title=\"'+title+'\" style=\"color:#212529;\" class=\"ds-analytics-blog-cross-selling-product\"><strong>'+title+'<\/strong><\/a><\/p><button id=\"product-addtocart-button\" class=\"action primary tocart btn btn--secondary btn--big\" title=\"\u00a1Comprar ahora!\" type=\"submit\">\u00a1Comprar ahora! <\/button><\/div>';\n \t\t\t\t    \/\/var product = '<div class=\"col-md-'+grid+' text-center ds-analytics-blog-cross-selling-product order-'+index+'\" style=\"cursor:pointer;\" onclick=\"dataLayer.push({\\'event\\':\\'blog_cross_selling_product\\', \\'ga4EventData\\': { \\'name\\':\\'d_blog\\', \\'category\\':\\'click\\', \\'label\\':\\'producto\\', \\'element\\': \\''+link+'\\'}});window.open(\\''+link+'\\');\"><img id=\"'+id_products+'\" '+image_link+' class=\"product-img-shop\" alt=\"'+title+'\"><p><a href=\"'+link+'\" target=\"_blank\" title=\"'+title+'\" style=\"color:#212529;\" class=\"ds-analytics-blog-cross-selling-product\"><strong>'+title+'<\/strong><\/a><\/p><button id=\"product-addtocart-button\" class=\"action primary tocart btn btn--secondary btn--big\" title=\"\u00a1Comprar ahora!\" type=\"submit\">\u00a1Comprar ahora! <\/button><\/div>'; \n                    var grid_div = document.getElementById(\"external-products-KWK506\");\n                    grid_div.innerHTML += product;\n                    products_found++;\n                }\n            });\n            if(products_found == all_ids.length){\n                break;\n            }\n        }\n        document.getElementById(\"load-products-KWK506\").style.display = \"none\";\n        <\/script>\n    \n<!-- \/wp:shortcode -->\n\n<!-- wp:paragraph -->\n<p> Aseg\u00farate de que esta persona puede llamarte cuando lo necesite. Independientemente de que tengas una persona que pueda ayudarte o no, si lo preparas todo con tiempo podr\u00e1s irte con tranquilidad de viaje. <\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Por \u00faltimo, no te pierdas los consejos de Marcel sobre este tema en nuestro Canal <strong><a aria-label=\"Kiwoko TV (abre en una nueva pesta\u00f1a)\" style=\"\" href=\"https:\/\/www.youtube.com\/c\/kiwokotv\/videos\" target=\"_blank\" rel=\"noreferrer noopener\">Kiwoko TV<\/a><\/strong>. Recuerda suscribirte y recibir\u00e1s una notificaci\u00f3n con contenido muy interesante para los amantes del mundo de los peces.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:html -->\n<iframe width=\"100%\" height=\"315\" data-src=\"https:\/\/www.youtube.com\/embed\/xQQmF4e1ORY\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" data-load-mode=\"1\"><\/iframe>\n<!-- \/wp:html -->\n\n<!-- wp:paragraph -->\n<p>Si quieres seguir leyendo, no te pierdas:<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:list -->\n<ul><!-- wp:list-item -->\n<li><a href=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/tipos-alimentacion-para-peces-acuario\/\" title=\"\u00bfQu\u00e9 comen tus peces? Tipo de alimentaci\u00f3n\"><strong>\u00bfQu\u00e9 comen tus peces? Tipo de alimentaci\u00f3n<\/strong><\/a><\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li><strong><a href=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/como-alimentar-pez-betta\/\" title=\"C\u00f3mo&nbsp;alimentar a un pez Betta Splendens\">C\u00f3mo&nbsp;alimentar a un pez Betta Splendens<\/a><\/strong><\/li>\n<!-- \/wp:list-item --><\/ul>\n<!-- \/wp:list -->\n\n<!-- wp:paragraph {\"style\":{\"color\":{\"background\":\"#f0f0f0\"}}} -->\n<p class=\"has-background\" style=\"background-color:#f0f0f0\">Si necesitas asesoramiento en tiendas Kiwoko contamos con personal experto en acuariofilia y  fauna acu\u00e1tica en general. Si ya sabes que necesitas para el mantenimiento de tu acuario o para tus peces, puedes realizar tu pedido en <strong><a href=\"https:\/\/www.kiwoko.mom\/\" target=\"_blank\" rel=\"noopener\" title=\"kiwoko.mom\">kiwoko.mom<\/a><\/strong> por &nbsp;<a href=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/servicio-venta-telefonica\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>v\u00eda telef\u00f3nica<\/strong><\/a> o en tu <a href=\"https:\/\/www.kiwoko.mom\/tiendas?showMap=true&amp;horizontalView=true&amp;isForm=true\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>tienda<\/strong> <strong>m\u00e1s cercana<\/strong><\/a>.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:spacer {\"height\":\"31px\"} -->\n<div style=\"height:31px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<!-- \/wp:spacer -->","protected":false},"excerpt":{"rendered":"<p>\u00bfTe preocupa el estado de tus peces y de tu acuario mientras est\u00e1s fuera? \u00a1L\u00f3gico! Te damos algunas pautas para que dejes todo listo para que tus peces se queden a buen recaudo antes de marcharte de vacaciones.<\/p>\n","protected":false},"author":40,"featured_media":34078,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1062],"tags":[1120,1083,1271,1275],"class_list":["post-10549","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-peces","tag-acuarios","tag-alimentacion","tag-nutricion","tag-verano"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-json\/wp\/v2\/posts\/10549","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-json\/wp\/v2\/users\/40"}],"replies":[{"embeddable":true,"href":"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-json\/wp\/v2\/comments?post=10549"}],"version-history":[{"count":28,"href":"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-json\/wp\/v2\/posts\/10549\/revisions"}],"predecessor-version":[{"id":44344,"href":"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-json\/wp\/v2\/posts\/10549\/revisions\/44344"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-json\/wp\/v2\/media\/34078"}],"wp:attachment":[{"href":"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-json\/wp\/v2\/media?parent=10549"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-json\/wp\/v2\/categories?post=10549"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-json\/wp\/v2\/tags?post=10549"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}