{"id":10589,"date":"2019-06-12T11:17:00","date_gmt":"2019-06-12T11:17:00","guid":{"rendered":"https:\/\/dev-kiwoko-es.on-dev.com\/blogmundoanimal\/miedo-de-perros-a-otros-perros\/"},"modified":"2023-09-15T13:18:44","modified_gmt":"2023-09-15T11:18:44","slug":"miedo-de-perros-a-otros-perros","status":"publish","type":"post","link":"https:\/\/www.kiwoko.mom\/blogmundoanimal\/miedo-de-perros-a-otros-perros\/","title":{"rendered":"\u00bfQu\u00e9 hacer si mi perro tiene miedo a otros perros?"},"content":{"rendered":"<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_82_2 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">\u00cdndice<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Alternar tabla de contenidos\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/miedo-de-perros-a-otros-perros\/#Posibles_causas_del_miedo_de_los_perros_a_otros_perros\" >Posibles causas del miedo de los perros a otros perros<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/miedo-de-perros-a-otros-perros\/#Miedo_debido_a_la_falta_de_socializacion\" >Miedo debido a la falta de socializaci\u00f3n<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/miedo-de-perros-a-otros-perros\/#Miedo_derivado_de_una_experiencia_traumatica\" >Miedo derivado de una experiencia traum\u00e1tica<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/miedo-de-perros-a-otros-perros\/#Miedo_reforzado_por_los_propietarios\" >Miedo reforzado por los propietarios<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/miedo-de-perros-a-otros-perros\/#%C2%BFQue_hago_si_mi_perro_tiene_miedo_a_otros_perros\" >\u00bfQu\u00e9 hago si mi perro tiene miedo a otros perros?<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/miedo-de-perros-a-otros-perros\/#Pasos_a_seguir_para_quitarle_ese_temor\" >Pasos a seguir para quitarle ese temor<\/a><\/li><\/ul><\/li><\/ul><\/nav><\/div>\n<!-- wp:paragraph -->\n<p>\u00bf<strong>Tu perro le tiene miedo a otros perros<\/strong>? Cuando ve a otros de su misma especie, \u00bfecha las orejas hacia abajo? \u00bfPone la cola entre las patas? \u00bfSe esconde y quiere huir? \u00bfGru\u00f1e al otro perro para tratar de intimidarle?<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Todas esas se\u00f1ales son s\u00edntomas de miedo, una emoci\u00f3n necesaria y vital. El temor permite que los animales reaccionen ante el peligro, pero si <strong>se convierte en una fobia<\/strong> puede convertirse en un gran problema, y los paseos pueden llegar a ser muy estresantes tanto para ti como para tu animal. En este post vamos a ver a qu\u00e9 se debe y <strong>c\u00f3mo evitar el recelo de un perro a otro perro<\/strong>.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:heading -->\n<h2><span class=\"ez-toc-section\" id=\"Posibles_causas_del_miedo_de_los_perros_a_otros_perros\"><\/span>Posibles causas del miedo de los perros a otros perros<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>Antes de pasar a la acci\u00f3n, es bueno saber localizar d\u00f3nde est\u00e1 el n\u00facleo del problema. A continuaci\u00f3n, te contamos d\u00f3nde pueden estar los <strong>motivos m\u00e1s frecuentes<\/strong>.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:heading {\"level\":3} -->\n<h3><span class=\"ez-toc-section\" id=\"Miedo_debido_a_la_falta_de_socializacion\"><\/span>Miedo debido a la falta de socializaci\u00f3n<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>Tu perro puede sentir temor debido a la <strong><a href=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/importancia-socializacion-temprana-perros\/\" target=\"_blank\" rel=\"noreferrer noopener\">falta de socializaci\u00f3n temprana<\/a><\/strong>. O en otras palabras, tu perro <strong>no tuvo suficiente contacto con otros perros cuando era un cachorro<\/strong>.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Este caso es frecuente en perros a los que separaron de su camada muy pronto y que no conviven con otro en su familia adoptiva.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:heading {\"level\":3} -->\n<h3><span class=\"ez-toc-section\" id=\"Miedo_derivado_de_una_experiencia_traumatica\"><\/span>Miedo derivado de una experiencia traum\u00e1tica<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>Si tu <strong>perro se asusta con bastante facilidad<\/strong>, se puede deber a que tuvo una <strong>experiencia traum\u00e1tica en el pasado<\/strong>. Por ejemplo, si ha vivido una experiencia en la que se encuentra con <strong>perros grandes con mucha energ\u00eda<\/strong> que quieren jugar con \u00e9l de una manera brusca y se asust\u00f3. Por supuesto, tambi\u00e9n puede deberse a los <strong>ataques reales de otros perros<\/strong>.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Es probable que en el futuro, cada vez que se cruce con un perro m\u00e1s grande que \u00e9l presente agresividad o desconfianza.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:heading {\"level\":3} -->\n<h3><span class=\"ez-toc-section\" id=\"Miedo_reforzado_por_los_propietarios\"><\/span>Miedo reforzado por los propietarios<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>Una respuesta muy frecuente de los due\u00f1os <strong>ante un perro asustado<\/strong> es acariciarlo y hablarle suavemente para calmarlo. Sin embargo, eso en realidad empeora la situaci\u00f3n. De hecho, hacerlo solo le est\u00e1 dando al perro la confirmaci\u00f3n de que es correcto comportarse as\u00ed.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p><strong>Forzarlo a estar entre los otros perros<\/strong> tampoco es una buena idea, e incluso puede <strong>empeorar la calidad de la relaci\u00f3n con tu animal<\/strong>.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:heading -->\n<h2><span class=\"ez-toc-section\" id=\"%C2%BFQue_hago_si_mi_perro_tiene_miedo_a_otros_perros\"><\/span>\u00bfQu\u00e9 hago si mi perro tiene miedo a otros perros?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>Para a<strong>yudar a un perro que se asusta ante la presencia de otros<\/strong> animales, lo primero es aceptar c\u00f3mo es y no tratar de forzarlo a superar ese sentimiento en un solo d\u00eda. Ser\u00e1 importante reforzar la confianza y la seguridad del perro. \u00a1C\u00e1rgate de paciencia y cari\u00f1o!<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:heading {\"level\":3} -->\n<h3><span class=\"ez-toc-section\" id=\"Pasos_a_seguir_para_quitarle_ese_temor\"><\/span>Pasos a seguir para quitarle ese temor<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>Al principio, lo m\u00e1s sencillo para tu amigo de cuatro patas es <strong>evitar el encuentro con otros perros<\/strong> pero te vamos a contar <strong>tres t\u00e9cnicas diferentes para tratar de rebajar la desconfianza de tu perro<\/strong>.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:list -->\n<ul><!-- wp:list-item -->\n<li><strong>Desensibilizaci\u00f3n<\/strong>. Consiste en <strong>exponer a tu perro progresivamente al problema<\/strong> hasta que ya no le estrese. Puedes comenzar por mantener a tu perro alejado de otros perros, e <strong>ir reduciendo gradualmente esta distancia<\/strong> durante los paseos de acuerdo con la evoluci\u00f3n y la mejora del perro. Tambi\u00e9n puedes organizar <strong>reuniones con perros muy amables y tranquilos<\/strong>, antes de exponerlo gradualmente a perros m\u00e1s en\u00e9rgicos o imponentes.<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li><strong>Familiarizaci\u00f3n<\/strong>. Consiste en ense\u00f1ar al perro a <strong>no reaccionar ante la situaci\u00f3n estresante<\/strong>. Si lo llevas a dar m\u00e1s paseos por zonas donde se encontrar\u00e1 con otros perros, permitir\u00e1s que tu perro se acostumbre a ellos y se d\u00e9 cuenta de que no son una amenaza. Si aplicas este m\u00e9todo, ten cuidado de no someter a tu perro a una situaci\u00f3n que sea demasiado estresante para \u00e9l, ya que esto empeorar\u00eda la situaci\u00f3n.<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li><strong>Contra-acondicionamiento<\/strong>. Este m\u00e9todo le permite <strong>asociar la situaci\u00f3n estresante con una experiencia positiva<\/strong>. Por ejemplo, al <strong><a href=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/juegos-perros-aire-libre-lanzamiento-de-disco\/\" target=\"_blank\" rel=\"noreferrer noopener\">jugar con tu perro<\/a><\/strong> cuando otros perros est\u00e1n cerca, asociar\u00e1 este momento con el tiempo de <strong><a href=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/tag\/juego\/\" target=\"_blank\" rel=\"noreferrer noopener\">juego<\/a><\/strong> y se relajar\u00e1 en presencia de otros perros.<\/li>\n<!-- \/wp:list-item --><\/ul>\n<!-- \/wp:list -->\n\n<!-- wp:paragraph -->\n<p>Puedes aplicar estos tres m\u00e9todos, sin embargo, lo m\u00e1s importante es que <strong>respetes la velocidad de aprendizaje de tu perro<\/strong>. Es un proceso que puede llevar tiempo, y cada caso es diferente. Si crees que no puedes hacer frente a esta situaci\u00f3n solo, siempre consultar a un <strong><a href=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/que-es-un-etologo\/\" target=\"_blank\" rel=\"noreferrer noopener\">experto en comportamiento canino<\/a><\/strong> que pueda aconsejarte sobre los mejores pasos a seguir para tu perro en concreto.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Los perros son animales sociales que necesitan interactuar con sus semejantes, y ayudarles a superar sus miedos para comunicarse con otros perros es una gran muestra de amor que puedes darle a tu perro. En nuestras <strong><a href=\"https:\/\/www.kiwoko.mom\/tiendas.html\" target=\"_blank\" rel=\"noreferrer noopener\">tiendas Kiwoko<\/a><\/strong> y en <strong><a href=\"https:\/\/www.kiwoko.mom\/\" target=\"_blank\" rel=\"noreferrer noopener\">www.kiwoko.mom<\/a><\/strong> encontrar\u00e1s todo el material que necesitas para ayudar a tu amigo a superar sus temores.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:shortcode -->\n        <div id=\"external-products-KNO16844\" class=\"row external-products\">\n            <img decoding=\"async\" id=\"load-products-KNO16844\" data-src=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/themes\/kiwoko\/inc\/assets\/images\/loading.gif\" width=\"50\" height=\"50\" alt=\"loading\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 50px; --smush-placeholder-aspect-ratio: 50\/50;\">\n        <\/div>\n        <script>\n        var id_products = \"KNO16844,OUT88712,DZL88029\";\n        id_products = id_products.replace(\/\\s\/g, '');\n        var all_ids = id_products.split(\",\");\n\n        \/\/ Agregar sufijo _M a todos los c\u00f3digos\n        var all_ids = all_ids.map(function(id) {\n            return id + '_M';\n        });\n\n        var not_found_products = 1;\n        var not_found_img_product = 0;\n        var ramdom_id = Math.round(Math.random() * 10000);\n        var grid = '12';\n\t\tvar width = '220';\n\t\tvar height = '220';\n        if(all_ids.length >= 4){\n            grid = '3';\n\t\t\twidth = '151';\n\t\t\theight = '151';\n        }else if(all_ids.length == 3){\n            grid = '4';\n\t\t\twidth = '211';\n\t\t\theight = '211';\n        }else if(all_ids.length == 2){\n            grid = '6';\n        }\n\t\n\tif(!items){\n        var feed = \"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/themes\/kiwoko\/feed-channable.xml\";\n        var request = new XMLHttpRequest();\n        request.open(\"GET\", feed, false);\n        request.send();\n        var xmlFromUrl = request.responseXML;\n        var parser = new DOMParser();\n        var xmlDoc = parser.parseFromString(feed, \"text\/xml\");\n        var items = xmlFromUrl.getElementsByTagName(\"item\");\n        }\n\n        var products_found = 0;\n        for (var item of items) {\n            all_ids.forEach(function(word, index) {\n                if(item.getElementsByTagName(\"g:item_group_id\")[0].textContent == word){\n                    not_found_products = 0;\n                    id_products = item.getElementsByTagName(\"g:item_group_id\")[0].textContent;\n                    var link = item.getElementsByTagName(\"link\")[0].textContent;\n                    var image_link = 'src=\"'+item.getElementsByTagName(\"g:image_link\")[0].textContent+'\" ';\n                    var title = item.getElementsByTagName(\"title\")[0].textContent;\n\t\t\t\t\tvar customLabel0 = item.getElementsByTagName(\"g:custom_label_0\")[0]?.textContent || '';\n                    var customLabel1 = item.getElementsByTagName(\"g:custom_label_1\")[0]?.textContent || '';\n                    var product = '<div class=\"col-md-'+grid+' text-center ds-analytics-blog-cross-selling-product order-'+index+'\" style=\"cursor:pointer;\" onclick=\"dataLayer.push({'+\n                    '\\'event\\':\\'crosseling_product_click\\', '+\n                    '\\'event_name\\':\\'crosseling_product_click\\', '+\n                    '\\'link_text\\':\\'\u00a1Comprar ahora!\\', '+\n                    '\\'link_url\\':\\''+link+'\\', '+\n                    '\\'category\\':\\''+customLabel0+'\/'+customLabel1+'\\', '+\n                    '\\'product_name\\':\\''+title+'\\''+\n                    '});window.open(\\''+link+'\\');\"><img id=\"'+id_products+'\" '+image_link+' class=\"product-img-shop\" alt=\"'+title+'\"><p><a href=\"'+link+'\" target=\"_blank\" title=\"'+title+'\" style=\"color:#212529;\" class=\"ds-analytics-blog-cross-selling-product\"><strong>'+title+'<\/strong><\/a><\/p><button id=\"product-addtocart-button\" class=\"action primary tocart btn btn--secondary btn--big\" title=\"\u00a1Comprar ahora!\" type=\"submit\">\u00a1Comprar ahora! <\/button><\/div>';\n \t\t\t\t    \/\/var product = '<div class=\"col-md-'+grid+' text-center ds-analytics-blog-cross-selling-product order-'+index+'\" style=\"cursor:pointer;\" onclick=\"dataLayer.push({\\'event\\':\\'blog_cross_selling_product\\', \\'ga4EventData\\': { \\'name\\':\\'d_blog\\', \\'category\\':\\'click\\', \\'label\\':\\'producto\\', \\'element\\': \\''+link+'\\'}});window.open(\\''+link+'\\');\"><img id=\"'+id_products+'\" '+image_link+' class=\"product-img-shop\" alt=\"'+title+'\"><p><a href=\"'+link+'\" target=\"_blank\" title=\"'+title+'\" style=\"color:#212529;\" class=\"ds-analytics-blog-cross-selling-product\"><strong>'+title+'<\/strong><\/a><\/p><button id=\"product-addtocart-button\" class=\"action primary tocart btn btn--secondary btn--big\" title=\"\u00a1Comprar ahora!\" type=\"submit\">\u00a1Comprar ahora! <\/button><\/div>'; \n                    var grid_div = document.getElementById(\"external-products-KNO16844\");\n                    grid_div.innerHTML += product;\n                    products_found++;\n                }\n            });\n            if(products_found == all_ids.length){\n                break;\n            }\n        }\n        document.getElementById(\"load-products-KNO16844\").style.display = \"none\";\n        <\/script>\n    \n<!-- \/wp:shortcode -->","protected":false},"excerpt":{"rendered":"<p dir=\"ltr\"><span>En este post te contamos cu\u00e1les son las principales razones por las que un perro se asusta de otro perro y c\u00f3mo evitar que les tenga fobia.<\/span><\/p>\n<div><span><br \/><\/span><\/div>\n","protected":false},"author":40,"featured_media":32563,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1089,1071],"tags":[1262,1202,1440,1284],"class_list":["post-10589","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-disfruta-de-tu-mascota","category-perros","tag-adiestramiento","tag-comportamiento","tag-entrenamiento","tag-miedos"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-json\/wp\/v2\/posts\/10589","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-json\/wp\/v2\/users\/40"}],"replies":[{"embeddable":true,"href":"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-json\/wp\/v2\/comments?post=10589"}],"version-history":[{"count":5,"href":"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-json\/wp\/v2\/posts\/10589\/revisions"}],"predecessor-version":[{"id":42576,"href":"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-json\/wp\/v2\/posts\/10589\/revisions\/42576"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-json\/wp\/v2\/media\/32563"}],"wp:attachment":[{"href":"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-json\/wp\/v2\/media?parent=10589"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-json\/wp\/v2\/categories?post=10589"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-json\/wp\/v2\/tags?post=10589"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}