{"id":10612,"date":"2024-04-01T11:19:06","date_gmt":"2024-04-01T09:19:06","guid":{"rendered":"https:\/\/dev-kiwoko-es.on-dev.com\/blogmundoanimal\/como-transportar-perro-de-manera-adecuada\/"},"modified":"2025-03-06T13:27:18","modified_gmt":"2025-03-06T12:27:18","slug":"como-transportar-perro-de-manera-adecuada","status":"publish","type":"post","link":"https:\/\/www.kiwoko.mom\/blogmundoanimal\/como-transportar-perro-de-manera-adecuada\/","title":{"rendered":"Opciones m\u00e1s recomendables para transportar a tu perro"},"content":{"rendered":"<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_82_2 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">\u00cdndice<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Alternar tabla de contenidos\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/como-transportar-perro-de-manera-adecuada\/#Tipos_de_bolsas_de_transporte_para_perros\" >Tipos de bolsas de transporte para perros<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/como-transportar-perro-de-manera-adecuada\/#1_Elige_una_mochila_disenada_especificamente_para_perros\" >1 Elige una mochila dise\u00f1ada espec\u00edficamente para perros<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/como-transportar-perro-de-manera-adecuada\/#2_Relleno_adecuado\" >2 Relleno adecuado<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/como-transportar-perro-de-manera-adecuada\/#3_No_te_fijes_solo_en_el_peso_de_tu_perro_para_elegir_el_tamano_de_la_mochila\" >3 No te fijes s\u00f3lo en el peso de tu perro para elegir el tama\u00f1o de la mochila<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/como-transportar-perro-de-manera-adecuada\/#4_Abertura_para_la_cabeza\" >4 Abertura para la cabeza<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/como-transportar-perro-de-manera-adecuada\/#5_Tomate_tu_tiempo\" >5 T\u00f3mate tu tiempo<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/como-transportar-perro-de-manera-adecuada\/#6_Revisa_el_fondo_de_la_mochila\" >6 Revisa el fondo de la mochila<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/como-transportar-perro-de-manera-adecuada\/#7_Consulta_a_tu_veterinario\" >7 Consulta a tu veterinario<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/como-transportar-perro-de-manera-adecuada\/#Diferentes_estilos_y_modelos_de_bolsas_de_transporte_para_perros\" >Diferentes estilos y modelos de bolsas de transporte para perros<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-10\" href=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/como-transportar-perro-de-manera-adecuada\/#Mochilas\" >Mochilas<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-11\" href=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/como-transportar-perro-de-manera-adecuada\/#Bolsa_de_deporte\" >Bolsa de deporte<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-12\" href=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/como-transportar-perro-de-manera-adecuada\/#Trolley\" >Trolley<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-13\" href=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/como-transportar-perro-de-manera-adecuada\/#Tipos_de_transportines_para_perros\" >Tipos de transportines para perros<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-14\" href=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/como-transportar-perro-de-manera-adecuada\/#1_Modelo_basico\" >1 Modelo b\u00e1sico<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-15\" href=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/como-transportar-perro-de-manera-adecuada\/#2_Transportin_tipo_bolso\" >2 Transport\u00edn tipo bolso<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-16\" href=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/como-transportar-perro-de-manera-adecuada\/#3_Plegable\" >3 Plegable<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-17\" href=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/como-transportar-perro-de-manera-adecuada\/#4_Modelo_avanzado_para_coche\" >4 Modelo avanzado para coche<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-18\" href=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/como-transportar-perro-de-manera-adecuada\/#5_Transportines_homologados_IATA\" >5 Transportines homologados IATA<\/a><\/li><\/ul><\/li><\/ul><\/nav><\/div>\n<!-- wp:paragraph -->\n<p>\u00bfNo quieres renunciar a salir a la calle con tu <strong>cachorro<\/strong> o con tu <strong>perro de raza mini<\/strong>? Tanto si lo que quieres es dar un paseo, como si se trata de irte <strong>de viaje con tu mascota<\/strong>, lo ideal ser\u00e1 que valores todas las posibilidades disponibles para que tu perro vaya lo m\u00e1s seguro y c\u00f3modo posible.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Lo primero que tendr\u00e1s que hacer es <strong>medir a tu mascota para elegir un transport\u00edn<\/strong> y a continuaci\u00f3n informarte sobre los distintos modelos que existen para ver cu\u00e1l se adapta mejor a tu mascota. <\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>\u00a1Vamos a verlo con m\u00e1s detalle!<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:heading -->\n<h2><span class=\"ez-toc-section\" id=\"Tipos_de_bolsas_de_transporte_para_perros\"><\/span>Tipos de bolsas de transporte para perros<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>A continuaci\u00f3n, esta serie de tips te ayudar\u00e1n a encontrar el<strong> tipo de bolsa ideal para transportar a tu mascota<\/strong>. <\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:list {\"ordered\":true} -->\n<ol><!-- wp:list-item -->\n<li>Elige una mochila dise\u00f1ada espec\u00edficamente para perros<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>Relleno adecuado<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>No te fije s\u00f3lo en el peso de tu perro para elegir el tama\u00f1o de la mochila<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>Abertura para la cabeza<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>T\u00f3mate tu tiempo<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>Revisa el fondo de la mochila<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>Consulta a tu veterinario<\/li>\n<!-- \/wp:list-item --><\/ol>\n<!-- \/wp:list -->\n\n<!-- wp:heading {\"level\":3,\"style\":{\"color\":{\"background\":\"#eeeeeeed\"}}} -->\n<h3 class=\"has-background\" style=\"background-color:#eeeeeeed\"><span class=\"ez-toc-section\" id=\"1_Elige_una_mochila_disenada_especificamente_para_perros\"><\/span>1 Elige una mochila dise\u00f1ada espec\u00edficamente para perros<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>Hoy en d\u00eda puedes encontrar todo tipo de bolsos y mochilas. Pero a la hora de adquirir una mochila para transportar a tu perro aseg\u00farate de que est\u00e9 <strong>dise\u00f1ada espec\u00edficamente para ellos<\/strong>. Busca una con <strong>materiales resistentes al agua, duraderos y que transpiren<\/strong>.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Las mochilas para perros est\u00e1n muy de moda, pero para hacer un buen uso de ellas hay que tener en cuenta una serie de factores para que ni tu perro ni t\u00fa salg\u00e1is perjudicados.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:table {\"className\":\"is-style-stripes\"} -->\n<figure class=\"wp-block-table is-style-stripes\"><table><tbody><tr><td>        <style>.ds-icon-mobile{display:none;}@media screen and (max-width: 767px) {.ds-icon-desktop{display:none;}.ds-icon-mobile{display:inline;}}<\/style>\n    <span style=\"color:#e20b12\">\n            <svg class=\"bi d-sm-inline-block d-md-inline-block d-lg-inline-block d-xl-inline-block ds-icon-desktop\" width=\"35\" height=\"35\" fill=\"#e20b12\">\n        <use xlink:href=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/plugins\/ds-icons\/bootstrap-icons\/bootstrap-icons.svg#exclamation-triangle\"\/>\n        <\/svg>\n        <svg class=\"bi d-inline-block d-sm-none d-md-none d-lg-none d-xl-none ds-icon-mobile\" width=\"35\" height=\"35\" fill=\"#e20b12\">\n        <use xlink:href=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/plugins\/ds-icons\/bootstrap-icons\/bootstrap-icons.svg#exclamation-triangle\"\/>\n        <\/svg>\n        <\/span>\n    <\/td><td>Natalia Garc\u00eda<em>, Veterinaria y Category Manager de Salud, Higiene y animal vivo de Kiwoko<\/em>&nbsp;alerta sobre el uso de mochilas que no est\u00e1n dise\u00f1adas espec\u00edficamente para perros:<br>- No hay que caer en el error de humanizar a nuestras mascotas y <strong>hay que tener en cuenta sus evidentes diferencias fision\u00f3micas<\/strong>.<br>- Hay que saber que el peso sobre la columna de los perros no se distribuye igual que en los humanos.<br>- <strong>Los perros son cuadr\u00fapedos<\/strong> y sus articulaciones no est\u00e1n preparadas para ciertas posturas en las que algunas mochilas les obliga a permanecer en posturas que para ellos son totalmente antinaturales.<br>- Adem\u00e1s, ciertas posiciones <strong>pueden sobrecargar sus columnas<\/strong>.<br>- En cachorros pueden ser perjudiciales para la conformaci\u00f3n y desarrollo normal de sus huesos y articulaciones.<\/td><\/tr><\/tbody><\/table><\/figure>\n<!-- \/wp:table -->\n\n<!-- wp:image -->\n<figure class=\"wp-block-image\"><img decoding=\"async\" data-src=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/uploads\/2020\/06\/infografia-posturas-no-recomendadas-2020.jpg\" alt=\"posturas no recomendadas para transportar a un perro\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 800px; --smush-placeholder-aspect-ratio: 800\/1070;\" \/><\/figure>\n<!-- \/wp:image -->\n\n<!-- wp:paragraph -->\n<p>Con esto en mente, repasamos el resto de caracter\u00edsticas.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:heading {\"level\":3,\"style\":{\"color\":{\"background\":\"#eeeeeeed\"}}} -->\n<h3 class=\"has-background\" style=\"background-color:#eeeeeeed\"><span class=\"ez-toc-section\" id=\"2_Relleno_adecuado\"><\/span>2 Relleno adecuado<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>F\u00edjate bien porque si la mochila tiene demasiado grosor a\u00f1adido, podr\u00eda haber una presi\u00f3n adicional en el pecho de tu perro o bien <strong><a rel=\"noreferrer noopener\" aria-label=\"odr\u00eda darle mucho calor (abre en una nueva pesta\u00f1a)\" href=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/evitar-golpe-de-calor-perros-coche\/\" target=\"_blank\">podr\u00eda darle mucho calor<\/a><\/strong>, as\u00ed que comprueba esas zonas para asegurarte de la comodidad de tu perro. Evita los colores oscuros, ya que absorben m\u00e1s calor y aumenta la temperatura.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:heading {\"level\":3,\"style\":{\"color\":{\"background\":\"#eeeeeeed\"}}} -->\n<h3 class=\"has-background\" style=\"background-color:#eeeeeeed\"><span class=\"ez-toc-section\" id=\"3_No_te_fijes_solo_en_el_peso_de_tu_perro_para_elegir_el_tamano_de_la_mochila\"><\/span>3 No te fijes s\u00f3lo en el peso de tu perro para elegir el tama\u00f1o de la mochila<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>Una f\u00f3rmula para calcular el tama\u00f1o que debe tener la mochila es <strong><a aria-label=\"medir alrededor del pecho de tu perro (abre en una nueva pesta\u00f1a)\" href=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/cual-es-la-talla-de-arnes-de-mi-perro\/\" target=\"_blank\" rel=\"noreferrer noopener\">medir alrededor del pecho de tu perro<\/a><\/strong>. Adem\u00e1s de caber, tu perro no debe quedar oprimido y debe poder ponerse de pie en su interior.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph {\"style\":{\"color\":{\"background\":\"#eeeeeeed\"}}} -->\n<p class=\"has-background\" style=\"background-color:#eeeeeeed\">Adem\u00e1s, te recomendamos que eches un vistazo a nuestro art\u00edculo \"<strong><a href=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/como-medir-mascota-para-elegir-transportin\/\">\u00bfC\u00f3mo medir a tu mascota para elegir bien el transport\u00edn?<\/a><\/strong>\"<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:heading {\"level\":3,\"style\":{\"color\":{\"background\":\"#eeeeeeed\"}}} -->\n<h3 class=\"has-background\" style=\"background-color:#eeeeeeed\"><span class=\"ez-toc-section\" id=\"4_Abertura_para_la_cabeza\"><\/span>4 Abertura para la cabeza<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>La bolsa para perros debe tener una ventana o alg\u00fan orificio para que tu perro pueda sacar la cabeza, adem\u00e1s la mochila deber\u00eda tener un clip en el interior para unir con el <a aria-label=\"collar de tu perro (abre en una nueva pesta\u00f1a)\" href=\"https:\/\/www.kiwoko.mom\/perros\/accesorios-para-perros\/paseo\/collares\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>collar de tu perro<\/strong><\/a> y as\u00ed asegurarte de que va en la posici\u00f3n correcta.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:shortcode -->\n        <div id=\"external-products-GOTYFR6026\" class=\"row external-products\">\n            <img decoding=\"async\" id=\"load-products-GOTYFR6026\" data-src=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/themes\/kiwoko\/inc\/assets\/images\/loading.gif\" width=\"50\" height=\"50\" alt=\"loading\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 50px; --smush-placeholder-aspect-ratio: 50\/50;\">\n        <\/div>\n        <script>\n        var id_products = \"GOTYFR6026,GOT42804,GOTYFR6221\";\n        id_products = id_products.replace(\/\\s\/g, '');\n        var all_ids = id_products.split(\",\");\n\n        \/\/ Agregar sufijo _M a todos los c\u00f3digos\n        var all_ids = all_ids.map(function(id) {\n            return id + '_M';\n        });\n\n        var not_found_products = 1;\n        var not_found_img_product = 0;\n        var ramdom_id = Math.round(Math.random() * 10000);\n        var grid = '12';\n\t\tvar width = '220';\n\t\tvar height = '220';\n        if(all_ids.length >= 4){\n            grid = '3';\n\t\t\twidth = '151';\n\t\t\theight = '151';\n        }else if(all_ids.length == 3){\n            grid = '4';\n\t\t\twidth = '211';\n\t\t\theight = '211';\n        }else if(all_ids.length == 2){\n            grid = '6';\n        }\n\t\n\tif(!items){\n        var feed = \"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/themes\/kiwoko\/feed-channable.xml\";\n        var request = new XMLHttpRequest();\n        request.open(\"GET\", feed, false);\n        request.send();\n        var xmlFromUrl = request.responseXML;\n        var parser = new DOMParser();\n        var xmlDoc = parser.parseFromString(feed, \"text\/xml\");\n        var items = xmlFromUrl.getElementsByTagName(\"item\");\n        }\n\n        var products_found = 0;\n        for (var item of items) {\n            all_ids.forEach(function(word, index) {\n                if(item.getElementsByTagName(\"g:item_group_id\")[0].textContent == word){\n                    not_found_products = 0;\n                    id_products = item.getElementsByTagName(\"g:item_group_id\")[0].textContent;\n                    var link = item.getElementsByTagName(\"link\")[0].textContent;\n                    var image_link = 'src=\"'+item.getElementsByTagName(\"g:image_link\")[0].textContent+'\" ';\n                    var title = item.getElementsByTagName(\"title\")[0].textContent;\n\t\t\t\t\tvar customLabel0 = item.getElementsByTagName(\"g:custom_label_0\")[0]?.textContent || '';\n                    var customLabel1 = item.getElementsByTagName(\"g:custom_label_1\")[0]?.textContent || '';\n                    var product = '<div class=\"col-md-'+grid+' text-center ds-analytics-blog-cross-selling-product order-'+index+'\" style=\"cursor:pointer;\" onclick=\"dataLayer.push({'+\n                    '\\'event\\':\\'crosseling_product_click\\', '+\n                    '\\'event_name\\':\\'crosseling_product_click\\', '+\n                    '\\'link_text\\':\\'\u00a1Comprar ahora!\\', '+\n                    '\\'link_url\\':\\''+link+'\\', '+\n                    '\\'category\\':\\''+customLabel0+'\/'+customLabel1+'\\', '+\n                    '\\'product_name\\':\\''+title+'\\''+\n                    '});window.open(\\''+link+'\\');\"><img id=\"'+id_products+'\" '+image_link+' class=\"product-img-shop\" alt=\"'+title+'\"><p><a href=\"'+link+'\" target=\"_blank\" title=\"'+title+'\" style=\"color:#212529;\" class=\"ds-analytics-blog-cross-selling-product\"><strong>'+title+'<\/strong><\/a><\/p><button id=\"product-addtocart-button\" class=\"action primary tocart btn btn--secondary btn--big\" title=\"\u00a1Comprar ahora!\" type=\"submit\">\u00a1Comprar ahora! <\/button><\/div>';\n \t\t\t\t    \/\/var product = '<div class=\"col-md-'+grid+' text-center ds-analytics-blog-cross-selling-product order-'+index+'\" style=\"cursor:pointer;\" onclick=\"dataLayer.push({\\'event\\':\\'blog_cross_selling_product\\', \\'ga4EventData\\': { \\'name\\':\\'d_blog\\', \\'category\\':\\'click\\', \\'label\\':\\'producto\\', \\'element\\': \\''+link+'\\'}});window.open(\\''+link+'\\');\"><img id=\"'+id_products+'\" '+image_link+' class=\"product-img-shop\" alt=\"'+title+'\"><p><a href=\"'+link+'\" target=\"_blank\" title=\"'+title+'\" style=\"color:#212529;\" class=\"ds-analytics-blog-cross-selling-product\"><strong>'+title+'<\/strong><\/a><\/p><button id=\"product-addtocart-button\" class=\"action primary tocart btn btn--secondary btn--big\" title=\"\u00a1Comprar ahora!\" type=\"submit\">\u00a1Comprar ahora! <\/button><\/div>'; \n                    var grid_div = document.getElementById(\"external-products-GOTYFR6026\");\n                    grid_div.innerHTML += product;\n                    products_found++;\n                }\n            });\n            if(products_found == all_ids.length){\n                break;\n            }\n        }\n        document.getElementById(\"load-products-GOTYFR6026\").style.display = \"none\";\n        <\/script>\n    \n<!-- \/wp:shortcode -->\n\n<!-- wp:heading {\"level\":3,\"style\":{\"color\":{\"background\":\"#eeeeeeed\"}}} -->\n<h3 class=\"has-background\" style=\"background-color:#eeeeeeed\"><span class=\"ez-toc-section\" id=\"5_Tomate_tu_tiempo\"><\/span>5 T\u00f3mate tu tiempo<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>No te quedes con la primera que veas, lo ideal es que puedas prob\u00e1rtela y asegurarte de que la mochila se adapta a tus movimientos. Y por supuesto, a los de tu perro.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:heading {\"level\":3,\"style\":{\"color\":{\"background\":\"#eeeeeeed\"}}} -->\n<h3 class=\"has-background\" style=\"background-color:#eeeeeeed\"><span class=\"ez-toc-section\" id=\"6_Revisa_el_fondo_de_la_mochila\"><\/span>6 Revisa el fondo de la mochila<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>El fondo de la bolsa es importante para equilibrar a tu perro. Este debe ser grueso, duro y flexible pero nunca suave.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:heading {\"level\":3,\"style\":{\"color\":{\"background\":\"#eeeeeeed\"}}} -->\n<h3 class=\"has-background\" style=\"background-color:#eeeeeeed\"><span class=\"ez-toc-section\" id=\"7_Consulta_a_tu_veterinario\"><\/span>7 Consulta a tu veterinario<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>Antes de lanzarte a comprar una mochila o transportar a tu mascota directamente en una que ya tengas, pregunta a tu <strong><a style=\"\" href=\"https:\/\/www.kivet.com\/\" target=\"_blank\" rel=\"noreferrer noopener\">veterinario<\/a><\/strong>, sobre todo si tu perro es mayor o tiene problemas de salud.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:heading -->\n<h2><span class=\"ez-toc-section\" id=\"Diferentes_estilos_y_modelos_de_bolsas_de_transporte_para_perros\"><\/span>Diferentes estilos y modelos de bolsas de transporte para perros<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>Ahora que ya sabemos todo lo que hay que tener en cuenta para elegir un modo de transporte y paseo adecuado para nuestro perro, vamos a repasar las diferentes opciones disponibles:<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:heading {\"level\":3} -->\n<h3><span class=\"ez-toc-section\" id=\"Mochilas\"><\/span>Mochilas<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>Si lo que buscas es una mochila de toda la vida, las hay cl\u00e1sicas o frontales. Con correas ajustables, lavables, fondo extra\u00edble, correa para que el perro no se escape\u2026 <strong> \u00a1A una aut\u00e9ntica mochila dise\u00f1ada para perro no le puede faltar ni un detalle!<\/strong><\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:shortcode -->\n        <div id=\"external-products-OUT41090\" class=\"row external-products\">\n            <img decoding=\"async\" id=\"load-products-OUT41090\" data-src=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/themes\/kiwoko\/inc\/assets\/images\/loading.gif\" width=\"50\" height=\"50\" alt=\"loading\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 50px; --smush-placeholder-aspect-ratio: 50\/50;\">\n        <\/div>\n        <script>\n        var id_products = \"OUT41090\";\n        id_products = id_products.replace(\/\\s\/g, '');\n        var all_ids = id_products.split(\",\");\n\n        \/\/ Agregar sufijo _M a todos los c\u00f3digos\n        var all_ids = all_ids.map(function(id) {\n            return id + '_M';\n        });\n\n        var not_found_products = 1;\n        var not_found_img_product = 0;\n        var ramdom_id = Math.round(Math.random() * 10000);\n        var grid = '12';\n\t\tvar width = '220';\n\t\tvar height = '220';\n        if(all_ids.length >= 4){\n            grid = '3';\n\t\t\twidth = '151';\n\t\t\theight = '151';\n        }else if(all_ids.length == 3){\n            grid = '4';\n\t\t\twidth = '211';\n\t\t\theight = '211';\n        }else if(all_ids.length == 2){\n            grid = '6';\n        }\n\t\n\tif(!items){\n        var feed = \"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/themes\/kiwoko\/feed-channable.xml\";\n        var request = new XMLHttpRequest();\n        request.open(\"GET\", feed, false);\n        request.send();\n        var xmlFromUrl = request.responseXML;\n        var parser = new DOMParser();\n        var xmlDoc = parser.parseFromString(feed, \"text\/xml\");\n        var items = xmlFromUrl.getElementsByTagName(\"item\");\n        }\n\n        var products_found = 0;\n        for (var item of items) {\n            all_ids.forEach(function(word, index) {\n                if(item.getElementsByTagName(\"g:item_group_id\")[0].textContent == word){\n                    not_found_products = 0;\n                    id_products = item.getElementsByTagName(\"g:item_group_id\")[0].textContent;\n                    var link = item.getElementsByTagName(\"link\")[0].textContent;\n                    var image_link = 'src=\"'+item.getElementsByTagName(\"g:image_link\")[0].textContent+'\" ';\n                    var title = item.getElementsByTagName(\"title\")[0].textContent;\n\t\t\t\t\tvar customLabel0 = item.getElementsByTagName(\"g:custom_label_0\")[0]?.textContent || '';\n                    var customLabel1 = item.getElementsByTagName(\"g:custom_label_1\")[0]?.textContent || '';\n                    var product = '<div class=\"col-md-'+grid+' text-center ds-analytics-blog-cross-selling-product order-'+index+'\" style=\"cursor:pointer;\" onclick=\"dataLayer.push({'+\n                    '\\'event\\':\\'crosseling_product_click\\', '+\n                    '\\'event_name\\':\\'crosseling_product_click\\', '+\n                    '\\'link_text\\':\\'\u00a1Comprar ahora!\\', '+\n                    '\\'link_url\\':\\''+link+'\\', '+\n                    '\\'category\\':\\''+customLabel0+'\/'+customLabel1+'\\', '+\n                    '\\'product_name\\':\\''+title+'\\''+\n                    '});window.open(\\''+link+'\\');\"><img id=\"'+id_products+'\" '+image_link+' class=\"product-img-shop\" alt=\"'+title+'\"><p><a href=\"'+link+'\" target=\"_blank\" title=\"'+title+'\" style=\"color:#212529;\" class=\"ds-analytics-blog-cross-selling-product\"><strong>'+title+'<\/strong><\/a><\/p><button id=\"product-addtocart-button\" class=\"action primary tocart btn btn--secondary btn--big\" title=\"\u00a1Comprar ahora!\" type=\"submit\">\u00a1Comprar ahora! <\/button><\/div>';\n \t\t\t\t    \/\/var product = '<div class=\"col-md-'+grid+' text-center ds-analytics-blog-cross-selling-product order-'+index+'\" style=\"cursor:pointer;\" onclick=\"dataLayer.push({\\'event\\':\\'blog_cross_selling_product\\', \\'ga4EventData\\': { \\'name\\':\\'d_blog\\', \\'category\\':\\'click\\', \\'label\\':\\'producto\\', \\'element\\': \\''+link+'\\'}});window.open(\\''+link+'\\');\"><img id=\"'+id_products+'\" '+image_link+' class=\"product-img-shop\" alt=\"'+title+'\"><p><a href=\"'+link+'\" target=\"_blank\" title=\"'+title+'\" style=\"color:#212529;\" class=\"ds-analytics-blog-cross-selling-product\"><strong>'+title+'<\/strong><\/a><\/p><button id=\"product-addtocart-button\" class=\"action primary tocart btn btn--secondary btn--big\" title=\"\u00a1Comprar ahora!\" type=\"submit\">\u00a1Comprar ahora! <\/button><\/div>'; \n                    var grid_div = document.getElementById(\"external-products-OUT41090\");\n                    grid_div.innerHTML += product;\n                    products_found++;\n                }\n            });\n            if(products_found == all_ids.length){\n                break;\n            }\n        }\n        document.getElementById(\"load-products-OUT41090\").style.display = \"none\";\n        <\/script>\n    \n<!-- \/wp:shortcode -->\n\n<!-- wp:spacer {\"height\":\"16px\"} -->\n<div style=\"height:16px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<!-- \/wp:spacer -->\n\n<!-- wp:buttons {\"className\":\"text-center\",\"layout\":{\"type\":\"flex\",\"justifyContent\":\"center\"}} -->\n<div class=\"wp-block-buttons text-center\"><!-- wp:button {\"textColor\":\"white\",\"style\":{\"color\":{\"background\":\"#cc292a\"}},\"className\":\"text-center\"} -->\n<div class=\"wp-block-button text-center\"><a class=\"wp-block-button__link has-white-color has-text-color has-background wp-element-button\" href=\"https:\/\/www.kiwoko.mom\/perros\/accesorios-para-perros\/viajes\/mochilas-y-bolsos\/\" style=\"background-color:#cc292a\" target=\"_blank\" rel=\"noreferrer noopener\">Ver todas las mochilas para perros<\/a><\/div>\n<!-- \/wp:button --><\/div>\n<!-- \/wp:buttons -->\n\n<!-- wp:spacer {\"height\":\"16px\"} -->\n<div style=\"height:16px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<!-- \/wp:spacer -->\n\n<!-- wp:heading {\"level\":3} -->\n<h3><span class=\"ez-toc-section\" id=\"Bolsa_de_deporte\"><\/span>Bolsa de deporte<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>Las que son tipo bolsas de deporte para perros est\u00e1n a caballo entre la mochila y el transport\u00edn de mano, es decir, tienen lo mejor de cada cosa. Por supuesto, la forma de la bolsa debe tener la forma adecuada para el transporte de tu perrito. Por lo general cuentan con dos asas peque\u00f1as y una banda m\u00e1s larga por si te la quieres colgar de un hombro, son f\u00e1ciles de desmontar y lavar, y algunas hasta tienen <strong>doble funcionalidad<\/strong>:<strong> transportar y cama de viaje<\/strong>.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:shortcode -->\n        <div id=\"external-products-OUT70887\" class=\"row external-products\">\n            <img decoding=\"async\" id=\"load-products-OUT70887\" data-src=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/themes\/kiwoko\/inc\/assets\/images\/loading.gif\" width=\"50\" height=\"50\" alt=\"loading\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 50px; --smush-placeholder-aspect-ratio: 50\/50;\">\n        <\/div>\n        <script>\n        var id_products = \"OUT70887\";\n        id_products = id_products.replace(\/\\s\/g, '');\n        var all_ids = id_products.split(\",\");\n\n        \/\/ Agregar sufijo _M a todos los c\u00f3digos\n        var all_ids = all_ids.map(function(id) {\n            return id + '_M';\n        });\n\n        var not_found_products = 1;\n        var not_found_img_product = 0;\n        var ramdom_id = Math.round(Math.random() * 10000);\n        var grid = '12';\n\t\tvar width = '220';\n\t\tvar height = '220';\n        if(all_ids.length >= 4){\n            grid = '3';\n\t\t\twidth = '151';\n\t\t\theight = '151';\n        }else if(all_ids.length == 3){\n            grid = '4';\n\t\t\twidth = '211';\n\t\t\theight = '211';\n        }else if(all_ids.length == 2){\n            grid = '6';\n        }\n\t\n\tif(!items){\n        var feed = \"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/themes\/kiwoko\/feed-channable.xml\";\n        var request = new XMLHttpRequest();\n        request.open(\"GET\", feed, false);\n        request.send();\n        var xmlFromUrl = request.responseXML;\n        var parser = new DOMParser();\n        var xmlDoc = parser.parseFromString(feed, \"text\/xml\");\n        var items = xmlFromUrl.getElementsByTagName(\"item\");\n        }\n\n        var products_found = 0;\n        for (var item of items) {\n            all_ids.forEach(function(word, index) {\n                if(item.getElementsByTagName(\"g:item_group_id\")[0].textContent == word){\n                    not_found_products = 0;\n                    id_products = item.getElementsByTagName(\"g:item_group_id\")[0].textContent;\n                    var link = item.getElementsByTagName(\"link\")[0].textContent;\n                    var image_link = 'src=\"'+item.getElementsByTagName(\"g:image_link\")[0].textContent+'\" ';\n                    var title = item.getElementsByTagName(\"title\")[0].textContent;\n\t\t\t\t\tvar customLabel0 = item.getElementsByTagName(\"g:custom_label_0\")[0]?.textContent || '';\n                    var customLabel1 = item.getElementsByTagName(\"g:custom_label_1\")[0]?.textContent || '';\n                    var product = '<div class=\"col-md-'+grid+' text-center ds-analytics-blog-cross-selling-product order-'+index+'\" style=\"cursor:pointer;\" onclick=\"dataLayer.push({'+\n                    '\\'event\\':\\'crosseling_product_click\\', '+\n                    '\\'event_name\\':\\'crosseling_product_click\\', '+\n                    '\\'link_text\\':\\'\u00a1Comprar ahora!\\', '+\n                    '\\'link_url\\':\\''+link+'\\', '+\n                    '\\'category\\':\\''+customLabel0+'\/'+customLabel1+'\\', '+\n                    '\\'product_name\\':\\''+title+'\\''+\n                    '});window.open(\\''+link+'\\');\"><img id=\"'+id_products+'\" '+image_link+' class=\"product-img-shop\" alt=\"'+title+'\"><p><a href=\"'+link+'\" target=\"_blank\" title=\"'+title+'\" style=\"color:#212529;\" class=\"ds-analytics-blog-cross-selling-product\"><strong>'+title+'<\/strong><\/a><\/p><button id=\"product-addtocart-button\" class=\"action primary tocart btn btn--secondary btn--big\" title=\"\u00a1Comprar ahora!\" type=\"submit\">\u00a1Comprar ahora! <\/button><\/div>';\n \t\t\t\t    \/\/var product = '<div class=\"col-md-'+grid+' text-center ds-analytics-blog-cross-selling-product order-'+index+'\" style=\"cursor:pointer;\" onclick=\"dataLayer.push({\\'event\\':\\'blog_cross_selling_product\\', \\'ga4EventData\\': { \\'name\\':\\'d_blog\\', \\'category\\':\\'click\\', \\'label\\':\\'producto\\', \\'element\\': \\''+link+'\\'}});window.open(\\''+link+'\\');\"><img id=\"'+id_products+'\" '+image_link+' class=\"product-img-shop\" alt=\"'+title+'\"><p><a href=\"'+link+'\" target=\"_blank\" title=\"'+title+'\" style=\"color:#212529;\" class=\"ds-analytics-blog-cross-selling-product\"><strong>'+title+'<\/strong><\/a><\/p><button id=\"product-addtocart-button\" class=\"action primary tocart btn btn--secondary btn--big\" title=\"\u00a1Comprar ahora!\" type=\"submit\">\u00a1Comprar ahora! <\/button><\/div>'; \n                    var grid_div = document.getElementById(\"external-products-OUT70887\");\n                    grid_div.innerHTML += product;\n                    products_found++;\n                }\n            });\n            if(products_found == all_ids.length){\n                break;\n            }\n        }\n        document.getElementById(\"load-products-OUT70887\").style.display = \"none\";\n        <\/script>\n    \n<!-- \/wp:shortcode -->\n\n<!-- wp:heading {\"level\":3} -->\n<h3><span class=\"ez-toc-section\" id=\"Trolley\"><\/span>Trolley<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>Si tu perro no es tan peque\u00f1o como para que aguantes su peso o t\u00fa no aguantas mucho el peso, la soluci\u00f3n ser\u00e1 <strong>llevarlo sobre ruedas<\/strong>. Para eso est\u00e1n las mochilas tipo trolley. Te las puedes colgar como mochila y por tramos puedes sacar los ruedines e ir m\u00e1s c\u00f3modamente.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:shortcode -->\n        <div id=\"external-products-ARP31375\" class=\"row external-products\">\n            <img decoding=\"async\" id=\"load-products-ARP31375\" data-src=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/themes\/kiwoko\/inc\/assets\/images\/loading.gif\" width=\"50\" height=\"50\" alt=\"loading\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 50px; --smush-placeholder-aspect-ratio: 50\/50;\">\n        <\/div>\n        <script>\n        var id_products = \"ARP31375\";\n        id_products = id_products.replace(\/\\s\/g, '');\n        var all_ids = id_products.split(\",\");\n\n        \/\/ Agregar sufijo _M a todos los c\u00f3digos\n        var all_ids = all_ids.map(function(id) {\n            return id + '_M';\n        });\n\n        var not_found_products = 1;\n        var not_found_img_product = 0;\n        var ramdom_id = Math.round(Math.random() * 10000);\n        var grid = '12';\n\t\tvar width = '220';\n\t\tvar height = '220';\n        if(all_ids.length >= 4){\n            grid = '3';\n\t\t\twidth = '151';\n\t\t\theight = '151';\n        }else if(all_ids.length == 3){\n            grid = '4';\n\t\t\twidth = '211';\n\t\t\theight = '211';\n        }else if(all_ids.length == 2){\n            grid = '6';\n        }\n\t\n\tif(!items){\n        var feed = \"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/themes\/kiwoko\/feed-channable.xml\";\n        var request = new XMLHttpRequest();\n        request.open(\"GET\", feed, false);\n        request.send();\n        var xmlFromUrl = request.responseXML;\n        var parser = new DOMParser();\n        var xmlDoc = parser.parseFromString(feed, \"text\/xml\");\n        var items = xmlFromUrl.getElementsByTagName(\"item\");\n        }\n\n        var products_found = 0;\n        for (var item of items) {\n            all_ids.forEach(function(word, index) {\n                if(item.getElementsByTagName(\"g:item_group_id\")[0].textContent == word){\n                    not_found_products = 0;\n                    id_products = item.getElementsByTagName(\"g:item_group_id\")[0].textContent;\n                    var link = item.getElementsByTagName(\"link\")[0].textContent;\n                    var image_link = 'src=\"'+item.getElementsByTagName(\"g:image_link\")[0].textContent+'\" ';\n                    var title = item.getElementsByTagName(\"title\")[0].textContent;\n\t\t\t\t\tvar customLabel0 = item.getElementsByTagName(\"g:custom_label_0\")[0]?.textContent || '';\n                    var customLabel1 = item.getElementsByTagName(\"g:custom_label_1\")[0]?.textContent || '';\n                    var product = '<div class=\"col-md-'+grid+' text-center ds-analytics-blog-cross-selling-product order-'+index+'\" style=\"cursor:pointer;\" onclick=\"dataLayer.push({'+\n                    '\\'event\\':\\'crosseling_product_click\\', '+\n                    '\\'event_name\\':\\'crosseling_product_click\\', '+\n                    '\\'link_text\\':\\'\u00a1Comprar ahora!\\', '+\n                    '\\'link_url\\':\\''+link+'\\', '+\n                    '\\'category\\':\\''+customLabel0+'\/'+customLabel1+'\\', '+\n                    '\\'product_name\\':\\''+title+'\\''+\n                    '});window.open(\\''+link+'\\');\"><img id=\"'+id_products+'\" '+image_link+' class=\"product-img-shop\" alt=\"'+title+'\"><p><a href=\"'+link+'\" target=\"_blank\" title=\"'+title+'\" style=\"color:#212529;\" class=\"ds-analytics-blog-cross-selling-product\"><strong>'+title+'<\/strong><\/a><\/p><button id=\"product-addtocart-button\" class=\"action primary tocart btn btn--secondary btn--big\" title=\"\u00a1Comprar ahora!\" type=\"submit\">\u00a1Comprar ahora! <\/button><\/div>';\n \t\t\t\t    \/\/var product = '<div class=\"col-md-'+grid+' text-center ds-analytics-blog-cross-selling-product order-'+index+'\" style=\"cursor:pointer;\" onclick=\"dataLayer.push({\\'event\\':\\'blog_cross_selling_product\\', \\'ga4EventData\\': { \\'name\\':\\'d_blog\\', \\'category\\':\\'click\\', \\'label\\':\\'producto\\', \\'element\\': \\''+link+'\\'}});window.open(\\''+link+'\\');\"><img id=\"'+id_products+'\" '+image_link+' class=\"product-img-shop\" alt=\"'+title+'\"><p><a href=\"'+link+'\" target=\"_blank\" title=\"'+title+'\" style=\"color:#212529;\" class=\"ds-analytics-blog-cross-selling-product\"><strong>'+title+'<\/strong><\/a><\/p><button id=\"product-addtocart-button\" class=\"action primary tocart btn btn--secondary btn--big\" title=\"\u00a1Comprar ahora!\" type=\"submit\">\u00a1Comprar ahora! <\/button><\/div>'; \n                    var grid_div = document.getElementById(\"external-products-ARP31375\");\n                    grid_div.innerHTML += product;\n                    products_found++;\n                }\n            });\n            if(products_found == all_ids.length){\n                break;\n            }\n        }\n        document.getElementById(\"load-products-ARP31375\").style.display = \"none\";\n        <\/script>\n    \n<!-- \/wp:shortcode -->\n\n<!-- wp:heading -->\n<h2><span class=\"ez-toc-section\" id=\"Tipos_de_transportines_para_perros\"><\/span>Tipos de transportines para perros<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>En cuanto a los transportines hay un mundo m\u00e1s all\u00e1 de lo que t\u00fa tienes en la cabeza. \u00bfNo te lo crees? \u00a1Echa un vistazo a todos los<strong> tipos de transportines<\/strong> que hay!<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:list {\"ordered\":true} -->\n<ol><!-- wp:list-item -->\n<li>Modelo b\u00e1sico<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>Transport\u00edn tipo bolso<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>Plegable<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>Modelo avanzado para coches<\/li>\n<!-- \/wp:list-item --><\/ol>\n<!-- \/wp:list -->\n\n<!-- wp:spacer {\"height\":\"16px\"} -->\n<div style=\"height:16px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<!-- \/wp:spacer -->\n\n<!-- wp:buttons {\"className\":\"text-center\",\"layout\":{\"type\":\"flex\",\"justifyContent\":\"center\"}} -->\n<div class=\"wp-block-buttons text-center\"><!-- wp:button {\"textColor\":\"white\",\"style\":{\"color\":{\"background\":\"#cc292a\"}},\"className\":\"text-center\"} -->\n<div class=\"wp-block-button text-center\"><a class=\"wp-block-button__link has-white-color has-text-color has-background wp-element-button\" href=\"https:\/\/www.kiwoko.mom\/perros\/accesorios-para-perros\/viajes\/transportin\/\" style=\"background-color:#cc292a\" target=\"_blank\" rel=\"noreferrer noopener\">Ver todos los transportines para perros<\/a><\/div>\n<!-- \/wp:button --><\/div>\n<!-- \/wp:buttons -->\n\n<!-- wp:spacer {\"height\":\"16px\"} -->\n<div style=\"height:16px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<!-- \/wp:spacer -->\n\n<!-- wp:heading {\"level\":3} -->\n<h3><span class=\"ez-toc-section\" id=\"1_Modelo_basico\"><\/span>1 Modelo b\u00e1sico<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>Los has visto un mill\u00f3n de veces, son r\u00edgidos y los tienes de muchos colores. Con aperturas laterales y frontales para evitar la sensaci\u00f3n de encierro.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:shortcode -->\n        <div id=\"external-products-OUT00277\" class=\"row external-products\">\n            <img decoding=\"async\" id=\"load-products-OUT00277\" data-src=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/themes\/kiwoko\/inc\/assets\/images\/loading.gif\" width=\"50\" height=\"50\" alt=\"loading\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 50px; --smush-placeholder-aspect-ratio: 50\/50;\">\n        <\/div>\n        <script>\n        var id_products = \"OUT00277\";\n        id_products = id_products.replace(\/\\s\/g, '');\n        var all_ids = id_products.split(\",\");\n\n        \/\/ Agregar sufijo _M a todos los c\u00f3digos\n        var all_ids = all_ids.map(function(id) {\n            return id + '_M';\n        });\n\n        var not_found_products = 1;\n        var not_found_img_product = 0;\n        var ramdom_id = Math.round(Math.random() * 10000);\n        var grid = '12';\n\t\tvar width = '220';\n\t\tvar height = '220';\n        if(all_ids.length >= 4){\n            grid = '3';\n\t\t\twidth = '151';\n\t\t\theight = '151';\n        }else if(all_ids.length == 3){\n            grid = '4';\n\t\t\twidth = '211';\n\t\t\theight = '211';\n        }else if(all_ids.length == 2){\n            grid = '6';\n        }\n\t\n\tif(!items){\n        var feed = \"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/themes\/kiwoko\/feed-channable.xml\";\n        var request = new XMLHttpRequest();\n        request.open(\"GET\", feed, false);\n        request.send();\n        var xmlFromUrl = request.responseXML;\n        var parser = new DOMParser();\n        var xmlDoc = parser.parseFromString(feed, \"text\/xml\");\n        var items = xmlFromUrl.getElementsByTagName(\"item\");\n        }\n\n        var products_found = 0;\n        for (var item of items) {\n            all_ids.forEach(function(word, index) {\n                if(item.getElementsByTagName(\"g:item_group_id\")[0].textContent == word){\n                    not_found_products = 0;\n                    id_products = item.getElementsByTagName(\"g:item_group_id\")[0].textContent;\n                    var link = item.getElementsByTagName(\"link\")[0].textContent;\n                    var image_link = 'src=\"'+item.getElementsByTagName(\"g:image_link\")[0].textContent+'\" ';\n                    var title = item.getElementsByTagName(\"title\")[0].textContent;\n\t\t\t\t\tvar customLabel0 = item.getElementsByTagName(\"g:custom_label_0\")[0]?.textContent || '';\n                    var customLabel1 = item.getElementsByTagName(\"g:custom_label_1\")[0]?.textContent || '';\n                    var product = '<div class=\"col-md-'+grid+' text-center ds-analytics-blog-cross-selling-product order-'+index+'\" style=\"cursor:pointer;\" onclick=\"dataLayer.push({'+\n                    '\\'event\\':\\'crosseling_product_click\\', '+\n                    '\\'event_name\\':\\'crosseling_product_click\\', '+\n                    '\\'link_text\\':\\'\u00a1Comprar ahora!\\', '+\n                    '\\'link_url\\':\\''+link+'\\', '+\n                    '\\'category\\':\\''+customLabel0+'\/'+customLabel1+'\\', '+\n                    '\\'product_name\\':\\''+title+'\\''+\n                    '});window.open(\\''+link+'\\');\"><img id=\"'+id_products+'\" '+image_link+' class=\"product-img-shop\" alt=\"'+title+'\"><p><a href=\"'+link+'\" target=\"_blank\" title=\"'+title+'\" style=\"color:#212529;\" class=\"ds-analytics-blog-cross-selling-product\"><strong>'+title+'<\/strong><\/a><\/p><button id=\"product-addtocart-button\" class=\"action primary tocart btn btn--secondary btn--big\" title=\"\u00a1Comprar ahora!\" type=\"submit\">\u00a1Comprar ahora! <\/button><\/div>';\n \t\t\t\t    \/\/var product = '<div class=\"col-md-'+grid+' text-center ds-analytics-blog-cross-selling-product order-'+index+'\" style=\"cursor:pointer;\" onclick=\"dataLayer.push({\\'event\\':\\'blog_cross_selling_product\\', \\'ga4EventData\\': { \\'name\\':\\'d_blog\\', \\'category\\':\\'click\\', \\'label\\':\\'producto\\', \\'element\\': \\''+link+'\\'}});window.open(\\''+link+'\\');\"><img id=\"'+id_products+'\" '+image_link+' class=\"product-img-shop\" alt=\"'+title+'\"><p><a href=\"'+link+'\" target=\"_blank\" title=\"'+title+'\" style=\"color:#212529;\" class=\"ds-analytics-blog-cross-selling-product\"><strong>'+title+'<\/strong><\/a><\/p><button id=\"product-addtocart-button\" class=\"action primary tocart btn btn--secondary btn--big\" title=\"\u00a1Comprar ahora!\" type=\"submit\">\u00a1Comprar ahora! <\/button><\/div>'; \n                    var grid_div = document.getElementById(\"external-products-OUT00277\");\n                    grid_div.innerHTML += product;\n                    products_found++;\n                }\n            });\n            if(products_found == all_ids.length){\n                break;\n            }\n        }\n        document.getElementById(\"load-products-OUT00277\").style.display = \"none\";\n        <\/script>\n    \n<!-- \/wp:shortcode -->\n\n<!-- wp:heading {\"level\":3} -->\n<h3><span class=\"ez-toc-section\" id=\"2_Transportin_tipo_bolso\"><\/span>2 Transport\u00edn tipo bolso<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>Si buscas la comodidad de un bolso, los hay dise\u00f1ados espec\u00edficamente para perros, tambi\u00e9n en varios colores y con varios acabados (r\u00edgidos o flexibles) \u00a1T\u00fa decides!<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:shortcode -->\n        <div id=\"external-products-OUT70886\" class=\"row external-products\">\n            <img decoding=\"async\" id=\"load-products-OUT70886\" data-src=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/themes\/kiwoko\/inc\/assets\/images\/loading.gif\" width=\"50\" height=\"50\" alt=\"loading\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 50px; --smush-placeholder-aspect-ratio: 50\/50;\">\n        <\/div>\n        <script>\n        var id_products = \"OUT70886\";\n        id_products = id_products.replace(\/\\s\/g, '');\n        var all_ids = id_products.split(\",\");\n\n        \/\/ Agregar sufijo _M a todos los c\u00f3digos\n        var all_ids = all_ids.map(function(id) {\n            return id + '_M';\n        });\n\n        var not_found_products = 1;\n        var not_found_img_product = 0;\n        var ramdom_id = Math.round(Math.random() * 10000);\n        var grid = '12';\n\t\tvar width = '220';\n\t\tvar height = '220';\n        if(all_ids.length >= 4){\n            grid = '3';\n\t\t\twidth = '151';\n\t\t\theight = '151';\n        }else if(all_ids.length == 3){\n            grid = '4';\n\t\t\twidth = '211';\n\t\t\theight = '211';\n        }else if(all_ids.length == 2){\n            grid = '6';\n        }\n\t\n\tif(!items){\n        var feed = \"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/themes\/kiwoko\/feed-channable.xml\";\n        var request = new XMLHttpRequest();\n        request.open(\"GET\", feed, false);\n        request.send();\n        var xmlFromUrl = request.responseXML;\n        var parser = new DOMParser();\n        var xmlDoc = parser.parseFromString(feed, \"text\/xml\");\n        var items = xmlFromUrl.getElementsByTagName(\"item\");\n        }\n\n        var products_found = 0;\n        for (var item of items) {\n            all_ids.forEach(function(word, index) {\n                if(item.getElementsByTagName(\"g:item_group_id\")[0].textContent == word){\n                    not_found_products = 0;\n                    id_products = item.getElementsByTagName(\"g:item_group_id\")[0].textContent;\n                    var link = item.getElementsByTagName(\"link\")[0].textContent;\n                    var image_link = 'src=\"'+item.getElementsByTagName(\"g:image_link\")[0].textContent+'\" ';\n                    var title = item.getElementsByTagName(\"title\")[0].textContent;\n\t\t\t\t\tvar customLabel0 = item.getElementsByTagName(\"g:custom_label_0\")[0]?.textContent || '';\n                    var customLabel1 = item.getElementsByTagName(\"g:custom_label_1\")[0]?.textContent || '';\n                    var product = '<div class=\"col-md-'+grid+' text-center ds-analytics-blog-cross-selling-product order-'+index+'\" style=\"cursor:pointer;\" onclick=\"dataLayer.push({'+\n                    '\\'event\\':\\'crosseling_product_click\\', '+\n                    '\\'event_name\\':\\'crosseling_product_click\\', '+\n                    '\\'link_text\\':\\'\u00a1Comprar ahora!\\', '+\n                    '\\'link_url\\':\\''+link+'\\', '+\n                    '\\'category\\':\\''+customLabel0+'\/'+customLabel1+'\\', '+\n                    '\\'product_name\\':\\''+title+'\\''+\n                    '});window.open(\\''+link+'\\');\"><img id=\"'+id_products+'\" '+image_link+' class=\"product-img-shop\" alt=\"'+title+'\"><p><a href=\"'+link+'\" target=\"_blank\" title=\"'+title+'\" style=\"color:#212529;\" class=\"ds-analytics-blog-cross-selling-product\"><strong>'+title+'<\/strong><\/a><\/p><button id=\"product-addtocart-button\" class=\"action primary tocart btn btn--secondary btn--big\" title=\"\u00a1Comprar ahora!\" type=\"submit\">\u00a1Comprar ahora! <\/button><\/div>';\n \t\t\t\t    \/\/var product = '<div class=\"col-md-'+grid+' text-center ds-analytics-blog-cross-selling-product order-'+index+'\" style=\"cursor:pointer;\" onclick=\"dataLayer.push({\\'event\\':\\'blog_cross_selling_product\\', \\'ga4EventData\\': { \\'name\\':\\'d_blog\\', \\'category\\':\\'click\\', \\'label\\':\\'producto\\', \\'element\\': \\''+link+'\\'}});window.open(\\''+link+'\\');\"><img id=\"'+id_products+'\" '+image_link+' class=\"product-img-shop\" alt=\"'+title+'\"><p><a href=\"'+link+'\" target=\"_blank\" title=\"'+title+'\" style=\"color:#212529;\" class=\"ds-analytics-blog-cross-selling-product\"><strong>'+title+'<\/strong><\/a><\/p><button id=\"product-addtocart-button\" class=\"action primary tocart btn btn--secondary btn--big\" title=\"\u00a1Comprar ahora!\" type=\"submit\">\u00a1Comprar ahora! <\/button><\/div>'; \n                    var grid_div = document.getElementById(\"external-products-OUT70886\");\n                    grid_div.innerHTML += product;\n                    products_found++;\n                }\n            });\n            if(products_found == all_ids.length){\n                break;\n            }\n        }\n        document.getElementById(\"load-products-OUT70886\").style.display = \"none\";\n        <\/script>\n    \n<!-- \/wp:shortcode -->\n\n<!-- wp:heading {\"level\":3} -->\n<h3><span class=\"ez-toc-section\" id=\"3_Plegable\"><\/span>3 Plegable<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>Otra opci\u00f3n muy c\u00f3moda es la de llevar un transport\u00edn durante el viaje y de tener una caseta una vez llegues a tu destino.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:heading {\"level\":3} -->\n<h3><span class=\"ez-toc-section\" id=\"4_Modelo_avanzado_para_coche\"><\/span>4 Modelo avanzado para coche<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>Para los <strong><a style=\"\" href=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/viaja-de-forma-segura-en-el-coche-con-tu-mascota\/\" target=\"_blank\" rel=\"noreferrer noopener\">viajes en coche<\/a><\/strong> tambi\u00e9n hay transportines especialmente dise\u00f1ados para tu veh\u00edculo y <a aria-label=\"accesorios para el coche (abre en una nueva pesta\u00f1a)\" href=\"https:\/\/www.kiwoko.mom\/perros\/accesorios-para-perros\/viajes\/para-el-coche\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>accesorios para el coche<\/strong><\/a> que har\u00e1n que el viaje sea m\u00e1s c\u00f3modo.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:shortcode -->\n        <div id=\"external-products-OUT41088\" class=\"row external-products\">\n            <img decoding=\"async\" id=\"load-products-OUT41088\" data-src=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/themes\/kiwoko\/inc\/assets\/images\/loading.gif\" width=\"50\" height=\"50\" alt=\"loading\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 50px; --smush-placeholder-aspect-ratio: 50\/50;\">\n        <\/div>\n        <script>\n        var id_products = \"OUT41088\";\n        id_products = id_products.replace(\/\\s\/g, '');\n        var all_ids = id_products.split(\",\");\n\n        \/\/ Agregar sufijo _M a todos los c\u00f3digos\n        var all_ids = all_ids.map(function(id) {\n            return id + '_M';\n        });\n\n        var not_found_products = 1;\n        var not_found_img_product = 0;\n        var ramdom_id = Math.round(Math.random() * 10000);\n        var grid = '12';\n\t\tvar width = '220';\n\t\tvar height = '220';\n        if(all_ids.length >= 4){\n            grid = '3';\n\t\t\twidth = '151';\n\t\t\theight = '151';\n        }else if(all_ids.length == 3){\n            grid = '4';\n\t\t\twidth = '211';\n\t\t\theight = '211';\n        }else if(all_ids.length == 2){\n            grid = '6';\n        }\n\t\n\tif(!items){\n        var feed = \"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/themes\/kiwoko\/feed-channable.xml\";\n        var request = new XMLHttpRequest();\n        request.open(\"GET\", feed, false);\n        request.send();\n        var xmlFromUrl = request.responseXML;\n        var parser = new DOMParser();\n        var xmlDoc = parser.parseFromString(feed, \"text\/xml\");\n        var items = xmlFromUrl.getElementsByTagName(\"item\");\n        }\n\n        var products_found = 0;\n        for (var item of items) {\n            all_ids.forEach(function(word, index) {\n                if(item.getElementsByTagName(\"g:item_group_id\")[0].textContent == word){\n                    not_found_products = 0;\n                    id_products = item.getElementsByTagName(\"g:item_group_id\")[0].textContent;\n                    var link = item.getElementsByTagName(\"link\")[0].textContent;\n                    var image_link = 'src=\"'+item.getElementsByTagName(\"g:image_link\")[0].textContent+'\" ';\n                    var title = item.getElementsByTagName(\"title\")[0].textContent;\n\t\t\t\t\tvar customLabel0 = item.getElementsByTagName(\"g:custom_label_0\")[0]?.textContent || '';\n                    var customLabel1 = item.getElementsByTagName(\"g:custom_label_1\")[0]?.textContent || '';\n                    var product = '<div class=\"col-md-'+grid+' text-center ds-analytics-blog-cross-selling-product order-'+index+'\" style=\"cursor:pointer;\" onclick=\"dataLayer.push({'+\n                    '\\'event\\':\\'crosseling_product_click\\', '+\n                    '\\'event_name\\':\\'crosseling_product_click\\', '+\n                    '\\'link_text\\':\\'\u00a1Comprar ahora!\\', '+\n                    '\\'link_url\\':\\''+link+'\\', '+\n                    '\\'category\\':\\''+customLabel0+'\/'+customLabel1+'\\', '+\n                    '\\'product_name\\':\\''+title+'\\''+\n                    '});window.open(\\''+link+'\\');\"><img id=\"'+id_products+'\" '+image_link+' class=\"product-img-shop\" alt=\"'+title+'\"><p><a href=\"'+link+'\" target=\"_blank\" title=\"'+title+'\" style=\"color:#212529;\" class=\"ds-analytics-blog-cross-selling-product\"><strong>'+title+'<\/strong><\/a><\/p><button id=\"product-addtocart-button\" class=\"action primary tocart btn btn--secondary btn--big\" title=\"\u00a1Comprar ahora!\" type=\"submit\">\u00a1Comprar ahora! <\/button><\/div>';\n \t\t\t\t    \/\/var product = '<div class=\"col-md-'+grid+' text-center ds-analytics-blog-cross-selling-product order-'+index+'\" style=\"cursor:pointer;\" onclick=\"dataLayer.push({\\'event\\':\\'blog_cross_selling_product\\', \\'ga4EventData\\': { \\'name\\':\\'d_blog\\', \\'category\\':\\'click\\', \\'label\\':\\'producto\\', \\'element\\': \\''+link+'\\'}});window.open(\\''+link+'\\');\"><img id=\"'+id_products+'\" '+image_link+' class=\"product-img-shop\" alt=\"'+title+'\"><p><a href=\"'+link+'\" target=\"_blank\" title=\"'+title+'\" style=\"color:#212529;\" class=\"ds-analytics-blog-cross-selling-product\"><strong>'+title+'<\/strong><\/a><\/p><button id=\"product-addtocart-button\" class=\"action primary tocart btn btn--secondary btn--big\" title=\"\u00a1Comprar ahora!\" type=\"submit\">\u00a1Comprar ahora! <\/button><\/div>'; \n                    var grid_div = document.getElementById(\"external-products-OUT41088\");\n                    grid_div.innerHTML += product;\n                    products_found++;\n                }\n            });\n            if(products_found == all_ids.length){\n                break;\n            }\n        }\n        document.getElementById(\"load-products-OUT41088\").style.display = \"none\";\n        <\/script>\n    \n<!-- \/wp:shortcode -->\n\n<!-- wp:heading {\"level\":3} -->\n<h3><span class=\"ez-toc-section\" id=\"5_Transportines_homologados_IATA\"><\/span>5 Transportines homologados IATA<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>Si decides coger un avi\u00f3n tienes que <strong>asegurarte de cumplir con las medidas cumpliendo con la normativa<\/strong> vigente.  Las caracter\u00edsticas de estos transportines son:<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:list {\"ordered\":true} -->\n<ol><!-- wp:list-item -->\n<li>El animal tendr\u00e1 espacio para girar sobre s\u00ed mismo.<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>Puede estar sentado con la cabeza erguida.<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>Puede levantarse y tener una posici\u00f3n normal.<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>El interior del transport\u00edn debe ser impermeable<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>El exterior debe de ser s\u00f3lido.<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>El transport\u00edn debe tener sistema de ventilaci\u00f3n y transpiraci\u00f3n.<\/li>\n<!-- \/wp:list-item --><\/ol>\n<!-- \/wp:list -->\n\n<!-- wp:paragraph {\"style\":{\"color\":{\"background\":\"#eeeeeeed\"}}} -->\n<p class=\"has-background\" style=\"background-color:#eeeeeeed\">Adem\u00e1s, puedes leer nuestros art\u00edculos \"<strong><a href=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/viajar-perro-avion\/\">Viajar con perro en avi\u00f3n<\/a><\/strong>\", \"<strong><a href=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/viajar-en-barco-con-perro\/\">Viajar en barco con perro: nuestros consejos<\/a><\/strong>\" y \"<a href=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/normas-para-viajar-con-tu-perro-en-tren\/\"><strong>Normas para viajar con tu perro en tren<\/strong><\/a>\" para m\u00e1s informaci\u00f3n.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Tanto sea en coche o en avi\u00f3n puedes recurrir a las feromonas <strong><a href=\"https:\/\/www.kiwoko.mom\/perros\/higiene-para-perros\/salud-del-perro\/antiestres\/\" target=\"_blank\" rel=\"noopener\" title=\"\">antiestr\u00e9s para perros<\/a><\/strong> que ayudar\u00e1n a que tu compa\u00f1ero vaya tranquilo durante el viaje. Este producto es una copia sint\u00e9tica de la feromona canina del apaciguamiento. Una hormona que existe en la naturaleza producida por la madre para tranquilizar a sus cachorros.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:shortcode -->\n        <div id=\"external-products-CEVC66420F\" class=\"row external-products\">\n            <img decoding=\"async\" id=\"load-products-CEVC66420F\" data-src=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/themes\/kiwoko\/inc\/assets\/images\/loading.gif\" width=\"50\" height=\"50\" alt=\"loading\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 50px; --smush-placeholder-aspect-ratio: 50\/50;\">\n        <\/div>\n        <script>\n        var id_products = \"CEVC66420F\";\n        id_products = id_products.replace(\/\\s\/g, '');\n        var all_ids = id_products.split(\",\");\n\n        \/\/ Agregar sufijo _M a todos los c\u00f3digos\n        var all_ids = all_ids.map(function(id) {\n            return id + '_M';\n        });\n\n        var not_found_products = 1;\n        var not_found_img_product = 0;\n        var ramdom_id = Math.round(Math.random() * 10000);\n        var grid = '12';\n\t\tvar width = '220';\n\t\tvar height = '220';\n        if(all_ids.length >= 4){\n            grid = '3';\n\t\t\twidth = '151';\n\t\t\theight = '151';\n        }else if(all_ids.length == 3){\n            grid = '4';\n\t\t\twidth = '211';\n\t\t\theight = '211';\n        }else if(all_ids.length == 2){\n            grid = '6';\n        }\n\t\n\tif(!items){\n        var feed = \"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/themes\/kiwoko\/feed-channable.xml\";\n        var request = new XMLHttpRequest();\n        request.open(\"GET\", feed, false);\n        request.send();\n        var xmlFromUrl = request.responseXML;\n        var parser = new DOMParser();\n        var xmlDoc = parser.parseFromString(feed, \"text\/xml\");\n        var items = xmlFromUrl.getElementsByTagName(\"item\");\n        }\n\n        var products_found = 0;\n        for (var item of items) {\n            all_ids.forEach(function(word, index) {\n                if(item.getElementsByTagName(\"g:item_group_id\")[0].textContent == word){\n                    not_found_products = 0;\n                    id_products = item.getElementsByTagName(\"g:item_group_id\")[0].textContent;\n                    var link = item.getElementsByTagName(\"link\")[0].textContent;\n                    var image_link = 'src=\"'+item.getElementsByTagName(\"g:image_link\")[0].textContent+'\" ';\n                    var title = item.getElementsByTagName(\"title\")[0].textContent;\n\t\t\t\t\tvar customLabel0 = item.getElementsByTagName(\"g:custom_label_0\")[0]?.textContent || '';\n                    var customLabel1 = item.getElementsByTagName(\"g:custom_label_1\")[0]?.textContent || '';\n                    var product = '<div class=\"col-md-'+grid+' text-center ds-analytics-blog-cross-selling-product order-'+index+'\" style=\"cursor:pointer;\" onclick=\"dataLayer.push({'+\n                    '\\'event\\':\\'crosseling_product_click\\', '+\n                    '\\'event_name\\':\\'crosseling_product_click\\', '+\n                    '\\'link_text\\':\\'\u00a1Comprar ahora!\\', '+\n                    '\\'link_url\\':\\''+link+'\\', '+\n                    '\\'category\\':\\''+customLabel0+'\/'+customLabel1+'\\', '+\n                    '\\'product_name\\':\\''+title+'\\''+\n                    '});window.open(\\''+link+'\\');\"><img id=\"'+id_products+'\" '+image_link+' class=\"product-img-shop\" alt=\"'+title+'\"><p><a href=\"'+link+'\" target=\"_blank\" title=\"'+title+'\" style=\"color:#212529;\" class=\"ds-analytics-blog-cross-selling-product\"><strong>'+title+'<\/strong><\/a><\/p><button id=\"product-addtocart-button\" class=\"action primary tocart btn btn--secondary btn--big\" title=\"\u00a1Comprar ahora!\" type=\"submit\">\u00a1Comprar ahora! <\/button><\/div>';\n \t\t\t\t    \/\/var product = '<div class=\"col-md-'+grid+' text-center ds-analytics-blog-cross-selling-product order-'+index+'\" style=\"cursor:pointer;\" onclick=\"dataLayer.push({\\'event\\':\\'blog_cross_selling_product\\', \\'ga4EventData\\': { \\'name\\':\\'d_blog\\', \\'category\\':\\'click\\', \\'label\\':\\'producto\\', \\'element\\': \\''+link+'\\'}});window.open(\\''+link+'\\');\"><img id=\"'+id_products+'\" '+image_link+' class=\"product-img-shop\" alt=\"'+title+'\"><p><a href=\"'+link+'\" target=\"_blank\" title=\"'+title+'\" style=\"color:#212529;\" class=\"ds-analytics-blog-cross-selling-product\"><strong>'+title+'<\/strong><\/a><\/p><button id=\"product-addtocart-button\" class=\"action primary tocart btn btn--secondary btn--big\" title=\"\u00a1Comprar ahora!\" type=\"submit\">\u00a1Comprar ahora! <\/button><\/div>'; \n                    var grid_div = document.getElementById(\"external-products-CEVC66420F\");\n                    grid_div.innerHTML += product;\n                    products_found++;\n                }\n            });\n            if(products_found == all_ids.length){\n                break;\n            }\n        }\n        document.getElementById(\"load-products-CEVC66420F\").style.display = \"none\";\n        <\/script>\n    \n<!-- \/wp:shortcode -->\n\n<!-- wp:paragraph -->\n<p>Como ves, <strong>tienes much\u00edsimas opciones adecuadas donde elegir<\/strong>. Ahora toca valorar cada una y decidir siempre pensando en la comodidad y salud de tu amigo. Hay tanta variedad que seguro que encuentras el m\u00e1s id\u00f3neo para que tanto t\u00fa, como tu perro compart\u00e1is muchos paseos y viajes juntos.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Por \u00faltimo, te recomendamos que eches un vistazo a los siguientes posts sobre viajes. \u00a1Seguro que te ser\u00e1n de mucha ayuda!<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:list -->\n<ul><!-- wp:list-item -->\n<li><a href=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/no-sin-mi-mascota-consejos-para-preparar-un-viaje-en-coche-con-tu-peludo\/\"><strong>Descubre cu\u00e1l es la normativa y algunas recomendaciones para viajar con un perro en coche<\/strong><\/a><\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li><strong><a href=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/por-que-a-los-perros-les-gusta-la-nieve\/\">Descubre c\u00f3mo ir a la nieve con perros de forma segura<\/a><\/strong><\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li><strong><a href=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/consejos-para-ir-a-la-playa-con-tu-perro\/\">Los mejores consejos para ir a la playa con tu perro<\/a><\/strong><\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li><strong><a href=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/vacaciones-con-perros\/\">\u00bfPlaneando unas vacaciones con tu perro inolvidables?<\/a><\/strong><\/li>\n<!-- \/wp:list-item --><\/ul>\n<!-- \/wp:list -->\n\n<!-- wp:paragraph {\"style\":{\"color\":{\"background\":\"#f0f0f0\"}}} -->\n<p class=\"has-background\" style=\"background-color:#f0f0f0\">Si tienes alguna duda <strong>&nbsp;nuestros expertos te asesorar\u00e1n<\/strong>, tanto en&nbsp;<a href=\"https:\/\/www.kiwoko.mom\/tiendas?showMap=true&amp;horizontalView=true&amp;isForm=true\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>tiendas Kiwoko<\/strong><\/a>&nbsp;como por&nbsp;<a href=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/servicio-venta-telefonica\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>v\u00eda telef\u00f3nica<\/strong><\/a>. Y si tienes claro lo que necesitas para tu mascota, puedes realizar tu pedido online en&nbsp;<a href=\"https:\/\/www.kiwoko.mom\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>kiwoko.mom<\/strong><\/a>, por tel\u00e9fono o en cualquiera de nuestras tiendas. \u00a1Te esperamos!<\/p>\n<!-- \/wp:paragraph -->","protected":false},"excerpt":{"rendered":"<p>\u00bfNo quieres renunciar a salir a la calle con tu cachorro o con tu perro de raza mini? Tanto si lo que quieres es dar un paseo, como si se trata de irte de viaje con tu mascota, lo ideal ser\u00e1 que valores todas las posibilidades disponibles para que tu perro vaya lo m\u00e1s seguro [&hellip;]<\/p>\n","protected":false},"author":40,"featured_media":45722,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1089,1071],"tags":[1272],"class_list":["post-10612","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-disfruta-de-tu-mascota","category-perros","tag-viajes"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-json\/wp\/v2\/posts\/10612","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-json\/wp\/v2\/users\/40"}],"replies":[{"embeddable":true,"href":"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-json\/wp\/v2\/comments?post=10612"}],"version-history":[{"count":19,"href":"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-json\/wp\/v2\/posts\/10612\/revisions"}],"predecessor-version":[{"id":50503,"href":"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-json\/wp\/v2\/posts\/10612\/revisions\/50503"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-json\/wp\/v2\/media\/45722"}],"wp:attachment":[{"href":"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-json\/wp\/v2\/media?parent=10612"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-json\/wp\/v2\/categories?post=10612"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-json\/wp\/v2\/tags?post=10612"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}