{"id":24222,"date":"2024-03-21T10:01:49","date_gmt":"2024-03-21T09:01:49","guid":{"rendered":"https:\/\/www.kiwoko.mom\/blogmundoanimal\/?p=24222"},"modified":"2025-03-06T13:54:37","modified_gmt":"2025-03-06T12:54:37","slug":"vacaciones-con-perros-tu-guia-2021","status":"publish","type":"post","link":"https:\/\/www.kiwoko.mom\/blogmundoanimal\/vacaciones-con-perros\/","title":{"rendered":"\u00bfPlaneando unas vacaciones con tu perro inolvidables?"},"content":{"rendered":"<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_82_2 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">\u00cdndice<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Alternar tabla de contenidos\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/vacaciones-con-perros\/#Escoge_destinos_pet-friendly_o_dog_friendly\" >Escoge destinos pet-friendly o dog friendly<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/vacaciones-con-perros\/#Busca_alojamiento_que_admita_perros\" >Busca alojamiento que admita perros<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/vacaciones-con-perros\/#Elige_el_medio_de_transporte\" >Elige el medio de transporte<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/vacaciones-con-perros\/#Coche\" >Coche<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/vacaciones-con-perros\/#Tren\" >Tren<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/vacaciones-con-perros\/#Avion\" >Avi\u00f3n<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/vacaciones-con-perros\/#Barco\" >Barco<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/vacaciones-con-perros\/#Revisa_la_normativa_vigente_y_pon_en_regla_la_documentacion_de_tu_perro\" >Revisa la normativa vigente y pon en regla la documentaci\u00f3n de tu perro<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/vacaciones-con-perros\/#Prepara_el_equipaje_de_tu_perro_para_el_viaje\" >Prepara el equipaje de tu perro para el viaje<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-10\" href=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/vacaciones-con-perros\/#Comida_y_agua\" >Comida y agua<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-11\" href=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/vacaciones-con-perros\/#Correa_y_collar\" >Correa y collar<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-12\" href=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/vacaciones-con-perros\/#Juguetes\" >Juguetes<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-13\" href=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/vacaciones-con-perros\/#Botiquin\" >Botiqu\u00edn<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-14\" href=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/vacaciones-con-perros\/#Tranquilizante_para_viajes\" >Tranquilizante para viajes<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-15\" href=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/vacaciones-con-perros\/#Planifica_las_actividades_en_el_destino\" >Planifica las actividades en el destino<\/a><\/li><\/ul><\/nav><\/div>\n<!-- wp:paragraph -->\n<p>\u00bfPensando en las pr\u00f3ximas vacaciones?<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Si eres de los que no se imagina unas <strong>vacaciones<\/strong> sin su <strong>perro<\/strong>, este art\u00edculo es para ti.&nbsp;<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Antes de lanzarte a comprar los billetes de avi\u00f3n, tren o reservar el hotel, es importante que tengas busques lugares en los que tu perro tambi\u00e9n vaya a disfrutar.&nbsp;<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Hoy te vamos a hablar de todo lo que necesitas saber para <strong>planificar las vacaciones perfectas con tu perro.&nbsp;<\/strong><\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:heading -->\n<h2><span class=\"ez-toc-section\" id=\"Escoge_destinos_pet-friendly_o_dog_friendly\"><\/span>Escoge destinos pet-friendly o dog friendly<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>El primer paso para unas <strong>vacaciones con tu perro<\/strong> es elegir un destino amigable con ellos, ya que no todos los lugares est\u00e1n permitidos.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Si tu compa\u00f1ero es muy activo y necesita mucho espacio para correr y jugar, es importante que escojas lugares m\u00e1s rurales o con parques grandes en los que poder disfrutar con \u00e9l. <\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Por otro lado, si tu perro es de los que se vuelve loco jugando con la playa y la arena, un destino costero con <a href=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/playas-perros-espana\/\" title=\"Gu\u00eda de playas para perros en Espa\u00f1a 2022\"><strong>playas que admitan perros<\/strong> <\/a>puede ser la opci\u00f3n ideal.&nbsp;<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Ten en cuenta tambi\u00e9n que debes informarte sobre el destino. Esto es importante para prevenir que tu perro <strong>pueda contagiarse de enfermedades transmitidas por par\u00e1sitos<\/strong>, como la <a href=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/leishmaniosis-en-perros-todo-lo-que-debes-saber\/\"><strong>leishmaniosis<\/strong><\/a> o la filaria. Investiga a fondo cu\u00e1l es la prevalencia de cada enfermedad en las comunidades para evitar exponer a tu perro.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Aqu\u00ed te dejamos un poco m\u00e1s de informaci\u00f3n:<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:image {\"align\":\"center\",\"id\":45527,\"sizeSlug\":\"full\",\"linkDestination\":\"none\"} -->\n<figure class=\"wp-block-image aligncenter size-full\"><img decoding=\"async\" width=\"715\" height=\"648\" data-src=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/uploads\/2024\/03\/Mapa-prevalencia-Leishmaniosis-Espana-1.jpg\" alt=\"\" class=\"wp-image-45527 lazyload\" data-srcset=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/uploads\/2024\/03\/Mapa-prevalencia-Leishmaniosis-Espana-1.jpg 715w, https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/uploads\/2024\/03\/Mapa-prevalencia-Leishmaniosis-Espana-1-300x272.jpg 300w\" data-sizes=\"(max-width: 715px) 100vw, 715px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 715px; --smush-placeholder-aspect-ratio: 715\/648;\" \/><\/figure>\n<!-- \/wp:image -->\n\n<!-- wp:image {\"align\":\"center\",\"id\":19133,\"sizeSlug\":\"full\",\"linkDestination\":\"none\"} -->\n<figure class=\"wp-block-image aligncenter size-full\"><img decoding=\"async\" width=\"800\" height=\"800\" data-src=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/uploads\/2020\/06\/infografia-mapa-dirofilariosis-2020.jpg\" alt=\"infograf\u00eda mapa dirofilariosis en Espa\u00f1a\" class=\"wp-image-19133 lazyload\" data-srcset=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/uploads\/2020\/06\/infografia-mapa-dirofilariosis-2020.jpg 800w, https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/uploads\/2020\/06\/infografia-mapa-dirofilariosis-2020-150x150.jpg 150w, https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/uploads\/2020\/06\/infografia-mapa-dirofilariosis-2020-300x300.jpg 300w, https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/uploads\/2020\/06\/infografia-mapa-dirofilariosis-2020-768x768.jpg 768w\" data-sizes=\"(max-width: 800px) 100vw, 800px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 800px; --smush-placeholder-aspect-ratio: 800\/800;\" \/><\/figure>\n<!-- \/wp:image -->\n\n<!-- wp:table {\"className\":\"is-style-stripes\"} -->\n<figure class=\"wp-block-table is-style-stripes\"><table><tbody><tr><td>        <style>.ds-icon-mobile{display:none;}@media screen and (max-width: 767px) {.ds-icon-desktop{display:none;}.ds-icon-mobile{display:inline;}}<\/style>\n    <span style=\"color:#e20b12\">\n            <svg class=\"bi d-sm-inline-block d-md-inline-block d-lg-inline-block d-xl-inline-block ds-icon-desktop\" width=\"35\" height=\"35\" fill=\"#e20b12\">\n        <use xlink:href=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/plugins\/ds-icons\/bootstrap-icons\/bootstrap-icons.svg#bug\"\/>\n        <\/svg>\n        <svg class=\"bi d-inline-block d-sm-none d-md-none d-lg-none d-xl-none ds-icon-mobile\" width=\"35\" height=\"35\" fill=\"#e20b12\">\n        <use xlink:href=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/plugins\/ds-icons\/bootstrap-icons\/bootstrap-icons.svg#bug\"\/>\n        <\/svg>\n        <\/span>\n    <\/td><td>La filariosis es una enfermedad provocada por un mosquito&nbsp;<em>Dirofilaria inmitis,<\/em>&nbsp;las larvas entran el torrente sangu\u00edneo traspasan la piel del animal y se instalan en las c\u00e1maras card\u00edacas o en los pulmones. La \u00fanica prevenci\u00f3n son los&nbsp;<strong><a href=\"https:\/\/www.kiwoko.mom\/perros\/higiene-para-perros\/antiparasitarios\/\" target=\"_blank\" rel=\"noopener\" title=\"\">antiparasitarios para perros<\/a><\/strong>&nbsp;y los chequeos veterinarios.<\/td><\/tr><\/tbody><\/table><\/figure>\n<!-- \/wp:table -->\n\n<!-- wp:heading -->\n<h2><span class=\"ez-toc-section\" id=\"Busca_alojamiento_que_admita_perros\"><\/span>Busca alojamiento que admita perros<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>Una vez que hayas escogido el destino, deber\u00e1s empezar con la b\u00fasqueda de <strong>alojamiento que permita perros.&nbsp;<\/strong><\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>En Espa\u00f1a y Europa, <strong>cada vez son m\u00e1s los hoteles, apartamentos, <a href=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/casas-rurales-con-mascotas-en-espana\/\" title=\"Casas rurales con mascotas en Espa\u00f1a\">casas rurales<\/a> y <a href=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/glampings-con-perros\">campings<\/a> que permiten la presencia de mascotas.<\/strong> Eso s\u00ed, ten en cuenta que puede que algunos alojamientos tengan alg\u00fan tipo de restricci\u00f3n en cuanto al tama\u00f1o y al n\u00famero de perros.&nbsp;<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Adem\u00e1s, algunos hoteles pueden permitir la presencia de perros en las habitaciones pero no en las zonas comunes, lo que limitar\u00e1 mucho tu estancia.&nbsp;<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Nuestra recomendaci\u00f3n es que, para asegurarte, contactes directamente con el alojamiento y les expongas tu situaci\u00f3n y el peso y tama\u00f1o de tu mascota. \u00a1As\u00ed evitar\u00e1s sorpresas!<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:heading -->\n<h2><span class=\"ez-toc-section\" id=\"Elige_el_medio_de_transporte\"><\/span>Elige el medio de transporte<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p><strong>Elegir el medio de transporte en el que viajar con tu mascota<\/strong>, depender\u00e1 en gran medida del tama\u00f1o de tu perro, su personalidad y la duraci\u00f3n del viaje. Las opciones m\u00e1s recomendadas son:<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:heading {\"level\":3} -->\n<h3><span class=\"ez-toc-section\" id=\"Coche\"><\/span>Coche<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>Si tu mascota est\u00e1 acostumbrada a viajar en coche, esta puede ser una buena opci\u00f3n. <\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph {\"style\":{\"color\":{\"background\":\"#eeeeeeed\"}}} -->\n<p class=\"has-background\" style=\"background-color:#eeeeeeed\">En el art\u00edculo \"<a href=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/viaja-de-forma-segura-en-el-coche-con-tu-mascota\/\"><strong>\u00bfC\u00f3mo viajar en coche con un perro? Consideraciones y consejos<\/strong><\/a>\" te contamos todo lo que necesitas saber antes de emprender un viaje en coche con tu mascota.&nbsp; <\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph {\"style\":{\"color\":{\"background\":\"#eeeeeeed\"}}} -->\n<p class=\"has-background\" style=\"background-color:#eeeeeeed\">Y en nuestro post \"<strong><a href=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/no-sin-mi-mascota-consejos-para-preparar-un-viaje-en-coche-con-tu-peludo\/\">Descubre cu\u00e1l es la normativa y algunas recomendaciones para viajar con un perro en coche<\/a><\/strong>\" encontrar\u00e1s informaci\u00f3n muy \u00fatil sobre la legislaci\u00f3n actual para viajar con perros.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:heading {\"level\":3} -->\n<h3><span class=\"ez-toc-section\" id=\"Tren\"><\/span>Tren<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>En Espa\u00f1a, Renfe permite viajar con mascotas siempre y cuando se cumplan ciertas condiciones. De la misma forma, es importante que consultes con las compa\u00f1\u00edas para asegurarte de que tu perro va a poder viajar sin ning\u00fan problema.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph {\"style\":{\"color\":{\"background\":\"#eeeeeeed\"}}} -->\n<p class=\"has-background\" style=\"background-color:#eeeeeeed\">En el art\u00edculo <a href=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/normas-para-viajar-con-tu-perro-en-tren\/\"><strong>Normativa para viajar con tu perro en tren<\/strong><\/a>, te explicamos la normativa vigente.&nbsp;<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:heading {\"level\":3} -->\n<h3><span class=\"ez-toc-section\" id=\"Avion\"><\/span>Avi\u00f3n<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>En caso de distancias largas, viajar en avi\u00f3n es siempre la mejor opci\u00f3n. Dependiendo de la compa\u00f1\u00eda a\u00e9rea y el destino, es necesario cumplir una serie de condiciones. <\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph {\"style\":{\"color\":{\"background\":\"#eeeeeeed\"}}} -->\n<p class=\"has-background\" style=\"background-color:#eeeeeeed\">Te recomendamos que revises el art\u00edculo <a href=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/viajar-perro-avion\/\"><strong>Viajar con perro en avi\u00f3n<\/strong><\/a> si est\u00e1s pensando viajar con tu mascota en avi\u00f3n y este otro post: <strong><a href=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/aerolineas-que-permiten-viajar-con-perros-en-cabina\/\" title=\"Aerol\u00edneas que permiten viajar con perros en cabina\">Aerol\u00edneas que permiten viajar con perros en cabina<\/a><\/strong>&nbsp;<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:heading {\"level\":3} -->\n<h3><span class=\"ez-toc-section\" id=\"Barco\"><\/span>Barco<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>En algunas ocasiones, el viaje en barco tambi\u00e9n es una opci\u00f3n interesante. <\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph {\"style\":{\"color\":{\"background\":\"#eeeeeeed\"}}} -->\n<p class=\"has-background\" style=\"background-color:#eeeeeeed\">Puedes echar un vistazo al art\u00edculo <a href=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/viajar-en-barco-con-perro\/\"><strong>Viajar en barco con perros: nuestros consejos<\/strong><\/a> si quieres conocer m\u00e1s.&nbsp;<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Es importante tener en cuenta que cada medio de transporte tiene sus propias normas y requisitos para viajar con mascotas, por lo que es fundamental <strong>informarse detalladamente antes de realizar el viaje para garantizar la comodidad y seguridad de tu mascota<\/strong>, adem\u00e1s de llevar todo lo necesario para que el viaje sea agradable.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:shortcode -->\n        <div id=\"external-products-OUT00274\" class=\"row external-products\">\n            <img decoding=\"async\" id=\"load-products-OUT00274\" data-src=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/themes\/kiwoko\/inc\/assets\/images\/loading.gif\" width=\"50\" height=\"50\" alt=\"loading\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 50px; --smush-placeholder-aspect-ratio: 50\/50;\">\n        <\/div>\n        <script>\n        var id_products = \"OUT00274,OUT00270\";\n        id_products = id_products.replace(\/\\s\/g, '');\n        var all_ids = id_products.split(\",\");\n\n        \/\/ Agregar sufijo _M a todos los c\u00f3digos\n        var all_ids = all_ids.map(function(id) {\n            return id + '_M';\n        });\n\n        var not_found_products = 1;\n        var not_found_img_product = 0;\n        var ramdom_id = Math.round(Math.random() * 10000);\n        var grid = '12';\n\t\tvar width = '220';\n\t\tvar height = '220';\n        if(all_ids.length >= 4){\n            grid = '3';\n\t\t\twidth = '151';\n\t\t\theight = '151';\n        }else if(all_ids.length == 3){\n            grid = '4';\n\t\t\twidth = '211';\n\t\t\theight = '211';\n        }else if(all_ids.length == 2){\n            grid = '6';\n        }\n\t\n\tif(!items){\n        var feed = \"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/themes\/kiwoko\/feed-channable.xml\";\n        var request = new XMLHttpRequest();\n        request.open(\"GET\", feed, false);\n        request.send();\n        var xmlFromUrl = request.responseXML;\n        var parser = new DOMParser();\n        var xmlDoc = parser.parseFromString(feed, \"text\/xml\");\n        var items = xmlFromUrl.getElementsByTagName(\"item\");\n        }\n\n        var products_found = 0;\n        for (var item of items) {\n            all_ids.forEach(function(word, index) {\n                if(item.getElementsByTagName(\"g:item_group_id\")[0].textContent == word){\n                    not_found_products = 0;\n                    id_products = item.getElementsByTagName(\"g:item_group_id\")[0].textContent;\n                    var link = item.getElementsByTagName(\"link\")[0].textContent;\n                    var image_link = 'src=\"'+item.getElementsByTagName(\"g:image_link\")[0].textContent+'\" ';\n                    var title = item.getElementsByTagName(\"title\")[0].textContent;\n\t\t\t\t\tvar customLabel0 = item.getElementsByTagName(\"g:custom_label_0\")[0]?.textContent || '';\n                    var customLabel1 = item.getElementsByTagName(\"g:custom_label_1\")[0]?.textContent || '';\n                    var product = '<div class=\"col-md-'+grid+' text-center ds-analytics-blog-cross-selling-product order-'+index+'\" style=\"cursor:pointer;\" onclick=\"dataLayer.push({'+\n                    '\\'event\\':\\'crosseling_product_click\\', '+\n                    '\\'event_name\\':\\'crosseling_product_click\\', '+\n                    '\\'link_text\\':\\'\u00a1Comprar ahora!\\', '+\n                    '\\'link_url\\':\\''+link+'\\', '+\n                    '\\'category\\':\\''+customLabel0+'\/'+customLabel1+'\\', '+\n                    '\\'product_name\\':\\''+title+'\\''+\n                    '});window.open(\\''+link+'\\');\"><img id=\"'+id_products+'\" '+image_link+' class=\"product-img-shop\" alt=\"'+title+'\"><p><a href=\"'+link+'\" target=\"_blank\" title=\"'+title+'\" style=\"color:#212529;\" class=\"ds-analytics-blog-cross-selling-product\"><strong>'+title+'<\/strong><\/a><\/p><button id=\"product-addtocart-button\" class=\"action primary tocart btn btn--secondary btn--big\" title=\"\u00a1Comprar ahora!\" type=\"submit\">\u00a1Comprar ahora! <\/button><\/div>';\n \t\t\t\t    \/\/var product = '<div class=\"col-md-'+grid+' text-center ds-analytics-blog-cross-selling-product order-'+index+'\" style=\"cursor:pointer;\" onclick=\"dataLayer.push({\\'event\\':\\'blog_cross_selling_product\\', \\'ga4EventData\\': { \\'name\\':\\'d_blog\\', \\'category\\':\\'click\\', \\'label\\':\\'producto\\', \\'element\\': \\''+link+'\\'}});window.open(\\''+link+'\\');\"><img id=\"'+id_products+'\" '+image_link+' class=\"product-img-shop\" alt=\"'+title+'\"><p><a href=\"'+link+'\" target=\"_blank\" title=\"'+title+'\" style=\"color:#212529;\" class=\"ds-analytics-blog-cross-selling-product\"><strong>'+title+'<\/strong><\/a><\/p><button id=\"product-addtocart-button\" class=\"action primary tocart btn btn--secondary btn--big\" title=\"\u00a1Comprar ahora!\" type=\"submit\">\u00a1Comprar ahora! <\/button><\/div>'; \n                    var grid_div = document.getElementById(\"external-products-OUT00274\");\n                    grid_div.innerHTML += product;\n                    products_found++;\n                }\n            });\n            if(products_found == all_ids.length){\n                break;\n            }\n        }\n        document.getElementById(\"load-products-OUT00274\").style.display = \"none\";\n        <\/script>\n    \n<!-- \/wp:shortcode -->\n\n<!-- wp:heading -->\n<h2><span class=\"ez-toc-section\" id=\"Revisa_la_normativa_vigente_y_pon_en_regla_la_documentacion_de_tu_perro\"><\/span>Revisa la normativa vigente y pon en regla la documentaci\u00f3n de tu perro<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>Para las <strong>vacaciones con perro<\/strong> hay que viajar, y esto requiere cumplir ciertas normas y requisitos en cuanto a la documentaci\u00f3n necesaria para garantizar la salud y seguridad del animal.&nbsp;<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Seg\u00fan las \u00faltimas modificaciones en la normativa vigente, esta es la <strong>documentaci\u00f3n b\u00e1sica que necesitar\u00e1s para viajar con tu perro:<\/strong><\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:list -->\n<ul><!-- wp:list-item -->\n<li><strong>Pasaporte de perros:<\/strong> Este documento es obligatorio para viajar dentro de Espa\u00f1a y de la Uni\u00f3n Europea y debe incluir informaci\u00f3n sobre la identidad y el historial sanitario del animal. Para que sea v\u00e1lido, debe haber sido emitido por un veterinario oficial.<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li><strong>Microchip: <\/strong>Los perros que no dispongan de microchip no podr\u00e1n viajar.&nbsp;<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li><strong>Certificado de vacunaci\u00f3n: <\/strong>Es necesario demostrar que el animal ha sido vacunado en los \u00faltimos meses y que dicha vacunaci\u00f3n est\u00e1 a\u00fan vigente.&nbsp;<\/li>\n<!-- \/wp:list-item --><\/ul>\n<!-- \/wp:list -->\n\n<!-- wp:paragraph -->\n<p>Sin embargo, para entrar en algunos pa\u00edses de la Uni\u00f3n Europea, es posible que necesites otra informaci\u00f3n adicional como una prueba de anticuerpo contra la rabia, el tratamiento contra la equinococosis o un certificado de salud. Ante la duda, consulta siempre con las autoridades del pa\u00eds o regi\u00f3n al que vayas a viajar antes de irte de<strong> vacaciones con tu perro<\/strong> y pide consejo a tu veterinario.&nbsp;<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:heading -->\n<h2><span class=\"ez-toc-section\" id=\"Prepara_el_equipaje_de_tu_perro_para_el_viaje\"><\/span>Prepara el equipaje de tu perro para el viaje<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>Una vez que tengas el destino, medio de transporte y alojamiento elegido, es importante que prepares el <strong>equipaje de tu <\/strong>compa\u00f1ero para disfrutar de unas incre\u00edbles <strong>vacaciones con tu perro<\/strong>.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Recuerda llevar:<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:heading {\"level\":3,\"style\":{\"color\":{\"background\":\"#eeeeeeed\"}}} -->\n<h3 class=\"has-background\" style=\"background-color:#eeeeeeed\"><span class=\"ez-toc-section\" id=\"Comida_y_agua\"><\/span>Comida y agua<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>Aseg\u00farate de llevar la comida habitual de tu perro y agua embotellada para evitar posibles problemas digestivos. Adem\u00e1s, lleva recipientes para servir la comida y el agua que ocupen poco espacio. (Los <a href=\"https:\/\/www.kiwoko.mom\/perros\/accesorios-para-perros\/comederos-y-bebederos\/de-viaje\/\" target=\"_blank\" rel=\"noopener\" title=\"\"><strong>comederos y bebederos plegables<\/strong><\/a> siempre son una buena opci\u00f3n).&nbsp;<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:shortcode -->\n        <div id=\"external-products-OUT88714\" class=\"row external-products\">\n            <img decoding=\"async\" id=\"load-products-OUT88714\" data-src=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/themes\/kiwoko\/inc\/assets\/images\/loading.gif\" width=\"50\" height=\"50\" alt=\"loading\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 50px; --smush-placeholder-aspect-ratio: 50\/50;\">\n        <\/div>\n        <script>\n        var id_products = \"OUT88714,OUT88700\";\n        id_products = id_products.replace(\/\\s\/g, '');\n        var all_ids = id_products.split(\",\");\n\n        \/\/ Agregar sufijo _M a todos los c\u00f3digos\n        var all_ids = all_ids.map(function(id) {\n            return id + '_M';\n        });\n\n        var not_found_products = 1;\n        var not_found_img_product = 0;\n        var ramdom_id = Math.round(Math.random() * 10000);\n        var grid = '12';\n\t\tvar width = '220';\n\t\tvar height = '220';\n        if(all_ids.length >= 4){\n            grid = '3';\n\t\t\twidth = '151';\n\t\t\theight = '151';\n        }else if(all_ids.length == 3){\n            grid = '4';\n\t\t\twidth = '211';\n\t\t\theight = '211';\n        }else if(all_ids.length == 2){\n            grid = '6';\n        }\n\t\n\tif(!items){\n        var feed = \"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/themes\/kiwoko\/feed-channable.xml\";\n        var request = new XMLHttpRequest();\n        request.open(\"GET\", feed, false);\n        request.send();\n        var xmlFromUrl = request.responseXML;\n        var parser = new DOMParser();\n        var xmlDoc = parser.parseFromString(feed, \"text\/xml\");\n        var items = xmlFromUrl.getElementsByTagName(\"item\");\n        }\n\n        var products_found = 0;\n        for (var item of items) {\n            all_ids.forEach(function(word, index) {\n                if(item.getElementsByTagName(\"g:item_group_id\")[0].textContent == word){\n                    not_found_products = 0;\n                    id_products = item.getElementsByTagName(\"g:item_group_id\")[0].textContent;\n                    var link = item.getElementsByTagName(\"link\")[0].textContent;\n                    var image_link = 'src=\"'+item.getElementsByTagName(\"g:image_link\")[0].textContent+'\" ';\n                    var title = item.getElementsByTagName(\"title\")[0].textContent;\n\t\t\t\t\tvar customLabel0 = item.getElementsByTagName(\"g:custom_label_0\")[0]?.textContent || '';\n                    var customLabel1 = item.getElementsByTagName(\"g:custom_label_1\")[0]?.textContent || '';\n                    var product = '<div class=\"col-md-'+grid+' text-center ds-analytics-blog-cross-selling-product order-'+index+'\" style=\"cursor:pointer;\" onclick=\"dataLayer.push({'+\n                    '\\'event\\':\\'crosseling_product_click\\', '+\n                    '\\'event_name\\':\\'crosseling_product_click\\', '+\n                    '\\'link_text\\':\\'\u00a1Comprar ahora!\\', '+\n                    '\\'link_url\\':\\''+link+'\\', '+\n                    '\\'category\\':\\''+customLabel0+'\/'+customLabel1+'\\', '+\n                    '\\'product_name\\':\\''+title+'\\''+\n                    '});window.open(\\''+link+'\\');\"><img id=\"'+id_products+'\" '+image_link+' class=\"product-img-shop\" alt=\"'+title+'\"><p><a href=\"'+link+'\" target=\"_blank\" title=\"'+title+'\" style=\"color:#212529;\" class=\"ds-analytics-blog-cross-selling-product\"><strong>'+title+'<\/strong><\/a><\/p><button id=\"product-addtocart-button\" class=\"action primary tocart btn btn--secondary btn--big\" title=\"\u00a1Comprar ahora!\" type=\"submit\">\u00a1Comprar ahora! <\/button><\/div>';\n \t\t\t\t    \/\/var product = '<div class=\"col-md-'+grid+' text-center ds-analytics-blog-cross-selling-product order-'+index+'\" style=\"cursor:pointer;\" onclick=\"dataLayer.push({\\'event\\':\\'blog_cross_selling_product\\', \\'ga4EventData\\': { \\'name\\':\\'d_blog\\', \\'category\\':\\'click\\', \\'label\\':\\'producto\\', \\'element\\': \\''+link+'\\'}});window.open(\\''+link+'\\');\"><img id=\"'+id_products+'\" '+image_link+' class=\"product-img-shop\" alt=\"'+title+'\"><p><a href=\"'+link+'\" target=\"_blank\" title=\"'+title+'\" style=\"color:#212529;\" class=\"ds-analytics-blog-cross-selling-product\"><strong>'+title+'<\/strong><\/a><\/p><button id=\"product-addtocart-button\" class=\"action primary tocart btn btn--secondary btn--big\" title=\"\u00a1Comprar ahora!\" type=\"submit\">\u00a1Comprar ahora! <\/button><\/div>'; \n                    var grid_div = document.getElementById(\"external-products-OUT88714\");\n                    grid_div.innerHTML += product;\n                    products_found++;\n                }\n            });\n            if(products_found == all_ids.length){\n                break;\n            }\n        }\n        document.getElementById(\"load-products-OUT88714\").style.display = \"none\";\n        <\/script>\n    \n<!-- \/wp:shortcode -->\n\n<!-- wp:heading {\"level\":3,\"style\":{\"color\":{\"background\":\"#eeeeeeed\"}}} -->\n<h3 class=\"has-background\" style=\"background-color:#eeeeeeed\"><span class=\"ez-toc-section\" id=\"Correa_y_collar\"><\/span>Correa y collar<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>A\u00f1ade informaci\u00f3n de contacto en el <a href=\"https:\/\/www.kiwoko.mom\/perros\/accesorios-para-perros\/paseo\/collares\/\" target=\"_blank\" rel=\"noopener\" title=\"\"><strong>collar de tu perro<\/strong><\/a> y en la <a href=\"https:\/\/www.kiwoko.mom\/perros\/accesorios-para-perros\/paseo\/correas\/\" target=\"_blank\" rel=\"noopener\" title=\"\"><strong>correa de paseo para perros<\/strong><\/a>. Puedes utilizar un localizador GPS para saber en todo momento d\u00f3nde est\u00e1 ubicada tu mascota.&nbsp;<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:shortcode -->\n        <div id=\"external-products-GOTYFR6556\" class=\"row external-products\">\n            <img decoding=\"async\" id=\"load-products-GOTYFR6556\" data-src=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/themes\/kiwoko\/inc\/assets\/images\/loading.gif\" width=\"50\" height=\"50\" alt=\"loading\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 50px; --smush-placeholder-aspect-ratio: 50\/50;\">\n        <\/div>\n        <script>\n        var id_products = \"GOTYFR6556,GOTYFR6555\";\n        id_products = id_products.replace(\/\\s\/g, '');\n        var all_ids = id_products.split(\",\");\n\n        \/\/ Agregar sufijo _M a todos los c\u00f3digos\n        var all_ids = all_ids.map(function(id) {\n            return id + '_M';\n        });\n\n        var not_found_products = 1;\n        var not_found_img_product = 0;\n        var ramdom_id = Math.round(Math.random() * 10000);\n        var grid = '12';\n\t\tvar width = '220';\n\t\tvar height = '220';\n        if(all_ids.length >= 4){\n            grid = '3';\n\t\t\twidth = '151';\n\t\t\theight = '151';\n        }else if(all_ids.length == 3){\n            grid = '4';\n\t\t\twidth = '211';\n\t\t\theight = '211';\n        }else if(all_ids.length == 2){\n            grid = '6';\n        }\n\t\n\tif(!items){\n        var feed = \"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/themes\/kiwoko\/feed-channable.xml\";\n        var request = new XMLHttpRequest();\n        request.open(\"GET\", feed, false);\n        request.send();\n        var xmlFromUrl = request.responseXML;\n        var parser = new DOMParser();\n        var xmlDoc = parser.parseFromString(feed, \"text\/xml\");\n        var items = xmlFromUrl.getElementsByTagName(\"item\");\n        }\n\n        var products_found = 0;\n        for (var item of items) {\n            all_ids.forEach(function(word, index) {\n                if(item.getElementsByTagName(\"g:item_group_id\")[0].textContent == word){\n                    not_found_products = 0;\n                    id_products = item.getElementsByTagName(\"g:item_group_id\")[0].textContent;\n                    var link = item.getElementsByTagName(\"link\")[0].textContent;\n                    var image_link = 'src=\"'+item.getElementsByTagName(\"g:image_link\")[0].textContent+'\" ';\n                    var title = item.getElementsByTagName(\"title\")[0].textContent;\n\t\t\t\t\tvar customLabel0 = item.getElementsByTagName(\"g:custom_label_0\")[0]?.textContent || '';\n                    var customLabel1 = item.getElementsByTagName(\"g:custom_label_1\")[0]?.textContent || '';\n                    var product = '<div class=\"col-md-'+grid+' text-center ds-analytics-blog-cross-selling-product order-'+index+'\" style=\"cursor:pointer;\" onclick=\"dataLayer.push({'+\n                    '\\'event\\':\\'crosseling_product_click\\', '+\n                    '\\'event_name\\':\\'crosseling_product_click\\', '+\n                    '\\'link_text\\':\\'\u00a1Comprar ahora!\\', '+\n                    '\\'link_url\\':\\''+link+'\\', '+\n                    '\\'category\\':\\''+customLabel0+'\/'+customLabel1+'\\', '+\n                    '\\'product_name\\':\\''+title+'\\''+\n                    '});window.open(\\''+link+'\\');\"><img id=\"'+id_products+'\" '+image_link+' class=\"product-img-shop\" alt=\"'+title+'\"><p><a href=\"'+link+'\" target=\"_blank\" title=\"'+title+'\" style=\"color:#212529;\" class=\"ds-analytics-blog-cross-selling-product\"><strong>'+title+'<\/strong><\/a><\/p><button id=\"product-addtocart-button\" class=\"action primary tocart btn btn--secondary btn--big\" title=\"\u00a1Comprar ahora!\" type=\"submit\">\u00a1Comprar ahora! <\/button><\/div>';\n \t\t\t\t    \/\/var product = '<div class=\"col-md-'+grid+' text-center ds-analytics-blog-cross-selling-product order-'+index+'\" style=\"cursor:pointer;\" onclick=\"dataLayer.push({\\'event\\':\\'blog_cross_selling_product\\', \\'ga4EventData\\': { \\'name\\':\\'d_blog\\', \\'category\\':\\'click\\', \\'label\\':\\'producto\\', \\'element\\': \\''+link+'\\'}});window.open(\\''+link+'\\');\"><img id=\"'+id_products+'\" '+image_link+' class=\"product-img-shop\" alt=\"'+title+'\"><p><a href=\"'+link+'\" target=\"_blank\" title=\"'+title+'\" style=\"color:#212529;\" class=\"ds-analytics-blog-cross-selling-product\"><strong>'+title+'<\/strong><\/a><\/p><button id=\"product-addtocart-button\" class=\"action primary tocart btn btn--secondary btn--big\" title=\"\u00a1Comprar ahora!\" type=\"submit\">\u00a1Comprar ahora! <\/button><\/div>'; \n                    var grid_div = document.getElementById(\"external-products-GOTYFR6556\");\n                    grid_div.innerHTML += product;\n                    products_found++;\n                }\n            });\n            if(products_found == all_ids.length){\n                break;\n            }\n        }\n        document.getElementById(\"load-products-GOTYFR6556\").style.display = \"none\";\n        <\/script>\n    \n<!-- \/wp:shortcode -->\n\n<!-- wp:heading {\"level\":3,\"style\":{\"color\":{\"background\":\"#eeeeeeed\"}}} -->\n<h3 class=\"has-background\" style=\"background-color:#eeeeeeed\"><span class=\"ez-toc-section\" id=\"Juguetes\"><\/span>Juguetes<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>Llevar <a href=\"https:\/\/www.kiwoko.mom\/perros\/juguetes-para-perros\/\" target=\"_blank\" rel=\"noopener\" title=\"\"><strong>juguetes para perros<\/strong><\/a> que le sean familiares ayudar\u00e1 a que se sienta m\u00e1s c\u00f3modo y seguro durante el trayecto. Adem\u00e1s, tambi\u00e9n servir\u00e1n para distraer a tu compa\u00f1ero en momentos de estr\u00e9s.&nbsp;<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:shortcode -->\n        <div id=\"external-products-TOODS50736\" class=\"row external-products\">\n            <img decoding=\"async\" id=\"load-products-TOODS50736\" data-src=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/themes\/kiwoko\/inc\/assets\/images\/loading.gif\" width=\"50\" height=\"50\" alt=\"loading\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 50px; --smush-placeholder-aspect-ratio: 50\/50;\">\n        <\/div>\n        <script>\n        var id_products = \"TOODS50736,TOOC35128B,TOO22DT1374\";\n        id_products = id_products.replace(\/\\s\/g, '');\n        var all_ids = id_products.split(\",\");\n\n        \/\/ Agregar sufijo _M a todos los c\u00f3digos\n        var all_ids = all_ids.map(function(id) {\n            return id + '_M';\n        });\n\n        var not_found_products = 1;\n        var not_found_img_product = 0;\n        var ramdom_id = Math.round(Math.random() * 10000);\n        var grid = '12';\n\t\tvar width = '220';\n\t\tvar height = '220';\n        if(all_ids.length >= 4){\n            grid = '3';\n\t\t\twidth = '151';\n\t\t\theight = '151';\n        }else if(all_ids.length == 3){\n            grid = '4';\n\t\t\twidth = '211';\n\t\t\theight = '211';\n        }else if(all_ids.length == 2){\n            grid = '6';\n        }\n\t\n\tif(!items){\n        var feed = \"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/themes\/kiwoko\/feed-channable.xml\";\n        var request = new XMLHttpRequest();\n        request.open(\"GET\", feed, false);\n        request.send();\n        var xmlFromUrl = request.responseXML;\n        var parser = new DOMParser();\n        var xmlDoc = parser.parseFromString(feed, \"text\/xml\");\n        var items = xmlFromUrl.getElementsByTagName(\"item\");\n        }\n\n        var products_found = 0;\n        for (var item of items) {\n            all_ids.forEach(function(word, index) {\n                if(item.getElementsByTagName(\"g:item_group_id\")[0].textContent == word){\n                    not_found_products = 0;\n                    id_products = item.getElementsByTagName(\"g:item_group_id\")[0].textContent;\n                    var link = item.getElementsByTagName(\"link\")[0].textContent;\n                    var image_link = 'src=\"'+item.getElementsByTagName(\"g:image_link\")[0].textContent+'\" ';\n                    var title = item.getElementsByTagName(\"title\")[0].textContent;\n\t\t\t\t\tvar customLabel0 = item.getElementsByTagName(\"g:custom_label_0\")[0]?.textContent || '';\n                    var customLabel1 = item.getElementsByTagName(\"g:custom_label_1\")[0]?.textContent || '';\n                    var product = '<div class=\"col-md-'+grid+' text-center ds-analytics-blog-cross-selling-product order-'+index+'\" style=\"cursor:pointer;\" onclick=\"dataLayer.push({'+\n                    '\\'event\\':\\'crosseling_product_click\\', '+\n                    '\\'event_name\\':\\'crosseling_product_click\\', '+\n                    '\\'link_text\\':\\'\u00a1Comprar ahora!\\', '+\n                    '\\'link_url\\':\\''+link+'\\', '+\n                    '\\'category\\':\\''+customLabel0+'\/'+customLabel1+'\\', '+\n                    '\\'product_name\\':\\''+title+'\\''+\n                    '});window.open(\\''+link+'\\');\"><img id=\"'+id_products+'\" '+image_link+' class=\"product-img-shop\" alt=\"'+title+'\"><p><a href=\"'+link+'\" target=\"_blank\" title=\"'+title+'\" style=\"color:#212529;\" class=\"ds-analytics-blog-cross-selling-product\"><strong>'+title+'<\/strong><\/a><\/p><button id=\"product-addtocart-button\" class=\"action primary tocart btn btn--secondary btn--big\" title=\"\u00a1Comprar ahora!\" type=\"submit\">\u00a1Comprar ahora! <\/button><\/div>';\n \t\t\t\t    \/\/var product = '<div class=\"col-md-'+grid+' text-center ds-analytics-blog-cross-selling-product order-'+index+'\" style=\"cursor:pointer;\" onclick=\"dataLayer.push({\\'event\\':\\'blog_cross_selling_product\\', \\'ga4EventData\\': { \\'name\\':\\'d_blog\\', \\'category\\':\\'click\\', \\'label\\':\\'producto\\', \\'element\\': \\''+link+'\\'}});window.open(\\''+link+'\\');\"><img id=\"'+id_products+'\" '+image_link+' class=\"product-img-shop\" alt=\"'+title+'\"><p><a href=\"'+link+'\" target=\"_blank\" title=\"'+title+'\" style=\"color:#212529;\" class=\"ds-analytics-blog-cross-selling-product\"><strong>'+title+'<\/strong><\/a><\/p><button id=\"product-addtocart-button\" class=\"action primary tocart btn btn--secondary btn--big\" title=\"\u00a1Comprar ahora!\" type=\"submit\">\u00a1Comprar ahora! <\/button><\/div>'; \n                    var grid_div = document.getElementById(\"external-products-TOODS50736\");\n                    grid_div.innerHTML += product;\n                    products_found++;\n                }\n            });\n            if(products_found == all_ids.length){\n                break;\n            }\n        }\n        document.getElementById(\"load-products-TOODS50736\").style.display = \"none\";\n        <\/script>\n    \n<!-- \/wp:shortcode -->\n\n<!-- wp:heading {\"level\":3,\"style\":{\"color\":{\"background\":\"#eeeeeeed\"}}} -->\n<h3 class=\"has-background\" style=\"background-color:#eeeeeeed\"><span class=\"ez-toc-section\" id=\"Botiquin\"><\/span>Botiqu\u00edn<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>Si tu mascota necesita alguna medicaci\u00f3n especial, tambi\u00e9n deber\u00e1s llevarla durante el viaje y acompa\u00f1arla de una prescripci\u00f3n m\u00e9dica (traducida al idioma del pa\u00eds al que viajes). Adem\u00e1s de llevar un botiqu\u00edn b\u00e1sico con gasas, vendas y l\u00edquidos desinfectantes, tambi\u00e9n es recomendable llevar alg\u00fan medicamento para problemas gastrointestinales.&nbsp;<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:heading {\"level\":3,\"style\":{\"color\":{\"background\":\"#eeeeeeed\"}}} -->\n<h3 class=\"has-background\" style=\"background-color:#eeeeeeed\"><span class=\"ez-toc-section\" id=\"Tranquilizante_para_viajes\"><\/span>Tranquilizante para viajes<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>En caso de perros muy nerviosos, puede ser conveniente utilizar <strong><a href=\"https:\/\/www.kiwoko.mom\/perros\/higiene-para-perros\/salud-del-perro\/antiestres\/\" target=\"_blank\" rel=\"noopener\" title=\"productos antiestr\u00e9s para perros\">productos antiestr\u00e9s para perros<\/a><\/strong> como un spray o un collar tranquilizante para mantenerlo relajado durante el trayecto.&nbsp;<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:shortcode -->\n        <div id=\"external-products-CEVC66420F\" class=\"row external-products\">\n            <img decoding=\"async\" id=\"load-products-CEVC66420F\" data-src=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/themes\/kiwoko\/inc\/assets\/images\/loading.gif\" width=\"50\" height=\"50\" alt=\"loading\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 50px; --smush-placeholder-aspect-ratio: 50\/50;\">\n        <\/div>\n        <script>\n        var id_products = \"CEVC66420F,CEVC95630F,\";\n        id_products = id_products.replace(\/\\s\/g, '');\n        var all_ids = id_products.split(\",\");\n\n        \/\/ Agregar sufijo _M a todos los c\u00f3digos\n        var all_ids = all_ids.map(function(id) {\n            return id + '_M';\n        });\n\n        var not_found_products = 1;\n        var not_found_img_product = 0;\n        var ramdom_id = Math.round(Math.random() * 10000);\n        var grid = '12';\n\t\tvar width = '220';\n\t\tvar height = '220';\n        if(all_ids.length >= 4){\n            grid = '3';\n\t\t\twidth = '151';\n\t\t\theight = '151';\n        }else if(all_ids.length == 3){\n            grid = '4';\n\t\t\twidth = '211';\n\t\t\theight = '211';\n        }else if(all_ids.length == 2){\n            grid = '6';\n        }\n\t\n\tif(!items){\n        var feed = \"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/themes\/kiwoko\/feed-channable.xml\";\n        var request = new XMLHttpRequest();\n        request.open(\"GET\", feed, false);\n        request.send();\n        var xmlFromUrl = request.responseXML;\n        var parser = new DOMParser();\n        var xmlDoc = parser.parseFromString(feed, \"text\/xml\");\n        var items = xmlFromUrl.getElementsByTagName(\"item\");\n        }\n\n        var products_found = 0;\n        for (var item of items) {\n            all_ids.forEach(function(word, index) {\n                if(item.getElementsByTagName(\"g:item_group_id\")[0].textContent == word){\n                    not_found_products = 0;\n                    id_products = item.getElementsByTagName(\"g:item_group_id\")[0].textContent;\n                    var link = item.getElementsByTagName(\"link\")[0].textContent;\n                    var image_link = 'src=\"'+item.getElementsByTagName(\"g:image_link\")[0].textContent+'\" ';\n                    var title = item.getElementsByTagName(\"title\")[0].textContent;\n\t\t\t\t\tvar customLabel0 = item.getElementsByTagName(\"g:custom_label_0\")[0]?.textContent || '';\n                    var customLabel1 = item.getElementsByTagName(\"g:custom_label_1\")[0]?.textContent || '';\n                    var product = '<div class=\"col-md-'+grid+' text-center ds-analytics-blog-cross-selling-product order-'+index+'\" style=\"cursor:pointer;\" onclick=\"dataLayer.push({'+\n                    '\\'event\\':\\'crosseling_product_click\\', '+\n                    '\\'event_name\\':\\'crosseling_product_click\\', '+\n                    '\\'link_text\\':\\'\u00a1Comprar ahora!\\', '+\n                    '\\'link_url\\':\\''+link+'\\', '+\n                    '\\'category\\':\\''+customLabel0+'\/'+customLabel1+'\\', '+\n                    '\\'product_name\\':\\''+title+'\\''+\n                    '});window.open(\\''+link+'\\');\"><img id=\"'+id_products+'\" '+image_link+' class=\"product-img-shop\" alt=\"'+title+'\"><p><a href=\"'+link+'\" target=\"_blank\" title=\"'+title+'\" style=\"color:#212529;\" class=\"ds-analytics-blog-cross-selling-product\"><strong>'+title+'<\/strong><\/a><\/p><button id=\"product-addtocart-button\" class=\"action primary tocart btn btn--secondary btn--big\" title=\"\u00a1Comprar ahora!\" type=\"submit\">\u00a1Comprar ahora! <\/button><\/div>';\n \t\t\t\t    \/\/var product = '<div class=\"col-md-'+grid+' text-center ds-analytics-blog-cross-selling-product order-'+index+'\" style=\"cursor:pointer;\" onclick=\"dataLayer.push({\\'event\\':\\'blog_cross_selling_product\\', \\'ga4EventData\\': { \\'name\\':\\'d_blog\\', \\'category\\':\\'click\\', \\'label\\':\\'producto\\', \\'element\\': \\''+link+'\\'}});window.open(\\''+link+'\\');\"><img id=\"'+id_products+'\" '+image_link+' class=\"product-img-shop\" alt=\"'+title+'\"><p><a href=\"'+link+'\" target=\"_blank\" title=\"'+title+'\" style=\"color:#212529;\" class=\"ds-analytics-blog-cross-selling-product\"><strong>'+title+'<\/strong><\/a><\/p><button id=\"product-addtocart-button\" class=\"action primary tocart btn btn--secondary btn--big\" title=\"\u00a1Comprar ahora!\" type=\"submit\">\u00a1Comprar ahora! <\/button><\/div>'; \n                    var grid_div = document.getElementById(\"external-products-CEVC66420F\");\n                    grid_div.innerHTML += product;\n                    products_found++;\n                }\n            });\n            if(products_found == all_ids.length){\n                break;\n            }\n        }\n        document.getElementById(\"load-products-CEVC66420F\").style.display = \"none\";\n        <\/script>\n    \n<!-- \/wp:shortcode -->\n\n<!-- wp:heading -->\n<h2><span class=\"ez-toc-section\" id=\"Planifica_las_actividades_en_el_destino\"><\/span>Planifica las actividades en el destino<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>Otro aspecto importante a considerar a la hora de <strong>planificar unas vacaciones con tu perro <\/strong>son las actividades que pod\u00e9is hacer juntos. Antes de visitar un lugar espec\u00edfico, te recomendamos que revises la normativa de cada lugar en cuanto a la presencia de animales.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Tambi\u00e9n te recomendamos una serie de actividades que puedes hacer durante tus <strong>vacaciones con tu perro<\/strong>:<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:list -->\n<ul><!-- wp:list-item -->\n<li><strong><a href=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/practicar-dogtrekking-senderismo-con-perro\/\">Deportes para divertirte con tu perro: dogtrekking<\/a><\/strong><\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li><a href=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/actividades-practicar-perro-dentro-de-casa\/\"><strong>Actividades y juegos para perros en casa<\/strong><\/a><\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li><strong><a href=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/juegos-con-perros-en-el-jardin\/\">5 juegos para divertirte con tu perro: actividades en el jard\u00edn<\/a><\/strong><\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li><strong><a href=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/practicar-bikejoring-con-el-perro\/\">Bikejoring: El deporte de moda para divertirte con tu perro<\/a><\/strong><\/li>\n<!-- \/wp:list-item --><\/ul>\n<!-- \/wp:list -->\n\n<!-- wp:paragraph -->\n<p>En definitiva, para irte de <strong>vacaciones con tu perro<\/strong> es importante planificar con antelaci\u00f3n y llevar todo lo necesario para garantizar su comodidad y seguridad durante el viaje.&nbsp;&nbsp;<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph {\"style\":{\"color\":{\"background\":\"#f0f0f0\"}}} -->\n<p class=\"has-background\" style=\"background-color:#f0f0f0\">Si tienes alguna duda <strong>&nbsp;nuestros expertos te asesorar\u00e1n<\/strong>, tanto en&nbsp;<a href=\"https:\/\/www.kiwoko.mom\/tiendas?showMap=true&amp;horizontalView=true&amp;isForm=true\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>tiendas Kiwoko<\/strong><\/a>&nbsp;como por&nbsp;<a href=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/servicio-venta-telefonica\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>v\u00eda telef\u00f3nica<\/strong><\/a>. Y si tienes claro lo que necesitas para tu mascota, puedes realizar tu pedido online en&nbsp;<a href=\"https:\/\/www.kiwoko.mom\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>kiwoko.mom<\/strong><\/a>, por tel\u00e9fono o en cualquiera de nuestras tiendas. \u00a1Te esperamos!<\/p>\n<!-- \/wp:paragraph -->","protected":false},"excerpt":{"rendered":"<p>Si est\u00e1s pensando organizar una escapada en compa\u00f1\u00eda de tu mascota, debes de seguir algunas recomendaciones para organizar unas vacaciones con perros.<\/p>\n","protected":false},"author":40,"featured_media":24240,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1089,1071],"tags":[1272],"class_list":["post-24222","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-disfruta-de-tu-mascota","category-perros","tag-viajes"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-json\/wp\/v2\/posts\/24222","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-json\/wp\/v2\/users\/40"}],"replies":[{"embeddable":true,"href":"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-json\/wp\/v2\/comments?post=24222"}],"version-history":[{"count":25,"href":"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-json\/wp\/v2\/posts\/24222\/revisions"}],"predecessor-version":[{"id":50520,"href":"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-json\/wp\/v2\/posts\/24222\/revisions\/50520"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-json\/wp\/v2\/media\/24240"}],"wp:attachment":[{"href":"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-json\/wp\/v2\/media?parent=24222"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-json\/wp\/v2\/categories?post=24222"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-json\/wp\/v2\/tags?post=24222"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}