{"id":33183,"date":"2022-04-28T09:00:00","date_gmt":"2022-04-28T07:00:00","guid":{"rendered":"https:\/\/www.kiwoko.mom\/blogmundoanimal\/?p=33183"},"modified":"2023-01-04T15:45:25","modified_gmt":"2023-01-04T14:45:25","slug":"peces-damisela-caracteristicas-y-cuidados","status":"publish","type":"post","link":"https:\/\/www.kiwoko.mom\/blogmundoanimal\/peces-damisela\/","title":{"rendered":"Peces damisela: caracter\u00edsticas y cuidados"},"content":{"rendered":"<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_82_2 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">\u00cdndice<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Alternar tabla de contenidos\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/peces-damisela\/#Tipos_de_peces_damisela\" >Tipos de peces damisela<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/peces-damisela\/#Cuidados_basicos_de_los_peces_damisela\" >Cuidados b\u00e1sicos de los peces damisela<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/peces-damisela\/#Alimentacion_de_los_damiselas\" >Alimentaci\u00f3n de los damiselas<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/peces-damisela\/#Mantenimiento_del_acuario_para_el_pez_damisela\" >Mantenimiento del acuario para el pez damisela<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/peces-damisela\/#Convivencia_de_los_damiselas_con_otras_especies\" >Convivencia de los damiselas con otras especies<\/a><\/li><\/ul><\/nav><\/div>\n<!-- wp:paragraph -->\n<p>Los <strong>peces damisela <\/strong>son peces marinos tropicales, de los cuales existen en todo el mundo unas 250 especies diferentes. Estos peces de la familia de las Pormacentridae son de car\u00e1cter ex\u00f3tico y se distinguen especialmente de otros por sus atractivos y llamativos colores y por ser muy activos.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Los damiselas se encuentran, sobre todo, en los <strong>arrecifes de los oc\u00e9anos Atl\u00e1ntico, \u00cdndico y Pac\u00edfico<\/strong>. Hay especies que viven tambi\u00e9n en r\u00edos de agua dulce, aunque la mayor\u00eda de ellos lo hacen en agua salada. Por el atractivo colorido que presentan, se han convertido en uno de los peces favoritos para los amantes de los acuarios.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:heading -->\n<h2><span class=\"ez-toc-section\" id=\"Tipos_de_peces_damisela\"><\/span>Tipos de peces damisela<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>Hay una gran variedad de especies y tipos de peces damisela. A continuaci\u00f3n te mostramos los m\u00e1s habituales y conocidos.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:list -->\n<ul><li><strong>Pez damisela azul<\/strong>. Probablemente sea el pez de acuario m\u00e1s popular. De color azul claro brillante, con el hocico y la cola amarillo brillante en los machos, apenas tiene 6 cent\u00edmetros de tama\u00f1o.<\/li><li><strong>Pez damisela joya<\/strong>. De color negro con puntos azules brillantes, es un pez om\u00ednovoro un tanto agresivo, por lo que, en la mayor\u00eda de las ocasiones, debe permanecer solo en el acuario.<\/li><li><strong>Pez damisela ne\u00f3n<\/strong>. Se caracteriza por su coloraci\u00f3n azul brillante ne\u00f3n, verde o amarillenta. No obstante, solo exhibe esta coloraci\u00f3n cuando se halla contento y seguro.<\/li><li><strong>Pez damisela blanco y negro<\/strong>. Pez de color tipo cebra, alcanza una longitud de 8 cent\u00edmetros y cuenta con tres bandas negras en posici\u00f3n vertical, por lo que resulta muy atractivo.<\/li><li><strong>Pez damisela verde<\/strong>. Su tama\u00f1o oscila entre los 6 y los 8 cent\u00edmetros y posee una coloraci\u00f3n verde claro con ciertos toques azulados. Es originario de los oc\u00e9anos \u00cdndico y Pac\u00edfico.<\/li><li><strong>Pez damisela sargento<\/strong>. Un pez omn\u00edvoro que vive en el oc\u00e9ano Atl\u00e1ntico y el mar Caribe. Si bien sus colores son muy atractivos de joven, pierde esta coloraci\u00f3n a medida que envejece.<\/li><li><strong>Pez damisela garibaldi<\/strong>. De color naranja brillante, vive en la parte subtropical del oc\u00e9ano Pac\u00edfico. Puede crecer hasta los 15 cent\u00edmetros de largo, por lo que se trata del damisela m\u00e1s grande.<\/li><\/ul>\n<!-- \/wp:list -->\n\n<!-- wp:heading -->\n<h2><span class=\"ez-toc-section\" id=\"Cuidados_basicos_de_los_peces_damisela\"><\/span>Cuidados b\u00e1sicos de los peces damisela<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>Los peces damisela son una excelente opci\u00f3n para aquellos que se inician por primera vez en el mundo de los acuarios. No en vano, <strong>son unos peces muy resistentes<\/strong>, por lo que no se trata de una especie delicada. El \u00fanico problema que plantean es que suelen ser peces bastante agresivos, a excepci\u00f3n del damisela azul.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:heading {\"level\":3} -->\n<h3><span class=\"ez-toc-section\" id=\"Alimentacion_de_los_damiselas\"><\/span>Alimentaci\u00f3n de los damiselas<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>Los damiselas son <strong>peces omn\u00edvoros<\/strong>, por lo que comen pr\u00e1cticamente de todo. Alimentos con escamas, alimentos vivos y congelados, camarones de salmuera, huevos de pescado, calamares, camarones, crust\u00e1ceos y cualquier otro organismo peque\u00f1o marino pueden formar parte de su dieta diaria.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Lo m\u00e1s recomendable es alimentarlos con <strong>peque\u00f1as porciones varias veces al d\u00eda <\/strong>para que puedan consumir grandes cantidades cada cierto tiempo. No obstante, hay tambi\u00e9n especies damiselas herb\u00edvoras a las que se les puede proporcionar <a href=\"https:\/\/www.kiwoko.mom\/peces\/comida-para-peces\/\" target=\"_blank\" rel=\"noreferrer noopener\">alimentos secos en escamas y alimentos verdes<\/a>.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:heading {\"level\":3} -->\n<h3><span class=\"ez-toc-section\" id=\"Mantenimiento_del_acuario_para_el_pez_damisela\"><\/span>Mantenimiento del acuario para el pez damisela<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>El tama\u00f1o peque\u00f1o de los peces damisela te permitir\u00e1 poder tenerlos c\u00f3modamente en un acuario mediano-grande. La temperatura del agua debe estar entre los <strong>22,7 y los 27,2 grados cent\u00edgrados<\/strong>. <a href=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/parametros-acuario-ph-gh-kh\/\" target=\"_blank\" rel=\"noreferrer noopener\">El pH<\/a>, por su parte, ha de situarse entre 8,1 y 8,4. Un cambio brusco en este concepto puede perjudicar seriamente la salud de tus peces.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Es muy importante que cambies al menos el 20% del agua del acuario cada 2 semanas, aunque todo depender\u00e1 de la cantidad de peces que tengas. Si solo tienes uno, podr\u00e1s cambiar el 20% de agua una vez al mes. Procura siempre que tus damiselas tengan espacio suficiente para nadar y se encuentren a su paso cuevas, rocas y otros escondites.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:heading -->\n<h2><span class=\"ez-toc-section\" id=\"Convivencia_de_los_damiselas_con_otras_especies\"><\/span>Convivencia de los damiselas con otras especies<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>Por lo general, es m\u00e1s que recomendable <strong>mantener solos en el acuario a los peces damiselas<\/strong>. La mayor\u00eda de las especies de este tipo tienen un comportamiento agresivo y muy territorial. Con otros peces damisela pueden tener un buen comportamiento cuando son muy j\u00f3venes o viven en un acuario muy grande.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Sin embargo, con otras especies es necesario que puedas <strong>proporcionarles refugios<\/strong>, ya que los damiselas pueden ser agresivos en su comportamiento. A este respecto, debes procurar introducir a todos los peces a la vez para que se aclimaten al grupo. De lo contrario, si introduces un pez diferente m\u00e1s tarde el pez damisela tendr\u00e1 la impresi\u00f3n de que le quieren invadir su territorio.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Los damiselas, en definitiva, son <strong>peces muy resistentes e ideales para <\/strong><a href=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/como-elegir-el-mejor-acuario\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>tener en un acuario<\/strong><\/a>. Son muy atractivos y llamativos y son capaces de comer de todo. Sin embargo, tienden a ser un poco agresivos, por lo que habr\u00e1 que cuidar su comportamiento con el resto de especies y conocer sus caracter\u00edsticas para ver si pueden convivir juntos.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:shortcode -->\n        <div id=\"external-products-AQS43232\" class=\"row external-products\">\n            <img decoding=\"async\" id=\"load-products-AQS43232\" data-src=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/themes\/kiwoko\/inc\/assets\/images\/loading.gif\" width=\"50\" height=\"50\" alt=\"loading\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 50px; --smush-placeholder-aspect-ratio: 50\/50;\">\n        <\/div>\n        <script>\n        var id_products = \"AQS43232\";\n        id_products = id_products.replace(\/\\s\/g, '');\n        var all_ids = id_products.split(\",\");\n\n        \/\/ Agregar sufijo _M a todos los c\u00f3digos\n        var all_ids = all_ids.map(function(id) {\n            return id + '_M';\n        });\n\n        var not_found_products = 1;\n        var not_found_img_product = 0;\n        var ramdom_id = Math.round(Math.random() * 10000);\n        var grid = '12';\n\t\tvar width = '220';\n\t\tvar height = '220';\n        if(all_ids.length >= 4){\n            grid = '3';\n\t\t\twidth = '151';\n\t\t\theight = '151';\n        }else if(all_ids.length == 3){\n            grid = '4';\n\t\t\twidth = '211';\n\t\t\theight = '211';\n        }else if(all_ids.length == 2){\n            grid = '6';\n        }\n\t\n\tif(!items){\n        var feed = \"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/themes\/kiwoko\/feed-channable.xml\";\n        var request = new XMLHttpRequest();\n        request.open(\"GET\", feed, false);\n        request.send();\n        var xmlFromUrl = request.responseXML;\n        var parser = new DOMParser();\n        var xmlDoc = parser.parseFromString(feed, \"text\/xml\");\n        var items = xmlFromUrl.getElementsByTagName(\"item\");\n        }\n\n        var products_found = 0;\n        for (var item of items) {\n            all_ids.forEach(function(word, index) {\n                if(item.getElementsByTagName(\"g:item_group_id\")[0].textContent == word){\n                    not_found_products = 0;\n                    id_products = item.getElementsByTagName(\"g:item_group_id\")[0].textContent;\n                    var link = item.getElementsByTagName(\"link\")[0].textContent;\n                    var image_link = 'src=\"'+item.getElementsByTagName(\"g:image_link\")[0].textContent+'\" ';\n                    var title = item.getElementsByTagName(\"title\")[0].textContent;\n\t\t\t\t\tvar customLabel0 = item.getElementsByTagName(\"g:custom_label_0\")[0]?.textContent || '';\n                    var customLabel1 = item.getElementsByTagName(\"g:custom_label_1\")[0]?.textContent || '';\n                    var product = '<div class=\"col-md-'+grid+' text-center ds-analytics-blog-cross-selling-product order-'+index+'\" style=\"cursor:pointer;\" onclick=\"dataLayer.push({'+\n                    '\\'event\\':\\'crosseling_product_click\\', '+\n                    '\\'event_name\\':\\'crosseling_product_click\\', '+\n                    '\\'link_text\\':\\'\u00a1Comprar ahora!\\', '+\n                    '\\'link_url\\':\\''+link+'\\', '+\n                    '\\'category\\':\\''+customLabel0+'\/'+customLabel1+'\\', '+\n                    '\\'product_name\\':\\''+title+'\\''+\n                    '});window.open(\\''+link+'\\');\"><img id=\"'+id_products+'\" '+image_link+' class=\"product-img-shop\" alt=\"'+title+'\"><p><a href=\"'+link+'\" target=\"_blank\" title=\"'+title+'\" style=\"color:#212529;\" class=\"ds-analytics-blog-cross-selling-product\"><strong>'+title+'<\/strong><\/a><\/p><button id=\"product-addtocart-button\" class=\"action primary tocart btn btn--secondary btn--big\" title=\"\u00a1Comprar ahora!\" type=\"submit\">\u00a1Comprar ahora! <\/button><\/div>';\n \t\t\t\t    \/\/var product = '<div class=\"col-md-'+grid+' text-center ds-analytics-blog-cross-selling-product order-'+index+'\" style=\"cursor:pointer;\" onclick=\"dataLayer.push({\\'event\\':\\'blog_cross_selling_product\\', \\'ga4EventData\\': { \\'name\\':\\'d_blog\\', \\'category\\':\\'click\\', \\'label\\':\\'producto\\', \\'element\\': \\''+link+'\\'}});window.open(\\''+link+'\\');\"><img id=\"'+id_products+'\" '+image_link+' class=\"product-img-shop\" alt=\"'+title+'\"><p><a href=\"'+link+'\" target=\"_blank\" title=\"'+title+'\" style=\"color:#212529;\" class=\"ds-analytics-blog-cross-selling-product\"><strong>'+title+'<\/strong><\/a><\/p><button id=\"product-addtocart-button\" class=\"action primary tocart btn btn--secondary btn--big\" title=\"\u00a1Comprar ahora!\" type=\"submit\">\u00a1Comprar ahora! <\/button><\/div>'; \n                    var grid_div = document.getElementById(\"external-products-AQS43232\");\n                    grid_div.innerHTML += product;\n                    products_found++;\n                }\n            });\n            if(products_found == all_ids.length){\n                break;\n            }\n        }\n        document.getElementById(\"load-products-AQS43232\").style.display = \"none\";\n        <\/script>\n    \n<!-- \/wp:shortcode -->\n\n<!-- wp:table {\"className\":\"is-style-stripes\"} -->\n<figure class=\"wp-block-table is-style-stripes\"><table><tbody><tr><td>Para todo lo que necesitas en el cuidado y mantenimiento de tu acuario puedes visitar las <a href=\"https:\/\/www.kiwoko.mom\/tiendas\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>tiendas Kiwoko<\/strong><\/a><strong> <\/strong>o la web <a href=\"https:\/\/www.kiwoko.mom\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>kiwoko.mom<\/strong><\/a>. \u00a1Ahora tambi\u00e9n puedes hacer tu pedido <a href=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/servicio-venta-telefonica\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>v\u00eda telef\u00f3nica<\/strong><\/a>!<\/td><\/tr><\/tbody><\/table><\/figure>\n<!-- \/wp:table -->","protected":false},"excerpt":{"rendered":"<p>Los peces damisela son ideales para montar un acuario, pero es importante conocer bien sus caracter\u00edsticas y cuidados especiales. \u00a1Desc\u00fabrelo!<\/p>\n","protected":false},"author":40,"featured_media":33227,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1062],"tags":[1290],"class_list":["post-33183","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-peces","tag-familias-de-peces"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-json\/wp\/v2\/posts\/33183","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-json\/wp\/v2\/users\/40"}],"replies":[{"embeddable":true,"href":"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-json\/wp\/v2\/comments?post=33183"}],"version-history":[{"count":2,"href":"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-json\/wp\/v2\/posts\/33183\/revisions"}],"predecessor-version":[{"id":33252,"href":"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-json\/wp\/v2\/posts\/33183\/revisions\/33252"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-json\/wp\/v2\/media\/33227"}],"wp:attachment":[{"href":"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-json\/wp\/v2\/media?parent=33183"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-json\/wp\/v2\/categories?post=33183"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-json\/wp\/v2\/tags?post=33183"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}