{"id":34882,"date":"2022-09-23T14:34:06","date_gmt":"2022-09-23T12:34:06","guid":{"rendered":"https:\/\/www.kiwoko.mom\/blogmundoanimal\/?p=34882"},"modified":"2025-03-06T13:40:40","modified_gmt":"2025-03-06T12:40:40","slug":"practicar-mantrailing-con-perros","status":"publish","type":"post","link":"https:\/\/www.kiwoko.mom\/blogmundoanimal\/practicar-mantrailing-con-perros\/","title":{"rendered":"Practicar mantrailing con perros"},"content":{"rendered":"<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_82_2 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">\u00cdndice<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Alternar tabla de contenidos\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/practicar-mantrailing-con-perros\/#%C2%BFQue_es_el_mantrailing\" >\u00bfQu\u00e9 es el mantrailing?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/practicar-mantrailing-con-perros\/#%C2%BFMi_perro_es_apto_para_el_mantrailing\" >\u00bfMi perro es apto para el mantrailing?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/practicar-mantrailing-con-perros\/#%C2%BFQue_necesito_para_hacer_mantrailing_con_mi_perro\" >\u00bfQu\u00e9 necesito para hacer mantrailing con mi perro?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/practicar-mantrailing-con-perros\/#Beneficios_del_mantrailing_para_tu_perro\" >Beneficios del mantrailing para tu perro<\/a><\/li><\/ul><\/nav><\/div>\n<!-- wp:paragraph -->\n<p>\u00bfAlguna vez has o\u00eddo hablar de <strong>mantrailing<\/strong>? Se trata de una pr\u00e1ctica muy usada por la polic\u00eda y por los grupos de b\u00fasqueda y rescate de personas. El mantraling est\u00e1 cada vez m\u00e1s extendido por todo el mundo, tanto es as\u00ed que algunas personas lo practican con sus perros como una actividad l\u00fadica o deportiva.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:heading -->\n<h2><span class=\"ez-toc-section\" id=\"%C2%BFQue_es_el_mantrailing\"><\/span><strong>\u00bfQu\u00e9 es el mantrailing?<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>El mantrailing es un deporte canino que <strong>consiste en ense\u00f1ar al perro a seguir la estela de olor de referencia<\/strong> (es decir, una prenda u objeto que lleve el olor de una persona) y lograr que, mediante el uso de su olfato, encuentre a esa persona. El due\u00f1o gu\u00eda la actividad y el perro sigue las instrucciones que se le van dando. Normalmente, este deporte no se practica de forma colectiva para evitar que tu perro se desconcentre con otros perros. A\u00fan as\u00ed, el <strong>due\u00f1o del perro act\u00faa como apoyo,<\/strong> ayudando al animal cuando se bloquea o se despista, pero nunca da la soluci\u00f3n.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>No es necesario ir a una zona espec\u00edfica para hacer mantrailing, pero s\u00ed es conveniente elegir un lugar amplio que permita al perro desarrollar su capacidad de atenci\u00f3n y sin que haya ning\u00fan tipo de distracci\u00f3n.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:heading -->\n<h2><span class=\"ez-toc-section\" id=\"%C2%BFMi_perro_es_apto_para_el_mantrailing\"><\/span><strong>\u00bfMi perro es apto para el mantrailing?<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>Todos los perros, sean de la raza que sean y tengan el tama\u00f1o que tengan, pueden practicar el mantrailing. <strong>En cuanto a la edad, <\/strong>si tu perro es joven, debes tener en cuenta que, hasta que no cumpla los ocho meses de edad, no ser\u00e1 capaz mental y f\u00edsicamente de seguir rastros por trayectos largos, pero con los perros de avanzada edad no hay limitaci\u00f3n.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Lo m\u00e1s importante es que tu perro goce de buena salud. Este deporte canino <strong>a veces exige hacer varios kil\u00f3metros<\/strong>, por lo que llevar\u00e1 a tu perro varias horas de trabajo f\u00edsico y concentraci\u00f3n. Adem\u00e1s, recuerda que puede que <strong>el camino no sea llano <\/strong>y os encontr\u00e9is con terrenos con relieves o intransitables. Por este motivo, es importante que te asegures de que tu perro est\u00e9 sano y preparado para el esfuerzo.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:heading -->\n<h2><span class=\"ez-toc-section\" id=\"%C2%BFQue_necesito_para_hacer_mantrailing_con_mi_perro\"><\/span><strong>\u00bfQu\u00e9 necesito para hacer mantrailing con mi perro?<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>Para realizar mantrailing con tu perro necesitar\u00e1s pocas cosas, pero todas ellas son importantes para poder practicar correctamente este deporte:<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:list -->\n<ul><!-- wp:list-item -->\n<li>Un <a href=\"https:\/\/www.kiwoko.mom\/perros\/accesorios-para-perros\/paseo\/arneses\/\" target=\"_blank\" rel=\"noopener\"><strong>arn\u00e9s<\/strong> <\/a>que se ajuste bien al tama\u00f1o de tu perro y que sea de un color llamativo para la se\u00f1alizaci\u00f3n.<\/li>\n<!-- \/wp:list-item --><\/ul>\n<!-- \/wp:list -->\n\n<!-- wp:shortcode -->\n        <div id=\"external-products-GOTYFR6181\" class=\"row external-products\">\n            <img decoding=\"async\" id=\"load-products-GOTYFR6181\" data-src=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/themes\/kiwoko\/inc\/assets\/images\/loading.gif\" width=\"50\" height=\"50\" alt=\"loading\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 50px; --smush-placeholder-aspect-ratio: 50\/50;\">\n        <\/div>\n        <script>\n        var id_products = \"GOTYFR6181,GOTYFR6137\";\n        id_products = id_products.replace(\/\\s\/g, '');\n        var all_ids = id_products.split(\",\");\n\n        \/\/ Agregar sufijo _M a todos los c\u00f3digos\n        var all_ids = all_ids.map(function(id) {\n            return id + '_M';\n        });\n\n        var not_found_products = 1;\n        var not_found_img_product = 0;\n        var ramdom_id = Math.round(Math.random() * 10000);\n        var grid = '12';\n\t\tvar width = '220';\n\t\tvar height = '220';\n        if(all_ids.length >= 4){\n            grid = '3';\n\t\t\twidth = '151';\n\t\t\theight = '151';\n        }else if(all_ids.length == 3){\n            grid = '4';\n\t\t\twidth = '211';\n\t\t\theight = '211';\n        }else if(all_ids.length == 2){\n            grid = '6';\n        }\n\t\n\tif(!items){\n        var feed = \"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/themes\/kiwoko\/feed-channable.xml\";\n        var request = new XMLHttpRequest();\n        request.open(\"GET\", feed, false);\n        request.send();\n        var xmlFromUrl = request.responseXML;\n        var parser = new DOMParser();\n        var xmlDoc = parser.parseFromString(feed, \"text\/xml\");\n        var items = xmlFromUrl.getElementsByTagName(\"item\");\n        }\n\n        var products_found = 0;\n        for (var item of items) {\n            all_ids.forEach(function(word, index) {\n                if(item.getElementsByTagName(\"g:item_group_id\")[0].textContent == word){\n                    not_found_products = 0;\n                    id_products = item.getElementsByTagName(\"g:item_group_id\")[0].textContent;\n                    var link = item.getElementsByTagName(\"link\")[0].textContent;\n                    var image_link = 'src=\"'+item.getElementsByTagName(\"g:image_link\")[0].textContent+'\" ';\n                    var title = item.getElementsByTagName(\"title\")[0].textContent;\n\t\t\t\t\tvar customLabel0 = item.getElementsByTagName(\"g:custom_label_0\")[0]?.textContent || '';\n                    var customLabel1 = item.getElementsByTagName(\"g:custom_label_1\")[0]?.textContent || '';\n                    var product = '<div class=\"col-md-'+grid+' text-center ds-analytics-blog-cross-selling-product order-'+index+'\" style=\"cursor:pointer;\" onclick=\"dataLayer.push({'+\n                    '\\'event\\':\\'crosseling_product_click\\', '+\n                    '\\'event_name\\':\\'crosseling_product_click\\', '+\n                    '\\'link_text\\':\\'\u00a1Comprar ahora!\\', '+\n                    '\\'link_url\\':\\''+link+'\\', '+\n                    '\\'category\\':\\''+customLabel0+'\/'+customLabel1+'\\', '+\n                    '\\'product_name\\':\\''+title+'\\''+\n                    '});window.open(\\''+link+'\\');\"><img id=\"'+id_products+'\" '+image_link+' class=\"product-img-shop\" alt=\"'+title+'\"><p><a href=\"'+link+'\" target=\"_blank\" title=\"'+title+'\" style=\"color:#212529;\" class=\"ds-analytics-blog-cross-selling-product\"><strong>'+title+'<\/strong><\/a><\/p><button id=\"product-addtocart-button\" class=\"action primary tocart btn btn--secondary btn--big\" title=\"\u00a1Comprar ahora!\" type=\"submit\">\u00a1Comprar ahora! <\/button><\/div>';\n \t\t\t\t    \/\/var product = '<div class=\"col-md-'+grid+' text-center ds-analytics-blog-cross-selling-product order-'+index+'\" style=\"cursor:pointer;\" onclick=\"dataLayer.push({\\'event\\':\\'blog_cross_selling_product\\', \\'ga4EventData\\': { \\'name\\':\\'d_blog\\', \\'category\\':\\'click\\', \\'label\\':\\'producto\\', \\'element\\': \\''+link+'\\'}});window.open(\\''+link+'\\');\"><img id=\"'+id_products+'\" '+image_link+' class=\"product-img-shop\" alt=\"'+title+'\"><p><a href=\"'+link+'\" target=\"_blank\" title=\"'+title+'\" style=\"color:#212529;\" class=\"ds-analytics-blog-cross-selling-product\"><strong>'+title+'<\/strong><\/a><\/p><button id=\"product-addtocart-button\" class=\"action primary tocart btn btn--secondary btn--big\" title=\"\u00a1Comprar ahora!\" type=\"submit\">\u00a1Comprar ahora! <\/button><\/div>'; \n                    var grid_div = document.getElementById(\"external-products-GOTYFR6181\");\n                    grid_div.innerHTML += product;\n                    products_found++;\n                }\n            });\n            if(products_found == all_ids.length){\n                break;\n            }\n        }\n        document.getElementById(\"load-products-GOTYFR6181\").style.display = \"none\";\n        <\/script>\n    \n<!-- \/wp:shortcode -->\n\n<!-- wp:list -->\n<ul><!-- wp:list-item -->\n<li>Una <a href=\"https:\/\/www.kiwoko.mom\/perros\/accesorios-para-perros\/paseo\/correas\/\" target=\"_blank\" rel=\"noopener\"><strong>correa<\/strong><\/a> especializada de rastreo de entre cinco y quince metros.<\/li>\n<!-- \/wp:list-item --><\/ul>\n<!-- \/wp:list -->\n\n<!-- wp:shortcode -->\n        <div id=\"external-products-GOTYFR6061\" class=\"row external-products\">\n            <img decoding=\"async\" id=\"load-products-GOTYFR6061\" data-src=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/themes\/kiwoko\/inc\/assets\/images\/loading.gif\" width=\"50\" height=\"50\" alt=\"loading\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 50px; --smush-placeholder-aspect-ratio: 50\/50;\">\n        <\/div>\n        <script>\n        var id_products = \"GOTYFR6061,GOTYFR6012\";\n        id_products = id_products.replace(\/\\s\/g, '');\n        var all_ids = id_products.split(\",\");\n\n        \/\/ Agregar sufijo _M a todos los c\u00f3digos\n        var all_ids = all_ids.map(function(id) {\n            return id + '_M';\n        });\n\n        var not_found_products = 1;\n        var not_found_img_product = 0;\n        var ramdom_id = Math.round(Math.random() * 10000);\n        var grid = '12';\n\t\tvar width = '220';\n\t\tvar height = '220';\n        if(all_ids.length >= 4){\n            grid = '3';\n\t\t\twidth = '151';\n\t\t\theight = '151';\n        }else if(all_ids.length == 3){\n            grid = '4';\n\t\t\twidth = '211';\n\t\t\theight = '211';\n        }else if(all_ids.length == 2){\n            grid = '6';\n        }\n\t\n\tif(!items){\n        var feed = \"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/themes\/kiwoko\/feed-channable.xml\";\n        var request = new XMLHttpRequest();\n        request.open(\"GET\", feed, false);\n        request.send();\n        var xmlFromUrl = request.responseXML;\n        var parser = new DOMParser();\n        var xmlDoc = parser.parseFromString(feed, \"text\/xml\");\n        var items = xmlFromUrl.getElementsByTagName(\"item\");\n        }\n\n        var products_found = 0;\n        for (var item of items) {\n            all_ids.forEach(function(word, index) {\n                if(item.getElementsByTagName(\"g:item_group_id\")[0].textContent == word){\n                    not_found_products = 0;\n                    id_products = item.getElementsByTagName(\"g:item_group_id\")[0].textContent;\n                    var link = item.getElementsByTagName(\"link\")[0].textContent;\n                    var image_link = 'src=\"'+item.getElementsByTagName(\"g:image_link\")[0].textContent+'\" ';\n                    var title = item.getElementsByTagName(\"title\")[0].textContent;\n\t\t\t\t\tvar customLabel0 = item.getElementsByTagName(\"g:custom_label_0\")[0]?.textContent || '';\n                    var customLabel1 = item.getElementsByTagName(\"g:custom_label_1\")[0]?.textContent || '';\n                    var product = '<div class=\"col-md-'+grid+' text-center ds-analytics-blog-cross-selling-product order-'+index+'\" style=\"cursor:pointer;\" onclick=\"dataLayer.push({'+\n                    '\\'event\\':\\'crosseling_product_click\\', '+\n                    '\\'event_name\\':\\'crosseling_product_click\\', '+\n                    '\\'link_text\\':\\'\u00a1Comprar ahora!\\', '+\n                    '\\'link_url\\':\\''+link+'\\', '+\n                    '\\'category\\':\\''+customLabel0+'\/'+customLabel1+'\\', '+\n                    '\\'product_name\\':\\''+title+'\\''+\n                    '});window.open(\\''+link+'\\');\"><img id=\"'+id_products+'\" '+image_link+' class=\"product-img-shop\" alt=\"'+title+'\"><p><a href=\"'+link+'\" target=\"_blank\" title=\"'+title+'\" style=\"color:#212529;\" class=\"ds-analytics-blog-cross-selling-product\"><strong>'+title+'<\/strong><\/a><\/p><button id=\"product-addtocart-button\" class=\"action primary tocart btn btn--secondary btn--big\" title=\"\u00a1Comprar ahora!\" type=\"submit\">\u00a1Comprar ahora! <\/button><\/div>';\n \t\t\t\t    \/\/var product = '<div class=\"col-md-'+grid+' text-center ds-analytics-blog-cross-selling-product order-'+index+'\" style=\"cursor:pointer;\" onclick=\"dataLayer.push({\\'event\\':\\'blog_cross_selling_product\\', \\'ga4EventData\\': { \\'name\\':\\'d_blog\\', \\'category\\':\\'click\\', \\'label\\':\\'producto\\', \\'element\\': \\''+link+'\\'}});window.open(\\''+link+'\\');\"><img id=\"'+id_products+'\" '+image_link+' class=\"product-img-shop\" alt=\"'+title+'\"><p><a href=\"'+link+'\" target=\"_blank\" title=\"'+title+'\" style=\"color:#212529;\" class=\"ds-analytics-blog-cross-selling-product\"><strong>'+title+'<\/strong><\/a><\/p><button id=\"product-addtocart-button\" class=\"action primary tocart btn btn--secondary btn--big\" title=\"\u00a1Comprar ahora!\" type=\"submit\">\u00a1Comprar ahora! <\/button><\/div>'; \n                    var grid_div = document.getElementById(\"external-products-GOTYFR6061\");\n                    grid_div.innerHTML += product;\n                    products_found++;\n                }\n            });\n            if(products_found == all_ids.length){\n                break;\n            }\n        }\n        document.getElementById(\"load-products-GOTYFR6061\").style.display = \"none\";\n        <\/script>\n    \n<!-- \/wp:shortcode -->\n\n<!-- wp:list -->\n<ul><!-- wp:list-item -->\n<li>Algunas <a href=\"https:\/\/www.kiwoko.mom\/perros\/comida-para-perros\/snacks-y-huesos-para-perros\/\" target=\"_blank\" rel=\"noopener\"><strong>golosinas<\/strong><\/a> a modo de recompensa por haber superado obst\u00e1culos o por cumplir el prop\u00f3sito.<\/li>\n<!-- \/wp:list-item --><\/ul>\n<!-- \/wp:list -->\n\n<!-- wp:shortcode -->\n        <div id=\"external-products-DGX88673\" class=\"row external-products\">\n            <img decoding=\"async\" id=\"load-products-DGX88673\" data-src=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/themes\/kiwoko\/inc\/assets\/images\/loading.gif\" width=\"50\" height=\"50\" alt=\"loading\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 50px; --smush-placeholder-aspect-ratio: 50\/50;\">\n        <\/div>\n        <script>\n        var id_products = \"DGX88673\";\n        id_products = id_products.replace(\/\\s\/g, '');\n        var all_ids = id_products.split(\",\");\n\n        \/\/ Agregar sufijo _M a todos los c\u00f3digos\n        var all_ids = all_ids.map(function(id) {\n            return id + '_M';\n        });\n\n        var not_found_products = 1;\n        var not_found_img_product = 0;\n        var ramdom_id = Math.round(Math.random() * 10000);\n        var grid = '12';\n\t\tvar width = '220';\n\t\tvar height = '220';\n        if(all_ids.length >= 4){\n            grid = '3';\n\t\t\twidth = '151';\n\t\t\theight = '151';\n        }else if(all_ids.length == 3){\n            grid = '4';\n\t\t\twidth = '211';\n\t\t\theight = '211';\n        }else if(all_ids.length == 2){\n            grid = '6';\n        }\n\t\n\tif(!items){\n        var feed = \"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/themes\/kiwoko\/feed-channable.xml\";\n        var request = new XMLHttpRequest();\n        request.open(\"GET\", feed, false);\n        request.send();\n        var xmlFromUrl = request.responseXML;\n        var parser = new DOMParser();\n        var xmlDoc = parser.parseFromString(feed, \"text\/xml\");\n        var items = xmlFromUrl.getElementsByTagName(\"item\");\n        }\n\n        var products_found = 0;\n        for (var item of items) {\n            all_ids.forEach(function(word, index) {\n                if(item.getElementsByTagName(\"g:item_group_id\")[0].textContent == word){\n                    not_found_products = 0;\n                    id_products = item.getElementsByTagName(\"g:item_group_id\")[0].textContent;\n                    var link = item.getElementsByTagName(\"link\")[0].textContent;\n                    var image_link = 'src=\"'+item.getElementsByTagName(\"g:image_link\")[0].textContent+'\" ';\n                    var title = item.getElementsByTagName(\"title\")[0].textContent;\n\t\t\t\t\tvar customLabel0 = item.getElementsByTagName(\"g:custom_label_0\")[0]?.textContent || '';\n                    var customLabel1 = item.getElementsByTagName(\"g:custom_label_1\")[0]?.textContent || '';\n                    var product = '<div class=\"col-md-'+grid+' text-center ds-analytics-blog-cross-selling-product order-'+index+'\" style=\"cursor:pointer;\" onclick=\"dataLayer.push({'+\n                    '\\'event\\':\\'crosseling_product_click\\', '+\n                    '\\'event_name\\':\\'crosseling_product_click\\', '+\n                    '\\'link_text\\':\\'\u00a1Comprar ahora!\\', '+\n                    '\\'link_url\\':\\''+link+'\\', '+\n                    '\\'category\\':\\''+customLabel0+'\/'+customLabel1+'\\', '+\n                    '\\'product_name\\':\\''+title+'\\''+\n                    '});window.open(\\''+link+'\\');\"><img id=\"'+id_products+'\" '+image_link+' class=\"product-img-shop\" alt=\"'+title+'\"><p><a href=\"'+link+'\" target=\"_blank\" title=\"'+title+'\" style=\"color:#212529;\" class=\"ds-analytics-blog-cross-selling-product\"><strong>'+title+'<\/strong><\/a><\/p><button id=\"product-addtocart-button\" class=\"action primary tocart btn btn--secondary btn--big\" title=\"\u00a1Comprar ahora!\" type=\"submit\">\u00a1Comprar ahora! <\/button><\/div>';\n \t\t\t\t    \/\/var product = '<div class=\"col-md-'+grid+' text-center ds-analytics-blog-cross-selling-product order-'+index+'\" style=\"cursor:pointer;\" onclick=\"dataLayer.push({\\'event\\':\\'blog_cross_selling_product\\', \\'ga4EventData\\': { \\'name\\':\\'d_blog\\', \\'category\\':\\'click\\', \\'label\\':\\'producto\\', \\'element\\': \\''+link+'\\'}});window.open(\\''+link+'\\');\"><img id=\"'+id_products+'\" '+image_link+' class=\"product-img-shop\" alt=\"'+title+'\"><p><a href=\"'+link+'\" target=\"_blank\" title=\"'+title+'\" style=\"color:#212529;\" class=\"ds-analytics-blog-cross-selling-product\"><strong>'+title+'<\/strong><\/a><\/p><button id=\"product-addtocart-button\" class=\"action primary tocart btn btn--secondary btn--big\" title=\"\u00a1Comprar ahora!\" type=\"submit\">\u00a1Comprar ahora! <\/button><\/div>'; \n                    var grid_div = document.getElementById(\"external-products-DGX88673\");\n                    grid_div.innerHTML += product;\n                    products_found++;\n                }\n            });\n            if(products_found == all_ids.length){\n                break;\n            }\n        }\n        document.getElementById(\"load-products-DGX88673\").style.display = \"none\";\n        <\/script>\n    \n<!-- \/wp:shortcode -->\n\n<!-- wp:list -->\n<ul><!-- wp:list-item -->\n<li>Un <a href=\"https:\/\/www.kiwoko.mom\/perros\/accesorios-para-perros\/comederos-y-bebederos\/de-viaje\/\" target=\"_blank\" rel=\"noopener\"><strong>bebedero<\/strong><\/a> para cuidar la hidrataci\u00f3n del perro.<\/li>\n<!-- \/wp:list-item --><\/ul>\n<!-- \/wp:list -->\n\n<!-- wp:shortcode -->\n        <div id=\"external-products-OUT88701\" class=\"row external-products\">\n            <img decoding=\"async\" id=\"load-products-OUT88701\" data-src=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/themes\/kiwoko\/inc\/assets\/images\/loading.gif\" width=\"50\" height=\"50\" alt=\"loading\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 50px; --smush-placeholder-aspect-ratio: 50\/50;\">\n        <\/div>\n        <script>\n        var id_products = \"OUT88701\";\n        id_products = id_products.replace(\/\\s\/g, '');\n        var all_ids = id_products.split(\",\");\n\n        \/\/ Agregar sufijo _M a todos los c\u00f3digos\n        var all_ids = all_ids.map(function(id) {\n            return id + '_M';\n        });\n\n        var not_found_products = 1;\n        var not_found_img_product = 0;\n        var ramdom_id = Math.round(Math.random() * 10000);\n        var grid = '12';\n\t\tvar width = '220';\n\t\tvar height = '220';\n        if(all_ids.length >= 4){\n            grid = '3';\n\t\t\twidth = '151';\n\t\t\theight = '151';\n        }else if(all_ids.length == 3){\n            grid = '4';\n\t\t\twidth = '211';\n\t\t\theight = '211';\n        }else if(all_ids.length == 2){\n            grid = '6';\n        }\n\t\n\tif(!items){\n        var feed = \"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/themes\/kiwoko\/feed-channable.xml\";\n        var request = new XMLHttpRequest();\n        request.open(\"GET\", feed, false);\n        request.send();\n        var xmlFromUrl = request.responseXML;\n        var parser = new DOMParser();\n        var xmlDoc = parser.parseFromString(feed, \"text\/xml\");\n        var items = xmlFromUrl.getElementsByTagName(\"item\");\n        }\n\n        var products_found = 0;\n        for (var item of items) {\n            all_ids.forEach(function(word, index) {\n                if(item.getElementsByTagName(\"g:item_group_id\")[0].textContent == word){\n                    not_found_products = 0;\n                    id_products = item.getElementsByTagName(\"g:item_group_id\")[0].textContent;\n                    var link = item.getElementsByTagName(\"link\")[0].textContent;\n                    var image_link = 'src=\"'+item.getElementsByTagName(\"g:image_link\")[0].textContent+'\" ';\n                    var title = item.getElementsByTagName(\"title\")[0].textContent;\n\t\t\t\t\tvar customLabel0 = item.getElementsByTagName(\"g:custom_label_0\")[0]?.textContent || '';\n                    var customLabel1 = item.getElementsByTagName(\"g:custom_label_1\")[0]?.textContent || '';\n                    var product = '<div class=\"col-md-'+grid+' text-center ds-analytics-blog-cross-selling-product order-'+index+'\" style=\"cursor:pointer;\" onclick=\"dataLayer.push({'+\n                    '\\'event\\':\\'crosseling_product_click\\', '+\n                    '\\'event_name\\':\\'crosseling_product_click\\', '+\n                    '\\'link_text\\':\\'\u00a1Comprar ahora!\\', '+\n                    '\\'link_url\\':\\''+link+'\\', '+\n                    '\\'category\\':\\''+customLabel0+'\/'+customLabel1+'\\', '+\n                    '\\'product_name\\':\\''+title+'\\''+\n                    '});window.open(\\''+link+'\\');\"><img id=\"'+id_products+'\" '+image_link+' class=\"product-img-shop\" alt=\"'+title+'\"><p><a href=\"'+link+'\" target=\"_blank\" title=\"'+title+'\" style=\"color:#212529;\" class=\"ds-analytics-blog-cross-selling-product\"><strong>'+title+'<\/strong><\/a><\/p><button id=\"product-addtocart-button\" class=\"action primary tocart btn btn--secondary btn--big\" title=\"\u00a1Comprar ahora!\" type=\"submit\">\u00a1Comprar ahora! <\/button><\/div>';\n \t\t\t\t    \/\/var product = '<div class=\"col-md-'+grid+' text-center ds-analytics-blog-cross-selling-product order-'+index+'\" style=\"cursor:pointer;\" onclick=\"dataLayer.push({\\'event\\':\\'blog_cross_selling_product\\', \\'ga4EventData\\': { \\'name\\':\\'d_blog\\', \\'category\\':\\'click\\', \\'label\\':\\'producto\\', \\'element\\': \\''+link+'\\'}});window.open(\\''+link+'\\');\"><img id=\"'+id_products+'\" '+image_link+' class=\"product-img-shop\" alt=\"'+title+'\"><p><a href=\"'+link+'\" target=\"_blank\" title=\"'+title+'\" style=\"color:#212529;\" class=\"ds-analytics-blog-cross-selling-product\"><strong>'+title+'<\/strong><\/a><\/p><button id=\"product-addtocart-button\" class=\"action primary tocart btn btn--secondary btn--big\" title=\"\u00a1Comprar ahora!\" type=\"submit\">\u00a1Comprar ahora! <\/button><\/div>'; \n                    var grid_div = document.getElementById(\"external-products-OUT88701\");\n                    grid_div.innerHTML += product;\n                    products_found++;\n                }\n            });\n            if(products_found == all_ids.length){\n                break;\n            }\n        }\n        document.getElementById(\"load-products-OUT88701\").style.display = \"none\";\n        <\/script>\n    \n<!-- \/wp:shortcode -->\n\n<!-- wp:list -->\n<ul><!-- wp:list-item -->\n<li>Una <strong>bolsa herm\u00e9tica<\/strong> para transportar el objeto que nuestro perro olfatear\u00e1.<\/li>\n<!-- \/wp:list-item --><\/ul>\n<!-- \/wp:list -->\n\n<!-- wp:heading -->\n<h2><span class=\"ez-toc-section\" id=\"Beneficios_del_mantrailing_para_tu_perro\"><\/span><strong>Beneficios del mantrailing para tu perro<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>Realizar mantrailing tiene muchos beneficios para tu perro. Aqu\u00ed te contamos algunos de ellos:<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:list -->\n<ul><!-- wp:list-item -->\n<li><strong>Refuerza su confianza:<\/strong> Al trabajar de manera aut\u00f3noma, tu perro reforzar\u00e1 su confianza en s\u00ed mismo y aumentar\u00e1 su independencia y su capacidad resolutiva.<br><\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li><strong>Estrecha el v\u00ednculo entre tu perro y t\u00fa:<\/strong> Al realizar una actividad diferente ver\u00e1s c\u00f3mo tu perro se desenvuelve para hacer una tarea y podr\u00e1s conocer m\u00e1s y mejor su temperamento a la vez que el aumenta su confianza hacia ti.<br><\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li><strong>Ayuda a resolver problemas de comportamiento<\/strong>: Si tu perro es miedoso, el mantrailing podr\u00eda ayudarle a ganar seguridad y reducir sus inseguridades y miedos.<br><\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li><strong>Aumenta su creatividad:<\/strong> En la b\u00fasqueda de solucionar problemas y tener una meta, tu perro pensar\u00e1 en c\u00f3mo resolverlos y c\u00f3mo llegar hasta su objetivo. Adem\u00e1s, le permitir\u00e1 despertar su naturaleza rastreadora.<br><\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li><strong>Mejora su condici\u00f3n f\u00edsica:<\/strong> Al moverse se mantendr\u00e1 activo y esto lo estimular\u00e1 tanto f\u00edsica como cognitivamente.<\/li>\n<!-- \/wp:list-item --><\/ul>\n<!-- \/wp:list -->\n\n<!-- wp:paragraph -->\n<p>Ahora que ya sabes que el mantrailing es uno de los deportes caninos que m\u00e1s beneficios aporta a tu perro, \u00bfa qu\u00e9 esperas para llevarlo a un club de <strong>mantraling<\/strong> o ponerlo en pr\u00e1ctica por tu cuenta? \u00a1Disfrutar\u00e1s de un plan tan divertido como original!<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:table {\"className\":\"is-style-stripes\"} -->\n<figure class=\"wp-block-table is-style-stripes\"><table><tbody><tr><td>Recuerda que en<a href=\"https:\/\/www.kiwoko.mom\/\" target=\"_blank\" rel=\"noopener\"> <strong>Kiwoko<\/strong><\/a> y en <a href=\"https:\/\/www.kiwoko.mom\/tiendas?showMap=true&amp;horizontalView=true&amp;isForm=true.html\" target=\"_blank\" rel=\"noopener\"><strong>nuestras tiendas f\u00edsicas<\/strong><\/a> tienes todo lo que necesitas para realizar este deporte para perros.<\/td><\/tr><\/tbody><\/table><\/figure>\n<!-- \/wp:table -->","protected":false},"excerpt":{"rendered":"<p>El mantrailing es una actividad que tiene muchos m\u00e1s beneficios de los que te imaginas. Desc\u00fabrelos en este art\u00edculo.<\/p>\n","protected":false},"author":40,"featured_media":34885,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1089,1071],"tags":[1266,1272],"class_list":["post-34882","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-disfruta-de-tu-mascota","category-perros","tag-curiosidades","tag-viajes"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-json\/wp\/v2\/posts\/34882","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-json\/wp\/v2\/users\/40"}],"replies":[{"embeddable":true,"href":"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-json\/wp\/v2\/comments?post=34882"}],"version-history":[{"count":8,"href":"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-json\/wp\/v2\/posts\/34882\/revisions"}],"predecessor-version":[{"id":50514,"href":"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-json\/wp\/v2\/posts\/34882\/revisions\/50514"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-json\/wp\/v2\/media\/34885"}],"wp:attachment":[{"href":"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-json\/wp\/v2\/media?parent=34882"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-json\/wp\/v2\/categories?post=34882"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-json\/wp\/v2\/tags?post=34882"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}