{"id":44326,"date":"2025-03-14T11:46:25","date_gmt":"2025-03-14T10:46:25","guid":{"rendered":"https:\/\/www.kiwoko.mom\/blogmundoanimal\/?p=44326"},"modified":"2025-12-01T08:34:15","modified_gmt":"2025-12-01T07:34:15","slug":"proyecto-momentos-by-kiwoko","status":"publish","type":"post","link":"https:\/\/www.kiwoko.mom\/blogmundoanimal\/proyecto-momentos-by-kiwoko\/","title":{"rendered":"Programa &#8216;Momentos by Kiwoko&#8217;: Terapia Asistida con Perros para transformar vidas"},"content":{"rendered":"<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_82_2 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">\u00cdndice<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Alternar tabla de contenidos\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/proyecto-momentos-by-kiwoko\/#%C2%BFQue_es_%C2%ABMomentos_by_Kiwoko%C2%BB\" >\u00bfQu\u00e9 es \u00abMomentos by Kiwoko\u00bb?<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/proyecto-momentos-by-kiwoko\/#Programa_de_Intervencion_Asistida_con_Perros_de_Terapia\" >Programa de Intervenci\u00f3n Asistida con Perros de Terapia<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/proyecto-momentos-by-kiwoko\/#Programa_de_Formacion_para_jovenes\" >Programa de Formaci\u00f3n para j\u00f3venes<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/proyecto-momentos-by-kiwoko\/#%C2%BFCuales_son_los_beneficios_de_los_perros_de_terapia\" >\u00bfCu\u00e1les son los beneficios de los perros de terapia?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/proyecto-momentos-by-kiwoko\/#Sobre_nuestro_Partner_Yaracan\" >Sobre nuestro Partner: Yaracan<\/a><\/li><\/ul><\/nav><\/div>\n<!-- wp:paragraph -->\n<p>Desde <strong>Kiwoko<\/strong> y en colaboraci\u00f3n con Hill's os queremos presentar \"Momentos by Kiwoko\", un programa de terapia asistida con perros para ni\u00f1os y j\u00f3venes con necesidades especiales.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>\u00bfQuieres saber c\u00f3mo funciona este nuevo proyecto?<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>\u00a1Sigue leyendo!<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:heading -->\n<h2 class=\"wp-block-heading\">\u00bfQu\u00e9 es \"Momentos by Kiwoko\"?<\/h2>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p><strong>Momentos by Kiwoko es un nuevo proyecto creado en colaboraci\u00f3n con <a href=\"https:\/\/www.hillspet.es\/\" target=\"_blank\" rel=\"noopener\" title=\"Hill\u2019s\">Hill's<\/a><\/strong>. <\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>\"<strong>Momentos by Kiwoko<\/strong>\" es un programa de Intervenci\u00f3n Asistida con Perros de Terapia en entornos escolares para ni\u00f1os y ni\u00f1as con necesidades educativas especiales, discapacidad, pluridiscapacidad o riesgo de exclusi\u00f3n social. <\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Adem\u00e1s, patrocinamos un programa para j\u00f3venes en riesgo de exclusi\u00f3n social, con el objetivo de que se conviertan en futuros t\u00e9cnicos de IAA. <\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:quote -->\n<blockquote class=\"wp-block-quote\"><!-- wp:paragraph {\"align\":\"center\",\"fontSize\":\"medium\"} -->\n<p class=\"has-text-align-center has-medium-font-size\"><em>El <strong>objetivo de este proyecto es llegar a ni\u00f1os\/as<\/strong> que, por su condici\u00f3n f\u00edsica, emocional, social o psicol\u00f3gica <strong>no pueden disfrutar de los beneficios que aportan los animales de compa\u00f1\u00eda.<\/strong><\/em> <\/p>\n<!-- \/wp:paragraph --><\/blockquote>\n<!-- \/wp:quote -->\n\n<!-- wp:paragraph -->\n<p>Por tanto, y como hemos comentado, este nuevo proyecto abarca dos programas diferentes: <\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:list -->\n<ul class=\"wp-block-list\"><!-- wp:list-item -->\n<li>Por un lado, un <strong>Programa de Terapia Asistida<\/strong>.<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>Y por otro, un <strong>Programa de Formaci\u00f3n para j\u00f3venes<\/strong>.<\/li>\n<!-- \/wp:list-item --><\/ul>\n<!-- \/wp:list -->\n\n<!-- wp:image {\"id\":44482,\"width\":\"840px\",\"height\":\"550px\",\"sizeSlug\":\"large\",\"linkDestination\":\"none\",\"align\":\"center\"} -->\n<figure class=\"wp-block-image aligncenter size-large is-resized\"><img decoding=\"async\" width=\"1024\" height=\"671\" data-src=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/uploads\/2024\/01\/Programa-Momentos-Perros-1024x671.jpg\" alt=\"Programa Momentos by Kiwoko Perros\" class=\"wp-image-44482 lazyload\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/671;width:840px;height:550px\" data-srcset=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/uploads\/2024\/01\/Programa-Momentos-Perros-1024x671.jpg 1024w, https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/uploads\/2024\/01\/Programa-Momentos-Perros-300x196.jpg 300w, https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/uploads\/2024\/01\/Programa-Momentos-Perros-768x503.jpg 768w, https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/uploads\/2024\/01\/Programa-Momentos-Perros.jpg 1333w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><figcaption class=\"wp-element-caption\">Programa Momentos by Kiwoko<\/figcaption><\/figure>\n<!-- \/wp:image -->\n\n<!-- wp:heading {\"level\":3,\"style\":{\"color\":{\"background\":\"#eeeeeeed\"}}} -->\n<h3 class=\"wp-block-heading has-background\" style=\"background-color:#eeeeeeed\"><span class=\"ez-toc-section\" id=\"Programa_de_Intervencion_Asistida_con_Perros_de_Terapia\"><\/span>Programa de Intervenci\u00f3n Asistida con Perros de Terapia<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>En primer lugar, nuestro <strong>Programa Asistencial con Perros de Terapia<\/strong> est\u00e1 dirigido a ni\u00f1os, ni\u00f1as y adolescentes en escuelas con necesidades educativas especiales y discapacidad. <\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Estos programas son trimestrales con periodicidad semanal, y en cada trimestre se atiende a 30 alumnos. <\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>El programa comenz\u00f3 el 29 de septiembre de 2023, en la <strong><a href=\"https:\/\/www.asociacionsipuedo.com\/\" target=\"_blank\" rel=\"noopener nofollow\" title=\"Asociaci\u00f3n S\u00ed Puedo - Colegio los \u00c1lamos\">Asociaci\u00f3n S\u00ed Puedo - Colegio los \u00c1lamos<\/a><\/strong>, donde un total de <strong>90 alumnos<\/strong> con pluridiscapacidad y TEA han participado en un programa especial que, a lo largo de <strong>tres trimestres<\/strong>, les ha permitido disfrutar <strong>cada viernes<\/strong> de los m\u00faltiples beneficios que aportan los animales de compa\u00f1\u00eda. De ellos, <strong>11 alumnos han contado con becas<\/strong>. <\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:image {\"id\":44481,\"width\":\"815px\",\"height\":\"545px\",\"sizeSlug\":\"large\",\"linkDestination\":\"none\",\"align\":\"center\"} -->\n<figure class=\"wp-block-image aligncenter size-large is-resized\"><img decoding=\"async\" width=\"1024\" height=\"686\" data-src=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/uploads\/2024\/01\/Programa-Momentos-by-Kiwoko-Terapia-Asistida-1024x686.jpg\" alt=\"Programa Momentos Terapia Asistida\" class=\"wp-image-44481 lazyload\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/686;width:815px;height:545px\" data-srcset=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/uploads\/2024\/01\/Programa-Momentos-by-Kiwoko-Terapia-Asistida-1024x686.jpg 1024w, https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/uploads\/2024\/01\/Programa-Momentos-by-Kiwoko-Terapia-Asistida-300x201.jpg 300w, https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/uploads\/2024\/01\/Programa-Momentos-by-Kiwoko-Terapia-Asistida-768x514.jpg 768w, https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/uploads\/2024\/01\/Programa-Momentos-by-Kiwoko-Terapia-Asistida.jpg 1333w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/figure>\n<!-- \/wp:image -->\n\n<!-- wp:paragraph -->\n<p>En el curso 2024 - 2025, nuestro Programa Asistencial con Perros de Terapia se est\u00e1 desarrollando en el <strong><a href=\"https:\/\/colegiocambrils.es\/\" target=\"_blank\" rel=\"noreferrer noopener\">Colegio Cambrils<\/a><\/strong>, en Carabanchel, un colegio de educaci\u00f3n especial centrado en atender las <strong>necesidades educativas de los alumnos con S\u00edndrome de Down<\/strong>. <\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>A lo largo de <strong>tres trimestres<\/strong>, <strong>90 alumnos con s\u00edndrome de Down<\/strong> disfrutar\u00e1n <strong>cada viernes<\/strong> de sesiones dise\u00f1adas para mejorar su bienestar y desarrollo. Adem\u00e1s, <strong>10 alumnos han recibido becas<\/strong>, y, como novedad este a\u00f1o, se han incorporado <strong>pr\u00e1cticas remuneradas<\/strong>, brindando nuevas oportunidades a los participantes. Tambi\u00e9n, uno de los alumnos becados del a\u00f1o anterior se ha integrado en la plantilla, reflejando el impacto positivo del programa.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:columns -->\n<div class=\"wp-block-columns\"><!-- wp:column -->\n<div class=\"wp-block-column\"><!-- wp:image {\"id\":50118,\"width\":\"285px\",\"height\":\"427px\",\"sizeSlug\":\"large\",\"linkDestination\":\"none\",\"align\":\"left\"} -->\n<figure class=\"wp-block-image alignleft size-large is-resized\"><img decoding=\"async\" width=\"683\" height=\"1024\" data-src=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/uploads\/2025\/02\/Momentos-by-KIWOKO_Programa-de-Terapia-Asistida-Colegio-Cambrils1-min-683x1024.jpg\" alt=\"Momentos bu Kiwoko Terapia asistida\" class=\"wp-image-50118 lazyload\" style=\"--smush-placeholder-width: 683px; --smush-placeholder-aspect-ratio: 683\/1024;width:285px;height:427px\" data-srcset=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/uploads\/2025\/02\/Momentos-by-KIWOKO_Programa-de-Terapia-Asistida-Colegio-Cambrils1-min-683x1024.jpg 683w, https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/uploads\/2025\/02\/Momentos-by-KIWOKO_Programa-de-Terapia-Asistida-Colegio-Cambrils1-min-200x300.jpg 200w, https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/uploads\/2025\/02\/Momentos-by-KIWOKO_Programa-de-Terapia-Asistida-Colegio-Cambrils1-min-768x1151.jpg 768w, https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/uploads\/2025\/02\/Momentos-by-KIWOKO_Programa-de-Terapia-Asistida-Colegio-Cambrils1-min-1025x1536.jpg 1025w, https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/uploads\/2025\/02\/Momentos-by-KIWOKO_Programa-de-Terapia-Asistida-Colegio-Cambrils1-min-1366x2048.jpg 1366w, https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/uploads\/2025\/02\/Momentos-by-KIWOKO_Programa-de-Terapia-Asistida-Colegio-Cambrils1-min-scaled.jpg 1708w\" data-sizes=\"(max-width: 683px) 100vw, 683px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/figure>\n<!-- \/wp:image --><\/div>\n<!-- \/wp:column -->\n\n<!-- wp:column -->\n<div class=\"wp-block-column\"><!-- wp:image {\"id\":50119,\"sizeSlug\":\"large\",\"linkDestination\":\"none\",\"align\":\"right\"} -->\n<figure class=\"wp-block-image alignright size-large\"><img decoding=\"async\" width=\"768\" height=\"1024\" data-src=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/uploads\/2025\/02\/Momentos-by-KIWOKO_Programa-de-Terapia-Asistida-Colegio-Cambrils3-min-768x1024.jpg\" alt=\"Momentos by kiwoko\" class=\"wp-image-50119 lazyload\" data-srcset=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/uploads\/2025\/02\/Momentos-by-KIWOKO_Programa-de-Terapia-Asistida-Colegio-Cambrils3-min-768x1024.jpg 768w, https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/uploads\/2025\/02\/Momentos-by-KIWOKO_Programa-de-Terapia-Asistida-Colegio-Cambrils3-min-225x300.jpg 225w, https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/uploads\/2025\/02\/Momentos-by-KIWOKO_Programa-de-Terapia-Asistida-Colegio-Cambrils3-min-1152x1536.jpg 1152w, https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/uploads\/2025\/02\/Momentos-by-KIWOKO_Programa-de-Terapia-Asistida-Colegio-Cambrils3-min-1536x2048.jpg 1536w, https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/uploads\/2025\/02\/Momentos-by-KIWOKO_Programa-de-Terapia-Asistida-Colegio-Cambrils3-min-scaled.jpg 1920w\" data-sizes=\"(max-width: 768px) 100vw, 768px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 768px; --smush-placeholder-aspect-ratio: 768\/1024;\" \/><\/figure>\n<!-- \/wp:image --><\/div>\n<!-- \/wp:column --><\/div>\n<!-- \/wp:columns -->\n\n<!-- wp:paragraph -->\n<p>Adem\u00e1s, durante este mismo curso,<strong> <\/strong>el programa ha sumado un centro muy especial: La <a href=\"https:\/\/www.gilgayarre.org\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Fundaci\u00f3n Gil Gayarre<\/strong><\/a>, que atiende a <strong>107 alumnos y alumnas<\/strong> con distintos grados de discapacidad (Moderada, grave y profunda) y con diagn\u00f3sticos asociados como <strong>autismo, problemas de conducta, trastornos de personalidad o discapacidades f\u00edsicas y sensoriales<\/strong>.Este colegio, concertado con la Consejer\u00eda de Educaci\u00f3n de la Comunidad de Madrid desde 1999, trabaja por el <strong>desarrollo integral del alumnado<\/strong>, promoviendo su <strong>autonom\u00eda y participaci\u00f3n activa<\/strong> a trav\u00e9s de metodolog\u00edas inclusivas y experiencias vivenciales como este proyecto con perros de terapia.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:spacer {\"height\":\"15px\"} -->\n<div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<!-- \/wp:spacer -->\n\n<!-- wp:columns -->\n<div class=\"wp-block-columns\"><!-- wp:column -->\n<div class=\"wp-block-column\"><!-- wp:image {\"id\":52906,\"sizeSlug\":\"large\",\"linkDestination\":\"none\",\"align\":\"left\"} -->\n<figure class=\"wp-block-image alignleft size-large\"><img decoding=\"async\" width=\"1024\" height=\"768\" data-src=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/uploads\/2025\/03\/Momentos-by-KIWOKO_3ra-Edicion-Gil-Gayarre_28-nov-2025-1-1024x768.jpg\" alt=\"fundaci\u00f3n gil gayarre momentos by kiwoko\" class=\"wp-image-52906 lazyload\" data-srcset=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/uploads\/2025\/03\/Momentos-by-KIWOKO_3ra-Edicion-Gil-Gayarre_28-nov-2025-1-1024x768.jpg 1024w, https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/uploads\/2025\/03\/Momentos-by-KIWOKO_3ra-Edicion-Gil-Gayarre_28-nov-2025-1-300x225.jpg 300w, https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/uploads\/2025\/03\/Momentos-by-KIWOKO_3ra-Edicion-Gil-Gayarre_28-nov-2025-1-768x576.jpg 768w, https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/uploads\/2025\/03\/Momentos-by-KIWOKO_3ra-Edicion-Gil-Gayarre_28-nov-2025-1-1536x1152.jpg 1536w, https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/uploads\/2025\/03\/Momentos-by-KIWOKO_3ra-Edicion-Gil-Gayarre_28-nov-2025-1-2048x1536.jpg 2048w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/768;\" \/><\/figure>\n<!-- \/wp:image --><\/div>\n<!-- \/wp:column -->\n\n<!-- wp:column -->\n<div class=\"wp-block-column\"><!-- wp:image {\"id\":52908,\"sizeSlug\":\"large\",\"linkDestination\":\"none\",\"align\":\"right\"} -->\n<figure class=\"wp-block-image alignright size-large\"><img decoding=\"async\" width=\"1024\" height=\"768\" data-src=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/uploads\/2025\/03\/Momentos-by-KIWOKO_3ra-Edicion-Gil-Gayarre_28-nov-2025-2-1024x768.jpg\" alt=\"programa funcacion gil gayarre\" class=\"wp-image-52908 lazyload\" data-srcset=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/uploads\/2025\/03\/Momentos-by-KIWOKO_3ra-Edicion-Gil-Gayarre_28-nov-2025-2-1024x768.jpg 1024w, https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/uploads\/2025\/03\/Momentos-by-KIWOKO_3ra-Edicion-Gil-Gayarre_28-nov-2025-2-300x225.jpg 300w, https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/uploads\/2025\/03\/Momentos-by-KIWOKO_3ra-Edicion-Gil-Gayarre_28-nov-2025-2-768x576.jpg 768w, https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/uploads\/2025\/03\/Momentos-by-KIWOKO_3ra-Edicion-Gil-Gayarre_28-nov-2025-2-1536x1152.jpg 1536w, https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/uploads\/2025\/03\/Momentos-by-KIWOKO_3ra-Edicion-Gil-Gayarre_28-nov-2025-2-2048x1536.jpg 2048w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/768;\" \/><\/figure>\n<!-- \/wp:image --><\/div>\n<!-- \/wp:column --><\/div>\n<!-- \/wp:columns -->\n\n<!-- wp:spacer {\"height\":\"15px\"} -->\n<div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<!-- \/wp:spacer -->\n\n<!-- wp:paragraph {\"style\":{\"color\":{\"background\":\"#eeeeeeed\"}}} -->\n<p class=\"has-background\" style=\"background-color:#eeeeeeed\">Adem\u00e1s, hemos tenido el privilegio de <strong><a href=\"https:\/\/www.rtve.es\/play\/audios\/madrid-informativos-rne\/cronica-madrid-informativo-cronica-madrid-31-01-25\/16430872\/\" target=\"_blank\" rel=\"noopener nofollow\" title=\"\">estar en RNE en el colegio<\/a><\/strong>, donde pudieron vivir de cerca la magia de <strong>Momentos by Kiwoko<\/strong>. Durante su visita, recogieron los testimonios de los ni\u00f1os y profesores, quienes compartieron su experiencia y el impacto positivo que los perros de terapia tienen en su d\u00eda a d\u00eda. \u00a1No os lo perd\u00e1is! \ud83c\udf99\ud83d\udc36\u2728<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:heading {\"level\":4} -->\n<h4 class=\"wp-block-heading\">D\u00eda Internacional de las Personas con Discapacidad: La fuerza de los perros de terapia<\/h4>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>Cada 3 de diciembre se conmemora el <strong>D\u00eda Internacional de las Personas con Discapacidad<\/strong>, una fecha clave para visibilizar los retos que enfrentan millones de personas en su d\u00eda a d\u00eda y, sobre todo, para recordar que la inclusi\u00f3n, la empat\u00eda y el respeto deben estar presentes en todos los \u00e1mbitos de la sociedad.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Desde Kiwoko, creemos firmemente que <strong>los animales tienen un papel fundamental en ese camino hacia una sociedad m\u00e1s justa<\/strong> e inclusiva. Y es aqu\u00ed donde iniciativas como \u201c<em>Momentos by Kiwoko<\/em>\u201d cobran todo el sentido del mundo.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Los perros de terapia son mucho m\u00e1s que compa\u00f1eros peludos: <strong>Son aliados emocionales<\/strong>, motores de confianza y puentes para la conexi\u00f3n social. En personas con distintas discapacidades (Ya sean f\u00edsicas, intelectuales o sensoriales), la <strong>intervenci\u00f3n asistida con animales<\/strong> puede marcar una diferencia real en su bienestar.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:heading {\"level\":4} -->\n<h4 class=\"wp-block-heading\">\u00bfC\u00f3mo ayudan los perros de terapia a las personas con discapacidad?<\/h4>\n<!-- \/wp:heading -->\n\n<!-- wp:heading {\"level\":5} -->\n<h5 class=\"wp-block-heading\">Mejoran el estado emocional y reducen el estr\u00e9s<\/h5>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>El contacto con un perro de terapia <strong>genera una sensaci\u00f3n inmediata de calma<\/strong>. Su sola presencia puede reducir la ansiedad, mejorar el estado de \u00e1nimo y favorecer una actitud m\u00e1s positiva frente a los desaf\u00edos del d\u00eda a d\u00eda.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:heading {\"level\":5} -->\n<h5 class=\"wp-block-heading\">Fomentan la autonom\u00eda y la autoestima<\/h5>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>Realizar tareas junto al perro, como pasearlo, acariciarlo o participar en juegos dirigidos,<strong> refuerza la sensaci\u00f3n de logro y ayuda a desarrollar habilidades <\/strong>que muchas veces se ven afectadas por la discapacidad.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:heading {\"level\":5} -->\n<h5 class=\"wp-block-heading\">Promueven la integraci\u00f3n social<\/h5>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p><strong>Los perros rompen barreras<\/strong>. Su presencia en sesiones grupales o actividades compartidas facilita la comunicaci\u00f3n, impulsa la interacci\u00f3n entre personas y crea un entorno m\u00e1s accesible, afectivo y libre de juicios.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:heading {\"level\":5} -->\n<h5 class=\"wp-block-heading\">Estimulan habilidades f\u00edsicas y cognitivas<\/h5>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>Desde mejorar la motricidad fina hasta trabajar la atenci\u00f3n y la memoria, l<strong>as terapias con perros se adaptan a las necesidades espec\u00edficas de cada persona<\/strong>, favoreciendo su desarrollo integral de forma l\u00fadica y motivadora.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:heading {\"level\":3,\"style\":{\"color\":{\"background\":\"#eeeeeeed\"}}} -->\n<h3 class=\"wp-block-heading has-background\" style=\"background-color:#eeeeeeed\"><span class=\"ez-toc-section\" id=\"Programa_de_Formacion_para_jovenes\"><\/span>Programa de Formaci\u00f3n para j\u00f3venes<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>Por otro lado, hemos patrocinado un <strong>Programa formativo para que estos j\u00f3venes<\/strong> puedan convertirse en un futuro en t\u00e9cnicos y expertos en intervenciones asistidas con animales. <\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Estos programas arrancaron el 21 de octubre de 2023, y son bimensuales, contando con 100 horas de formaci\u00f3n. <\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:image {\"id\":44483,\"width\":\"661px\",\"height\":\"438px\",\"sizeSlug\":\"large\",\"linkDestination\":\"none\",\"align\":\"center\"} -->\n<figure class=\"wp-block-image aligncenter size-large is-resized\"><img decoding=\"async\" width=\"1024\" height=\"680\" data-src=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/uploads\/2024\/01\/Programa-Momentos-Formacion-1024x680.jpg\" alt=\"Programa Momentos Programa de formaci\u00f3n\" class=\"wp-image-44483 lazyload\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/680;width:661px;height:438px\" data-srcset=\"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/uploads\/2024\/01\/Programa-Momentos-Formacion-1024x680.jpg 1024w, https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/uploads\/2024\/01\/Programa-Momentos-Formacion-300x199.jpg 300w, https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/uploads\/2024\/01\/Programa-Momentos-Formacion-768x510.jpg 768w, https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-content\/uploads\/2024\/01\/Programa-Momentos-Formacion.jpg 1333w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/figure>\n<!-- \/wp:image -->\n\n<!-- wp:paragraph -->\n<p>Adem\u00e1s, en nuestra segunda edici\u00f3n hemos incorporado un nuevo programa de becas con pr\u00e1cticas remuneradas. <\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:heading -->\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"%C2%BFCuales_son_los_beneficios_de_los_perros_de_terapia\"><\/span>\u00bfCu\u00e1les son los beneficios de los perros de terapia?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>Los <strong>perros de terapia asistida pueden ayudar a las personas con necesidades especiales<\/strong> de muchas maneras, algunas de las m\u00e1s importantes son:<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:list -->\n<ul class=\"wp-block-list\"><!-- wp:list-item -->\n<li>Aparecen en un lugar donde no se les espera y <strong>se convierten en el centro de atenci\u00f3n<\/strong>.<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>El perro no juzga, no critica, no siente l\u00e1stima ni pena.<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>Los perros <strong>ayudan a segregar endorfinas y oxitocina<\/strong>, y adem\u00e1s, ayudan a reducir el ritmo card\u00edaco, la presi\u00f3n arterial y los niveles de cortisol en sangre. <\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>Su acercamiento no es invasivo y establece desde el principio una <strong>relaci\u00f3n sincera<\/strong> centr\u00e1ndose en la persona y no en sus problemas. <\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>Adem\u00e1s, los perros de terapia fomentan la comunicaci\u00f3n y la empat\u00eda, reducen el aislamiento e incrementan la autoestima, las conductas de juego y el trabajo en equipo.<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li><strong>Acceden a las personas a trav\u00e9s del \u00e1rea emocional<\/strong>, para trabajar en la evoluci\u00f3n de una persona por medio de sus \u00e1reas comunicativas, sociales, cognitivas o psicomotrices. <\/li>\n<!-- \/wp:list-item --><\/ul>\n<!-- \/wp:list -->\n\n<!-- wp:heading -->\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Sobre_nuestro_Partner_Yaracan\"><\/span>Sobre nuestro Partner: Yaracan<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>Nuestro Partner, <strong><a href=\"https:\/\/www.yaracan.com\/\" target=\"_blank\" rel=\"noopener nofollow\" title=\"Yaracan\">Yaracan<\/a><\/strong>, responde a un prop\u00f3sito fundamental: <strong>Mejorar la calidad de la vida de las personas mediante intervenciones asistidas por animales<\/strong>. Esta empresa se fund\u00f3 en 2010, y sus ra\u00edces se remontan a una experiencia de apoyo y ayuda emocional de los perros de familia hace 40 a\u00f1os. \u00c9sta evolucion\u00f3 con el tiempo y se materializ\u00f3 en la empresa socialmente responsable que es hoy. <\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>A lo largo de estos a\u00f1os, Yacaran ha forjado un <strong>m\u00e9todo de trabajo \u00fanico y profesional<\/strong>, basado en la aplicaci\u00f3n de programas internacionales y el desarrollo de proyectos innovadores en colaboraci\u00f3n con destacados profesionales de la salud, veterinaria y educaci\u00f3n en Espa\u00f1a.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph {\"style\":{\"color\":{\"background\":\"#eeeeeeed\"}}} -->\n<p class=\"has-background\" style=\"background-color:#eeeeeeed\">En definitiva, desde <strong><a href=\"https:\/\/www.kiwoko.mom\/\" target=\"_blank\" rel=\"noopener\" title=\"\">Kiwoko<\/a> <\/strong>creemos que cada conexi\u00f3n entre humanos y animales es un paso m\u00e1s hacia la transformaci\u00f3n. Por eso, desde Momentos by Kiwoko queremos crear un futuro donde la empat\u00eda y la inclusi\u00f3n sean la norma, y por tanto, donde cualquier ni\u00f1o o joven pueda vivir la incre\u00edble experiencia de disfrutar todos los beneficios que aportan los animales de compa\u00f1\u00eda. <\/p>\n<!-- \/wp:paragraph -->","protected":false},"excerpt":{"rendered":"<p>Desde Kiwoko y en colaboraci\u00f3n con Hill&#8217;s os queremos presentar \u00abMomentos by Kiwoko\u00bb, un programa de terapia asistida con perros para ni\u00f1os y j\u00f3venes con necesidades especiales. \u00bfQuieres saber c\u00f3mo funciona este nuevo proyecto? \u00a1Sigue leyendo! \u00bfQu\u00e9 es \u00abMomentos by Kiwoko\u00bb? Momentos by Kiwoko es un nuevo proyecto creado en colaboraci\u00f3n con Hill&#8217;s. \u00abMomentos by [&hellip;]<\/p>\n","protected":false},"author":40,"featured_media":52892,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1057],"tags":[1109,1444],"class_list":["post-44326","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mundo-animal","tag-eventos","tag-eventos-y-aperturas"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-json\/wp\/v2\/posts\/44326","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-json\/wp\/v2\/users\/40"}],"replies":[{"embeddable":true,"href":"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-json\/wp\/v2\/comments?post=44326"}],"version-history":[{"count":16,"href":"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-json\/wp\/v2\/posts\/44326\/revisions"}],"predecessor-version":[{"id":52909,"href":"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-json\/wp\/v2\/posts\/44326\/revisions\/52909"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-json\/wp\/v2\/media\/52892"}],"wp:attachment":[{"href":"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-json\/wp\/v2\/media?parent=44326"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-json\/wp\/v2\/categories?post=44326"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-json\/wp\/v2\/tags?post=44326"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}