{"id":9980,"date":"2015-07-15T11:17:00","date_gmt":"2015-07-15T11:17:00","guid":{"rendered":"https:\/\/dev-kiwoko-es.on-dev.com\/blogmundoanimal\/kiwoko-anuncia-mejoras-en-su-protocolo-de-emergencias\/"},"modified":"2023-09-13T11:05:04","modified_gmt":"2023-09-13T09:05:04","slug":"kiwoko-anuncia-mejoras-en-su-protocolo-de-emergencias","status":"publish","type":"post","link":"https:\/\/www.kiwoko.mom\/blogmundoanimal\/kiwoko-anuncia-mejoras-en-su-protocolo-de-emergencias\/","title":{"rendered":"Kiwoko anuncia mejoras en su protocolo de emergencias"},"content":{"rendered":"<!-- wp:heading -->\n<h2 id=\"la-compania-manifiesta-su-tristeza-por-lo-ocurrido-en-elche-y-reconoce-el-error\"><strong>La compa\u00f1\u00eda manifiesta su tristeza por lo ocurrido en Elche y reconoce el error<\/strong><\/h2>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p><strong>Madrid, 15 de julio 2015.&nbsp;<\/strong>Ante el suceso ocurrido en nuestra tienda de Parque Comercial el Sauce en Elche (Alicante) el pasado 8 de julio, desde Kiwoko queremos mostrar nuestra tristeza y manifestar que lamentamos profundamente que un fallo t\u00e9cnico en el conducto del aire acondicionado ocasionara el fallecimiento de tres h\u00e1msteres y una cobaya.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Por esa raz\u00f3n, la compa\u00f1\u00eda desea realizar unas manifestaciones sobre nuestra filosof\u00eda y lo acontecido:<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:list {\"ordered\":true} -->\n<ol><!-- wp:list-item -->\n<li>En Kiwoko asesoramos a las personas interesadas en convivir con animales sobre aquellos que son los m\u00e1s indicados en funci\u00f3n de sus condiciones, explic\u00e1ndoles las peculiaridades del animal seleccionado y qu\u00e9 cuidados precisar\u00e1. De esta manera <strong>contribuimos a la toma de decisiones responsables y facilitamos la convivencia<\/strong> posterior.<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li><strong>Defendemos la adopci\u00f3n responsable de perros y gatos desde nuestros Centros de Adopci\u00f3n<\/strong> supervisados por veterinarios profesionales de las cl\u00ednicas Kivet repartidas por Alicante. Trabajamos de forma estrecha, con protectoras de las zonas donde est\u00e1n ubicadas nuestras tiendas para la concienciaci\u00f3n social y ayudar a buscar nuevas familias a los animales que lo precisan. Gracias a estas colaboraciones, ayudamos a que cada d\u00eda m\u00e1s de 10 perros y gatos consigan un nuevo hogar. Adem\u00e1s, donamos cada a\u00f1o toneladas de pienso para ayudar a las protectoras que no tienen medios.<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li><strong>Nuestro compromiso con los animales <\/strong>nos ha llevado a expedir un certificado en el que nuestros clientes manifiestan conocer que se<strong> hacen responsables de un ser vivo<\/strong> y como tal se comprometen a cuidarlo en las mejores condiciones posibles y de acuerdo a la Ley de Protecci\u00f3n Animal. Tambi\u00e9n ofrecemos a nuestros clientes la primera revisi\u00f3n veterinaria gratuita si as\u00ed lo desean.<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>Como parte de nuestra filosof\u00eda y nuestro compromiso con el mundo animal, <strong>velamos siempre por el bienestar de los animales<\/strong>. Por eso durante el tiempo que est\u00e1n en Kiwoko, y para asegurarnos de proporcionarles unas condiciones adecuadas, <strong>nuestras instalaciones cumplen todos los requisitos previstos para los n\u00facleos zool\u00f3gicos<\/strong>, tales como dimensiones necesarias y limpieza.<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li><strong>Nuestro personal est\u00e1 compuesto por un equipo de profesionales altamente preparado<\/strong> (ATVs, veterinarios, adiestradores, etc), que comparten con la compa\u00f1\u00eda su pasi\u00f3n por los animales y reciben formaci\u00f3n continua.<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li><strong>Dentro de la formaci\u00f3n que impartimos a nuestro equipo se encuentran los protocolos generales y espec\u00edficos Kiwoko, de obligado cumplimiento,<\/strong> que establecen c\u00f3mo se ha de proceder ante diversas situaciones, incluidas las de emergencia como la acontecida en Elche.<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>La misi\u00f3n de Kiwoko es <strong>ayudar a mejorar la vida de todas las mascotas<\/strong>, y trabajamos d\u00eda a d\u00eda asumiendo esa responsabilidad.<\/li>\n<!-- \/wp:list-item --><\/ol>\n<!-- \/wp:list -->\n\n<!-- wp:paragraph -->\n<p>Dado que algunas fuentes han publicado informaci\u00f3n inexacta sobre lo ocurrido, nos gustar\u00eda aclarar los hechos:<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:list {\"ordered\":true} -->\n<ol><!-- wp:list-item -->\n<li><strong>El pasado 8 de julio se produjo un fallo en el aire acondicionado de nuestras instalaciones de Elche<\/strong> que fue detectado por nuestro equipo. Nuestro personal se puso r\u00e1pidamente en contacto con la empresa de mantenimiento, cuyos operarios se personaron en las instalaciones de Kiwoko. El problema exigi\u00f3 el recambio de una pieza que, a pesar de nuestra insistencia, no pudo sustituirse hasta el jueves 9 de julio a las 14h.<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>Dado que el problema no se pod\u00eda reparar de forma instant\u00e1nea, <strong>el personal de tienda, junto a su equipo veterinario de la Cl\u00ednica Sanitos de Kiwoko, activ\u00f3 el plan de protocolo previsto ante situaciones de calor extremo<\/strong>.<\/li>\n<!-- \/wp:list-item --><\/ol>\n<!-- \/wp:list -->\n\n<!-- wp:paragraph -->\n<p>Este protocolo incluy\u00f3:<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:list -->\n<ul><!-- wp:list-item -->\n<li><strong>Colocaci\u00f3n de hielo en los comederos y bebederos<\/strong> de todos los animales para evitar un golpe de calor y favorecer su hidrataci\u00f3n.<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li><strong>Utilizaci\u00f3n de sprays con frecuencia para paliar la sensaci\u00f3n de calor<\/strong> entre los animales.<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>La noche del 8 al 9 de julio <strong>el personal de Kiwoko acogi\u00f3 en sus casas a varios animales<\/strong> para que estuvieran atendidos todo el tiempo.<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li><strong>El equipo directivo y el personal veterinario estudiaron planes de traslado de animales a otros centros<\/strong> que fueron desestimados debido al tiempo que precisaban y el riesgo que supon\u00edan.<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li><strong>El personal fue muy proactivo en la b\u00fasqueda e implementaci\u00f3n de soluciones alternativas<\/strong>. Por ejemplo, el equipo detect\u00f3 que una zona del almac\u00e9n reun\u00eda mejores condiciones y traslad\u00f3 all\u00ed a algunos animales, para lo que se don\u00f3 la mercanc\u00eda que hasta ese momento estaba ah\u00ed emplazada.<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li><strong>Kiwoko trabaj\u00f3 conjuntamente con la Polic\u00eda Local de Elche para garantizar el bienestar de todos los animales.<\/strong> Durante el suceso, la Polic\u00eda Local de Elche fue alertada por una ciudadana y se desplaz\u00f3 hasta el centro para verificar que la situaci\u00f3n estuviera controlada y los animales estuvieran siendo bien tratados. Una vez realizaron los pertinentes controles, los agentes ayudaron al personal a encontrar ubicaciones mejores para los animales, <strong>expidiendo un parte oficial en el que se constata el fallecimiento de tres h\u00e1msteres y una cobaya<\/strong>.<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>Como amantes de los animales que somos y para evitar que en el futuro puedan volver a darse situaciones de este tipo, <strong>Kiwoko ha puesto en marcha un programa de mejoras <\/strong>que parte del an\u00e1lisis de este caso y de la escucha activa de nuestros clientes.<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>Producto de esta acci\u00f3n <strong>se han tomado una serie de decisiones para su puesta en pr\u00e1ctica de inmediato, como la realizaci\u00f3n de una comprobaci\u00f3n de los sistemas de refrigeraci\u00f3n fuera del calendario habitual de mantenimiento<\/strong>. <strong>Adicionalmente Kiwoko se compromete a instalar un sistema independiente de Climatizaci\u00f3n en los establecimientos con Cl\u00ednicas Veterinarias Sanitos<\/strong> (como es el caso de Elche).<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li><strong>Se est\u00e1n revisando todos los protocolos actuales, estudiando la viabilidad de implementar otras acciones.<\/strong> Se ha solicitado la colaboraci\u00f3n de representantes de todos los perfiles relacionados con los establecimientos Kiwoko con el fin de elaborar planes \u00f3ptimos y realizables.<\/li>\n<!-- \/wp:list-item --><\/ul>\n<!-- \/wp:list -->\n\n<!-- wp:paragraph -->\n<p>Desde Kiwoko nos gustar\u00eda<strong> expresar el pesar de todo el personal por lo ocurrido y nuestra solidaridad con los compa\u00f1eros del centro de Elche<\/strong>, que se volc\u00f3 en esta situaci\u00f3n excepcional y est\u00e1 sufriendo la incomprensi\u00f3n de algunas personas que critican duramente su actuaci\u00f3n. Si bien es cierto que la resoluci\u00f3n del problema no estaba en nuestra mano, nos apena profundamente no haber sabido reaccionar mejor ante algunos puntos manifiestamente mejorables de nuestro protocolo. Por este motivo, <strong>Kiwoko ha convertido en un objetivo prioritario la toma inmediata de medidas para que no se vuelva a dar nunca una situaci\u00f3n similar.<\/strong><\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p><strong>Kiwoko<\/strong><\/p>\n<!-- \/wp:paragraph -->","protected":false},"excerpt":{"rendered":"<p>Ante el suceso ocurrido en nuestra tienda de Parque Comercial el Sauce en Elche (Alicante) el pasado 8 de julio, desde Kiwoko queremos mostrar nuestra tristeza y manifestar que lamentamos profundamente lo ocurrido.<\/p>\n","protected":false},"author":40,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1057],"tags":[1109,1439],"class_list":["post-9980","post","type-post","status-publish","format-standard","hentry","category-mundo-animal","tag-eventos","tag-interno"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-json\/wp\/v2\/posts\/9980","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-json\/wp\/v2\/users\/40"}],"replies":[{"embeddable":true,"href":"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-json\/wp\/v2\/comments?post=9980"}],"version-history":[{"count":5,"href":"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-json\/wp\/v2\/posts\/9980\/revisions"}],"predecessor-version":[{"id":42443,"href":"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-json\/wp\/v2\/posts\/9980\/revisions\/42443"}],"wp:attachment":[{"href":"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-json\/wp\/v2\/media?parent=9980"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-json\/wp\/v2\/categories?post=9980"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.kiwoko.mom\/blogmundoanimal\/wp-json\/wp\/v2\/tags?post=9980"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}